{"id":1169,"date":"2021-05-23T14:57:18","date_gmt":"2021-05-23T20:57:18","guid":{"rendered":"https:\/\/costaricainfolink.com\/directorio\/?p=1169"},"modified":"2021-06-02T16:10:10","modified_gmt":"2021-06-02T22:10:10","slug":"almacenes-el-rey-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/","title":{"rendered":"Almacenes El Rey Costa Rica"},"content":{"rendered":"<h2><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"1310\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?fit=1667%2C1667&amp;ssl=1\" data-orig-size=\"1667,1667\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Almacen El Rey Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?fit=1024%2C1024&amp;ssl=1\" class=\"alignright wp-image-1310 size-thumbnail\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?resize=150%2C150&#038;ssl=1\" alt=\"Almacen El Rey Costa Rica\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?w=1667&amp;ssl=1 1667w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>Almacenes<\/h2>\n<p><a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#cartago\">Cartago<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#cristorey\">Cristo Rey<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#curridabat\">Curridabat<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#escazu\">Escazu<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#guapiles\">Gu\u00e1piles<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#montserratalajuela\">Monserrat<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#paseodelasfloresheredia\">Paseo de Las Flores<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#sanfranciscoheredia\">San Francisco<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#sanjose\">San Jose<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#sanramon\">San Ram\u00f3n Centro<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#sanramonplazaoccidente\">San Ram\u00f3n Mall<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#zapote\">Zapote<\/a><\/p>\n<h2>BODEGAS<\/h2>\n<p><a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#liberia\">Liberia<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#perezzeledon\">Perez Zeled\u00f3n<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#puntarenas\">Puntarenas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#santacruz\">Santa Cruz<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#sancarlos\">San Carlos<\/a><\/p>\n<h2 id=\"cartago\">Almacen El Rey Cartago<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 8pm. Domingos de 9am a 6pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50625528002\">+506 2552-8002<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nCostado oeste del parque central. Distrito: Oriental, cant\u00f3n: Cartago, provincia: Cartago, Costa Rica. C\u00f3digo postal de la zona: 30101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u247f29\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Cartago Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/5cy9S2qf8pJJPUcQ6\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey Cartago Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"cristorey\">Almacen El Rey Cristo Rey<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 9pm. Domingos de 9am a 8pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50624304125\">+506 2430-4125<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nFrente al INA. Distrito: Alajuela, cant\u00f3n: Alajuela, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 20101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0gx25n\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Cristo Rey Alajuela Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/UuFHdBxuJ8gbXRb57\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey Cristo Rey Alajuela Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"curridabat\">Almacen El Rey Curridabat<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 9pm. Domingos de 9am a 8pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50625241821\">+506 2524-1821<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nFrente a Multiuplaza del Este. Distrito: Curridabat, cant\u00f3n: Curridabat, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11801.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rmxh1\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Curridabat Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/yZezuFZic5szMxHU8\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey Curridabat Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"escazu\">Almacen El Rey Escazu<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 9pm. Domingos de 9am a 8pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50622156313\">+506 2215-6313<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nFrente a Multiuplaza, contiguo a Color Visi\u00f3n. Distrito: San Rafael, cant\u00f3n: Escazu, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0t4s9z\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Escazu Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/vV8MsGdYnJhqZjPW8\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey Escazu Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"guapiles\">Almacen El Rey Guapiles<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 8pm. Domingos de 9am a 7pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50640806969\">+506 4080-6969<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nBarrio Pinares. Distrito: Guapiles, cant\u00f3n: Pococi, provincia: Limon, Costa Rica. C\u00f3digo postal de la zona: 70201.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u6j7n1k\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Guapiles Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/VD3KVcjnzG6kxGbg7\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey Guapiles Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"montserratalajuela\">Almacen El Rey Montserrat, Alajuela<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 8pm. Domingos de 9am a 8pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50624303003\">+506 2430-3003<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\n150 metros sur de Molinos de Costa Rica, Montserrat. Distrito: Alajuela, cant\u00f3n: Alajuela, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 20101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0gtvdf\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Montserrat Alajuela Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/nM55qnS6GeGYu2Dq9\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey Montserrat Alajuela Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"paseodelasfloresheredia\">Almacen El Rey Paseo de Las Flores<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 9pm. Domingos de 9am a 8pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50622384017\">+506 2238-4017<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nCostado norte Paseo de las Flores, 200 metros oeste. Distrito: San Francisco, cant\u00f3n: Heredia, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40103.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0vfjcj\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Paseo de Las Flores Heredia Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/qgDoXpPJyvAD8oyH7\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey Paseo de Las Flores Heredia Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"sanfranciscoheredia\">Almacen El Rey San Francisco Heredia<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 9pm. Domingos de 9am a 8pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50640807770\">+506 4080-7770<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\n800 metros oeste de Oxigeno. Distrito: San Francisco, cant\u00f3n: Heredia, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40103.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0vk5bh\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey San Francisco Heredia Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/d5pKbsPZ8gcCTHSQ7\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey San Francisco Heredia Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"sanramon\">Almacen El Rey San Ram\u00f3n<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 8pm. Domingos de 9am a 6pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50624456473\">+506 2445-6473<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nFrente a Supermercado Pal\u00ed, antigua Ferreter\u00eda Dimar. Distrito: San Ram\u00f3n, cant\u00f3n: San Ram\u00f3n, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 20201.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1gcmv489\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey San Ramon Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/MatxTg7v7fVfyi8U7\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey San Ramon Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"sanramonplazaoccidente\">Almacen El Rey Plaza Occidente<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 8pm. Domingos de 9am a 6pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50624453317\">+506 2445-3317<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nMall Plaza Occidente, local #50. Distrito: San Rafael, cant\u00f3n: San Ram\u00f3n, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 20206.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1gcmfej1\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Plaza Occidente San Ramon Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/wDJsbfev9yXUfnNF6\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey en Plaza Occidente San Ramon Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"zapote\">Almacen El Rey Zapote<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a S\u00e1bado de 8am a 9pm. Domingos de 9am a 8pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50622345151\">+506 2234-5151<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\n150 metros norte de la rotonda de las garant\u00edas sociales. Distrito: Zapote, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10105.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rnrjh\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Zapote San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/cwHnV2TZEEgbi5Dq8\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey Zapote San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"liberia\">Almacen El Rey Liberia<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a Domingo de 9am a 7pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50672405028\">+506 7240-5028<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nFrente a plaza 25 de Julio. Distrito: Liberia, cant\u00f3n: Liberia, provincia: Guanacaste, Costa Rica. C\u00f3digo postal de la zona: 50101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1ghryb2p\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Liberia Guanacaste Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/vvNpT31NgYqf2ukt6\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey Liberia Guanacaste Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"perezzeledon\">Almacen El Rey Perez Zeled\u00f3n<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a Domingo de 9am a 7pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50672375664\">+506 7237-5664<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nMall Monte General. Distrito: Daniel Flores, cant\u00f3n: Perez Zeled\u00f3n, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11903.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1smpuqxg\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey Daniel Flores Zeledon San Jose Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/mzeJJ1Hia4yJsxTZ9\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey en Daniel Flores Zeledon San Jose Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"puntarenas\">Almacen El Rey Puntarenas<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a Domingo de 9am a 7pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50672376756\">+506 7237-6756<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nFrente al AyA. Distrito: Barranca, cant\u00f3n: Puntarenas, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 60108.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1g8zbqup\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey en Barranca, Puntarenas Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/kh1YZAaVbMWMo2Uk6\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey en Barranca, Puntarenas Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"santacruz\">Almacen El Rey Santa Cruz<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a Domingo de 9am a 7pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50672371547\">+506 7237-1547<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nCostado norte de la plaza de Buenos Aires, contiguo a Repuestos Gomez. Distrito: Santa Cruz, cant\u00f3n: Santa Cruz, provincia: Guanacaste, Costa Rica. C\u00f3digo postal de la zona: 50301.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1g4kktwx\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey en Santa Cruz Guanacaste Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/tzwrvN89AvfCeGfg8\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey en Santa Cruz Guanacaste Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"sancarlos\">Almacen El Rey San Carlos<\/h2>\n<p><strong>Horario<\/strong><br \/>\nLunes a Domingo de 9am a 7pm.<\/p>\n<p><strong>Tel\u00e9fono<\/strong><br \/>\n<a href=\"tel:+50640805800\">+506 4080-5800<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong><br \/>\nEn Plaza San Carlos. Distrito: Quesada, cant\u00f3n: San Carlos, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 21001.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1gfy9hdz\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Almacen El Rey en San Carlos Alajuela Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/MHtCaBEeQc25YXR5A\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Almacen El Rey en San Carlos Alajuela Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Almacenes Cartago \u00b7 Cristo Rey \u00b7 Curridabat \u00b7 Escazu \u00b7 Gu\u00e1piles \u00b7 Monserrat \u00b7 Paseo de Las Flores \u00b7 San Francisco \u00b7 San Jose \u00b7 San Ram\u00f3n Centro \u00b7 San Ram\u00f3n Mall \u00b7 Zapote BODEGAS Liberia \u00b7 Perez Zeled\u00f3n \u00b7 Puntarenas \u00b7 Santa Cruz \u00b7 San Carlos Almacen El Rey Cartago Horario Lunes a S\u00e1bado &#8230; <a title=\"Almacenes El Rey Costa Rica\" class=\"read-more\" href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/\" aria-label=\"Leer m\u00e1s sobre Almacenes El Rey Costa Rica\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[49,17,16,150,4,146,149,159,63,42,70,156,153,33,3,155,157,46,15,152,18,68,36,21,69,34,64,151,35,73,154,158,97,43,5,148,19,147,120,48],"tags":[],"class_list":["post-1169","post","type-post","status-publish","format-standard","hentry","category-49","category-17","category-16","category-150","category-4","category-146","category-149","category-159","category-63","category-42","category-70","category-156","category-153","category-33","category-alajuela","category-barranca","category-buenos-aires","category-cartago","category-curridabat","category-daniel-flores","category-escazu","category-guanacaste","category-guapiles","category-heredia","category-liberia","category-limon","category-oriental","category-perez-zeledon-san-jose","category-pococi","category-puntarenas","category-puntarenas-puntarenas","category-quesada","category-san-carlos","category-san-francisco","category-san-jose","category-san-rafael-san-ramon","category-san-rafael","category-san-ramon","category-santa-cruz","category-zapote"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Almacenes El Rey Costa Rica - Ubicaciones, Horarios, Tel\u00e9fonos<\/title>\n<meta name=\"description\" content=\"Almacenes El Rey Costa Rica . Direcciones, horarios, telefonos, ubicaciones WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Almacenes El Rey Costa Rica - Ubicaciones, Horarios, Tel\u00e9fonos\" \/>\n<meta property=\"og:description\" content=\"Almacenes El Rey Costa Rica . Direcciones, horarios, telefonos, ubicaciones WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-23T20:57:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-02T22:10:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion-150x150.png\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\"},\"headline\":\"Almacenes El Rey Costa Rica\",\"datePublished\":\"2021-05-23T20:57:18+00:00\",\"dateModified\":\"2021-06-02T22:10:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/\"},\"wordCount\":778,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion-150x150.png\",\"articleSection\":[\"10105\",\"10203\",\"11801\",\"11903\",\"20101\",\"20201\",\"20206\",\"21001\",\"30101\",\"40103\",\"50101\",\"50301\",\"60108\",\"70201\",\"Alajuela\",\"Barranca\",\"Buenos Aires\",\"Cartago\",\"Curridabat\",\"Daniel Flores\",\"Escaz\u00fa\",\"Guanacaste\",\"Gu\u00e1piles\",\"Heredia\",\"Liberia\",\"Lim\u00f3n\",\"Oriental\",\"Perez Zeled\u00f3n\",\"Pococ\u00ed\",\"Puntarenas\",\"Puntarenas\",\"Quesada\",\"San Carlos\",\"San Francisco\",\"San Jos\u00e9\",\"San Rafael\",\"San Rafael\",\"San Ram\u00f3n\",\"Santa Cruz\",\"Zapote\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/\",\"name\":\"Almacenes El Rey Costa Rica - Ubicaciones, Horarios, Tel\u00e9fonos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion-150x150.png\",\"datePublished\":\"2021-05-23T20:57:18+00:00\",\"dateModified\":\"2021-06-02T22:10:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\"},\"description\":\"Almacenes El Rey Costa Rica . Direcciones, horarios, telefonos, ubicaciones WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?fit=1667%2C1667&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?fit=1667%2C1667&ssl=1\",\"width\":1667,\"height\":1667,\"caption\":\"Almacen El Rey Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/almacenes-el-rey-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Almacenes El Rey Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/\",\"name\":\"Costa Rica\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"],\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/author\\\/costaricainfolink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Almacenes El Rey Costa Rica - Ubicaciones, Horarios, Tel\u00e9fonos","description":"Almacenes El Rey Costa Rica . Direcciones, horarios, telefonos, ubicaciones WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Almacenes El Rey Costa Rica - Ubicaciones, Horarios, Tel\u00e9fonos","og_description":"Almacenes El Rey Costa Rica . Direcciones, horarios, telefonos, ubicaciones WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2021-05-23T20:57:18+00:00","article_modified_time":"2021-06-02T22:10:10+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion-150x150.png","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce"},"headline":"Almacenes El Rey Costa Rica","datePublished":"2021-05-23T20:57:18+00:00","dateModified":"2021-06-02T22:10:10+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/"},"wordCount":778,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion-150x150.png","articleSection":["10105","10203","11801","11903","20101","20201","20206","21001","30101","40103","50101","50301","60108","70201","Alajuela","Barranca","Buenos Aires","Cartago","Curridabat","Daniel Flores","Escaz\u00fa","Guanacaste","Gu\u00e1piles","Heredia","Liberia","Lim\u00f3n","Oriental","Perez Zeled\u00f3n","Pococ\u00ed","Puntarenas","Puntarenas","Quesada","San Carlos","San Francisco","San Jos\u00e9","San Rafael","San Rafael","San Ram\u00f3n","Santa Cruz","Zapote"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/","url":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/","name":"Almacenes El Rey Costa Rica - Ubicaciones, Horarios, Tel\u00e9fonos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/directorio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion-150x150.png","datePublished":"2021-05-23T20:57:18+00:00","dateModified":"2021-06-02T22:10:10+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce"},"description":"Almacenes El Rey Costa Rica . Direcciones, horarios, telefonos, ubicaciones WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?fit=1667%2C1667&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion.png?fit=1667%2C1667&ssl=1","width":1667,"height":1667,"caption":"Almacen El Rey Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/directorio\/"},{"@type":"ListItem","position":2,"name":"Almacenes El Rey Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/directorio\/#website","url":"https:\/\/costaricainfolink.com\/directorio\/","name":"Costa Rica","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/directorio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644","url":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644","contentUrl":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"],"url":"https:\/\/costaricainfolink.com\/directorio\/author\/costaricainfolink\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p88Lb6-iR","jetpack-related-posts":[{"id":489,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-fischel\/","url_meta":{"origin":1169,"position":0},"title":"Farmacias Fischel Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"26 agosto, 2019","format":false,"excerpt":"Farmacias Fischel es una de las cadenas farmac\u00e9uticas m\u00e1s grandes de Costa Rica, con m\u00e1s de 50 sucursales en San Jos\u00e9, Escaz\u00fa, Heredia, Alajuela, Cartago, Guanacaste, Puntarenas y Lim\u00f3n. La mayor\u00eda de sucursales abre todos los d\u00edas de 9am a 9pm; varias sedes tienen horario extendido hasta medianoche. Adem\u00e1s del\u2026","rel":"","context":"En \u00ab10102\u00bb","block_context":{"text":"10102","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10102\/"},"img":{"alt_text":"Farmacias Fischel Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":404,"url":"https:\/\/costaricainfolink.com\/directorio\/automercado\/","url_meta":{"origin":1169,"position":1},"title":"AutoMercado","author":"Costa Rica Info Link","date":"20 septiembre, 2018","format":false,"excerpt":"Ubicaciones San Jos\u00e9 Centro - Escaz\u00fa - Guadalupe - Guachipel\u00edn - Moravia - Multiplaza - Plaza del Sol - Plaza Mayor - R\u00edo Oro - Santa Ana - Yoses Puntarenas Herradura Heredia Barva - Plaza Bratsi - Santo Domingo - San Francisco Cartago Tres R\u00edos Guanacaste El Coco - Tamarindo\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10101\/"},"img":{"alt_text":"AutoMercado Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/09\/automercado-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":808,"url":"https:\/\/costaricainfolink.com\/directorio\/walmart\/","url_meta":{"origin":1169,"position":2},"title":"Walmart Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"5 octubre, 2019","format":false,"excerpt":"Walmart Costa Rica opera 13 tiendas en todo el pa\u00eds, con presencia en San Jos\u00e9, Alajuela, Heredia, Cartago y Guanacaste. La cadena ofrece supermercado, electr\u00f3nica, ropa, l\u00ednea blanca y m\u00e1s bajo un mismo techo. La mayor\u00eda de tiendas abre los 7 d\u00edas de la semana con horario extendido los viernes\u2026","rel":"","context":"En \u00ab10111\u00bb","block_context":{"text":"10111","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10111\/"},"img":{"alt_text":"Walmart Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/walmart-costa-rica-2-1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":79,"url":"https:\/\/costaricainfolink.com\/directorio\/pricesmart\/","url_meta":{"origin":1169,"position":3},"title":"PriceSmart Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"3 enero, 2017","format":false,"excerpt":"PriceSmart es un club de compras mayorista que opera en Costa Rica con 7 sucursales en San Jos\u00e9, Escaz\u00fa, Heredia, Alajuela, Cartago y Santa Ana. Requiere membres\u00eda anual para acceder a precios de mayorista en alimentos, electr\u00f3nica, llantas, farmacia, panader\u00eda y m\u00e1s. Todas las sedes abren los 7 d\u00edas de\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10203\/"},"img":{"alt_text":"PriceSmart Costa Rica Zapote, Escaz\u00fa, Heredia, Llorente, Alajuela, Tres R\u00edos y santa Ana.","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/01\/pricesmart-costa-rica-1-300x96.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":198,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/","url_meta":{"origin":1169,"position":4},"title":"Farma Value \u2014 Sucursales y Horarios en Costa Rica","author":"Costa Rica Info Link","date":"12 marzo, 2018","format":false,"excerpt":"Farma Value es una cadena de farmacias centroamericana fundada en Honduras en 2002, especializada en medicamentos gen\u00e9ricos de bajo costo y productos de salud. Con m\u00e1s de 5,000 empleados y 300 puntos de servicio en M\u00e9xico, Guatemala, Honduras, El Salvador, Nicaragua, Costa Rica, Panam\u00e1 y Rep\u00fablica Dominicana, Farma Value es\u2026","rel":"","context":"En \u00ab10102\u00bb","block_context":{"text":"10102","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10102\/"},"img":{"alt_text":"Farmacias Farma Value Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":833,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-saba\/","url_meta":{"origin":1169,"position":5},"title":"Farmacias Saba Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"10 octubre, 2019","format":false,"excerpt":"Farmacia Saba es una cadena de farmacias originaria de Honduras, presente en Costa Rica desde 2018 con m\u00e1s de 30 sucursales en el Gran \u00c1rea Metropolitana y zonas como San Ram\u00f3n, Grecia y P\u00e9rez Zeled\u00f3n. Se especializa en medicamentos gen\u00e9ricos de bajo costo. Ofrecen entrega a domicilio gratis llamando al\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10101\/"},"img":{"alt_text":"Farmacias Saba Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-saba-costa-rica-21.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/1169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/comments?post=1169"}],"version-history":[{"count":80,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/1169\/revisions"}],"predecessor-version":[{"id":1323,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/1169\/revisions\/1323"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/media?parent=1169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/categories?post=1169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/tags?post=1169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}