{"id":119,"date":"2017-03-03T00:59:07","date_gmt":"2017-03-03T00:59:07","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/directorio\/?p=119"},"modified":"2017-03-07T18:23:36","modified_gmt":"2017-03-07T18:23:36","slug":"ganadera-america","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/","title":{"rendered":"Ganadera Am\u00e9rica"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"120\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/ganadera-america-ganaderia-barva-heredia-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica.jpg?fit=900%2C800&amp;ssl=1\" data-orig-size=\"900,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica.jpg?fit=900%2C800&amp;ssl=1\" class=\"alignright size-medium wp-image-120\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica-300x267.jpg?resize=300%2C267&#038;ssl=1\" alt=\"Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" width=\"300\" height=\"267\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica.jpg?resize=300%2C267&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica.jpg?resize=768%2C683&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica.jpg?resize=560%2C498&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica.jpg?resize=260%2C231&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica.jpg?resize=160%2C142&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica.jpg?w=900&amp;ssl=1 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h2>Ubicaci\u00f3n:<\/h2>\n<p><strong>Distrito<\/strong>: San Jose de la Monta\u00f1a, <strong>cant\u00f3n<\/strong>: Barva, <strong>provincia<\/strong>: Heredia. C\u00f3digo postal de la zona: 40206.<\/p>\n<h2>Tel\u00e9fono:<\/h2>\n<p><a href=\"tel:+50625096038\">+506 2509-6038<\/a><\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u1jv5es\" target=\"_blank\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Ganader\u00eda Am\u00e9rica, San Jos\u00e9 de la Monta\u00f1a, Barva, Heredia, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/10%C2%B002'51.7%22N+84%C2%B007'01.9%22W\/@10.0477043,-84.1193797,17z\/data=!3m1!4b1!4m5!3m4!1s0x0:0x0!8m2!3d10.047699!4d-84.117191\" target=\"_blank\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google Ganader\u00eda Am\u00e9rica, San Jos\u00e9 de la Monta\u00f1a, Barva, Heredia, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<p>Hacienda dedicada a la cr\u00eda y entrenamiento de Caballos de Pura Raza Espa\u00f1ola. Ha participado en m\u00faltiples concursos tanto nacionales como internacionales, e incluso este a\u00f1o es la sede de la VIII Feria Centroamericana del Caballo de Pura Raza Espa\u00f1ola.<\/p>\n<h2>Correo Electr\u00f3nico<\/h2>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"133\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/correo-electronico-ganadera-america-barva-heredia-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/correo-electronico-ganadera-america-barva-heredia-costa-rica.png?fit=554%2C35&amp;ssl=1\" data-orig-size=\"554,35\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Ganadera Am\u00e9rica &amp;#8211; Barva, Heredia, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/correo-electronico-ganadera-america-barva-heredia-costa-rica.png?fit=554%2C35&amp;ssl=1\" class=\"alignnone size-full wp-image-133\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/correo-electronico-ganadera-america-barva-heredia-costa-rica.png?resize=554%2C35&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Ganadera Am\u00e9rica - Barva, Heredia, Costa Rica\" width=\"554\" height=\"35\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/correo-electronico-ganadera-america-barva-heredia-costa-rica.png?w=554&amp;ssl=1 554w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/correo-electronico-ganadera-america-barva-heredia-costa-rica.png?resize=300%2C19&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/correo-electronico-ganadera-america-barva-heredia-costa-rica.png?resize=260%2C16&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/correo-electronico-ganadera-america-barva-heredia-costa-rica.png?resize=160%2C10&amp;ssl=1 160w\" sizes=\"(max-width: 554px) 100vw, 554px\" \/><br \/>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1200\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/&quot;,&quot;likes_blog_id&quot;:120298668}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1200px; height: 573px;\" data-original-width=\"1200\" data-original-height=\"573\" > <div class=\"gallery-group images-1\" style=\"width: 857px; height: 573px;\" data-original-width=\"857\" data-original-height=\"573\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/alta-escuela-con-lacayo-y-nuestro-jinete-sergio-quesada-ganadera-america-1\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"853\"> <meta itemprop=\"height\" content=\"569\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"124\" data-orig-file=\"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg\" data-orig-size=\"2048,1367\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Alta escuela con Lacayo y nuestro jinete Sergio Quesada &amp;#8211; Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?fit=1024%2C684&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?w=853&#038;h=569&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?resize=560%2C374&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?resize=260%2C174&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?resize=160%2C107&amp;ssl=1 160w\" width=\"853\" height=\"569\" loading=\"lazy\" data-original-width=\"853\" data-original-height=\"569\" itemprop=\"http:\/\/schema.org\/image\" title=\"Alta escuela con Lacayo y nuestro jinete Sergio Quesada - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" alt=\"Alta escuela con Lacayo y nuestro jinete Sergio Quesada - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" style=\"width: 853px; height: 569px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 343px; height: 573px;\" data-original-width=\"343\" data-original-height=\"573\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/fruto-de-nuestra-dedicacion-y-esfuerzo-tipo-de-enganche-cuarta-ganaderia-america\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"339\"> <meta itemprop=\"height\" content=\"226\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"125\" data-orig-file=\"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Fruto-de-nuestra-dedicaci\u00f3n-y-esfuerzo-Tipo-de-enganche-Cuarta-ganaderia-america.jpg\" data-orig-size=\"2048,1367\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Fruto de nuestra dedicaci\u00f3n y esfuerzo-Tipo de enganche Cuarta &amp;#8211; Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Fruto-de-nuestra-dedicaci%C3%B3n-y-esfuerzo-Tipo-de-enganche-Cuarta-ganaderia-america.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Fruto-de-nuestra-dedicaci%C3%B3n-y-esfuerzo-Tipo-de-enganche-Cuarta-ganaderia-america.jpg?fit=1024%2C684&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Fruto-de-nuestra-dedicaci%C3%B3n-y-esfuerzo-Tipo-de-enganche-Cuarta-ganaderia-america.jpg?w=339&#038;h=226&#038;ssl=1\" width=\"339\" height=\"226\" loading=\"lazy\" data-original-width=\"339\" data-original-height=\"226\" itemprop=\"http:\/\/schema.org\/image\" title=\"Fruto de nuestra dedicaci\u00f3n y esfuerzo-Tipo de enganche Cuarta - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" alt=\"Fruto de nuestra dedicaci\u00f3n y esfuerzo-Tipo de enganche Cuarta - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" style=\"width: 339px; height: 226px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/lacayo-fv-realizando-una-elevada-con-la-guia-de-nuestro-jinete-sergio-quesada-ganadera-america\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"339\"> <meta itemprop=\"height\" content=\"339\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"126\" data-orig-file=\"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Lacayo-FV-realizando-una-elevada-con-la-gu\u00eda-de-nuestro-jinete-Sergio-Quesada-ganadera-america.jpg\" data-orig-size=\"1875,1875\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Lacayo FV realizando una elevada con la gu\u00eda de nuestro jinete Sergio Quesada &amp;#8211; Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Lacayo-FV-realizando-una-elevada-con-la-gu%C3%ADa-de-nuestro-jinete-Sergio-Quesada-ganadera-america.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Lacayo-FV-realizando-una-elevada-con-la-gu%C3%ADa-de-nuestro-jinete-Sergio-Quesada-ganadera-america.jpg?fit=1024%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Lacayo-FV-realizando-una-elevada-con-la-gu%C3%ADa-de-nuestro-jinete-Sergio-Quesada-ganadera-america.jpg?w=339&#038;h=339&#038;crop=1&#038;ssl=1\" width=\"339\" height=\"339\" loading=\"lazy\" data-original-width=\"339\" data-original-height=\"339\" itemprop=\"http:\/\/schema.org\/image\" title=\"Lacayo FV realizando una elevada con la gu\u00eda de nuestro jinete Sergio Quesada - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" alt=\"Lacayo FV realizando una elevada con la gu\u00eda de nuestro jinete Sergio Quesada - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" style=\"width: 339px; height: 339px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 402px;\" data-original-width=\"1200\" data-original-height=\"402\" > <div class=\"gallery-group images-1\" style=\"width: 600px; height: 402px;\" data-original-width=\"600\" data-original-height=\"402\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/nuestro-jinete-sergio-quesada-realiza-pruebas-de-adiestramiento-con-tango-ganadera-america\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"398\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"127\" data-orig-file=\"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg\" data-orig-size=\"2048,1367\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Nuestro jinete Sergio Quesada realiza pruebas de adiestramiento con Tango-ganadera &amp;#8211; Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?fit=1024%2C684&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?w=596&#038;h=398&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?resize=560%2C374&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?resize=260%2C174&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Nuestro-jinete-Sergio-Quesada-realiza-pruebas-de-adiestramiento-con-Tango-ganadera-america.jpg?resize=160%2C107&amp;ssl=1 160w\" width=\"596\" height=\"398\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"398\" itemprop=\"http:\/\/schema.org\/image\" title=\"Nuestro jinete Sergio Quesada realiza pruebas de adiestramiento con Tango-ganadera - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" alt=\"Nuestro jinete Sergio Quesada realiza pruebas de adiestramiento con Tango-ganadera - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" style=\"width: 596px; height: 398px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 600px; height: 402px;\" data-original-width=\"600\" data-original-height=\"402\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/olivia-y-gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"398\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"128\" data-orig-file=\"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg\" data-orig-size=\"2048,1367\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Olivia y Gitano, madre e hijo compartiendo en nuestro campo abierto &amp;#8211; Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?fit=1024%2C684&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?w=596&#038;h=398&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?resize=560%2C374&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?resize=260%2C174&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Olivia-y-Gitano-madre-e-hijo-compartiendo-en-nuestro-campo-abierto-ganadera-america.jpg?resize=160%2C107&amp;ssl=1 160w\" width=\"596\" height=\"398\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"398\" itemprop=\"http:\/\/schema.org\/image\" title=\"Olivia y Gitano, madre e hijo compartiendo en nuestro campo abierto - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" alt=\"Olivia y Gitano, madre e hijo compartiendo en nuestro campo abierto - Ganadera Am\u00e9rica, Barva, Heredia, Costa Rica\" style=\"width: 596px; height: 398px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div><\/p>\n<h2>Facebook<\/h2>\n<div class=\"fb-page\" data-href=\"https:\/\/www.facebook.com\/GanaderaAmerica\" data-tabs=\"timeline\" data-width=\"500\" data-height=\"200\" data-small-header=\"true\" data-adapt-container-width=\"true\" data-hide-cover=\"true\" data-show-facepile=\"false\">\n<blockquote class=\"fb-xfbml-parse-ignore\" cite=\"https:\/\/www.facebook.com\/GanaderaAmerica\"><p><a href=\"https:\/\/www.facebook.com\/GanaderaAmerica\" target=\"_blank\">Ganadera Am\u00e9rica<\/a><\/p><\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ubicaci\u00f3n: Distrito: San Jose de la Monta\u00f1a, cant\u00f3n: Barva, provincia: Heredia. C\u00f3digo postal de la zona: 40206. Tel\u00e9fono: +506 2509-6038 Hacienda dedicada a la cr\u00eda y entrenamiento de Caballos de Pura Raza Espa\u00f1ola. Ha participado en m\u00faltiples concursos tanto nacionales como internacionales, e incluso este a\u00f1o es la sede de la VIII Feria Centroamericana del &#8230; <a title=\"Ganadera Am\u00e9rica\" class=\"read-more\" href=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/\" aria-label=\"Leer m\u00e1s sobre Ganadera Am\u00e9rica\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30,31,21,32,1],"tags":[],"class_list":["post-119","post","type-post","status-publish","format-standard","hentry","category-30","category-barva","category-heredia","category-san-jose-de-la-montana","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ganadera Am\u00e9rica - Costa Rica<\/title>\n<meta name=\"description\" content=\"Direcci\u00f3n, tel\u00e9fono, fotos, ubicaci\u00f3n WAZE y mapas de Google. Ganadera Am\u00e9rica en San Jos\u00e9 de la Monta\u00f1a, Barva, Heredia, Costa Rica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ganadera Am\u00e9rica - Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n, tel\u00e9fono, fotos, ubicaci\u00f3n WAZE y mapas de Google. Ganadera Am\u00e9rica en San Jos\u00e9 de la Monta\u00f1a, Barva, Heredia, Costa Rica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-03T00:59:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-07T18:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?w=682&#038;h=455&#038;ssl=1\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\"},\"headline\":\"Ganadera Am\u00e9rica\",\"datePublished\":\"2017-03-03T00:59:07+00:00\",\"dateModified\":\"2017-03-07T18:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/\"},\"wordCount\":82,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/ganadera-america-ganaderia-barva-heredia-costa-rica-300x267.jpg\",\"articleSection\":[\"40206\",\"Barva\",\"Heredia\",\"San Jos\u00e9 de La Monta\u00f1a\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/\",\"name\":\"Ganadera Am\u00e9rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/ganadera-america-ganaderia-barva-heredia-costa-rica-300x267.jpg\",\"datePublished\":\"2017-03-03T00:59:07+00:00\",\"dateModified\":\"2017-03-07T18:23:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\"},\"description\":\"Direcci\u00f3n, tel\u00e9fono, fotos, ubicaci\u00f3n WAZE y mapas de Google. Ganadera Am\u00e9rica en San Jos\u00e9 de la Monta\u00f1a, Barva, Heredia, Costa Rica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/ganadera-america-ganaderia-barva-heredia-costa-rica-300x267.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/ganadera-america-ganaderia-barva-heredia-costa-rica-300x267.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/ganadera-america\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ganadera Am\u00e9rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/\",\"name\":\"Costa Rica\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"],\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/author\\\/costaricainfolink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ganadera Am\u00e9rica - Costa Rica","description":"Direcci\u00f3n, tel\u00e9fono, fotos, ubicaci\u00f3n WAZE y mapas de Google. Ganadera Am\u00e9rica en San Jos\u00e9 de la Monta\u00f1a, Barva, Heredia, Costa Rica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/","og_locale":"es_ES","og_type":"article","og_title":"Ganadera Am\u00e9rica - Costa Rica","og_description":"Direcci\u00f3n, tel\u00e9fono, fotos, ubicaci\u00f3n WAZE y mapas de Google. Ganadera Am\u00e9rica en San Jos\u00e9 de la Monta\u00f1a, Barva, Heredia, Costa Rica.","og_url":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/","og_site_name":"Costa Rica","article_published_time":"2017-03-03T00:59:07+00:00","article_modified_time":"2017-03-07T18:23:36+00:00","og_image":[{"url":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/Alta-escuela-con-Lacayo-y-nuestro-jinete-Sergio-Quesada-ganadera-america-1.jpg?w=682&#038;h=455&#038;ssl=1","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce"},"headline":"Ganadera Am\u00e9rica","datePublished":"2017-03-03T00:59:07+00:00","dateModified":"2017-03-07T18:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/"},"wordCount":82,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica-300x267.jpg","articleSection":["40206","Barva","Heredia","San Jos\u00e9 de La Monta\u00f1a"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/","url":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/","name":"Ganadera Am\u00e9rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/directorio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica-300x267.jpg","datePublished":"2017-03-03T00:59:07+00:00","dateModified":"2017-03-07T18:23:36+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce"},"description":"Direcci\u00f3n, tel\u00e9fono, fotos, ubicaci\u00f3n WAZE y mapas de Google. Ganadera Am\u00e9rica en San Jos\u00e9 de la Monta\u00f1a, Barva, Heredia, Costa Rica.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica-300x267.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/03\/ganadera-america-ganaderia-barva-heredia-costa-rica-300x267.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/directorio\/ganadera-america\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/directorio\/"},{"@type":"ListItem","position":2,"name":"Ganadera Am\u00e9rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/directorio\/#website","url":"https:\/\/costaricainfolink.com\/directorio\/","name":"Costa Rica","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/directorio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644","url":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644","contentUrl":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"],"url":"https:\/\/costaricainfolink.com\/directorio\/author\/costaricainfolink\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p88Lb6-1V","jetpack-related-posts":[{"id":1320,"url":"https:\/\/costaricainfolink.com\/directorio\/laboratorios-paez\/","url_meta":{"origin":119,"position":0},"title":"Laboratorios P\u00e1ez","author":"Costa Rica Info Link","date":"2 junio, 2021","format":false,"excerpt":"Guadalupe \u00b7 Sabana \u00b7 Los Yoses \u00b7 Calle Blancos \u00b7 Barva \u00b7 Heredia \u2013 San Francisco \u00b7 Heredia Centro \u00b7 Lindora \u00b7 Escaz\u00fa \u00b7 San Pedro \u00b7 Tib\u00e1s \u00b7 Curridabat \u00b7 San Jos\u00e9 \u2013 Americana \u00b7 Avenida Segunda Laboratorio P\u00e1ez Guadalupe Direcci\u00f3nCruce de Guadalupe \u2013 Moravia, frente a la Cl\u00ednica\u2026","rel":"","context":"En \u00ab10102\u00bb","block_context":{"text":"10102","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10102\/"},"img":{"alt_text":"Laboratorios Paez Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/06\/laboratorios-paez-costa-rica-2-1-300x109.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":198,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/","url_meta":{"origin":119,"position":1},"title":"Farma Value \u2014 Sucursales y Horarios en Costa Rica","author":"Costa Rica Info Link","date":"12 marzo, 2018","format":false,"excerpt":"Farma Value es una cadena de farmacias centroamericana fundada en Honduras en 2002, especializada en medicamentos gen\u00e9ricos de bajo costo y productos de salud. Con m\u00e1s de 5,000 empleados y 300 puntos de servicio en M\u00e9xico, Guatemala, Honduras, El Salvador, Nicaragua, Costa Rica, Panam\u00e1 y Rep\u00fablica Dominicana, Farma Value es\u2026","rel":"","context":"En \u00ab10102\u00bb","block_context":{"text":"10102","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10102\/"},"img":{"alt_text":"Farmacias Farma Value Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":404,"url":"https:\/\/costaricainfolink.com\/directorio\/automercado\/","url_meta":{"origin":119,"position":2},"title":"AutoMercado","author":"Costa Rica Info Link","date":"20 septiembre, 2018","format":false,"excerpt":"Ubicaciones San Jos\u00e9 Centro - Escaz\u00fa - Guadalupe - Guachipel\u00edn - Moravia - Multiplaza - Plaza del Sol - Plaza Mayor - R\u00edo Oro - Santa Ana - Yoses Puntarenas Herradura Heredia Barva - Plaza Bratsi - Santo Domingo - San Francisco Cartago Tres R\u00edos Guanacaste El Coco - Tamarindo\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10101\/"},"img":{"alt_text":"AutoMercado Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/09\/automercado-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":489,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-fischel\/","url_meta":{"origin":119,"position":3},"title":"Farmacias Fischel Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"26 agosto, 2019","format":false,"excerpt":"Farmacias Fischel es una de las cadenas farmac\u00e9uticas m\u00e1s grandes de Costa Rica, con m\u00e1s de 50 sucursales en San Jos\u00e9, Escaz\u00fa, Heredia, Alajuela, Cartago, Guanacaste, Puntarenas y Lim\u00f3n. La mayor\u00eda de sucursales abre todos los d\u00edas de 9am a 9pm; varias sedes tienen horario extendido hasta medianoche. Adem\u00e1s del\u2026","rel":"","context":"En \u00ab10102\u00bb","block_context":{"text":"10102","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10102\/"},"img":{"alt_text":"Farmacias Fischel Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1506,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacia-santa-lucia\/","url_meta":{"origin":119,"position":4},"title":"Farmacias Santa Luc\u00eda","author":"Costa Rica Info Link","date":"5 septiembre, 2021","format":false,"excerpt":"WhatsApp +506 8711-0404Servicio A Domicilio +506 2436-0404 SAN JOSE: Avenida 14 \u00b7 Hospital de Ni\u00f1os \u00b7 Guachipel\u00edn \u00b7 Plaza Am\u00e9rica \u00b7 Curridabat \u00b7 Granadilla \u00b7 Moravia \u00b7 Coronado \u00b7 ALAJUELA: Alajuela Central \u00b7 Alajuela Centro \u00b7 Coraz\u00f3n de Jes\u00fas \u00b7 El Carmen \u00b7 La Ceiba \u00b7 Del Este \u00b7 Del\u2026","rel":"","context":"En \u00ab10103\u00bb","block_context":{"text":"10103","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10103\/"},"img":{"alt_text":"Farmacia Santa Luc\u00eda, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/09\/farmacia-santa-lucia-costa-rica-logo-300x195.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":833,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-saba\/","url_meta":{"origin":119,"position":5},"title":"Farmacias Saba Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"10 octubre, 2019","format":false,"excerpt":"Farmacia Saba es una cadena de farmacias originaria de Honduras, presente en Costa Rica desde 2018 con m\u00e1s de 30 sucursales en el Gran \u00c1rea Metropolitana y zonas como San Ram\u00f3n, Grecia y P\u00e9rez Zeled\u00f3n. Se especializa en medicamentos gen\u00e9ricos de bajo costo. Ofrecen entrega a domicilio gratis llamando al\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10101\/"},"img":{"alt_text":"Farmacias Saba Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-saba-costa-rica-21.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/comments?post=119"}],"version-history":[{"count":14,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/119\/revisions"}],"predecessor-version":[{"id":142,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/119\/revisions\/142"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/media?parent=119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/categories?post=119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/tags?post=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}