{"id":198,"date":"2018-03-12T18:50:11","date_gmt":"2018-03-12T18:50:11","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/directorio\/?p=198"},"modified":"2026-05-12T06:59:08","modified_gmt":"2026-05-12T12:59:08","slug":"farmacias-farma-value","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/","title":{"rendered":"Farma Value \u2014 Sucursales y Horarios en Costa Rica"},"content":{"rendered":"\n<script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\",\n  \"@type\": \"Pharmacy\",\n  \"name\": \"Farmacias Farma Value\",\n  \"url\": \"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/\",\n  \"description\": \"Cadena de farmacias Farma Value en Costa Rica con 19 sucursales. Tel\u00e9fonos, horarios y direcciones de todas las sedes en San Jos\u00e9, Escaz\u00fa, Heredia, Cartago, Alajuela y Guanacaste.\",\n  \"areaServed\": {\n    \"@type\": \"Country\",\n    \"name\": \"Costa Rica\"\n  },\n  \"sameAs\": [\n    \"https:\/\/www.farmavalue.com\"\n  ],\n  \"department\": [\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Plaza Itskatz\u00fa\",\n      \"telephone\": \"+50622882156\",\n      \"openingHours\": [\"Mo-Su 09:00-21:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Centro Comercial Plaza Itskatz\u00fa\",\n        \"addressLocality\": \"San Rafael\",\n        \"addressRegion\": \"Escaz\u00fa\",\n        \"postalCode\": \"10203\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Guachipel\u00edn\",\n      \"telephone\": \"+50622156389\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Decoplaza, 500 metros NE de Multiplaza Escaz\u00fa\",\n        \"addressLocality\": \"San Rafael\",\n        \"addressRegion\": \"Escaz\u00fa\",\n        \"postalCode\": \"10203\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Rohrmoser\",\n      \"telephone\": \"+50622906157\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"700 metros oeste de Plaza Mayor\",\n        \"addressLocality\": \"Pavas\",\n        \"addressRegion\": \"San Jos\u00e9\",\n        \"postalCode\": \"10109\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Heredia\",\n      \"telephone\": \"+50622392685\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Plaza Rub\u00ed La Aurora\",\n        \"addressLocality\": \"San Francisco\",\n        \"addressRegion\": \"Heredia\",\n        \"postalCode\": \"40103\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Alajuela\",\n      \"telephone\": \"+50622403114\",\n      \"openingHours\": [\"Mo-Sa 09:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Plaza PriceSmart, costado sur de la mutual\",\n        \"addressLocality\": \"Alajuela\",\n        \"addressRegion\": \"Alajuela\",\n        \"postalCode\": \"20101\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue San Jos\u00e9\",\n      \"telephone\": \"+50622221789\",\n      \"openingHours\": [\"Mo-Sa 07:00-19:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"50 metros oeste del Banco Nacional, Avenida 1\",\n        \"addressLocality\": \"Merced\",\n        \"addressRegion\": \"San Jos\u00e9\",\n        \"postalCode\": \"10102\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Cartago\",\n      \"telephone\": \"+50625517344\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\", \"Su 09:00-18:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"350 metros oeste del Mercado Municipal\",\n        \"addressLocality\": \"Occidental\",\n        \"addressRegion\": \"Cartago\",\n        \"postalCode\": \"30102\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Zapote\",\n      \"telephone\": \"+50622342146\",\n      \"openingHours\": [\"Mo-Su 09:00-21:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"100 metros sur de la rotonda de las garant\u00edas sociales, Shoppers\",\n        \"addressLocality\": \"Zapote\",\n        \"addressRegion\": \"San Jos\u00e9\",\n        \"postalCode\": \"10105\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Curridabat\",\n      \"telephone\": \"+50622343664\",\n      \"openingHours\": [\"Mo-Su 09:00-21:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"100 metros este de la POPS, Centro Comercial El Campanario\",\n        \"addressLocality\": \"Curridabat\",\n        \"addressRegion\": \"Curridabat\",\n        \"postalCode\": \"11801\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Lindora\",\n      \"telephone\": \"+50622030250\",\n      \"openingHours\": [\"Mo-Su 08:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Centro Comercial Vistana Este, detr\u00e1s de BAC Credomatic\",\n        \"addressLocality\": \"Pozos\",\n        \"addressRegion\": \"Santa Ana\",\n        \"postalCode\": \"10903\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Heredia Centro\",\n      \"telephone\": \"+50622385004\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Avenida 1 entre calles 7 y 9, frente a ANTIGUO FRESAS\",\n        \"addressLocality\": \"Heredia\",\n        \"addressRegion\": \"Heredia\",\n        \"postalCode\": \"40101\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Moravia\",\n      \"telephone\": \"+50622366301\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\", \"Su 10:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Plaza Los Colegios, 500 metros Oeste de Plaza Lincoln\",\n        \"addressLocality\": \"San Vicente\",\n        \"addressRegion\": \"Moravia\",\n        \"postalCode\": \"11401\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue San Jos\u00e9 Centro 2\",\n      \"telephone\": \"+50622480264\",\n      \"openingHours\": [\"Mo-Sa 07:00-19:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Avenida 6, entre calles central y 1era, 100 metros sur del Parque Central\",\n        \"addressLocality\": \"Hospital\",\n        \"addressRegion\": \"San Jos\u00e9\",\n        \"postalCode\": \"10103\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Paseo Col\u00f3n\",\n      \"telephone\": \"+50622019236\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Costado oeste de la TOYOTA, contiguo AM-PM\",\n        \"addressLocality\": \"Merced\",\n        \"addressRegion\": \"San Jos\u00e9\",\n        \"postalCode\": \"10102\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Desamparados\",\n      \"telephone\": \"+50622502593\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\", \"Su 10:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"200 metros sur de la Cl\u00ednica Marcial Fallas, Centro Comercial Plazo 209\",\n        \"addressLocality\": \"Gravilias\",\n        \"addressRegion\": \"Desamparados\",\n        \"postalCode\": \"10312\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Cartago 2\",\n      \"telephone\": \"+50625521083\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\", \"Su 08:00-17:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Costado sur de la bas\u00edlica, contiguo a TIGO\",\n        \"addressLocality\": \"Oriental\",\n        \"addressRegion\": \"Cartago\",\n        \"postalCode\": \"30101\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Alajuela Centro\",\n      \"telephone\": \"+50622430780\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"150 metros sur de la esquina sureste del parque central\",\n        \"addressLocality\": \"Alajuela\",\n        \"addressRegion\": \"Alajuela\",\n        \"postalCode\": \"20101\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue P\u00e9rez Zeled\u00f3n\",\n      \"telephone\": \"+50622771735\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"100 oeste, 200 norte y 25 oeste de la esquina NO del Parque Central, frente a Toys\",\n        \"addressLocality\": \"San Isidro del General\",\n        \"addressRegion\": \"P\u00e9rez Zeled\u00f3n\",\n        \"postalCode\": \"11901\",\n        \"addressCountry\": \"CR\"\n      }\n    },\n    {\n      \"@type\": \"Pharmacy\",\n      \"name\": \"FarmaValue Liberia\",\n      \"telephone\": \"+50622650386\",\n      \"openingHours\": [\"Mo-Sa 08:00-20:00\", \"Su 09:00-18:00\"],\n      \"address\": {\n        \"@type\": \"PostalAddress\",\n        \"streetAddress\": \"Avenida 25 de Julio, contiguo a los tribunales de justicia\",\n        \"addressLocality\": \"Liberia\",\n        \"addressRegion\": \"Guanacaste\",\n        \"postalCode\": \"50101\",\n        \"addressCountry\": \"CR\"\n      }\n    }\n  ]\n}\n<\/script>\n<script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\",\n  \"@type\": \"FAQPage\",\n  \"mainEntity\": [\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfCu\u00e1l es el horario de Farma Value?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"Depende de la sucursal. Santo Domingo, San Joaqu\u00edn y Barva abren lunes a viernes 7am\u20139pm, s\u00e1bado 8am\u20138pm y domingo 8am\u20138pm. La mayor\u00eda de sucursales atiende lunes a s\u00e1bado 8am\u20138pm. Plaza Itskatz\u00fa, Zapote y Curridabat abren todos los d\u00edas 9am\u20139pm.\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfAbren las farmacias Farma Value los domingos?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"S\u00ed, 12 de las 22 sucursales abren los domingos: Santo Domingo, San Joaqu\u00edn, Barva, Plaza Itskatz\u00fa, Zapote, Curridabat, Lindora, Moravia, Desamparados, Cartago, Cartago 2 y Liberia. Las 10 sedes restantes permanecen cerradas los domingos.\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfCu\u00e1ntas sucursales tiene Farma Value en Costa Rica?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"Farma Value cuenta con 22 sucursales en Costa Rica, distribuidas en San Jos\u00e9, Escaz\u00fa, Heredia, Alajuela, Cartago, P\u00e9rez Zeled\u00f3n y Liberia.\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfA qu\u00e9 hora cierra Farma Value?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"Santo Domingo, San Joaqu\u00edn y Barva cierran a las 9pm de lunes a viernes. Plaza Itskatz\u00fa, Zapote y Curridabat cierran a las 9pm todos los d\u00edas. La mayor\u00eda cierra a las 8pm. Las sedes del centro de San Jos\u00e9 cierran a las 7pm.\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfC\u00f3mo contactar a Farma Value por WhatsApp?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"Cada sucursal tiene su propio WhatsApp. Por ejemplo: Plaza Itskatz\u00fa +506 8677-6001, Guachipel\u00edn +506 8677-6002, Rohrmoser +506 8677-6003. Los n\u00fameros de todas las sedes aparecen en la tabla de tel\u00e9fonos en esta p\u00e1gina.\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfD\u00f3nde queda la Farma Value m\u00e1s cercana?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"Con 22 sedes hay opciones en Escaz\u00fa, Rohrmoser, San Jos\u00e9, Moravia, Zapote, Curridabat, Desamparados, Heredia, Santo Domingo, San Joaqu\u00edn, Barva, Lindora, Alajuela, Cartago, P\u00e9rez Zeled\u00f3n y Liberia.\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfQu\u00e9 tipo de medicamentos vende Farma Value?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"Farma Value se especializa en medicamentos gen\u00e9ricos de bajo costo, adem\u00e1s de productos de salud, belleza y cuidado personal. Los precios son significativamente menores que en las farmacias de marca.\"\n      }\n    }\n  ]\n}\n<\/script>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Farma Value es una cadena de farmacias centroamericana fundada en Honduras en 2002, especializada en medicamentos gen\u00e9ricos de bajo costo y productos de salud. Con m\u00e1s de 5,000 empleados y 300 puntos de servicio en M\u00e9xico, Guatemala, Honduras, El Salvador, Nicaragua, Costa Rica, Panam\u00e1 y Rep\u00fablica Dominicana, Farma Value es una de las cadenas farmac\u00e9uticas m\u00e1s grandes de la regi\u00f3n. En Costa Rica cuenta con 22 sucursales distribuidas en San Jos\u00e9, Escaz\u00fa, Heredia, Alajuela, Cartago y Guanacaste. A continuaci\u00f3n encontr\u00e1s los horarios, tel\u00e9fonos y direcciones de todas las sedes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Horarios de todas las sucursales Farma Value<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Sucursal<\/th><th>Lunes \u2013 Viernes<\/th><th>S\u00e1bado<\/th><th>Domingo<\/th><\/tr><\/thead><tbody><tr><td>Plaza Itskatz\u00fa (Escaz\u00fa)<\/td><td>9:00 am \u2013 9:00 pm<\/td><td>9:00 am \u2013 9:00 pm<\/td><td>9:00 am \u2013 9:00 pm<\/td><\/tr><tr><td>Guachipel\u00edn (Escaz\u00fa)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>Rohrmoser (Pavas)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>Heredia (Plaza Rub\u00ed, San Francisco)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>Alajuela (Plaza PriceSmart)<\/td><td>9:00 am \u2013 8:00 pm<\/td><td>9:00 am \u2013 8:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>San Jos\u00e9 (Avenida 1, Merced)<\/td><td>7:00 am \u2013 7:00 pm<\/td><td>7:00 am \u2013 7:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>Cartago (Mercado Municipal)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>9:00 am \u2013 6:00 pm<\/td><\/tr><tr><td>Zapote (Shoppers)<\/td><td>9:00 am \u2013 9:00 pm<\/td><td>9:00 am \u2013 9:00 pm<\/td><td>9:00 am \u2013 9:00 pm<\/td><\/tr><tr><td>Curridabat (El Campanario)<\/td><td>9:00 am \u2013 9:00 pm<\/td><td>9:00 am \u2013 9:00 pm<\/td><td>9:00 am \u2013 9:00 pm<\/td><\/tr><tr><td>Lindora (Vistana Este, Santa Ana)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><\/tr><tr><td>Heredia Centro (Av 1)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>Moravia (Plaza Los Colegios)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>10:00 am \u2013 8:00 pm<\/td><\/tr><tr><td>San Jos\u00e9 Centro 2 (Hospital)<\/td><td>7:00 am \u2013 7:00 pm<\/td><td>7:00 am \u2013 7:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>Paseo Col\u00f3n (Merced)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>Desamparados (Plaza 209)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>10:00 am \u2013 8:00 pm<\/td><\/tr><tr><td>Cartago 2 (Bas\u00edlica)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 5:00 pm<\/td><\/tr><tr><td>Alajuela Centro (Calle Central)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>P\u00e9rez Zeled\u00f3n (San Isidro)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>Cerrado<\/td><\/tr><tr><td>Liberia (Av. 25 de Julio)<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>8:00 am \u2013 8:00 pm<\/td><td>9:00 am \u2013 6:00 pm<\/td><\/tr><tr><td><strong>Santo Domingo (Plaza Santo Domingo)<\/strong><\/td><td><strong>7:00 am \u2013 9:00 pm<\/strong><\/td><td><strong>8:00 am \u2013 8:00 pm<\/strong><\/td><td><strong>8:00 am \u2013 8:00 pm<\/strong><\/td><\/tr><tr><td><strong>San Joaqu\u00edn (Heredia)<\/strong><\/td><td><strong>7:00 am \u2013 9:00 pm<\/strong><\/td><td><strong>8:00 am \u2013 8:00 pm<\/strong><\/td><td><strong>8:00 am \u2013 8:00 pm<\/strong><\/td><\/tr><tr><td><strong>Barva (Centro Comercial Plaza Vistana)<\/strong><\/td><td><strong>7:00 am \u2013 9:00 pm<\/strong><\/td><td><strong>8:00 am \u2013 8:00 pm<\/strong><\/td><td><strong>8:00 am \u2013 8:00 pm<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Tel\u00e9fonos de todas las sucursales Farma Value<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Sucursal<\/th><th>Tel\u00e9fono<\/th><th>WhatsApp<\/th><\/tr><\/thead><tbody><tr><td>Plaza Itskatz\u00fa (Escaz\u00fa)<\/td><td>2288-2156<\/td><td>8677-6001<\/td><\/tr><tr><td>Guachipel\u00edn (Escaz\u00fa)<\/td><td>2215-6389<\/td><td>8677-6002<\/td><\/tr><tr><td>Rohrmoser (Pavas)<\/td><td>2290-6157<\/td><td>8677-6003<\/td><\/tr><tr><td>Heredia (Plaza Rub\u00ed)<\/td><td>2239-2685<\/td><td>8677-6004<\/td><\/tr><tr><td>Alajuela (Plaza PriceSmart)<\/td><td>2440-3114<\/td><td>8677-6005<\/td><\/tr><tr><td>San Jos\u00e9 (Avenida 1)<\/td><td>2222-1789<\/td><td>8677-6006<\/td><\/tr><tr><td>Cartago (Mercado Municipal)<\/td><td>2551-7344<\/td><td>8677-6007<\/td><\/tr><tr><td>Zapote (Shoppers)<\/td><td>2234-2146<\/td><td>8677-6008<\/td><\/tr><tr><td>Curridabat (El Campanario)<\/td><td>2234-3664<\/td><td>8677-6009<\/td><\/tr><tr><td>Lindora (Vistana Este)<\/td><td>2203-0250<\/td><td>8677-6010<\/td><\/tr><tr><td>Heredia Centro (Av 1)<\/td><td>2238-5004<\/td><td>8677-6014<\/td><\/tr><tr><td>Moravia (Plaza Los Colegios)<\/td><td>2236-6301<\/td><td>8677-6015<\/td><\/tr><tr><td>San Jos\u00e9 Centro 2 (Hospital)<\/td><td>2248-0264<\/td><td>8677-6021<\/td><\/tr><tr><td>Paseo Col\u00f3n<\/td><td>2201-9236<\/td><td>8677-6023<\/td><\/tr><tr><td>Desamparados (Plaza 209)<\/td><td>2250-2593<\/td><td>8677-6026<\/td><\/tr><tr><td>Cartago 2 (Bas\u00edlica)<\/td><td>2552-1083<\/td><td>8677-6025<\/td><\/tr><tr><td>Alajuela Centro<\/td><td>2430-6780<\/td><td>8677-6045<\/td><\/tr><tr><td>P\u00e9rez Zeled\u00f3n<\/td><td>2771-0735<\/td><td>8677-6053<\/td><\/tr><tr><td>Liberia (Av. 25 de Julio)<\/td><td>2665-0386<\/td><td>8677-6033<\/td><\/tr><tr><td><strong>Santo Domingo de Heredia<\/strong><\/td><td><strong>4036-7171<\/strong><\/td><td><a href=\"https:\/\/wa.me\/50686279611\">8627-9611<\/a><\/td><\/tr><tr><td><strong>San Joaqu\u00edn (Heredia)<\/strong><\/td><td><strong>4036-7171<\/strong><\/td><td><a href=\"https:\/\/wa.me\/50686279611\">8627-9611<\/a><\/td><\/tr><tr><td><strong>Barva (Plaza Vistana)<\/strong><\/td><td><strong>4036-7171<\/strong><\/td><td><a href=\"https:\/\/wa.me\/50686279611\">8627-9611<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Farmacia FarmaValue SANTO DOMINGO<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Direcci\u00f3n:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo de Heredia, Plaza Santo Domingo, 100 m Norte del cementerio, frente a gasolinera Delta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Horario:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lunes a Viernes: 7:00 am \u2013 9:00 pm<br>S\u00e1bado: 8:00 am \u2013 8:00 pm<br>Domingo: 8:00 am \u2013 8:00 pm<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tel\u00e9fonos:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono: 4036-7171<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Farmacia FarmaValue SAN JOAQU\u00cdN<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Direcci\u00f3n:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Heredia, San Joaqu\u00edn, 250 m Oeste de Peque\u00f1o Mundo, sobre carretera principal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Horario:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lunes a Viernes: 7:00 am \u2013 9:00 pm<br>S\u00e1bado: 8:00 am \u2013 8:00 pm<br>Domingo: 8:00 am \u2013 8:00 pm<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tel\u00e9fonos:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono: 4036-7171<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Farmacia FarmaValue BARVA<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Direcci\u00f3n:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Barva de Heredia, Centro Comercial Plaza Vistana.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Horario:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lunes a Viernes: 7:00 am \u2013 9:00 pm<br>S\u00e1bado: 8:00 am \u2013 8:00 pm<br>Domingo: 8:00 am \u2013 8:00 pm<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tel\u00e9fonos:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono: 4036-7171<\/p>\n\n\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"232\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/farmacias-farma-value-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?fit=498%2C126&amp;ssl=1\" data-orig-size=\"498,126\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Farmacias Farma Value Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?fit=498%2C126&amp;ssl=1\" class=\"aligncenter size-full wp-image-232\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?resize=498%2C126&#038;ssl=1\" alt=\"Farmacias Farma Value Costa Rica\" width=\"498\" height=\"126\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?w=498&amp;ssl=1 498w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?resize=300%2C76&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?resize=260%2C66&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?resize=160%2C40&amp;ssl=1 160w\" sizes=\"(max-width: 498px) 100vw, 498px\" \/><\/p>\n<h1>Farma Value Sucursales<\/h1>\n<p><a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#itskatzu\">Plaza Itskatz\u00fa<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#guachipelin\">Guachipel\u00edn<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#rohrmoser\">Rohrmoser<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#heredia\">Heredia<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#alajuela\">Alajuela<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#sanjose\">San Jos\u00e9<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#cartago\">Cartago<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#zapote\">Zapote<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#curridabat\">Curridabat<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#lindora\">Lindora<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#herediacentro\">Heredia Centro<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#moravia\">Moravia<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#sanjosecentro2\">San Jos\u00e9 centro 2<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#paseocolon\">Paseo Col\u00f3n<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#desamparados\">Desamparados<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#cartago2\">Cartago 2<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#alajuelacentro\">Alajuela Centro<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#perezzeledon\">Perez Zeledon<\/a> &#8211; <a href=\"https:\/\/www.costaricainfolink.com\/directorio\/farmacias-farma-value\/#liberia\">Liberia<\/a><\/p>\n<h3 id=\"itskatzu\">Farmacia FarmaValue PLAZA ITSKATZ\u00da<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>Centro comercial plaza Itskatz\u00fa, <strong>distrito<\/strong>: San Rafael, <strong>cant\u00f3n<\/strong>: Escaz\u00fa, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0t4nku\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value Plaza Itskatz\u00fa, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Escaz%C3%BA\/@9.9433543,-84.1485617,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0fb8106c5bf09:0xadda69ebfc5b2568!8m2!3d9.943349!4d-84.146373\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value Plaza Itskatz\u00fa, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a Domingo de 9am a 9pm.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622882156\">+506 2288-2156<\/a>, <a href=\"tel:+50622887248\">+506 2288-7248<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776001\">+506 8677-6001<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"206\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farma-value-plaza-itskatzu-san-rafael-escazu-san-jose-costa-rica-1\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-plaza-itskatzu-san-rafael-escazu-san-jose-costa-rica-1.png?fit=258%2C19&amp;ssl=1\" data-orig-size=\"258,19\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Plaza Itskatz\u00fa, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-plaza-itskatzu-san-rafael-escazu-san-jose-costa-rica-1.png?fit=258%2C19&amp;ssl=1\" class=\"size-full wp-image-206 alignnone\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-plaza-itskatzu-san-rafael-escazu-san-jose-costa-rica-1.png?resize=258%2C19&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Plaza Itskatz\u00fa, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" width=\"258\" height=\"19\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-plaza-itskatzu-san-rafael-escazu-san-jose-costa-rica-1.png?w=258&amp;ssl=1 258w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-plaza-itskatzu-san-rafael-escazu-san-jose-costa-rica-1.png?resize=160%2C12&amp;ssl=1 160w\" sizes=\"(max-width: 258px) 100vw, 258px\" \/><\/p>\n<h3 id=\"guachipelin\">Farmacia FarmaValue GUACHIPEL\u00cdN<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>En Decoplaza, 500 metros NE de Multiplaza Escaz\u00fa <strong>distrito<\/strong>: San Rafael, <strong>cant\u00f3n<\/strong>: Escaz\u00fa, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0t51yb\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value Decoplaza Guachipel\u00edn, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Guachipelin\/@9.949286,-84.153378,18.93z\/data=!4m5!3m4!1s0x8fa0fb851373b65f:0xcbeb7551c7c169d5!8m2!3d9.9492848!4d-84.1528025\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value Decoplaza Guachipel\u00edn, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingo cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622156389\">+506 2215-6389<\/a>, <a href=\"tel:+50622156453\">+506 2215-6453<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776002\">+506 8677-6002<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"216\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farma-value-guachipelin-san-rafael-escazu-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-guachipelin-san-rafael-escazu-san-jose-costa-rica.png?fit=307%2C22&amp;ssl=1\" data-orig-size=\"307,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Decoplaza Guachipel\u00edn, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-guachipelin-san-rafael-escazu-san-jose-costa-rica.png?fit=307%2C22&amp;ssl=1\" class=\"size-medium wp-image-216 alignnone\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-guachipelin-san-rafael-escazu-san-jose-costa-rica-300x21.png?resize=300%2C21&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Decoplaza Guachipel\u00edn, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" width=\"300\" height=\"21\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-guachipelin-san-rafael-escazu-san-jose-costa-rica.png?resize=300%2C21&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-guachipelin-san-rafael-escazu-san-jose-costa-rica.png?resize=260%2C19&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-guachipelin-san-rafael-escazu-san-jose-costa-rica.png?resize=160%2C11&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-guachipelin-san-rafael-escazu-san-jose-costa-rica.png?w=307&amp;ssl=1 307w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3 id=\"rohrmoser\">Farmacia FarmaValue ROHRMOSER<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>700 metros oeste de Plaza Mayor\u00a0<strong>distrito<\/strong>: Pavas, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10109.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0tdv9v\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value Rohrmoser, Pavas, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Rohrmoser\/@9.9470524,-84.1260777,18.94z\/data=!4m5!3m4!1s0x8fa0fb66e696c4af:0x68323ab5a2a0acb3!8m2!3d9.9470511!4d-84.125509\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value Rohrmoser, Pavas, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingo cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622906157\">+506 2290-6157<\/a>, <a href=\"tel:+50622910526\">+506 2291-0526<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776003\">+506 8677-6003<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"235\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farma-value-rohrmoser-pavas-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-rohrmoser-pavas-san-jose-costa-rica.png?fit=252%2C22&amp;ssl=1\" data-orig-size=\"252,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Rohrmoser, Pavas,, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-rohrmoser-pavas-san-jose-costa-rica.png?fit=252%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-235\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-rohrmoser-pavas-san-jose-costa-rica.png?resize=252%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Rohrmoser, Pavas,, San Jos\u00e9, Costa Rica\" width=\"252\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-rohrmoser-pavas-san-jose-costa-rica.png?w=252&amp;ssl=1 252w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-rohrmoser-pavas-san-jose-costa-rica.png?resize=160%2C14&amp;ssl=1 160w\" sizes=\"(max-width: 252px) 100vw, 252px\" \/><\/p>\n<h3 id=\"heredia\">Farmacia FarmaValue HEREDIA<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>En Plaza Rub\u00ed La Aurora\u00a0<strong>distrito<\/strong>: San Francisco, <strong>cant\u00f3n<\/strong>: Heredia, <strong>provincia<\/strong>: Heredia. C\u00f3digo postal de la zona: 40103.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0ucz31\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value La Aurora, San Francisco, Heredia, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Heredia+La+Aurora\/@9.9856403,-84.15803,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0fa4d27b3fe79:0xe9ba5a53a9bf5eb7!8m2!3d9.9856366!4d-84.1564824\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value La Aurora, San Francisco, Heredia, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingo cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622392685\">+506 2239-2685<\/a>, <a href=\"tel:+50622393263\">+506 2239-3263<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776004\">+506 8677-6004<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"239\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-la-aurora-san-francisco-heredia-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-la-aurora-san-francisco-heredia-costa-rica.png?fit=233%2C22&amp;ssl=1\" data-orig-size=\"233,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value La Aurora, San Francisco, Heredia, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-la-aurora-san-francisco-heredia-costa-rica.png?fit=233%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-239\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-la-aurora-san-francisco-heredia-costa-rica.png?resize=233%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value La Aurora, San Francisco, Heredia, Costa Rica\" width=\"233\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-la-aurora-san-francisco-heredia-costa-rica.png?w=233&amp;ssl=1 233w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-la-aurora-san-francisco-heredia-costa-rica.png?resize=160%2C15&amp;ssl=1 160w\" sizes=\"(max-width: 233px) 100vw, 233px\" \/><\/p>\n<h3 id=\"alajuela\">Farmacia FarmaValue ALAJUELA<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>En Plaza PriceSmart, costado sur de la mutual\u00a0<strong>distrito<\/strong>: Alajuela, <strong>cant\u00f3n<\/strong>: Alajuela, <strong>provincia<\/strong>: Alajuela. C\u00f3digo postal de la zona: 20101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0gqy99\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value Alajuela, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Alajuela\/@10.0131785,-84.2241878,18z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0f9cbedd7d4d1:0xa49eb18a96e070c3!8m2!3d10.0131785!4d-84.2232222\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value Alajuela, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 9am a 8pm. Domingo cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50624403114\">+506 2440-3114<\/a>, <a href=\"tel:+50624403110\">+506 2440-3110<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776005\">+506 8677-6005<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"242\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-alajuela-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-alajuela-costa-rica.png?fit=222%2C22&amp;ssl=1\" data-orig-size=\"222,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Alajuela, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-alajuela-costa-rica.png?fit=222%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-242\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-alajuela-costa-rica.png?resize=222%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Alajuela, Costa Rica\" width=\"222\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-alajuela-costa-rica.png?w=222&amp;ssl=1 222w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-alajuela-costa-rica.png?resize=160%2C16&amp;ssl=1 160w\" sizes=\"(max-width: 222px) 100vw, 222px\" \/><\/p>\n<h3 id=\"sanjose\">Farmacia FarmaValue SAN JOS\u00c9<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>50 metros oeste del Banco Nacional, sobre Avenida 1\u00a0<strong>distrito<\/strong>: Merced, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10102.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0w8w5k\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+San+Jos%C3%A9\/@9.9350932,-84.0816372,19z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e35e3c05e0ad:0x56e6cd741a59f17a!8m2!3d9.9350919!4d-84.08109\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 7am a 7pm. Domingo cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622221789\">+506 2222-1789<\/a>, <a href=\"tel:+50622222021\">+506 2222-2021<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776006\">+506 8677-6006<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"248\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-costa-rica.png?fit=267%2C22&amp;ssl=1\" data-orig-size=\"267,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-costa-rica.png?fit=267%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-248\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-costa-rica.png?resize=267%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value San Jos\u00e9, Costa Rica\" width=\"267\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-costa-rica.png?w=267&amp;ssl=1 267w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-costa-rica.png?resize=260%2C21&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-costa-rica.png?resize=160%2C13&amp;ssl=1 160w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/><\/p>\n<h3 id=\"cartago\">Farmacia FarmaValue CARTAGO<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>350 metros oeste del Mercado Municipal\u00a0<strong>distrito<\/strong>: Occidental, <strong>cant\u00f3n<\/strong>: Cartago, <strong>provincia<\/strong>: Cartago. C\u00f3digo postal de la zona: 30102.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u24hpf7\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Occidental, Cartago, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue\/@9.8660292,-83.9268094,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0dfe6fa95f21b:0xe3f7c668d0ff8820!8m2!3d9.8660243!4d-83.924783\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en Occidental, Cartago, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos de 9am a 6pm.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50625517344\">+506 2551-7344<\/a>, <a href=\"tel:+50625517886\">+506 2551-7886<\/a>, F<strong>arma Value WhatsApp Cartago<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776007\">+506 8677-6007<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"250\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-occidental-cartago-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-occidental-cartago-costa-rica.png?fit=220%2C22&amp;ssl=1\" data-orig-size=\"220,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Occidental, Cartago, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-occidental-cartago-costa-rica.png?fit=220%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-250\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-occidental-cartago-costa-rica.png?resize=220%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Occidental, Cartago, Costa Rica\" width=\"220\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-occidental-cartago-costa-rica.png?w=220&amp;ssl=1 220w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-occidental-cartago-costa-rica.png?resize=160%2C16&amp;ssl=1 160w\" sizes=\"(max-width: 220px) 100vw, 220px\" \/><\/p>\n<h3 id=\"zapote\">Farmacia FarmaValue ZAPOTE<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>100 metros sur de la rotonda de las garant\u00edas sociales, en Shoppers\u00a0<strong>distrito<\/strong>: Zapote, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10105.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u24hpf7\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Zapote, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Zapote\/@9.9186915,-84.0621914,19z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e374fb40832f:0xb05735e4b62d2805!8m2!3d9.9186902!4d-84.0616442\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en Zapote, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a Domingo de 9am a 9pm.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622342146\">+506 2234-2146<\/a>, <a href=\"tel:+50622342142\">+506 2234-2142<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776008\">+506 8677-6008<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"253\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-zapote-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-zapote-san-jose-costa-rica.png?fit=211%2C22&amp;ssl=1\" data-orig-size=\"211,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Zapote, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-zapote-san-jose-costa-rica.png?fit=211%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-253\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-zapote-san-jose-costa-rica.png?resize=211%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Zapote, San Jos\u00e9, Costa Rica\" width=\"211\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-zapote-san-jose-costa-rica.png?w=211&amp;ssl=1 211w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-zapote-san-jose-costa-rica.png?resize=160%2C17&amp;ssl=1 160w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/><\/p>\n<h3 id=\"curridabat\">Farmacia FarmaValue CURRIDABAT<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>100 metros este de la POPS, Centro Comercial El Campanario\u00a0<strong>distrito<\/strong>: Curridabat, <strong>cant\u00f3n<\/strong>: Curridabat, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 11801.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u24hpf7\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Curridabat, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Curridabat\/@9.9254313,-84.0421657,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e392f1898499:0x7f8c07e09e18ab5!8m2!3d9.925426!4d-84.039977\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en Curridabat, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a Domingo de 9am a 9pm.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622343664\">+506 2234-3664<\/a>, <a href=\"tel:+50622343665\">+506 2234-3665<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776009\">+506 8677-6009<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"259\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-curridabat-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-curridabat-san-jose-costa-rica.png?fit=249%2C22&amp;ssl=1\" data-orig-size=\"249,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Curridabat, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-curridabat-san-jose-costa-rica.png?fit=249%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-259\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-curridabat-san-jose-costa-rica.png?resize=249%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Curridabat, San Jos\u00e9, Costa Rica\" width=\"249\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-curridabat-san-jose-costa-rica.png?w=249&amp;ssl=1 249w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-curridabat-san-jose-costa-rica.png?resize=160%2C14&amp;ssl=1 160w\" sizes=\"(max-width: 249px) 100vw, 249px\" \/><\/p>\n<h3 id=\"lindora\">Farmacia FarmaValue LINDORA<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>Centro comercial Vistana Este, detr\u00e1s de BAC Credomatic\u00a0<strong>distrito<\/strong>: Pozos, <strong>cant\u00f3n<\/strong>: Santa Ana, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10903.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0s5gze\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Lindora, Pozos, Santa Ana, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Lindora\/@9.9533193,-84.1959097,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0f95a8a12090f:0x10e7b55aac2d32b1!8m2!3d9.953314!4d-84.193721\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en Lindora, Pozos, Santa Ana, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a Domingo de 8am a 8pm.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622030250\">+506 2203-0250<\/a>, <a href=\"tel:+50622030371\">+506 2203-0371<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776010\">+506 8677-6010<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"270\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-lindora-pozos-santa-ana-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-lindora-pozos-santa-ana-san-jose-costa-rica.png?fit=215%2C22&amp;ssl=1\" data-orig-size=\"215,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Lindora, Pozos, Santa Ana, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-lindora-pozos-santa-ana-san-jose-costa-rica.png?fit=215%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-270\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-lindora-pozos-santa-ana-san-jose-costa-rica.png?resize=215%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Lindora, Pozos, Santa Ana, San Jos\u00e9, Costa Rica\" width=\"215\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-lindora-pozos-santa-ana-san-jose-costa-rica.png?w=215&amp;ssl=1 215w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-lindora-pozos-santa-ana-san-jose-costa-rica.png?resize=160%2C16&amp;ssl=1 160w\" sizes=\"(max-width: 215px) 100vw, 215px\" \/><\/p>\n<h3 id=\"herediacentro\">Farmacia FarmaValue HEREDIA CENTRO<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>Sobre AV 1 entre calles 7 y 9 \u00f3 75 metros oeste de la entrada principal de la UNA, frente ANTIGUO FRESAS\u00a0<strong>distrito<\/strong>: Heredia, <strong>cant\u00f3n<\/strong>: Heredia, <strong>provincia<\/strong>: Heredia. C\u00f3digo postal de la zona: 40101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0vuq9s\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Heredia Centro, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Heredia+Centro\/@9.9992085,-84.115403,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0fac5be35f94d:0xd762404c83e1b0a0!8m2!3d9.9992032!4d-84.1132143\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en Heredia Centro, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622385004\">+506 2238-5004<\/a>, <a href=\"tel:+50622384752\">+506 2238-4752<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776014\">+506 8677-6014<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"272\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-heredia-centro-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-heredia-centro-costa-rica.png?fit=286%2C22&amp;ssl=1\" data-orig-size=\"286,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Heredia Centro, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-heredia-centro-costa-rica.png?fit=286%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-272\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-heredia-centro-costa-rica.png?resize=286%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Heredia Centro, Costa Rica\" width=\"286\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-heredia-centro-costa-rica.png?w=286&amp;ssl=1 286w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-heredia-centro-costa-rica.png?resize=260%2C20&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-heredia-centro-costa-rica.png?resize=160%2C12&amp;ssl=1 160w\" sizes=\"(max-width: 286px) 100vw, 286px\" \/><\/p>\n<h3 id=\"moravia\">Farmacia FarmaValue MORAVIA<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>En Plaza Los Colegios, 500 metros Oeste de Plaza Lincoln\u00a0<strong>distrito<\/strong>: San Vicente, <strong>cant\u00f3n<\/strong>: Moravia, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 11401.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0xjt4k\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en San Vicente, Moravia, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Moravia\/@9.9622733,-84.0625267,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e4f540064935:0x7f3abf5ab53c0958!8m2!3d9.962268!4d-84.060338\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en San Vicente, Moravia, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos de 10am a 8pm.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622366301\">+506 2236-6301<\/a>, <a href=\"tel:+50622366170\">+506 2236-6170<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776015\">+506 8677-6015<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"276\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-san-vicente-moravia-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-vicente-moravia-san-jose-costa-rica.png?fit=226%2C22&amp;ssl=1\" data-orig-size=\"226,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value San Vicente, Moravia, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-vicente-moravia-san-jose-costa-rica.png?fit=226%2C22&amp;ssl=1\" class=\"alignnone wp-image-276 size-full\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-vicente-moravia-san-jose-costa-rica.png?resize=226%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value San Vicente, Moravia, San Jos\u00e9, Costa Rica\" width=\"226\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-vicente-moravia-san-jose-costa-rica.png?w=226&amp;ssl=1 226w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-vicente-moravia-san-jose-costa-rica.png?resize=160%2C16&amp;ssl=1 160w\" sizes=\"(max-width: 226px) 100vw, 226px\" \/><\/p>\n<h3 id=\"sanjosecentro2\">SAN JOS\u00c9 CENTRO 2<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>Sobre avenida 6, entre calles central y 1era \u00f3 100 metros sur y 25 este del Parque Central\u00a0<strong>distrito<\/strong>: Hospital, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10103.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0qxzw8\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Farmavalue+San+Jos%C3%A9+2+-+Av.+6\/@9.9314215,-84.0800598,18z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e3676d98c2d5:0xa96c05c52e6cb481!8m2!3d9.931419!4d-84.079031\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 7am a 7pm. Domingos cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622480264\">+506 2248-0264<\/a>, <a href=\"tel:+50622019801\">+506 2201-9801<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776021\">+506 8677-6021<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"279\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-san-jose-2-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-2-costa-rica.png?fit=234%2C22&amp;ssl=1\" data-orig-size=\"234,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-2-costa-rica.png?fit=234%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-279\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-2-costa-rica.png?resize=234%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value San Jos\u00e9, Costa Rica\" width=\"234\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-2-costa-rica.png?w=234&amp;ssl=1 234w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-san-jose-2-costa-rica.png?resize=160%2C15&amp;ssl=1 160w\" sizes=\"(max-width: 234px) 100vw, 234px\" \/><\/p>\n<h3 id=\"paseocolon\">Farmacia FarmaValue PASEO COL\u00d3N<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>Costado oeste de la TOYOTA, contiguo AM-PM\u00a0<strong>distrito<\/strong>: Merced, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10102.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0w2erh\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Paseo Col\u00f3n, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Paseo+Col%C3%B3n\/@9.9356203,-84.0978707,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e3569c542bb5:0x92ee9dfec578d16!8m2!3d9.935615!4d-84.095682\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en Paseo Col\u00f3n, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622019236\">+506 2201-9236<\/a>, <a href=\"tel:+50622480596\">+506 2248-0596<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776023\">+506 8677-6023<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"293\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farma-value-paseo-colon-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-paseo-colon-san-jose-costa-rica.png?fit=260%2C22&amp;ssl=1\" data-orig-size=\"260,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Paseo Col\u00f3n, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-paseo-colon-san-jose-costa-rica.png?fit=260%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-293\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-paseo-colon-san-jose-costa-rica.png?resize=260%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Paseo Col\u00f3n, San Jos\u00e9, Costa Rica\" width=\"260\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-paseo-colon-san-jose-costa-rica.png?w=260&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-paseo-colon-san-jose-costa-rica.png?resize=160%2C14&amp;ssl=1 160w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/><\/p>\n<h3 id=\"desamparados\">Farmacia FarmaValue DESAMPARADOS<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>200 metros SUR de la Cl\u00ednica Marcial Fallas, frente a EKONO, centro comercial plazo 209\u00a0<strong>distrito<\/strong>: Gravilias, <strong>cant\u00f3n<\/strong>: Desamparados, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10312.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0r0dt6\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Gravilias, Desamparados, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Farmavalue+Desamparados\/@9.8913533,-84.0660267,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e2fe87afb5e5:0x9529d31818a8e685!8m2!3d9.891348!4d-84.063838\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en Gravilias, Desamparados, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos de 10am a 8pm.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50622502593\">+506 2250-2593<\/a>, <a href=\"tel:+50622501684\">+506 2250-1684<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776026\">+506 8677-6026<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"298\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farma-value-gravilias-desamparados-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-gravilias-desamparados-san-jose-costa-rica.png?fit=294%2C22&amp;ssl=1\" data-orig-size=\"294,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Gravilias, Desamparados, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-gravilias-desamparados-san-jose-costa-rica.png?fit=294%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-298\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-gravilias-desamparados-san-jose-costa-rica.png?resize=294%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Gravilias, Desamparados, San Jos\u00e9, Costa Rica\" width=\"294\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-gravilias-desamparados-san-jose-costa-rica.png?w=294&amp;ssl=1 294w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-gravilias-desamparados-san-jose-costa-rica.png?resize=260%2C19&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-gravilias-desamparados-san-jose-costa-rica.png?resize=160%2C12&amp;ssl=1 160w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/><\/p>\n<h3 id=\"cartago2\">CARTAGO 2<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>Costado Sur de la bas\u00edlica, contiguo a TIGO\u00a0<strong>distrito<\/strong>: Oriental, <strong>cant\u00f3n<\/strong>: Cartago, <strong>provincia<\/strong>: Cartago. C\u00f3digo postal de la zona: 30101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u247xut\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Oriental, Cartago, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Farmavalue+Cartago+2\/@9.8637683,-83.9158757,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0dfec7f454c67:0x9ad9c2ccd1a9bf78!8m2!3d9.863763!4d-83.913687\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en Oriental, Cartago, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos de 8am a 5pm.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50625521083\">+506 2552-1083<\/a>, <a href=\"tel:+50625517134\">+506 2551-7134<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776025\">+506 8677-6025<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"302\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farma-value-oriental-cartago-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-oriental-cartago-costa-rica.png?fit=233%2C22&amp;ssl=1\" data-orig-size=\"233,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Oriental, Cartago,, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-oriental-cartago-costa-rica.png?fit=233%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-302\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-oriental-cartago-costa-rica.png?resize=233%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Oriental, Cartago, Costa Rica\" width=\"233\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-oriental-cartago-costa-rica.png?w=233&amp;ssl=1 233w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-oriental-cartago-costa-rica.png?resize=160%2C15&amp;ssl=1 160w\" sizes=\"(max-width: 233px) 100vw, 233px\" \/><\/p>\n<h3 id=\"alajuelacentro\">ALAJUELA CENTRO<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>150 metros sur de la esquina sureste del parque central, sobre calle central\u00a0<strong>distrito<\/strong>: Alajuela, <strong>cant\u00f3n<\/strong>: Alajuela, <strong>provincia<\/strong>: Alajuela. C\u00f3digo postal de la zona: 20101.<\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50624306780\">+506 2430-6780<\/a>, <a href=\"tel:+5062430-6683\">+506 2430-6683<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776045\">+506 8677-6045<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"304\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farma-value-alajuela-centro-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-alajuela-centro-costa-rica.png?fit=288%2C22&amp;ssl=1\" data-orig-size=\"288,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Alajuela Centro, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-alajuela-centro-costa-rica.png?fit=288%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-304\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-alajuela-centro-costa-rica.png?resize=288%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Alajuela Centro, Costa Rica\" width=\"288\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-alajuela-centro-costa-rica.png?w=288&amp;ssl=1 288w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-alajuela-centro-costa-rica.png?resize=260%2C20&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-alajuela-centro-costa-rica.png?resize=160%2C12&amp;ssl=1 160w\" sizes=\"(max-width: 288px) 100vw, 288px\" \/><\/p>\n<h3 id=\"perezzeledon\">Farmacia FarmaValue P\u00c9REZ ZELED\u00d3N<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>De la esquina NorOeste del Parque Central, 100 Oeste, 200 Norte y 25 Oeste, frente a Toys, detr\u00e1s de la terminal MUSOC \u00a0<strong>distrito<\/strong>: San Isidro del General, <strong>cant\u00f3n<\/strong>: P\u00e9rez Zeled\u00f3n, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 11901.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1smr6btu\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Oriental, Cartago, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+P%C3%A9rez+Zeled%C3%B3n\/@9.3783542,-83.7144026,15.28z\/data=!4m8!1m2!2m1!1sFarmaValue,+Perez+Zeledon!3m4!1s0x0:0x2ac2168bec61bec3!8m2!3d9.3764953!4d-83.7039757\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en San Isidro del General, Perez Zeled\u00f3n, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos cerrado.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50627710735\">+506 2771-0735<\/a>, <a href=\"tel:+50627710939\">+506 2771-0939<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776053\">+506 8677-6053<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"307\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farma-value-san-isidro-del-general-perez-zeledon-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-san-isidro-del-general-perez-zeledon-san-jose-costa-rica.png?fit=278%2C22&amp;ssl=1\" data-orig-size=\"278,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value San Isidro del General, P\u00e9rez Zeled\u00f3n, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-san-isidro-del-general-perez-zeledon-san-jose-costa-rica.png?fit=278%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-307\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-san-isidro-del-general-perez-zeledon-san-jose-costa-rica.png?resize=278%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value San Isidro del General, P\u00e9rez Zeled\u00f3n, San Jos\u00e9, Costa Rica\" width=\"278\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-san-isidro-del-general-perez-zeledon-san-jose-costa-rica.png?w=278&amp;ssl=1 278w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-san-isidro-del-general-perez-zeledon-san-jose-costa-rica.png?resize=260%2C21&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farma-value-san-isidro-del-general-perez-zeledon-san-jose-costa-rica.png?resize=160%2C13&amp;ssl=1 160w\" sizes=\"(max-width: 278px) 100vw, 278px\" \/><\/p>\n<h3 id=\"liberia\">Farmacia FarmaValue LIBERIA<\/h3>\n<h3>Direcci\u00f3n:<\/h3>\n<p>Sobre Avenida 25 de Julio, contiguo a los tribunales de justicia, en tienda Mundo M\u00e1gico <strong>distrito<\/strong>: Liberia, <strong>cant\u00f3n<\/strong>: Liberia, <strong>provincia<\/strong>: Guanacaste. C\u00f3digo postal de la zona: 50101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1ghrwwvc\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farma Value en Liberia, Guanacaste, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/FarmaValue+Liberia+Centro\/@10.627552,-85.4444947,17z\/data=!3m1!4b1!4m5!3m4!1s0x8f757d2bdd8aef4d:0x4c381cbf1c4f7f00!8m2!3d10.627552!4d-85.442306\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farma Value en Liberia, Guanacaste, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h3>Horario:<\/h3>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos 9am a 6pm.<\/p>\n<h3>Tel\u00e9fonos:<\/h3>\n<p><a href=\"tel:+50626650386\">+506 2665-0386<\/a>, <a href=\"tel:+50626650602\">+506 2665-0602<\/a>,\u00a0<strong>WhatsApp<\/strong>: <a href=\"https:\/\/api.whatsapp.com\/send?phone=50686776033\">+506 8677-6033<\/a><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"310\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/correo-farmacia-farma-value-liberia-centro-guanacaste-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-liberia-centro-guanacaste-costa-rica.png?fit=207%2C22&amp;ssl=1\" data-orig-size=\"207,22\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Correo Electr\u00f3nico Farmacia Farma Value Liberia Centro, Guanacaste, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-liberia-centro-guanacaste-costa-rica.png?fit=207%2C22&amp;ssl=1\" class=\"alignnone size-full wp-image-310\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-liberia-centro-guanacaste-costa-rica.png?resize=207%2C22&#038;ssl=1\" alt=\"Correo Electr\u00f3nico Farmacia Farma Value Liberia Centro, Guanacaste, Costa Rica\" width=\"207\" height=\"22\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-liberia-centro-guanacaste-costa-rica.png?w=207&amp;ssl=1 207w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/correo-farmacia-farma-value-liberia-centro-guanacaste-costa-rica.png?resize=160%2C17&amp;ssl=1 160w\" sizes=\"(max-width: 207px) 100vw, 207px\" \/><\/p>\n\n\n<h2 class=\"wp-block-heading\">Sobre Farma Value<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Farma Value fue fundada en Honduras en 2002 y pertenece al Grupo 3C (Central American Consulting &amp; Capital), un conglomerado regional especializado en el sector salud. El grupo opera marcas como An\u00e1lisis Cl\u00ednicos del Ahorro, Value Laboratorios, Cl\u00ednicas del Ahorro, Farmacias Regis, FarmaCl\u00ednicas de la Comunidad, Apomedix, M\u00e9dica Hogar y Farmacias del Ahorro (su marca en Honduras).<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">La cadena se distingue por su compromiso con cuatro principios:<\/p>\n\n\n\n<ul class=\"wp-block-list has-medium-font-size\">\n<li>Siempre el mejor precio posible.<\/li>\n\n\n\n<li>Siempre el producto disponible.<\/li>\n\n\n\n<li>Expertos en su oficio.<\/li>\n\n\n\n<li>El inter\u00e9s del cliente, primero.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Su misi\u00f3n es ofrecer acceso a medicamentos de alta calidad al precio m\u00e1s accesible del mercado, en un ambiente profesional y amigable. Su visi\u00f3n es ser la farmacia n\u00famero 1 de Centroam\u00e9rica y el Caribe en servicio y distribuci\u00f3n de productos m\u00e9dicos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Preguntas frecuentes sobre Farma Value<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1l es el horario de Farma Value?<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Depende de la sucursal. Las sedes de Santo Domingo, San Joaqu\u00edn y Barva abren de lunes a viernes de 7:00 am a 9:00 pm, s\u00e1bado de 8:00 am a 8:00 pm y domingo de 8:00 am a 8:00 pm. La mayor\u00eda de las dem\u00e1s sucursales atiende de lunes a s\u00e1bado de 8:00 am a 8:00 pm. Plaza Itskatz\u00fa, Zapote y Curridabat abren todos los d\u00edas de 9:00 am a 9:00 pm. Consult\u00e1 la tabla de horarios al inicio de esta p\u00e1gina.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfAbren las farmacias Farma Value los domingos?<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">S\u00ed, 12 de las 22 sucursales abren los domingos: Santo Domingo (8am\u20138pm), San Joaqu\u00edn (8am\u20138pm), Barva (8am\u20138pm), Plaza Itskatz\u00fa (9am\u20139pm), Zapote (9am\u20139pm), Curridabat (9am\u20139pm), Lindora (8am\u20138pm), Moravia (10am\u20138pm), Desamparados (10am\u20138pm), Cartago (9am\u20136pm), Cartago 2 (8am\u20135pm) y Liberia (9am\u20136pm). Las 10 sedes restantes permanecen cerradas los domingos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1ntas sucursales tiene Farma Value en Costa Rica?<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Farma Value cuenta con 22 sucursales en Costa Rica, en San Jos\u00e9, Escaz\u00fa, Heredia (Heredia Centro, San Francisco, Santo Domingo, San Joaqu\u00edn y Barva), Alajuela, Cartago, P\u00e9rez Zeled\u00f3n y Liberia en Guanacaste.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfA qu\u00e9 hora cierra Farma Value?<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Las sedes de Santo Domingo, San Joaqu\u00edn y Barva cierran a las 9:00 pm de lunes a viernes (y a las 8:00 pm s\u00e1bado y domingo). Plaza Itskatz\u00fa, Zapote y Curridabat cierran a las 9:00 pm todos los d\u00edas. La mayor\u00eda de las dem\u00e1s sucursales cierra a las 8:00 pm. Las sedes del centro de San Jos\u00e9 cierran a las 7:00 pm.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo contactar a Farma Value por WhatsApp?<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Cada sucursal tiene su propio n\u00famero de WhatsApp. Por ejemplo: Plaza Itskatz\u00fa al +506 8677-6001, Guachipel\u00edn al +506 8677-6002, Rohrmoser al +506 8677-6003. Encontr\u00e1s el WhatsApp de cada sede en la tabla de tel\u00e9fonos al inicio de esta p\u00e1gina.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfD\u00f3nde queda la Farma Value m\u00e1s cercana?<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Con 22 sedes en el pa\u00eds es muy probable que haya una Farma Value cerca. En el Gran \u00c1rea Metropolitana hay sedes en Escaz\u00fa, Rohrmoser, San Jos\u00e9 Centro, Paseo Col\u00f3n, Moravia, Zapote, Curridabat, Desamparados, Heredia, Santo Domingo, San Joaqu\u00edn, Barva, Lindora y Alajuela. Tambi\u00e9n hay sedes en Cartago, P\u00e9rez Zeled\u00f3n y Liberia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 tipo de medicamentos vende Farma Value?<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Farma Value se especializa en medicamentos gen\u00e9ricos de bajo costo, adem\u00e1s de productos de salud, belleza y cuidado personal. Al ser gen\u00e9ricos, los precios suelen ser significativamente menores que en las farmacias de marca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Farma Value es una cadena de farmacias centroamericana fundada en Honduras en 2002, especializada en medicamentos gen\u00e9ricos de bajo costo y productos de salud. Con m\u00e1s de 5,000 empleados y 300 puntos de servicio en M\u00e9xico, Guatemala, Honduras, El Salvador, Nicaragua, Costa Rica, Panam\u00e1 y Rep\u00fablica Dominicana, Farma Value es una de las cadenas farmac\u00e9uticas &#8230; <a title=\"Farma Value \u2014 Sucursales y Horarios en Costa Rica\" class=\"read-more\" href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/\" aria-label=\"Leer m\u00e1s sobre Farma Value \u2014 Sucursales y Horarios en Costa Rica\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[44,56,49,40,17,59,60,50,53,65,4,63,45,52,42,70,3,46,61,18,39,62,68,21,57,69,58,54,47,64,41,66,51,43,67,5,19,55,6,48],"tags":[],"class_list":["post-198","post","type-post","status-publish","format-standard","hentry","category-44","category-56","category-49","category-40","category-17","category-59","category-60","category-50","category-53","category-65","category-4","category-63","category-45","category-52","category-42","category-70","category-alajuela","category-cartago","category-desamparados-san-jose","category-escazu","category-farmacias","category-gravilias","category-guanacaste","category-heredia","category-hospital","category-liberia","category-merced","category-moravia","category-occidental","category-oriental","category-pavas","category-perez-zeledon","category-pozos","category-san-francisco","category-san-isidro-del-general","category-san-jose","category-san-rafael","category-san-vicente","category-santa-ana","category-zapote"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Farma Value Horarios y Sucursales Costa Rica | 22 Sedes<\/title>\n<meta name=\"description\" content=\"Farma Value Costa Rica: 22 sucursales con horarios, tel\u00e9fonos y direcciones. Varias sedes abren domingos. Lun\u2013Vie hasta 9pm en Santo Domingo, San Joaqu\u00edn y Barva. Encontr\u00e1 la m\u00e1s cercana.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Farma Value Horarios y Sucursales Costa Rica | 22 Sedes\" \/>\n<meta property=\"og:description\" content=\"Farma Value Costa Rica: 22 sucursales con horarios, tel\u00e9fonos y direcciones. Varias sedes abren domingos. Lun\u2013Vie hasta 9pm en Santo Domingo, San Joaqu\u00edn y Barva. Encontr\u00e1 la m\u00e1s cercana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-12T18:50:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T12:59:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-farma-value\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-farma-value\\\/\",\"name\":\"Farma Value Horarios y Sucursales Costa Rica | 22 Sedes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-farma-value\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-farma-value\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/farmacias-farma-value-costa-rica.png\",\"datePublished\":\"2018-03-12T18:50:11+00:00\",\"dateModified\":\"2026-05-12T12:59:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\"},\"description\":\"Farma Value Costa Rica: 22 sucursales con horarios, tel\u00e9fonos y direcciones. Varias sedes abren domingos. Lun\u2013Vie hasta 9pm en Santo Domingo, San Joaqu\u00edn y Barva. Encontr\u00e1 la m\u00e1s cercana.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-farma-value\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-farma-value\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-farma-value\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/farmacias-farma-value-costa-rica.png\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/farmacias-farma-value-costa-rica.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-farma-value\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Farma Value \u2014 Sucursales y Horarios en Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/\",\"name\":\"Costa Rica\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farma Value Horarios y Sucursales Costa Rica | 22 Sedes","description":"Farma Value Costa Rica: 22 sucursales con horarios, tel\u00e9fonos y direcciones. Varias sedes abren domingos. Lun\u2013Vie hasta 9pm en Santo Domingo, San Joaqu\u00edn y Barva. Encontr\u00e1 la m\u00e1s cercana.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/","og_locale":"es_ES","og_type":"article","og_title":"Farma Value Horarios y Sucursales Costa Rica | 22 Sedes","og_description":"Farma Value Costa Rica: 22 sucursales con horarios, tel\u00e9fonos y direcciones. Varias sedes abren domingos. Lun\u2013Vie hasta 9pm en Santo Domingo, San Joaqu\u00edn y Barva. Encontr\u00e1 la m\u00e1s cercana.","og_url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/","og_site_name":"Costa Rica","article_published_time":"2018-03-12T18:50:11+00:00","article_modified_time":"2026-05-12T12:59:08+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"21 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/","url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/","name":"Farma Value Horarios y Sucursales Costa Rica | 22 Sedes","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/directorio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png","datePublished":"2018-03-12T18:50:11+00:00","dateModified":"2026-05-12T12:59:08+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce"},"description":"Farma Value Costa Rica: 22 sucursales con horarios, tel\u00e9fonos y direcciones. Varias sedes abren domingos. Lun\u2013Vie hasta 9pm en Santo Domingo, San Joaqu\u00edn y Barva. Encontr\u00e1 la m\u00e1s cercana.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png","contentUrl":"https:\/\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/directorio\/"},{"@type":"ListItem","position":2,"name":"Farma Value \u2014 Sucursales y Horarios en Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/directorio\/#website","url":"https:\/\/costaricainfolink.com\/directorio\/","name":"Costa Rica","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/directorio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p88Lb6-3c","jetpack-related-posts":[{"id":489,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-fischel\/","url_meta":{"origin":198,"position":0},"title":"Farmacias Fischel Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"26 agosto, 2019","format":false,"excerpt":"Farmacias Fischel es una de las cadenas farmac\u00e9uticas m\u00e1s grandes de Costa Rica, con m\u00e1s de 50 sucursales en San Jos\u00e9, Escaz\u00fa, Heredia, Alajuela, Cartago, Guanacaste, Puntarenas y Lim\u00f3n. La mayor\u00eda de sucursales abre todos los d\u00edas de 9am a 9pm; varias sedes tienen horario extendido hasta medianoche. Adem\u00e1s del\u2026","rel":"","context":"En \u00ab10102\u00bb","block_context":{"text":"10102","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10102\/"},"img":{"alt_text":"Farmacias Fischel Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":833,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-saba\/","url_meta":{"origin":198,"position":1},"title":"Farmacias Saba Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"10 octubre, 2019","format":false,"excerpt":"Farmacia Saba es una cadena de farmacias originaria de Honduras, presente en Costa Rica desde 2018 con m\u00e1s de 30 sucursales en el Gran \u00c1rea Metropolitana y zonas como San Ram\u00f3n, Grecia y P\u00e9rez Zeled\u00f3n. Se especializa en medicamentos gen\u00e9ricos de bajo costo. Ofrecen entrega a domicilio gratis llamando al\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10101\/"},"img":{"alt_text":"Farmacias Saba Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-saba-costa-rica-21.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":808,"url":"https:\/\/costaricainfolink.com\/directorio\/walmart\/","url_meta":{"origin":198,"position":2},"title":"Walmart Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"5 octubre, 2019","format":false,"excerpt":"Walmart Costa Rica opera 13 tiendas en todo el pa\u00eds, con presencia en San Jos\u00e9, Alajuela, Heredia, Cartago y Guanacaste. La cadena ofrece supermercado, electr\u00f3nica, ropa, l\u00ednea blanca y m\u00e1s bajo un mismo techo. La mayor\u00eda de tiendas abre los 7 d\u00edas de la semana con horario extendido los viernes\u2026","rel":"","context":"En \u00ab10111\u00bb","block_context":{"text":"10111","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10111\/"},"img":{"alt_text":"Walmart Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/walmart-costa-rica-2-1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1169,"url":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/","url_meta":{"origin":198,"position":3},"title":"Almacenes El Rey Costa Rica","author":"Costa Rica Info Link","date":"23 mayo, 2021","format":false,"excerpt":"Almacenes Cartago \u00b7 Cristo Rey \u00b7 Curridabat \u00b7 Escazu \u00b7 Gu\u00e1piles \u00b7 Monserrat \u00b7 Paseo de Las Flores \u00b7 San Francisco \u00b7 San Jose \u00b7 San Ram\u00f3n Centro \u00b7 San Ram\u00f3n Mall \u00b7 Zapote BODEGAS Liberia \u00b7 Perez Zeled\u00f3n \u00b7 Puntarenas \u00b7 Santa Cruz \u00b7 San Carlos Almacen El Rey\u2026","rel":"","context":"En \u00ab10105\u00bb","block_context":{"text":"10105","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10105\/"},"img":{"alt_text":"Almacen El Rey Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion-150x150.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":79,"url":"https:\/\/costaricainfolink.com\/directorio\/pricesmart\/","url_meta":{"origin":198,"position":4},"title":"PriceSmart Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"3 enero, 2017","format":false,"excerpt":"PriceSmart es un club de compras mayorista que opera en Costa Rica con 7 sucursales en San Jos\u00e9, Escaz\u00fa, Heredia, Alajuela, Cartago y Santa Ana. Requiere membres\u00eda anual para acceder a precios de mayorista en alimentos, electr\u00f3nica, llantas, farmacia, panader\u00eda y m\u00e1s. Todas las sedes abren los 7 d\u00edas de\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10203\/"},"img":{"alt_text":"PriceSmart Costa Rica Zapote, Escaz\u00fa, Heredia, Llorente, Alajuela, Tres R\u00edos y santa Ana.","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/01\/pricesmart-costa-rica-1-300x96.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":404,"url":"https:\/\/costaricainfolink.com\/directorio\/automercado\/","url_meta":{"origin":198,"position":5},"title":"AutoMercado","author":"Costa Rica Info Link","date":"20 septiembre, 2018","format":false,"excerpt":"Ubicaciones San Jos\u00e9 Centro - Escaz\u00fa - Guadalupe - Guachipel\u00edn - Moravia - Multiplaza - Plaza del Sol - Plaza Mayor - R\u00edo Oro - Santa Ana - Yoses Puntarenas Herradura Heredia Barva - Plaza Bratsi - Santo Domingo - San Francisco Cartago Tres R\u00edos Guanacaste El Coco - Tamarindo\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10101\/"},"img":{"alt_text":"AutoMercado Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/09\/automercado-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/comments?post=198"}],"version-history":[{"count":97,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/198\/revisions"}],"predecessor-version":[{"id":2093,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/198\/revisions\/2093"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/media?parent=198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/categories?post=198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/tags?post=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}