{"id":923,"date":"2019-10-18T19:29:28","date_gmt":"2019-10-19T01:29:28","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/directorio\/?p=923"},"modified":"2024-04-25T05:59:49","modified_gmt":"2024-04-25T11:59:49","slug":"farmacias-la-bomba","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/","title":{"rendered":"Farmacias La Bomba"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"928\" data-permalink=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/farmacias-la-bomba-costa-rica-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg?fit=341%2C265&amp;ssl=1\" data-orig-size=\"341,265\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Farmacias La Bomba Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg?fit=341%2C265&amp;ssl=1\" class=\"aligncenter wp-image-928\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg?resize=199%2C155&#038;ssl=1\" alt=\"Farmacias La Bomba Costa Rica\" width=\"199\" height=\"155\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg?w=341&amp;ssl=1 341w, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg?resize=300%2C233&amp;ssl=1 300w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/p>\n<p align=\"center\">Farmacia La Bomba Sucursales<br \/>\n<a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#sanrafaelescazu\">Escaz\u00fa<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#plazacronos\">Plaza Cronos<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#sanfrancisco\">San Francisco<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#decosuredesamparados\">Decosure<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#curridabat\">Curridabat<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#zapote\">Zapote<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#santaana\">Santa Ana<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#sanantoniodesamparados\">San Antonio<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#guadalupe\">Guadalupe<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#tibas\">Tib\u00e1s<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#zapoteplazaregistro\">Zapote Plaza Registro<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#montesacrocurridabat\">Contiguo a Montesacro Curridabat<\/a><\/p>\n<h2>Tel\u00e9fono<br \/>\n<a href=\"tel:+50622809983\">+506 2280-9983<\/a><\/h2>\n<h2 id=\"sanrafaelescazu\">Farmacia La Bomba Escaz\u00fa<\/h2>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 7am a 10pm. Domingos de 9am a 9pm<\/p>\n<h2>Direcci\u00f3n<\/h2>\n<p>Contiguo a Toys Escaz\u00fa, Paralela Ruta 27. Distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0t38v2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba Escaz\u00fa San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/jQcYMctEZzUDJz4XA\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba Escaz\u00fa San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2 id=\"plazacronos\">Farmacia La Bomba Plaza Cronos<\/h2>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 7am a 10pm. Domingos de 9am a 9pm.<\/p>\n<h2>Direcci\u00f3n<\/h2>\n<p>Plaza Cronos Curridabat, Contiguo a Momentum Pinares. Distrito: Sanchez, cant\u00f3n: Curridabat, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11803.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u22hkte\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba Plaza Cronos Sanchez, Curridabat San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/h7nB5ekkKamjMrWu5\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba Plaza Cronos Sanchez, Curridabat San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2 id=\"sanfrancisco\">Farmacia La Bomba San Francisco<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>400m este de la Y Griega San Francisco de 2 R\u00edos. Distrito: San Francisco de Dos R\u00edos, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10106.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rh961\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba San Francisco De Dos R\u00edos San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/2q2fdhtz4iphWXrK9\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba San Francisco De Dos R\u00edos San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 8am a 10pm. Domingos de 9am a 7pm<\/p>\n<h2 id=\"decosuredesamparados\">Farmacia La Bomba Centro Comercial Decosure<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>Centro Comercial Decosure. Distrito: Desamparados, cant\u00f3n: Desamparados, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10301.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0r16d6\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba Centro Comercial Decosure Desamparados San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/tMbjWNujMpaRNr8S8\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba Centro Comercial Decosure Desamparados San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos de 9am a 7pm.<\/p>\n<h2 id=\"curridabat\">Farmacia La Bomba Curridabat 2<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>Frente al AM\/PM. Distrito: Curridabat, cant\u00f3n: Curridabat, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11801.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rv84v\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba Curridabat San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/6MoskXtJDS2a2BWb9\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba Curridabat San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 7am a 10pm. Domingos de 9am a 9pm.<\/p>\n<h2 id=\"zapote\">Farmacia La Bomba Zapote<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>125m sur de la Iglesia cat\u00f3lica de Zapote. Distrito: Zapote, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10105.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rmf10\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba Zapote San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/Qp2UL6UqHtpk15PT6\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba Zapote San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 8am a 10pm. Domingos de 9am a 7pm.<\/p>\n<h2 id=\"santaana\">Farmacia La Bomba Santa Ana<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>1 Km este del cruce de la Cruz Roja de Santa Ana. Dentro de Ekono. Distrito: Santa Ana, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10901.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0krgwn\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba Santa Ana San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/5SLhmaFte1u1wpUB6\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba Santa Ana San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 8am a 10pm. Domingos de 9am a 7pm.<\/p>\n<h2 id=\"sanantoniodesamparados\">Farmacia La Bomba San Antonio<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>100m este del cruce de San Antonio de Desamparados. Dentro de Ekono. Distrito: San Antonio, cant\u00f3n: Desamparados, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10305.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0r6004\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba San Antonio San Antonio Desamparados San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/hpkbhuuWT6TnDJsh9\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba San Antonio Desamparados San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1badp de 8am a 10pm. Domingos de 9am a 7pm.<\/p>\n<h2 id=\"guadalupe\">Farmacia La Bomba Guadalupe<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>Del cruce de Moravia, 50m oeste. Dentro de Ekono. Distrito: Guadalupe, cant\u00f3n: Goicoechea, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10801.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0x7q1w\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba Guadalupe Goicoechea San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/ARU5GwE152uMvhvg9\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba Guadalupe Goicoechea San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<br \/>\n<a href=\"tel:+50640017597\">+506 4001-7597<\/a><\/h2>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 8am a 8pm. Domingos de 9am a 7pm.<\/p>\n<h2 id=\"tibas\">Farmacia La Bomba Tib\u00e1s<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>400m sur de la Iglesia cat\u00f3lica de Tib\u00e1s. Dentro de Ekono. Distrito: San Juan, cant\u00f3n: Tib\u00e1s, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11301.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0wsxtt\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba San Juan Tib\u00e1s San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/xEcPhN8hf3BxQJgRA\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba San Juan Tib\u00e1s San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<br \/>\n<a href=\"tel:+50640017857\">+506 4001-7857<\/a><\/h2>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 8am a 10pm. Domingos de 9am a 7pm.<\/p>\n<h2 id=\"zapoteplazaregistro\">Farmacia La Bomba Zapote 2<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>Plaza Registro, frente al Registro Nacional. Distrito: Curridabat, cant\u00f3n: Curridabat, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11801.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rmtd3\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba Zapote Curridabat San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/i7ALuompxaoVzAgu5\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba Zapote Curridabat San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 7am a 10pm. Domingos de 09:00\u201321:00<\/p>\n<h2 id=\"montesacrocurridabat\">Farmacia La Bomba Curridabat 3<\/h2>\n<h2>Direcci\u00f3n<\/h2>\n<p>Contiguo a Funeraria Montesacro de Curridabat \/ 600m oeste de Ferreter\u00eda EPA. Distrito: Curridabat, cant\u00f3n: Curridabat, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11801.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rwn78\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Farmacia La Bomba Curridabat San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/X2M3uKZFUZiqyZ2P6\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Farmacia La Bomba Curridabat San Jos\u00e9 Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Horario<\/h2>\n<p>De Lunes a S\u00e1bado de 7am a 10pm. Domingos de 9am a 9pm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Farmacia La Bomba Sucursales Escaz\u00fa \u00b7 Plaza Cronos \u00b7 San Francisco \u00b7 Decosure \u00b7 Curridabat \u00b7 Zapote \u00b7 Santa Ana \u00b7 San Antonio \u00b7 Guadalupe \u00b7 Tib\u00e1s \u00b7 Zapote Plaza Registro \u00b7 Contiguo a Montesacro Curridabat Tel\u00e9fono +506 2280-9983 Farmacia La Bomba Escaz\u00fa Horario De Lunes a S\u00e1bado de 7am a 10pm. Domingos de 9am &#8230; <a title=\"Farmacias La Bomba\" class=\"read-more\" href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/\" aria-label=\"Leer m\u00e1s sobre Farmacias La Bomba\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[49,17,7,124,16,15,18,39,94,95,5,127,19,6,25,48],"tags":[],"class_list":["post-923","post","type-post","status-publish","format-standard","hentry","category-49","category-17","category-7","category-124","category-16","category-curridabat","category-escazu","category-farmacias","category-goicoechea","category-guadalupe","category-san-jose","category-san-juan-tibas","category-san-rafael","category-santa-ana","category-tibas","category-zapote"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Farmacias La Bomba Costa Rica - Tel\u00e9fono, Direcci\u00f3n, Horarios<\/title>\n<meta name=\"description\" content=\"Farmacias La Bomba Costa Rica. Tel\u00e9fono, direcci\u00f3n, horarios, ubicaciones WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Farmacias La Bomba Costa Rica - Tel\u00e9fono, Direcci\u00f3n, Horarios\" \/>\n<meta property=\"og:description\" content=\"Farmacias La Bomba Costa Rica. Tel\u00e9fono, direcci\u00f3n, horarios, ubicaciones WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-19T01:29:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-25T11:59:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\"},\"headline\":\"Farmacias La Bomba\",\"datePublished\":\"2019-10-19T01:29:28+00:00\",\"dateModified\":\"2024-04-25T11:59:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/\"},\"wordCount\":605,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/farmacias-la-bomba-costa-rica-2.jpg\",\"articleSection\":[\"10105\",\"10203\",\"10901\",\"11301\",\"11801\",\"Curridabat\",\"Escaz\u00fa\",\"Farmacias\",\"Goicoechea\",\"Guadalupe\",\"San Jos\u00e9\",\"San Juan\",\"San Rafael\",\"Santa Ana\",\"Tib\u00e1s\",\"Zapote\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/\",\"name\":\"Farmacias La Bomba Costa Rica - Tel\u00e9fono, Direcci\u00f3n, Horarios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/farmacias-la-bomba-costa-rica-2.jpg\",\"datePublished\":\"2019-10-19T01:29:28+00:00\",\"dateModified\":\"2024-04-25T11:59:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\"},\"description\":\"Farmacias La Bomba Costa Rica. Tel\u00e9fono, direcci\u00f3n, horarios, ubicaciones WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/farmacias-la-bomba-costa-rica-2.jpg?fit=341%2C265&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/farmacias-la-bomba-costa-rica-2.jpg?fit=341%2C265&ssl=1\",\"width\":341,\"height\":265,\"caption\":\"Farmacias La Bomba Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/farmacias-la-bomba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Farmacias La Bomba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/\",\"name\":\"Costa Rica\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/#\\\/schema\\\/person\\\/02377696952a9295a2697e0a148cc0ce\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"],\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/directorio\\\/author\\\/costaricainfolink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farmacias La Bomba Costa Rica - Tel\u00e9fono, Direcci\u00f3n, Horarios","description":"Farmacias La Bomba Costa Rica. Tel\u00e9fono, direcci\u00f3n, horarios, ubicaciones WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/","og_locale":"es_ES","og_type":"article","og_title":"Farmacias La Bomba Costa Rica - Tel\u00e9fono, Direcci\u00f3n, Horarios","og_description":"Farmacias La Bomba Costa Rica. Tel\u00e9fono, direcci\u00f3n, horarios, ubicaciones WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/","og_site_name":"Costa Rica","article_published_time":"2019-10-19T01:29:28+00:00","article_modified_time":"2024-04-25T11:59:49+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce"},"headline":"Farmacias La Bomba","datePublished":"2019-10-19T01:29:28+00:00","dateModified":"2024-04-25T11:59:49+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/"},"wordCount":605,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg","articleSection":["10105","10203","10901","11301","11801","Curridabat","Escaz\u00fa","Farmacias","Goicoechea","Guadalupe","San Jos\u00e9","San Juan","San Rafael","Santa Ana","Tib\u00e1s","Zapote"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/","url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/","name":"Farmacias La Bomba Costa Rica - Tel\u00e9fono, Direcci\u00f3n, Horarios","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/directorio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg","datePublished":"2019-10-19T01:29:28+00:00","dateModified":"2024-04-25T11:59:49+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce"},"description":"Farmacias La Bomba Costa Rica. Tel\u00e9fono, direcci\u00f3n, horarios, ubicaciones WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg?fit=341%2C265&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-la-bomba-costa-rica-2.jpg?fit=341%2C265&ssl=1","width":341,"height":265,"caption":"Farmacias La Bomba Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/directorio\/farmacias-la-bomba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/directorio\/"},{"@type":"ListItem","position":2,"name":"Farmacias La Bomba"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/directorio\/#website","url":"https:\/\/costaricainfolink.com\/directorio\/","name":"Costa Rica","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/directorio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/directorio\/#\/schema\/person\/02377696952a9295a2697e0a148cc0ce","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644","url":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644","contentUrl":"https:\/\/costaricainfolink.com\/directorio\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783693644","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"],"url":"https:\/\/costaricainfolink.com\/directorio\/author\/costaricainfolink\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p88Lb6-eT","jetpack-related-posts":[{"id":79,"url":"https:\/\/costaricainfolink.com\/directorio\/pricesmart\/","url_meta":{"origin":923,"position":0},"title":"PriceSmart Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"3 enero, 2017","format":false,"excerpt":"PriceSmart es un club de compras mayorista que opera en Costa Rica con 7 sucursales en San Jos\u00e9, Escaz\u00fa, Heredia, Alajuela, Cartago y Santa Ana. Requiere membres\u00eda anual para acceder a precios de mayorista en alimentos, electr\u00f3nica, llantas, farmacia, panader\u00eda y m\u00e1s. Todas las sedes abren los 7 d\u00edas de\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10203\/"},"img":{"alt_text":"PriceSmart Costa Rica Zapote, Escaz\u00fa, Heredia, Llorente, Alajuela, Tres R\u00edos y santa Ana.","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2017\/01\/pricesmart-costa-rica-1-300x96.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":198,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-farma-value\/","url_meta":{"origin":923,"position":1},"title":"Farma Value \u2014 Sucursales y Horarios en Costa Rica","author":"Costa Rica Info Link","date":"12 marzo, 2018","format":false,"excerpt":"Farma Value es una cadena de farmacias centroamericana fundada en Honduras en 2002, especializada en medicamentos gen\u00e9ricos de bajo costo y productos de salud. Con m\u00e1s de 5,000 empleados y 300 puntos de servicio en M\u00e9xico, Guatemala, Honduras, El Salvador, Nicaragua, Costa Rica, Panam\u00e1 y Rep\u00fablica Dominicana, Farma Value es\u2026","rel":"","context":"En \u00ab10102\u00bb","block_context":{"text":"10102","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10102\/"},"img":{"alt_text":"Farmacias Farma Value Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/directorio\/wp-content\/uploads\/2018\/03\/farmacias-farma-value-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":833,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-saba\/","url_meta":{"origin":923,"position":2},"title":"Farmacias Saba Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"10 octubre, 2019","format":false,"excerpt":"Farmacia Saba es una cadena de farmacias originaria de Honduras, presente en Costa Rica desde 2018 con m\u00e1s de 30 sucursales en el Gran \u00c1rea Metropolitana y zonas como San Ram\u00f3n, Grecia y P\u00e9rez Zeled\u00f3n. Se especializa en medicamentos gen\u00e9ricos de bajo costo. Ofrecen entrega a domicilio gratis llamando al\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10101\/"},"img":{"alt_text":"Farmacias Saba Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/farmacias-saba-costa-rica-21.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1169,"url":"https:\/\/costaricainfolink.com\/directorio\/almacenes-el-rey-costa-rica\/","url_meta":{"origin":923,"position":3},"title":"Almacenes El Rey Costa Rica","author":"Costa Rica Info Link","date":"23 mayo, 2021","format":false,"excerpt":"Almacenes Cartago \u00b7 Cristo Rey \u00b7 Curridabat \u00b7 Escazu \u00b7 Gu\u00e1piles \u00b7 Monserrat \u00b7 Paseo de Las Flores \u00b7 San Francisco \u00b7 San Jose \u00b7 San Ram\u00f3n Centro \u00b7 San Ram\u00f3n Mall \u00b7 Zapote BODEGAS Liberia \u00b7 Perez Zeled\u00f3n \u00b7 Puntarenas \u00b7 Santa Cruz \u00b7 San Carlos Almacen El Rey\u2026","rel":"","context":"En \u00ab10105\u00bb","block_context":{"text":"10105","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10105\/"},"img":{"alt_text":"Almacen El Rey Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2021\/05\/almacen-el-rey-costa-rica-ubicacion-telefonos-horario-direccion-150x150.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":489,"url":"https:\/\/costaricainfolink.com\/directorio\/farmacias-fischel\/","url_meta":{"origin":923,"position":4},"title":"Farmacias Fischel Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"26 agosto, 2019","format":false,"excerpt":"Farmacias Fischel es una de las cadenas farmac\u00e9uticas m\u00e1s grandes de Costa Rica, con m\u00e1s de 50 sucursales en San Jos\u00e9, Escaz\u00fa, Heredia, Alajuela, Cartago, Guanacaste, Puntarenas y Lim\u00f3n. La mayor\u00eda de sucursales abre todos los d\u00edas de 9am a 9pm; varias sedes tienen horario extendido hasta medianoche. Adem\u00e1s del\u2026","rel":"","context":"En \u00ab10102\u00bb","block_context":{"text":"10102","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10102\/"},"img":{"alt_text":"Farmacias Fischel Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/08\/farmacias-fischel-costa-rica-1.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":808,"url":"https:\/\/costaricainfolink.com\/directorio\/walmart\/","url_meta":{"origin":923,"position":5},"title":"Walmart Costa Rica \u2014 Horarios, Sucursales y Tel\u00e9fonos","author":"Costa Rica Info Link","date":"5 octubre, 2019","format":false,"excerpt":"Walmart Costa Rica opera 13 tiendas en todo el pa\u00eds, con presencia en San Jos\u00e9, Alajuela, Heredia, Cartago y Guanacaste. La cadena ofrece supermercado, electr\u00f3nica, ropa, l\u00ednea blanca y m\u00e1s bajo un mismo techo. La mayor\u00eda de tiendas abre los 7 d\u00edas de la semana con horario extendido los viernes\u2026","rel":"","context":"En \u00ab10111\u00bb","block_context":{"text":"10111","link":"https:\/\/costaricainfolink.com\/directorio\/category\/10111\/"},"img":{"alt_text":"Walmart Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/directorio\/wp-content\/uploads\/2019\/10\/walmart-costa-rica-2-1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/comments?post=923"}],"version-history":[{"count":32,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/923\/revisions"}],"predecessor-version":[{"id":1895,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/posts\/923\/revisions\/1895"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/media?parent=923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/categories?post=923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/directorio\/wp-json\/wp\/v2\/tags?post=923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}