{"id":117,"count":1,"description":"","link":"https:\/\/costaricainfolink.com\/en\/category\/nature-and-wildlife\/","name":"Nature and Wildlife","slug":"nature-and-wildlife","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nature and Wildlife Archives<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nature and Wildlife Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/en\/category\/nature-and-wildlife\/\" \/>\n<meta property=\"og:site_name\" content=\"CostaRicaInfoLink.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/category\\\/nature-and-wildlife\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/category\\\/nature-and-wildlife\\\/\",\"name\":\"Nature and Wildlife Archives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/category\\\/nature-and-wildlife\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/category\\\/nature-and-wildlife\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nature and Wildlife\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/\",\"name\":\"CostaRicaInfoLink.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nature and Wildlife Archives","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Nature and Wildlife Archives","og_url":"https:\/\/costaricainfolink.com\/en\/category\/nature-and-wildlife\/","og_site_name":"CostaRicaInfoLink.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/costaricainfolink.com\/en\/category\/nature-and-wildlife\/","url":"https:\/\/costaricainfolink.com\/en\/category\/nature-and-wildlife\/","name":"Nature and Wildlife Archives","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/en\/category\/nature-and-wildlife\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/en\/category\/nature-and-wildlife\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/en\/"},{"@type":"ListItem","position":2,"name":"Nature and Wildlife"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/en\/#website","url":"https:\/\/costaricainfolink.com\/en\/","name":"CostaRicaInfoLink.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/categories\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/posts?categories=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}