{"id":72,"count":1,"description":"","link":"https:\/\/costaricainfolink.com\/en\/category\/postal-code\/20505\/","name":"20505","slug":"20505","taxonomy":"category","parent":33,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>20505 Archives<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20505 Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/en\/category\/postal-code\/20505\/\" \/>\n<meta property=\"og:site_name\" content=\"CostaRicaInfoLink.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/category\\\/postal-code\\\/20505\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/category\\\/postal-code\\\/20505\\\/\",\"name\":\"20505 Archives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/category\\\/postal-code\\\/20505\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/category\\\/postal-code\\\/20505\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Postal code\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/category\\\/postal-code\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"20505\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/\",\"name\":\"CostaRicaInfoLink.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20505 Archives","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"20505 Archives","og_url":"https:\/\/costaricainfolink.com\/en\/category\/postal-code\/20505\/","og_site_name":"CostaRicaInfoLink.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/costaricainfolink.com\/en\/category\/postal-code\/20505\/","url":"https:\/\/costaricainfolink.com\/en\/category\/postal-code\/20505\/","name":"20505 Archives","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/en\/category\/postal-code\/20505\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/en\/category\/postal-code\/20505\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/en\/"},{"@type":"ListItem","position":2,"name":"Postal code","item":"https:\/\/costaricainfolink.com\/en\/category\/postal-code\/"},{"@type":"ListItem","position":3,"name":"20505"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/en\/#website","url":"https:\/\/costaricainfolink.com\/en\/","name":"CostaRicaInfoLink.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/categories\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/categories\/33"}],"wp:post_type":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/posts?categories=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}