{"id":18033,"date":"2018-11-18T22:45:00","date_gmt":"2018-11-18T22:45:00","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg"},"modified":"2018-11-18T22:53:34","modified_gmt":"2018-11-18T22:53:34","slug":"lankester-botanical-garden-costa-rica-9","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/en\/lankester-botanical-gardens-park-costa-rica\/lankester-botanical-garden-costa-rica-9\/#main","title":{"rendered":"Lankester Botanical Gardens Costa Rica"},"author":21,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-18033","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lankester Botanical Gardens Costa Rica - CostaRicaInfoLink.com<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lankester Botanical Gardens Costa Rica - CostaRicaInfoLink.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg\" \/>\n<meta property=\"og:site_name\" content=\"CostaRicaInfoLink.com\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-18T22:53:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/lankester-botanical-garden-costa-rica-9.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/lankester-botanical-garden-costa-rica-9.jpg\",\"name\":\"Lankester Botanical Gardens Costa Rica - CostaRicaInfoLink.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/#website\"},\"datePublished\":\"2018-11-18T22:45:00+00:00\",\"dateModified\":\"2018-11-18T22:53:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/lankester-botanical-garden-costa-rica-9.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/lankester-botanical-garden-costa-rica-9.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/lankester-botanical-garden-costa-rica-9.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lankester Botanical Gardens Park Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/lankester-botanical-gardens-park-costa-rica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lankester Botanical Gardens Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/\",\"name\":\"CostaRicaInfoLink.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lankester Botanical Gardens Costa Rica - CostaRicaInfoLink.com","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Lankester Botanical Gardens Costa Rica - CostaRicaInfoLink.com","og_url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg","og_site_name":"CostaRicaInfoLink.com","article_modified_time":"2018-11-18T22:53:34+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg","url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg","name":"Lankester Botanical Gardens Costa Rica - CostaRicaInfoLink.com","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/en\/#website"},"datePublished":"2018-11-18T22:45:00+00:00","dateModified":"2018-11-18T22:53:34+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/en\/"},{"@type":"ListItem","position":2,"name":"Lankester Botanical Gardens Park Costa Rica","item":"https:\/\/costaricainfolink.com\/en\/lankester-botanical-gardens-park-costa-rica\/"},{"@type":"ListItem","position":3,"name":"Lankester Botanical Gardens Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/en\/#website","url":"https:\/\/costaricainfolink.com\/en\/","name":"CostaRicaInfoLink.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?resize=160%2C120&amp;ssl=1 160w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"18033\" data-permalink=\"https:\/\/costaricainfolink.com\/en\/lankester-botanical-gardens-park-costa-rica\/lankester-botanical-garden-costa-rica-9\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?fit=1920%2C1440&amp;ssl=1\" data-orig-size=\"1920,1440\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Lankester Botanical Gardens Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?fit=1024%2C768&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1440,"file":"2010\/04\/lankester-botanical-garden-costa-rica-9.jpg","sizes":{"thumbnail":{"file":"lankester-botanical-garden-costa-rica-9-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"lankester-botanical-garden-costa-rica-9-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?fit=300%2C225&ssl=1"},"medium_large":{"file":"lankester-botanical-garden-costa-rica-9-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?fit=768%2C576&ssl=1"},"large":{"file":"lankester-botanical-garden-costa-rica-9-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?fit=1024%2C768&ssl=1"},"1_column":{"file":"lankester-botanical-garden-costa-rica-9-560x420.jpg","width":560,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9-560x420.jpg"},"2_column":{"file":"lankester-botanical-garden-costa-rica-9-260x195.jpg","width":260,"height":195,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9-260x195.jpg"},"3_column":{"file":"lankester-botanical-garden-costa-rica-9-160x120.jpg","width":160,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9-160x120.jpg"},"full":{"file":"lankester-botanical-garden-costa-rica-9.jpg?fit=1920%2C1440&ssl=1","width":1920,"height":1440,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg?fit=1920%2C1440&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1381,"source_url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/04\/lankester-botanical-garden-costa-rica-9.jpg","filename":"lankester-botanical-garden-costa-rica-9.jpg","filesize":295734,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/media\/18033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/comments?post=18033"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1381,"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/posts\/1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}