{"id":18791,"date":"2022-04-30T14:12:51","date_gmt":"2022-04-30T14:12:51","guid":{"rendered":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg"},"modified":"2022-04-30T14:13:33","modified_gmt":"2022-04-30T14:13:33","slug":"casona-parque-nacional-santa-rosa-costa-rica","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/en\/santa-rosa-national-park-costa-rica\/casona-parque-nacional-santa-rosa-costa-rica\/#main","title":{"rendered":"Santa Rosa National Park Costa Rica"},"author":21,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-18791","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Rosa National Park Costa Rica - CostaRicaInfoLink.com<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Rosa National Park Costa Rica - CostaRicaInfoLink.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg\" \/>\n<meta property=\"og:site_name\" content=\"CostaRicaInfoLink.com\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-30T14:13:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/11\\\/casona-parque-nacional-santa-rosa-costa-rica.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/11\\\/casona-parque-nacional-santa-rosa-costa-rica.jpg\",\"name\":\"Santa Rosa National Park Costa Rica - CostaRicaInfoLink.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/#website\"},\"datePublished\":\"2022-04-30T14:12:51+00:00\",\"dateModified\":\"2022-04-30T14:13:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/11\\\/casona-parque-nacional-santa-rosa-costa-rica.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/11\\\/casona-parque-nacional-santa-rosa-costa-rica.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2010\\\/11\\\/casona-parque-nacional-santa-rosa-costa-rica.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Rosa National Park Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/santa-rosa-national-park-costa-rica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Santa Rosa National Park Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/\",\"name\":\"CostaRicaInfoLink.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Rosa National Park Costa Rica - CostaRicaInfoLink.com","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Santa Rosa National Park Costa Rica - CostaRicaInfoLink.com","og_url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg","og_site_name":"CostaRicaInfoLink.com","article_modified_time":"2022-04-30T14:13:33+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg","url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg","name":"Santa Rosa National Park Costa Rica - CostaRicaInfoLink.com","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/en\/#website"},"datePublished":"2022-04-30T14:12:51+00:00","dateModified":"2022-04-30T14:13:33+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/en\/"},{"@type":"ListItem","position":2,"name":"Santa Rosa National Park Costa Rica","item":"https:\/\/costaricainfolink.com\/en\/santa-rosa-national-park-costa-rica\/"},{"@type":"ListItem","position":3,"name":"Santa Rosa National Park Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/en\/#website","url":"https:\/\/costaricainfolink.com\/en\/","name":"CostaRicaInfoLink.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Santa Rosa National Park Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"18791\" data-permalink=\"https:\/\/costaricainfolink.com\/en\/santa-rosa-national-park-costa-rica\/casona-parque-nacional-santa-rosa-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Santa Rosa National Park Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=1024%2C768&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Santa Rosa National Park Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1920,"file":"2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg","sizes":{"medium":{"file":"casona-parque-nacional-santa-rosa-costa-rica-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=300%2C225&ssl=1"},"large":{"file":"casona-parque-nacional-santa-rosa-costa-rica-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=1024%2C768&ssl=1"},"thumbnail":{"file":"casona-parque-nacional-santa-rosa-costa-rica-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"casona-parque-nacional-santa-rosa-costa-rica-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=768%2C576&ssl=1"},"1536x1536":{"file":"casona-parque-nacional-santa-rosa-costa-rica-1536x1152.jpg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=1536%2C1152&ssl=1"},"2048x2048":{"file":"casona-parque-nacional-santa-rosa-costa-rica-2048x1536.jpg","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=2048%2C1536&ssl=1"},"full":{"file":"casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=2560%2C1920&ssl=1","width":2560,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg?fit=2560%2C1920&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2767,"source_url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2010\/11\/casona-parque-nacional-santa-rosa-costa-rica.jpg","filename":"casona-parque-nacional-santa-rosa-costa-rica.jpg","filesize":716181,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/media\/18791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/comments?post=18791"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2767,"href":"https:\/\/costaricainfolink.com\/en\/wp-json\/wp\/v2\/posts\/2767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}