{"id":17352,"date":"2017-03-08T09:09:22","date_gmt":"2017-03-08T14:09:22","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg"},"modified":"2017-03-08T09:09:42","modified_gmt":"2017-03-08T14:09:42","slug":"arbol-de-guanacaste-simbolo-nacional-costa-rica","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/arbol-de-guanacaste-simbolo-nacional-costa-rica\/#main","title":{"rendered":"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica"},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-17352","attachment","type-attachment","status-inherit","hentry","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica - Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-08T14:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1546\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg\",\"name\":\"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"datePublished\":\"2017-03-08T14:09:22+00:00\",\"dateModified\":\"2017-03-08T14:09:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c1rbol de Guanacaste, S\u00edmbolo Nacional de Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica - Costa Rica","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica - Costa Rica","og_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg","og_site_name":"Costa Rica","article_modified_time":"2017-03-08T14:09:42+00:00","og_image":[{"width":2048,"height":1546,"url":"https:\/\/i2.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg","name":"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"datePublished":"2017-03-08T14:09:22+00:00","dateModified":"2017-03-08T14:09:42+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00c1rbol de Guanacaste, S\u00edmbolo Nacional de Costa Rica","item":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/"},{"@type":"ListItem","position":3,"name":"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a5dwqG-4vS","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?ssl=1\"><img decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=300%2C226&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=300%2C226&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=768%2C580&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=1024%2C773&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=560%2C423&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=260%2C196&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=160%2C121&amp;ssl=1 160w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"17352\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/arbol-de-guanacaste-simbolo-nacional-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&amp;ssl=1\" data-orig-size=\"2048,1546\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=1024%2C773&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1546,"file":"2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg","sizes":{"thumbnail":{"file":"arbol-de-guanacaste-simbolo-nacional-costa-rica-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"arbol-de-guanacaste-simbolo-nacional-costa-rica-300x226.jpg","width":300,"height":226,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=300%2C226&ssl=1"},"medium_large":{"file":"arbol-de-guanacaste-simbolo-nacional-costa-rica-768x580.jpg","width":768,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=768%2C580&ssl=1"},"large":{"file":"arbol-de-guanacaste-simbolo-nacional-costa-rica-1024x773.jpg","width":1024,"height":773,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=1024%2C773&ssl=1"},"1_column":{"file":"arbol-de-guanacaste-simbolo-nacional-costa-rica-560x423.jpg","width":560,"height":423,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica-560x423.jpg"},"2_column":{"file":"arbol-de-guanacaste-simbolo-nacional-costa-rica-260x196.jpg","width":260,"height":196,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica-260x196.jpg"},"3_column":{"file":"arbol-de-guanacaste-simbolo-nacional-costa-rica-160x121.jpg","width":160,"height":121,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica-160x121.jpg"},"full":{"file":"arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&ssl=1","width":2048,"height":1546,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":139,"source_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg","filename":"arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg","filesize":508693,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media\/17352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=17352"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":139,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}