{"id":18433,"date":"2019-04-18T10:00:40","date_gmt":"2019-04-18T15:00:40","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg"},"modified":"2019-04-18T10:00:50","modified_gmt":"2019-04-18T15:00:50","slug":"playa-manzanillo-costa-rica-40","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/es\/playa-manzanillo-en-liberia-costa-rica\/playa-manzanillo-costa-rica-40\/#main","title":{"rendered":"Playa Manzanillo Costa Rica"},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-18433","attachment","type-attachment","status-inherit","hentry","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Playa Manzanillo Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playa Manzanillo Costa Rica - Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-18T15:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?fit=1920%2C1276&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1276\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-manzanillo-costa-rica-40.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-manzanillo-costa-rica-40.jpg\",\"name\":\"Playa Manzanillo Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"datePublished\":\"2019-04-18T15:00:40+00:00\",\"dateModified\":\"2019-04-18T15:00:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-manzanillo-costa-rica-40.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-manzanillo-costa-rica-40.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-manzanillo-costa-rica-40.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Playa Manzanillo en Liberia, Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-manzanillo-en-liberia-costa-rica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Playa Manzanillo Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playa Manzanillo Costa Rica - Costa Rica","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Playa Manzanillo Costa Rica - Costa Rica","og_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg","og_site_name":"Costa Rica","article_modified_time":"2019-04-18T15:00:50+00:00","og_image":[{"width":1920,"height":1276,"url":"https:\/\/i1.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?fit=1920%2C1276&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg","name":"Playa Manzanillo Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"datePublished":"2019-04-18T15:00:40+00:00","dateModified":"2019-04-18T15:00:50+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Playa Manzanillo en Liberia, Costa Rica","item":"https:\/\/costaricainfolink.com\/es\/playa-manzanillo-en-liberia-costa-rica\/"},{"@type":"ListItem","position":3,"name":"Playa Manzanillo Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a5dwqG-4Nj","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?ssl=1\"><img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?fit=768%2C510&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Playa Manzanillo Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?resize=768%2C510&amp;ssl=1 768w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-attachment-id=\"18433\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-manzanillo-en-liberia-costa-rica\/playa-manzanillo-costa-rica-40\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?fit=1920%2C1276&amp;ssl=1\" data-orig-size=\"1920,1276\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Manzanillo Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?fit=1200%2C798&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Playa Manzanillo Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1276,"file":"2012\/05\/playa-manzanillo-costa-rica-40.jpg","sizes":{"medium_large":{"file":"playa-manzanillo-costa-rica-40-768x510.jpg","width":768,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?fit=768%2C510&ssl=1"},"full":{"file":"playa-manzanillo-costa-rica-40.jpg?fit=1920%2C1276&ssl=1","width":1920,"height":1276,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg?fit=1920%2C1276&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":6128,"source_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-manzanillo-costa-rica-40.jpg","filename":"playa-manzanillo-costa-rica-40.jpg","filesize":453136,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media\/18433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=18433"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6128,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/6128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}