{"id":19041,"date":"2021-08-24T18:15:01","date_gmt":"2021-08-24T23:15:01","guid":{"rendered":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg"},"modified":"2021-08-24T18:15:41","modified_gmt":"2021-08-24T23:15:41","slug":"oso-perezoso-costa-rica","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/es\/perezoso-simbolo-nacional-de-costa-rica\/oso-perezoso-costa-rica\/#main","title":{"rendered":"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica"},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-19041","attachment","type-attachment","status-inherit","hentry","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica - Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-24T23:15:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?fit=1920%2C1440&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/oso-perezoso-costa-rica.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/oso-perezoso-costa-rica.jpg\",\"name\":\"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"datePublished\":\"2021-08-24T23:15:01+00:00\",\"dateModified\":\"2021-08-24T23:15:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/oso-perezoso-costa-rica.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/oso-perezoso-costa-rica.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/oso-perezoso-costa-rica.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perezoso, S\u00edmbolo Nacional de Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/perezoso-simbolo-nacional-de-costa-rica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica - Costa Rica","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica - Costa Rica","og_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg","og_site_name":"Costa Rica","article_modified_time":"2021-08-24T23:15:41+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?fit=1920%2C1440&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg","name":"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"datePublished":"2021-08-24T23:15:01+00:00","dateModified":"2021-08-24T23:15:41+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Perezoso, S\u00edmbolo Nacional de Costa Rica","item":"https:\/\/costaricainfolink.com\/es\/perezoso-simbolo-nacional-de-costa-rica\/"},{"@type":"ListItem","position":3,"name":"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a5dwqG-4X7","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?ssl=1\"><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?fit=768%2C576&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?resize=1536%2C1152&amp;ssl=1 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-attachment-id=\"19041\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/perezoso-simbolo-nacional-de-costa-rica\/oso-perezoso-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?fit=1920%2C1440&amp;ssl=1\" data-orig-size=\"1920,1440\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?fit=1200%2C900&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1440,"file":"2021\/08\/oso-perezoso-costa-rica.jpg","sizes":{"medium_large":{"file":"oso-perezoso-costa-rica-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?fit=768%2C576&ssl=1"},"1536x1536":{"file":"oso-perezoso-costa-rica-1536x1152.jpg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?fit=1536%2C1152&ssl=1"},"full":{"file":"oso-perezoso-costa-rica.jpg?fit=1920%2C1440&ssl=1","width":1920,"height":1440,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?fit=1920%2C1440&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":19019,"source_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg","filename":"oso-perezoso-costa-rica.jpg","filesize":229005,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media\/19041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=19041"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":19019,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/19019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}