{"id":19418,"date":"2022-04-09T11:32:59","date_gmt":"2022-04-09T16:32:59","guid":{"rendered":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg"},"modified":"2022-04-09T11:33:48","modified_gmt":"2022-04-09T16:33:48","slug":"refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43\/#main","title":{"rendered":"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica"},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-19418","attachment","type-attachment","status-inherit","hentry","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica - Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-09T16:33:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg\",\"name\":\"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"datePublished\":\"2022-04-09T16:32:59+00:00\",\"dateModified\":\"2022-04-09T16:33:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica - Costa Rica","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica - Costa Rica","og_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg","og_site_name":"Costa Rica","article_modified_time":"2022-04-09T16:33:48+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg","name":"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"datePublished":"2022-04-09T16:32:59+00:00","dateModified":"2022-04-09T16:33:48+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica","item":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica\/"},{"@type":"ListItem","position":3,"name":"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a5dwqG-53c","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?ssl=1\"><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?fit=768%2C576&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?w=2500&amp;ssl=1 2500w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-attachment-id=\"19418\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?fit=1200%2C900&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Refugio de Vida Silvestre Bah\u00eda Junquillal Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2500,"height":1875,"file":"2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg","sizes":{"medium_large":{"file":"refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?fit=768%2C576&ssl=1"},"1536x1536":{"file":"refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43-1536x1152.jpg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?fit=1536%2C1152&ssl=1"},"2048x2048":{"file":"refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43-2048x1536.jpg","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?fit=2048%2C1536&ssl=1"},"full":{"file":"refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?fit=2500%2C1875&ssl=1","width":2500,"height":1875,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg?fit=2500%2C1875&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3017,"source_url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/12\/refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg","filename":"refugio-de-vida-silvestre-bahia-junquillal-costa-rica-43.jpg","filesize":316548,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media\/19418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=19418"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3017,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/3017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}