{"id":1209,"date":"2010-01-03T10:29:00","date_gmt":"2010-01-03T15:29:00","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=1209"},"modified":"2013-09-02T20:46:42","modified_gmt":"2013-09-03T01:46:42","slug":"reserva-biologica-isla-del-cano-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/","title":{"rendered":"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica"},"content":{"rendered":"<h6>Click the following link to read this page in English: <a href=\"https:\/\/www.costaricainfolink.com\/en\/isla-del-cano-biological-reserve-costa-rica\/\">Ca\u00f1o Island Biological Reserve, Costa Rica<\/a><\/h6>\n<p>Situada en el maravilloso y azul Oc\u00e9ano Pac\u00edfico, a unos 20 km de la costa de la Pen\u00ednsula de Osa en Bah\u00eda Drake, Isla del Ca\u00f1o es una incre\u00edble reserva biol\u00f3gica marina en Costa Rica. Parte de la provincia de Puntarenas y al noreste del Parque Nacional Corcovado, Isla del Ca\u00f1o es una isla de importancia geogr\u00e1fica y arqueol\u00f3gica, ya que anteriormente era un cementerio o necr\u00f3polis que data de la \u00e9poca precolombina. Isla del Ca\u00f1o fue nombrada as\u00ed en 1519 por Juan de Casta\u00f1eda. En 1976, la isla fue anexada a ser parte del Parque Nacional Corcovado<img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"6774\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/isla-del-cano-parque-nacional-costa-rica-entrada1\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg?fit=500%2C375&amp;ssl=1\" data-orig-size=\"500,375\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Entrada a la Reserva Biol\u00f3gica Isla del Ca\u00f1o en Puntarenas, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg?fit=500%2C375&amp;ssl=1\" class=\"alignright wp-image-6774\" title=\"Entrada a la Reserva Biol\u00f3gica Isla del Ca\u00f1o en Puntarenas, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg?resize=350%2C263&#038;ssl=1\" alt=\"\" width=\"350\" height=\"263\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/> y fue declarada reserva biol\u00f3gica en 1978.<\/p>\n<p>Isla del Ca\u00f1o es conocida principalmente por sus arrecifes de coral, ya que su verdadera belleza no se encuentra en su tierra, sino bajo el agua. Sus aguas v\u00edrgenes son de las m\u00e1s azules del pa\u00eds, y son adem\u00e1s el hogar de una gran variedad de la espectacular flora y fauna marinas, as\u00ed como algunos magn\u00edficos arrecifes de coral. Calificada como uno de los mejores puntos de aventura de buceo en el mundo, la Reserva Biol\u00f3gica Isla del Ca\u00f1o es tambi\u00e9n el hogar de una gran variedad de peces, ballenas y tiburones. Hasta el momento, los cient\u00edficos han podido identificar 19 especies diferentes de corales y 60 especies de moluscos. La especie dominante es la del coral Porites lobata, que es altamente resistente a las fluctuaciones del medio ambiente. Debido a esto y combinado con el hecho de que se recupera r\u00e1pidamente y tiene muy pocos animales que se alimentan de \u00e9l, el ecosistema de las aguas que rodean la Isla del Ca\u00f1o es uno de los m\u00e1s sanos y mejor conservados en el Pac\u00edfico de Costa Rica.<\/p>\n<p>Con una visibilidad bajo el agua fant\u00e1stica, las personas que realizan snorkeling y los buzos pueden ver en un d\u00eda cualquiera una abundante vida marina incluyendo langostas espinosas, erizos de mar, cohombros de mar, manta rayas, abanicos de mar, morenas, serpientes de mar, barracudas, muchos tiburones, en especial el tibur\u00f3n de puntas blancas (Triaenodon obesus), que var\u00edan en tama\u00f1o desde las 6\u2019 a las 10\u2019, tortugas marinas, atunes, agujones o bel\u00f3nidos (Belonidae), delfines, pargos, meros o chernas, as\u00ed como tambi\u00e9n toda una gama de coloridos peces tropicales. Debajo de los acantilados, las playas de arena blanca son atractivas para las tortugas golfinas o del golfo (Lepidochelys olivacea), mientras que las aguas costeras cuentan con la migraci\u00f3n de orcas, falsas orcas, la rorcual o ballena de Bryde (Balaenoptera brydei), calderones o ballenas piloto, cachalotes, ballenas jorobadas, cachalotes pigmeos, as\u00ed como un gran n\u00famero de delfines mular o nariz de botella (Tursiops truncatus).<\/p>\n<p>Otro aspecto importante de la Reserva Biol\u00f3gica Isla del Ca\u00f1o es su car\u00e1cter arqueol\u00f3gico, ya que la isla fue una vez usada como cementerio por las culturas precolombinas de las comunidades de Chiriqu\u00ed desde 1500 a 700 A.C., con una clara influencia de Am\u00e9rica del Sur. Las esferas l\u00edticas famosas de la tribu Diquis de piedra perfectamente redondas realizadas por los ind\u00edgenas antiguos de esta tierra se encuentran aqu\u00ed en abundancia, junto con otros artefactos. En el <img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"1212\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/isla-del-cano-parque-nacional-costa-rica3\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica3.jpg?fit=459%2C309&amp;ssl=1\" data-orig-size=\"459,309\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D300&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1236692652&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.00025&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica3.jpg?fit=459%2C309&amp;ssl=1\" class=\"alignleft wp-image-1212\" title=\"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica3.jpg?resize=367%2C247&#038;ssl=1\" alt=\"\" width=\"367\" height=\"247\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica3.jpg?w=459&amp;ssl=1 459w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica3.jpg?resize=300%2C201&amp;ssl=1 300w\" sizes=\"(max-width: 367px) 100vw, 367px\" \/>centro de la isla se encuentra un vaco (Brosimun utile) de las plantaciones, que se cree que han sido utilizados para fines religiosos por los Quepos y Cotos.<\/p>\n<p>La fauna es escasa, compuesta principalmente de insectos como abejas, mariposas, escarabajos y mosquitos, as\u00ed como algunas ranas y lagartijas. La reserva tambi\u00e9n cuenta con pacas, zarig\u00fceyas, cerdos, boas, murci\u00e9lagos.\u00a0 A pesar de que solo posee unas 13 especies de aves terrestres, si cuenta con un gran n\u00famero de aves marinas, como el \u00e1guila pescadora, el halc\u00f3n negro,\u00a0 los falaropos (Phalaropus), el Alcatraz Pardo (Sula leucogaster) y la garcilla bueyera (garcita del ganado, garza boyera o Bubulcus ibis). Aparte de los bosques siempre verdes que se encuentran en la isla, los \u00fanicos \u00e1rboles que crecen aqu\u00ed incluyen el \u00e1rbol de caucho, el cacao silvestre, algunos arbustos y matorrales.<\/p>\n<p>Los mayores atractivos de la Isla del Ca\u00f1o se encuentran bajo las aguas que rodean la isla, ya que la isla est\u00e1 rodeada por cinco plataformas de arrecifes de coral bajos, por lo que puede ser el mejor lugar para bucear en Costa Rica. La revista Skin Diver ha calificado el lugar como uno de los mejores del mundo y uno de los puntos recientes de moda para el buceo de aventura. Esta \u00e1rea virgen ofrece una gran variedad de atracciones de buceo, con \u201cparedes\u201d de arrecifes que van desde las 15\u2019-16&#8242; hasta las 80\u2019. Sin embargo, debido a que es una reserva biol\u00f3gica, los n\u00fameros de buceo est\u00e1n estrictamente regulados. Existen \u00fanicamente 5 sitios de buceo, y s\u00f3lo a 10 buceadores se les permite estar en el agua a la vez. Adem\u00e1s, por ley, est\u00e1 totalmente prohibido llevarse cualquier objeto marino vivo o muerto, ya sean conchas, corales, etc.<\/p>\n<p>Existe un solo sendero que recorre por el interior de la estaci\u00f3n de guardabosques a trav\u00e9s del bosque. Se permite acampar en la playa, cerca de la estaci\u00f3n de guardaparques, la cual disfruta de agua potable, pero no cuenta con instalaciones. Por otra parte, muchas de las excursiones para ver delfines y ballenas se ofrecen <img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"1213\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/isla-del-cano-parque-nacional-costa-rica4\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica4.JPG?fit=450%2C338&amp;ssl=1\" data-orig-size=\"450,338\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot S1 IS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1170348838&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.8&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Esferas de Piedra en la Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica4.JPG?fit=450%2C338&amp;ssl=1\" class=\"alignright wp-image-1213\" title=\"Esferas de Piedra en la Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica4.JPG?resize=315%2C237&#038;ssl=1\" alt=\"\" width=\"315\" height=\"237\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica4.JPG?w=450&amp;ssl=1 450w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica4.JPG?resize=300%2C225&amp;ssl=1 300w\" sizes=\"(max-width: 315px) 100vw, 315px\" \/>desde la Pen\u00ednsula de Osa. Si bien la experiencia es maravillosa, es recomendable que observen los reglamentos para estas actividades, a fin de asegurarse de que no afecten negativamente el comportamiento de estos visitantes maravillosos.<\/p>\n<p>Teniendo en cuenta todo esto, no es sorprendente que muchas personas consideran la Isla del Ca\u00f1o como el mejor punto de buceo en todo el pa\u00eds. As\u00ed que si usted planea visitar aqu\u00ed, no se olvide de traer su equipo de buceo o snorkel, y estar preparado para una aventura bajo el agua.<\/p>\n<p><strong>Como llegar a la Reserva Biol\u00f3gica Isla del Ca\u00f1o?<\/strong><\/p>\n<p>Tome la carretera Interamericana desde San Jos\u00e9 hacia Piedras Blancas, hasta la estaci\u00f3n de gasolina La Chacarita y luego se gira hacia la derecha (carretera de lastre) hasta Puerto Jim\u00e9nez o tambi\u00e9n puede tomar la salida a Sierpe y de ah\u00ed tomar un bote a Bah\u00eda Drake. Son unos 395 kil\u00f3metros (240 millas) por carretera. El recorrido total desde San Jos\u00e9 tarda unas 7 horas.<\/p>\n<p><strong>En autob\u00fas:<\/strong><\/p>\n<p>Usted puede tomar un autob\u00fas de la ruta San Jos\u00e9 \u2013 Puerto Jim\u00e9nez, el cual tarda unas 8 horas (Transportes Blanco, 2771-4744). Desde ah\u00ed puede tomar un bote hasta la Reserva Biol\u00f3gica Isla del Ca\u00f1o, lo cual puede tardar aproximadamente 50 minutos. Otra ruta ser\u00eda tomar un autob\u00fas de la ruta San Jos\u00e9 \u2013 Puerto Jim\u00e9nez, el cual tarda unas 8 horas, y bajarse en Palmar Norte (Transportes Blanco, 2771-4744). Desde ah\u00ed dirigirse hasta Sierpe, y ah\u00ed tomar un bote hacia la Reserva Biol\u00f3gica Isla del Ca\u00f1o.<\/p>\n<p><strong>En avi\u00f3n:<\/strong><\/p>\n<p>Tambi\u00e9n se puede tomar un vuelo entre el aeropuerto Juan Santamar\u00eda hacia Golfito, Puerto Jim\u00e9nez o Bah\u00eda Drake ya sea con Sansa o <a href=\"https:\/\/www.costaricainfolink.com\/aerobell.html\" target=\"_blank\">Aerobell Airlines<\/a> todos los d\u00edas. Desde ah\u00ed puede tomar un bote hasta Reserva Biol\u00f3gica Isla del Ca\u00f1o, lo cual puede tardar aproximadamente 50 minutos.<\/p>\n<p><strong>Ubicaci\u00f3n:<\/strong> en la Pen\u00ednsula de Osa, distrito:<\/strong> Sierpe, <strong>cant\u00f3n:<\/strong> Osa, <strong>provincia:<\/strong> Puntarenas, Costa Rica. <strong>C\u00f3digo postal de la zona:<\/strong> 60503.<br \/>\n<strong>Coordenadas GPS para Isla del Ca\u00f1o:<\/strong> 8.705333,-83.878367 (8\u00b042&#8217;19.20&#8243;N, 83\u00b052&#8217;42.12&#8243;W)<br \/>\n<strong>Coordenadas GPS para Bah\u00eda Drake:<\/strong> 8.690428,-83.664175 (8\u00b041&#8217;25.54&#8243;N, 83\u00b039&#8217;51.03&#8243;W)<br \/>\n<strong>Tama\u00f1o: <\/strong>300 hect\u00e1reas (741 acres)<br \/>\n<strong>Altitud:<\/strong> nivel del mar hasta 110m (361 pies)<br \/>\n<strong>Tel\u00e9fono del \u00c1rea de Conservaci\u00f3n Osa (ACOSA):<\/strong> +(506) 2735-5580 \/ 2735-5276<br \/>\n<strong>Informaci\u00f3n Tur\u00edstica INFOTUR:<\/strong> 1192<\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-de-la-reserva-biologica-isla-del-cano\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica a la Reserva Biol\u00f3gica Isla del Ca\u00f1o en Puntarenas, Costa Rica.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click the following link to read this page in English: Ca\u00f1o Island Biological Reserve, Costa Rica Situada en el maravilloso y azul Oc\u00e9ano Pac\u00edfico, a unos 20 km de la costa de la Pen\u00ednsula de Osa en Bah\u00eda Drake, Isla del Ca\u00f1o es una incre\u00edble reserva biol\u00f3gica marina en Costa Rica. Parte de la provincia &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/#more-1209\" aria-label=\"Leer m\u00e1s sobre Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[123,32,23],"tags":[],"class_list":["post-1209","post","type-post","status-publish","format-standard","hentry","category-123","category-parques-nacionales","category-puntarenas","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica - Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Click the following link to read this page in English: Ca\u00f1o Island Biological Reserve, Costa Rica Situada en el maravilloso y azul Oc\u00e9ano Pac\u00edfico, a unos 20 km de la costa de la Pen\u00ednsula de Osa en Bah\u00eda Drake, Isla del Ca\u00f1o es una incre\u00edble reserva biol\u00f3gica marina en Costa Rica. Parte de la provincia ... Leer M\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-03T15:29:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-09-03T01:46:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica\",\"datePublished\":\"2010-01-03T15:29:00+00:00\",\"dateModified\":\"2013-09-03T01:46:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/\"},\"wordCount\":1347,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg\",\"articleSection\":[\"60503\",\"Parques Nacionales\",\"Puntarenas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/\",\"name\":\"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg\",\"datePublished\":\"2010-01-03T15:29:00+00:00\",\"dateModified\":\"2013-09-03T01:46:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-del-cano-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica - Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica - Costa Rica","og_description":"Click the following link to read this page in English: Ca\u00f1o Island Biological Reserve, Costa Rica Situada en el maravilloso y azul Oc\u00e9ano Pac\u00edfico, a unos 20 km de la costa de la Pen\u00ednsula de Osa en Bah\u00eda Drake, Isla del Ca\u00f1o es una incre\u00edble reserva biol\u00f3gica marina en Costa Rica. Parte de la provincia ... Leer M\u00e1s","og_url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2010-01-03T15:29:00+00:00","article_modified_time":"2013-09-03T01:46:42+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica","datePublished":"2010-01-03T15:29:00+00:00","dateModified":"2013-09-03T01:46:42+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/"},"wordCount":1347,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg","articleSection":["60503","Parques Nacionales","Puntarenas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/","name":"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg","datePublished":"2010-01-03T15:29:00+00:00","dateModified":"2013-09-03T01:46:42+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-jv","jetpack-related-posts":[{"id":1770,"url":"https:\/\/costaricainfolink.com\/es\/parques-nacionales-de-costa-rica\/","url_meta":{"origin":1209,"position":0},"title":"Parques Nacionales de Costa Rica","author":"Costa Rica Info Link","date":"11 agosto 2011","format":false,"excerpt":"Debajo del siguiente texto usted encontrar\u00e1 una lista de los parques nacionales ordenada por provincia, si hace click sobre el nombre de cada parque, el enlace lo llevar\u00e1 a la p\u00e1gina exclusiva de su selecci\u00f3n, con informaci\u00f3n detallada, coordenadas para GPS, instrucciones de c\u00f3mo llegar, mapa con direcci\u00f3n, tel\u00e9fonos, horarios\u2026","rel":"","context":"En \u00abParques Nacionales\u00bb","block_context":{"text":"Parques Nacionales","link":"https:\/\/costaricainfolink.com\/es\/category\/parques-nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/hacienda-finca-la-avellana-parque-nacional-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1414,"url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-pajaros-costa-rica\/","url_meta":{"origin":1209,"position":1},"title":"Reserva Biol\u00f3gica Isla Los P\u00e1jaros, Costa Rica","author":"Costa Rica Info Link","date":"24 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: Pajaros Island Biological Reserve Costa Rica La Reserva Biol\u00f3gica Isla Los P\u00e1jaros, ubicada en el Golfo de Nicoya, fue incluida en el sistema de parques nacionales el 27 de diciembre de 1982, con el fin de preservar las abundantes poblaciones\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-pajaros-parque-nacional3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1425,"url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/","url_meta":{"origin":1209,"position":2},"title":"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica","author":"Costa Rica Info Link","date":"24 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: Los Negritos Island Biological Reserve Costa Rica La Reserva Biol\u00f3gica Isla Los Negritos, ubicada en el Golfo de Nicoya fue incluida en el sistema de parques nacionales\u00a0el 27 de Diciembre de 1982, con el fin de\u00a0 preservar las abundantes poblaciones\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1429,"url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-guayabo-costa-rica\/","url_meta":{"origin":1209,"position":3},"title":"Reserva Biol\u00f3gica Isla Guayabo, Costa Rica","author":"Costa Rica Info Link","date":"24 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: Guayabo Island Biological Reserve Costa Rica La Reserva Biol\u00f3gica Isla Guayabo, ubicada en el Golfo de Nicoya fue incluida en el sistema de parques nacionales\u00a0el 27 de diciembre de 1982, con el fin de\u00a0 preservar las abundantes poblaciones de aves\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"Aves en la Reserva Biol\u00f3gica Isla Guayabo, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-pajaros-parque-nacional-aves22.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1404,"url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-guayabo-negritos-y-pajaros-costa-rica\/","url_meta":{"origin":1209,"position":4},"title":"Reserva Biol\u00f3gica Isla Guayabo, Negritos y P\u00e1jaros, Costa Rica","author":"Costa Rica Info Link","date":"25 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: Guayabo, Negritos and Pajaros Island Biological Reserves Costa Rica Estas cuatro islas deshabitadas (ya que Negritos consiste en dos islas) fueron incluidas en el sistema de parques nacionales, como Reservas Biol\u00f3gicas el 27 de diciembre de 1982, con el fin\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"Isla Guayabo, parte de la Reserva Biol\u00f3gica Isla Guayabo, Negritos y P\u00e1jaros, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-guayabo-parque-nacional3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1452,"url":"https:\/\/costaricainfolink.com\/es\/refugio-nacional-de-vida-silvestre-isla-san-lucas-costa-rica\/","url_meta":{"origin":1209,"position":5},"title":"Refugio Nacional de Vida Silvestre Isla San Lucas Costa Rica","author":"Costa Rica Info Link","date":"26 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: San Lucas Island National Wildlife Refuge Costa Rica El Refugio Nacional de Vida Silvestre Isla San Lucas fue establecido el 12 de febrero del 2001, con el fin de proteger una isla en el Golfo de Nicoya, cerca de la\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-san-lucas-parque-nacional-costa-rica-entrada.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/1209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=1209"}],"version-history":[{"count":21,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/1209\/revisions"}],"predecessor-version":[{"id":9193,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/1209\/revisions\/9193"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=1209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=1209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=1209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}