{"id":139,"date":"2009-06-06T17:12:24","date_gmt":"2009-06-06T22:12:24","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=139"},"modified":"2023-09-11T07:52:50","modified_gmt":"2023-09-11T12:52:50","slug":"arbol-de-guanacaste-simbolo-nacional-de-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/","title":{"rendered":"\u00c1rbol de Guanacaste, S\u00edmbolo Nacional de Costa Rica"},"content":{"rendered":"<p>Fue declarado como el \u00e1rbol nacional de Costa Rica el 31 de agosto de 1959, bajo el gobierno de don Mario Echandi Jim\u00e9nez, por decreto No. 7.<\/p>\n<p>El \u00e1rbol de Guanacaste fue escogido como homenaje a los guanacastecos por su anexi\u00f3n a nuestro pa\u00eds en 1824. Al mismo tiempo, tambi\u00e9n se debi\u00f3 a su hermosura y verdor cuya inmensa sombra se asemeja a la protecci\u00f3n que el Estado brinda a todos los costarricenses.<\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/arbol-de-guanacaste-simbolo-nacional-costa-rica\/#main\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"17352\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/arbol-de-guanacaste-simbolo-nacional-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&amp;ssl=1\" data-orig-size=\"2048,1546\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=1024%2C773&amp;ssl=1\" class=\"aligncenter wp-image-17352 size-large\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=1024%2C773&#038;ssl=1\" alt=\"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica\" width=\"1024\" height=\"773\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=1024%2C773&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=300%2C226&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=768%2C580&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=560%2C423&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=260%2C196&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?resize=160%2C121&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?w=2048&amp;ssl=1 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Guanacaste viene de una lengua azteca, el n\u00e1huatl, en la que Guautil es \u00e1rbol y Nacaztli quiere decir oreja, por lo que nuestros abor\u00edgenes lo llamaban \u00abarbol de oreja\u00bb, ya que los frutos del mismo se parecen a las orejas de las personas, unas vainas duras de brillante color caf\u00e9 con forma de oreja.<\/p>\n<p>Su nombre cient\u00edfico es Enterolobium Cyclocarpum, perteneciente a la familia Fabaceae Mimosoideae. Es un \u00e1rbol de tipo caducifolio y es considerado un \u00e1rbol vivaz, por su potencia y larga vida, que va de los 60 a 70 a\u00f1os. En estado natural, se distribuye en ambos litorales, tanto el Pac\u00edfico como el Atl\u00e1ntico, pero es m\u00e1s com\u00fan en el Pac\u00edfico Norte, motivo por el cual se le asign\u00f3 a la provincia de Guanacaste con su nombre.<\/p>\n<p>Este \u00e1rbol tiene su copa muy ancha, con una extensa frondosidad de sus ramas, y un permanente verdor. Puede alcanzar hasta 15 metros de alto y 4 metros de di\u00e1metro; su tronco es grueso, de un color gris claro con matices. Su flor es blanca y con estambres largos; su fruto es una legumbre que sirve de alimento a la fauna silvestre y al\u00a0 ganado. Las semillas se usan para elaborar artesan\u00edas, al igual que los frutos. Adem\u00e1s, se les usa como materia prima para la elaboraci\u00f3n de jab\u00f3n por su alto contenido de saponinas. En Costa Rica generalmente florece entre noviembre y marzo y produce frutos entre enero y mayo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue declarado como el \u00e1rbol nacional de Costa Rica el 31 de agosto de 1959, bajo el gobierno de don Mario Echandi Jim\u00e9nez, por decreto No. 7. El \u00e1rbol de Guanacaste fue escogido como homenaje a los guanacastecos por su anexi\u00f3n a nuestro pa\u00eds en 1824. Al mismo tiempo, tambi\u00e9n se debi\u00f3 a su hermosura &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"\u00c1rbol de Guanacaste, S\u00edmbolo Nacional de Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/#more-139\" aria-label=\"Leer m\u00e1s sobre \u00c1rbol de Guanacaste, S\u00edmbolo Nacional de Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12],"tags":[],"class_list":["post-139","post","type-post","status-publish","format-standard","hentry","category-simbolos-nacionales","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional<\/title>\n<meta name=\"description\" content=\"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional. Fue declarado el 31 de agosto de 1959, bajo el gobierno de don Mario Echandi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional\" \/>\n<meta property=\"og:description\" content=\"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional. Fue declarado el 31 de agosto de 1959, bajo el gobierno de don Mario Echandi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-06T22:12:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-11T12:52:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica-1024x773.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"\u00c1rbol de Guanacaste, S\u00edmbolo Nacional de Costa Rica\",\"datePublished\":\"2009-06-06T22:12:24+00:00\",\"dateModified\":\"2023-09-11T12:52:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/\"},\"wordCount\":333,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/arbol-de-guanacaste-simbolo-nacional-costa-rica-1024x773.jpg\",\"articleSection\":[\"S\u00edmbolos Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/\",\"name\":\"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/arbol-de-guanacaste-simbolo-nacional-costa-rica-1024x773.jpg\",\"datePublished\":\"2009-06-06T22:12:24+00:00\",\"dateModified\":\"2023-09-11T12:52:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"description\":\"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional. Fue declarado el 31 de agosto de 1959, bajo el gobierno de don Mario Echandi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&ssl=1\",\"width\":2048,\"height\":1546,\"caption\":\"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c1rbol de Guanacaste, S\u00edmbolo Nacional de Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional","description":"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional. Fue declarado el 31 de agosto de 1959, bajo el gobierno de don Mario Echandi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional","og_description":"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional. Fue declarado el 31 de agosto de 1959, bajo el gobierno de don Mario Echandi.","og_url":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2009-06-06T22:12:24+00:00","article_modified_time":"2023-09-11T12:52:50+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica-1024x773.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"\u00c1rbol de Guanacaste, S\u00edmbolo Nacional de Costa Rica","datePublished":"2009-06-06T22:12:24+00:00","dateModified":"2023-09-11T12:52:50+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/"},"wordCount":333,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica-1024x773.jpg","articleSection":["S\u00edmbolos Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/","name":"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica-1024x773.jpg","datePublished":"2009-06-06T22:12:24+00:00","dateModified":"2023-09-11T12:52:50+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"description":"\u00c1rbol Nacional de Costa Rica: Guanacaste, S\u00edmbolo Nacional. Fue declarado el 31 de agosto de 1959, bajo el gobierno de don Mario Echandi.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/arbol-de-guanacaste-simbolo-nacional-costa-rica.jpg?fit=2048%2C1546&ssl=1","width":2048,"height":1546,"caption":"\u00c1rbol de Guanacaste (Enterolobium Cyclocarpum), S\u00edmbolo Nacional de Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/arbol-de-guanacaste-simbolo-nacional-de-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00c1rbol de Guanacaste, S\u00edmbolo Nacional de Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-2f","jetpack-related-posts":[{"id":7004,"url":"https:\/\/costaricainfolink.com\/es\/simbolos-nacionales-de-costa-rica\/","url_meta":{"origin":139,"position":0},"title":"S\u00edmbolos Nacionales de Costa Rica","author":"Costa Rica Info Link","date":"7 junio 2009","format":false,"excerpt":"S\u00edmbolos Nacionales de Costa Rica o s\u00edmbolos patrios, son aquellos que representan el esp\u00edritu esforzado del pueblo costarricense, para poder ser reconocidos no s\u00f3lo en Costa Rica, sino por otros pa\u00edses. Generalmente estos s\u00edmbolos se formulan a partir de representaciones visuales o verbales que pretenden difundir los valores de la\u2026","rel":"","context":"En \u00abCultura Costarricense\u00bb","block_context":{"text":"Cultura Costarricense","link":"https:\/\/costaricainfolink.com\/es\/category\/cultura-costarricense\/"},"img":{"alt_text":"Mariposa Morpho, S\u00edmbolo Nacional de Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":20147,"url":"https:\/\/costaricainfolink.com\/es\/imagenes-de-simbolos-nacionales-de-costa-rica\/","url_meta":{"origin":139,"position":1},"title":"Im\u00e1genes de S\u00edmbolos Nacionales de Costa Rica","author":"Costa Rica Info Link","date":"25 septiembre 2023","format":false,"excerpt":"Click en las im\u00e1genes para verlas m\u00e1s grandes.","rel":"","context":"En \u00abS\u00edmbolos Nacionales\u00bb","block_context":{"text":"S\u00edmbolos Nacionales","link":"https:\/\/costaricainfolink.com\/es\/category\/simbolos-nacionales\/"},"img":{"alt_text":"Antorcha de la Independencia S\u00edmbolo Nacional de la Libertad","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2023\/09\/Antorcha-de-la-Independencia-Simbolo-Nacional-de-la-Libertad.webp?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2023\/09\/Antorcha-de-la-Independencia-Simbolo-Nacional-de-la-Libertad.webp?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2023\/09\/Antorcha-de-la-Independencia-Simbolo-Nacional-de-la-Libertad.webp?resize=525%2C300 1.5x"},"classes":[]},{"id":7011,"url":"https:\/\/costaricainfolink.com\/es\/marimba-simbolo-nacional-de-la-cultura-y-tradicion\/","url_meta":{"origin":139,"position":2},"title":"Marimba, S\u00edmbolo Nacional de la Cultura y Tradici\u00f3n","author":"Costa Rica Info Link","date":"5 junio 2009","format":false,"excerpt":"Este hist\u00f3rico y popular instrumento musical es un emblema que representa y dignifica el arte y la cultura del pueblo costarricense, un pueblo pac\u00edfico, amante de la paz y la democracia, la cual prevalece desde la Anexi\u00f3n de Guanacaste a Costa Rica. Seg\u00fan cuenta la historia, la Marimba, que ha\u2026","rel":"","context":"En \u00abCultura de Costa Rica\u00bb","block_context":{"text":"Cultura de Costa Rica","link":"https:\/\/costaricainfolink.com\/es\/category\/cultura-de-costa-rica\/"},"img":{"alt_text":"Marimba, S\u00edmbolo Nacional de la Cultura y Tradici\u00f3n","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/07\/marimba-simbolo-nacional-costa-rica005.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6067,"url":"https:\/\/costaricainfolink.com\/es\/playa-panama-costa-rica\/","url_meta":{"origin":139,"position":3},"title":"Playa Panam\u00e1 Costa Rica","author":"Costa Rica Info Link","date":"14 mayo 2012","format":false,"excerpt":"Playa Panama donde queda? Ubicaci\u00f3n: entre Playa Buena y Playa Arenilla en Guanacaste, Costa Rica. Coordenadas para GPS: 10.590210,-85.650358 (10\u00b035'24.76\"N, 85\u00b039'01.29\"W) Distrito: Sardinal, cant\u00f3n: Carrillo, provincia: Guanacaste C\u00f3digo postal de la zona: 50503. \u00a0\u00a0 C\u00f3mo llegar a Playa Panam\u00e1 en Guanacaste? Desde San Jos\u00e9 Conduzca al norte hacia Puntarenas y\u2026","rel":"","context":"En \u00ab50503\u00bb","block_context":{"text":"50503","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/50503\/"},"img":{"alt_text":"Playa Panama Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-panama-costa-rica-32-2-min-scaled.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-panama-costa-rica-32-2-min-scaled.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-panama-costa-rica-32-2-min-scaled.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-panama-costa-rica-32-2-min-scaled.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-panama-costa-rica-32-2-min-scaled.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-panama-costa-rica-32-2-min-scaled.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":3152,"url":"https:\/\/costaricainfolink.com\/es\/reserva-forestal-taboga-costa-rica\/","url_meta":{"origin":139,"position":4},"title":"Reserva Forestal Taboga Costa Rica","author":"Costa Rica Info Link","date":"13 abril 2011","format":false,"excerpt":"Reserva Forestal Taboga Costa Rica ubicaci\u00f3n: 5 km al sur de Ca\u00f1as, distrito: San Miguel, cant\u00f3n: Ca\u00f1as, provincia: Guanacaste, Costa Rica. C\u00f3digo postal de la zona: 50603.Coordenadas para GPS: 10.344769,-85.147759 (10\u00b020'41.17\"N, 85\u00b008'51.93\"W)Coordenadas para GPS de Ca\u00f1as: 10.427281,-85.094589 (10\u00b025'38.21\"N, 85\u00b005'40.52\"W)Tama\u00f1o: 297 ha (748 acres)Tel\u00e9fonos del \u00c1rea de Conservaci\u00f3n Arenal-Tempisque: +506 26955908,\u2026","rel":"","context":"En \u00ab50603\u00bb","block_context":{"text":"50603","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/50603\/"},"img":{"alt_text":"Reserva Forestal Taboga Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/04\/Reserva-Forestal-Taboga-Costa-Rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/04\/Reserva-Forestal-Taboga-Costa-Rica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/04\/Reserva-Forestal-Taboga-Costa-Rica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/04\/Reserva-Forestal-Taboga-Costa-Rica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/04\/Reserva-Forestal-Taboga-Costa-Rica.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/04\/Reserva-Forestal-Taboga-Costa-Rica.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":2129,"url":"https:\/\/costaricainfolink.com\/es\/parque-nacional-palo-verde-costa-rica\/","url_meta":{"origin":139,"position":5},"title":"Parque Nacional Palo Verde Costa Rica","author":"Costa Rica Info Link","date":"17 septiembre 2010","format":false,"excerpt":"Ubicaci\u00f3n: 19 km (12 millas) al sur de Bagaces, distrito: Bagaces, cant\u00f3n: Bagaces, provincia: Guanacaste, Costa Rica. C\u00f3digo postal de la zona: 50401. Coordenadas GPS para Bagaces: 10.520894,-85.254769 (10\u00b031'15.22\"N, 85\u00b015'17.17\"W) Tama\u00f1o: 18,418 hect\u00e1reas (45,492 acres) Altitud: desde el nivel del mar hasta los 200m (656 pi\u00e9s) Horario: de 8 a.m.\u2026","rel":"","context":"En \u00ab50401\u00bb","block_context":{"text":"50401","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/50401\/"},"img":{"alt_text":"Ubicaci\u00f3n WAZE de Parque Nacional Palo Verde Guanacaste, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=139"}],"version-history":[{"count":13,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/139\/revisions"}],"predecessor-version":[{"id":18987,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/139\/revisions\/18987"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}