{"id":1425,"date":"2010-01-24T18:10:34","date_gmt":"2010-01-24T23:10:34","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=1425"},"modified":"2016-01-19T11:08:50","modified_gmt":"2016-01-19T16:08:50","slug":"reserva-biologica-isla-los-negritos-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/","title":{"rendered":"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica"},"content":{"rendered":"<h5>Click the following link to read this page in English: <a href=\"https:\/\/www.costaricainfolink.com\/en\/los-negritos-island-biological-reserve-costa-rica\/\">Los Negritos Island Biological Reserve Costa Rica<\/a><\/h5>\n<p>La Reserva Biol\u00f3gica Isla Los Negritos, ubicada en el Golfo de Nicoya fue incluida en el sistema de parques nacionales\u00a0el 27 de Diciembre de 1982, con el fin de\u00a0 preservar las abundantes poblaciones de aves marinas, su flora y fauna, <img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"1426\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/isla-los-negritos-parque-nacional\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg?fit=350%2C229&amp;ssl=1\" data-orig-size=\"350,229\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg?fit=350%2C229&amp;ssl=1\" class=\"alignleft wp-image-1426\" title=\"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg?resize=350%2C229&#038;ssl=1\" alt=\"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica\" width=\"350\" height=\"229\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg?w=350&amp;ssl=1 350w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg?resize=300%2C196&amp;ssl=1 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>proteger las colonias de anidaci\u00f3n de aves marinas y para salvarlos del desarrollo de otros. Forma parte de la Reserva Biol\u00f3gica Isla Guayabo, Negritos y P\u00e1jaros. El clima es c\u00e1lido y soleado la mayor\u00eda de los d\u00edas del a\u00f1o. La peque\u00f1a cantidad de lluvia se da entre los meses de mayo y noviembre.<\/p>\n<p>Las Islas Negritos son vecinas de la Isla Tortuga en el Golfo de Nicoya; constan de dos islas separadas por un estrecho canal. Consisten en basaltos de Nicoya, y est\u00e1n cubiertas de bosque semideciduo. Los \u00e1rboles predominantes son Frangipani o cacalos\u00fachil (Plumeria rubra), Pochote (Bombacopsis quintanum), Madro\u00f1o (Calycophyllum candidissimum) y el Indio Desnudo o Palo Mulato (Bursera simaruba). En algunas partes, cerca de las rocas, hay parches homog\u00e9neos de Pi\u00f1uelas (Bromelia pinguin) y de Coyol o Uvita (Bactris guineensis).<\/p>\n<p>Las aguas que rodean estas islas son muy ricas en fauna marina; algunos de los peces m\u00e1s comunes son el Pargo Rojo del Pac\u00edfico o Huachinango (Lutjanus), el pargo rosa manchado (Lutjanus guttatus) y el Pargo Amarillo (Lutjanus argentiventris). Algunos de los animales que viven en esta isla son los mapaches, loros, palomas, cangrejos ermita\u00f1os (que son numerosos), pel\u00edcanos pardos y las ostras, adem\u00e1s, de pelicanos pardos o caf\u00e9 y el loro de nuca amarilla o amazona de nuca amarilla (Amazona auropalliata) que anidan aqu\u00ed. Tambi\u00e9n existen algunas poblaciones de delfines, at\u00fan y verdeles\u00a0alrededor de la isla.<\/p>\n<p>Las Isla Los Negritos no cuenta con instalaciones ni senderos para los visitantes. Sin embargo, en Puntarenas hay hoteles, restaurantes, mercados, y es posible alquilar botes, ya que todas las islas son accesibles por bote desde Puntarenas, y as\u00ed tener una observaci\u00f3n m\u00e1s detallada de la isla. Adem\u00e1s, para visitarla, se precisa de un permiso por parte del \u00c1rea de Conservaci\u00f3n Tempisque.<\/p>\n<p><strong>C\u00f3mo llegar a la Reserva Biol\u00f3gica Isla Los Negritos?<\/strong><\/p>\n<p>Conduzca al norte en direcci\u00f3n a Guanacaste por la carretera #27. Cuando vea la desviaci\u00f3n de Puntarenas, tomela, contin\u00fae por esta carretera unos 12 km (7 millas) hasta llegar a Puntarenas. Probablemente la forma m\u00e1s sencilla de ver la Reserva Biol\u00f3gica Isla Los Negritos es tomar uno de los barcos diarios de Puntarenas a la Isla Tortuga, ya que la ruta en estas excursiones pasa por las islas. Esta ruta requiere un total de 1 hora desde San Jos\u00e9. <\/p>\n<p>Conduzca hacia el Noreste en direcci\u00f3n a Liberia. Una vez en Liberia, debe continuar por la misma autopista en direcci\u00f3n hacia Puntarenas por unos 120 km (75 millas). Una vez en la entrada hacia Puntarenas, gire a la derecha, contin\u00fae por unos 12 km (7 millas), hasta llegar a Puntarenas. Probablemente la forma m\u00e1s sencilla de ver la Reserva Biol\u00f3gica Isla Los Negritos es tomar uno de los barcos diarios de Puntarenas a la Isla Tortuga, ya que la ruta en estas excursiones pasa por las islas. Esta ruta requiere un total de 2.5 horas. <\/p>\n<p><strong>En autob\u00fas:<\/strong><\/p>\n<p>Usted puede tomar un autob\u00fas con la ruta San Jos\u00e9 \u2013 Puntarenas, el cual tarda unas 2 horas y luego tomar un bote, preferiblemente a Isla Tortuga, para poder observar la Reserva Biol\u00f3gica Isla Los Negritos. (Empresarios Unidos, <a href=\"callto:+5062222-0064\">+506 2222-0064<\/a>).<\/p>\n<p><strong>Ubicaci\u00f3n:<\/strong> 16,5 km al sur de Puntarenas en el Golfo de Nicoya,  distrito: Puntarenas, cant\u00f3n: Puntarenas, en la provincia de Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 60101.<br \/>\n<strong>Coordenadas para GPS del Ferry de Puntarenas: <\/strong>9.977431,-84.848553 (9\u00b058&#8217;38.75&#8243;N, 84\u00b050&#8217;54.79&#8243;W)<br \/>\n<strong>Tama\u00f1o: <\/strong>140 hect\u00e1reas (350 acres)<br \/>\n<strong>Altitud:<\/strong> nivel del mar hasta los 100 metros<br \/>\n<strong>Tel\u00e9fono del \u00c1rea de Conservaci\u00f3n Tempisque:<\/strong> <a href=\"callto:+5062686-4967\">+506 2686-4967<\/a> \/ <a href=\"callto:+5062686-4968\">+506 2686-4968<\/a><br \/>\n<strong>Fax del \u00c1rea de Conservaci\u00f3n Tempisque:<\/strong> +506 2686-4969<br \/>\n<strong>Informaci\u00f3n Tur\u00edstica INFOTUR:<\/strong> 1192<\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-de-la-reserva-biologica-isla-los-negritos\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Puerto de Puntarenas, Costa Rica.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click the following link to read this page in English: Los Negritos Island Biological Reserve Costa Rica La Reserva Biol\u00f3gica Isla Los Negritos, ubicada en el Golfo de Nicoya fue incluida en el sistema de parques nacionales\u00a0el 27 de Diciembre de 1982, con el fin de\u00a0 preservar las abundantes poblaciones de aves marinas, su flora &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/#more-1425\" aria-label=\"Leer m\u00e1s sobre Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[95,32,23],"tags":[],"class_list":["post-1425","post","type-post","status-publish","format-standard","hentry","category-95","category-parques-nacionales","category-puntarenas","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica - Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Click the following link to read this page in English: Los Negritos Island Biological Reserve Costa Rica La Reserva Biol\u00f3gica Isla Los Negritos, ubicada en el Golfo de Nicoya fue incluida en el sistema de parques nacionales\u00a0el 27 de Diciembre de 1982, con el fin de\u00a0 preservar las abundantes poblaciones de aves marinas, su flora ... Leer M\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-24T23:10:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-19T16:08:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica\",\"datePublished\":\"2010-01-24T23:10:34+00:00\",\"dateModified\":\"2016-01-19T16:08:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/\"},\"wordCount\":712,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/isla-los-negritos-parque-nacional.jpeg\",\"articleSection\":[\"60101\",\"Parques Nacionales\",\"Puntarenas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/\",\"name\":\"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/isla-los-negritos-parque-nacional.jpeg\",\"datePublished\":\"2010-01-24T23:10:34+00:00\",\"dateModified\":\"2016-01-19T16:08:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/isla-los-negritos-parque-nacional.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/isla-los-negritos-parque-nacional.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/reserva-biologica-isla-los-negritos-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica - Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica - Costa Rica","og_description":"Click the following link to read this page in English: Los Negritos Island Biological Reserve Costa Rica La Reserva Biol\u00f3gica Isla Los Negritos, ubicada en el Golfo de Nicoya fue incluida en el sistema de parques nacionales\u00a0el 27 de Diciembre de 1982, con el fin de\u00a0 preservar las abundantes poblaciones de aves marinas, su flora ... Leer M\u00e1s","og_url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2010-01-24T23:10:34+00:00","article_modified_time":"2016-01-19T16:08:50+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica","datePublished":"2010-01-24T23:10:34+00:00","dateModified":"2016-01-19T16:08:50+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/"},"wordCount":712,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg","articleSection":["60101","Parques Nacionales","Puntarenas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/","name":"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg","datePublished":"2010-01-24T23:10:34+00:00","dateModified":"2016-01-19T16:08:50+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg","contentUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-negritos-parque-nacional.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-negritos-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Reserva Biol\u00f3gica Isla Los Negritos, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-mZ","jetpack-related-posts":[{"id":1404,"url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-guayabo-negritos-y-pajaros-costa-rica\/","url_meta":{"origin":1425,"position":0},"title":"Reserva Biol\u00f3gica Isla Guayabo, Negritos y P\u00e1jaros, Costa Rica","author":"Costa Rica Info Link","date":"25 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: Guayabo, Negritos and Pajaros Island Biological Reserves Costa Rica Estas cuatro islas deshabitadas (ya que Negritos consiste en dos islas) fueron incluidas en el sistema de parques nacionales, como Reservas Biol\u00f3gicas el 27 de diciembre de 1982, con el fin\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"Isla Guayabo, parte de la Reserva Biol\u00f3gica Isla Guayabo, Negritos y P\u00e1jaros, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-guayabo-parque-nacional3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1414,"url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-los-pajaros-costa-rica\/","url_meta":{"origin":1425,"position":1},"title":"Reserva Biol\u00f3gica Isla Los P\u00e1jaros, Costa Rica","author":"Costa Rica Info Link","date":"24 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: Pajaros Island Biological Reserve Costa Rica La Reserva Biol\u00f3gica Isla Los P\u00e1jaros, ubicada en el Golfo de Nicoya, fue incluida en el sistema de parques nacionales el 27 de diciembre de 1982, con el fin de preservar las abundantes poblaciones\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-pajaros-parque-nacional3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1429,"url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-guayabo-costa-rica\/","url_meta":{"origin":1425,"position":2},"title":"Reserva Biol\u00f3gica Isla Guayabo, Costa Rica","author":"Costa Rica Info Link","date":"24 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: Guayabo Island Biological Reserve Costa Rica La Reserva Biol\u00f3gica Isla Guayabo, ubicada en el Golfo de Nicoya fue incluida en el sistema de parques nacionales\u00a0el 27 de diciembre de 1982, con el fin de\u00a0 preservar las abundantes poblaciones de aves\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"Aves en la Reserva Biol\u00f3gica Isla Guayabo, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-los-pajaros-parque-nacional-aves22.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1770,"url":"https:\/\/costaricainfolink.com\/es\/parques-nacionales-de-costa-rica\/","url_meta":{"origin":1425,"position":3},"title":"Parques Nacionales de Costa Rica","author":"Costa Rica Info Link","date":"11 agosto 2011","format":false,"excerpt":"Debajo del siguiente texto usted encontrar\u00e1 una lista de los parques nacionales ordenada por provincia, si hace click sobre el nombre de cada parque, el enlace lo llevar\u00e1 a la p\u00e1gina exclusiva de su selecci\u00f3n, con informaci\u00f3n detallada, coordenadas para GPS, instrucciones de c\u00f3mo llegar, mapa con direcci\u00f3n, tel\u00e9fonos, horarios\u2026","rel":"","context":"En \u00abParques Nacionales\u00bb","block_context":{"text":"Parques Nacionales","link":"https:\/\/costaricainfolink.com\/es\/category\/parques-nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/hacienda-finca-la-avellana-parque-nacional-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1209,"url":"https:\/\/costaricainfolink.com\/es\/reserva-biologica-isla-del-cano-costa-rica\/","url_meta":{"origin":1425,"position":4},"title":"Reserva Biol\u00f3gica Isla del Ca\u00f1o, Costa Rica","author":"Costa Rica Info Link","date":"3 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: Ca\u00f1o Island Biological Reserve, Costa Rica Situada en el maravilloso y azul Oc\u00e9ano Pac\u00edfico, a unos 20 km de la costa de la Pen\u00ednsula de Osa en Bah\u00eda Drake, Isla del Ca\u00f1o es una incre\u00edble reserva biol\u00f3gica marina en Costa\u2026","rel":"","context":"En \u00ab60503\u00bb","block_context":{"text":"60503","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60503\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/isla-del-cano-parque-nacional-costa-rica-entrada1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1476,"url":"https:\/\/costaricainfolink.com\/es\/reserva-natural-absoluta-cabo-blanco-costa-rica\/","url_meta":{"origin":1425,"position":5},"title":"Reserva Natural Absoluta Cabo Blanco, Costa Rica","author":"Costa Rica Info Link","date":"31 enero 2010","format":false,"excerpt":"Click the following link to read this page in English: Cabo Blanco Absolute Natural Reserve Costa Rica La Reserva Natural Absoluta Cabo Blanco protege los bosques tropicales y zonas de playa en el extremo sur de la Pen\u00ednsula de Nicoya, en Costa Rica. Cabo Blanco recibi\u00f3 su estatus de protecci\u00f3n\u2026","rel":"","context":"En \u00ab60111\u00bb","block_context":{"text":"60111","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60111\/"},"img":{"alt_text":"Entrada a la Reserva Natural Absoluta Cabo Blanco en Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/01\/cabo-blanco-parque-nacional-costa-rica-entrada.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/1425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=1425"}],"version-history":[{"count":18,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/1425\/revisions"}],"predecessor-version":[{"id":16823,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/1425\/revisions\/16823"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=1425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=1425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=1425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}