{"id":1796,"date":"2009-08-07T20:22:41","date_gmt":"2009-08-08T01:22:41","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=1796"},"modified":"2018-02-28T11:58:49","modified_gmt":"2018-02-28T16:58:49","slug":"refugio-de-vida-silvestre-limoncito-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/","title":{"rendered":"Refugio de Vida Silvestre Limoncito, Costa Rica"},"content":{"rendered":"<h6>Click the following link to read this page in English: <a href=\"https:\/\/www.costaricainfolink.com\/en\/limoncito-wildlife-refuge-costa-rica\/\">Limoncito National Wildlife Refuge Costa Rica<\/a><\/h6>\n<p><strong>Ubicaci\u00f3n:<\/strong> al sur de la ciudad de Lim\u00f3n, distrito: Matama, cant\u00f3n: Lim\u00f3n, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70104.<br \/>\n<strong>Coordenadas para GPS de Lim\u00f3n:<\/strong> 9.989639,-83.03325 (9\u00b059&#8217;22.70&#8243;N, 83\u00b001&#8217;59.70&#8243;W)<br \/>\n<strong>Tama\u00f1o:<\/strong> 1.056 hect\u00e1reas (2.790 acres)<br \/>\n<strong>Tel\u00e9fono del \u00c1rea de Conservaci\u00f3n La Amistad Caribe (ACLA-C):<\/strong> <a href=\"tel:+50627586612\">+506 2758-6612<\/a>, <a href=\"tel:+50627586509\">+506 2758-6509<\/a><br \/>\n<strong>Informaci\u00f3n Tur\u00edstica INFOTUR:<\/strong> 1192<\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-del-refugio-de-vida-silvestre-limoncito\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica a Lim\u00f3n centro, Costa Rica.<\/a><\/p>\n<p>El Refugio Nacional de Vida Silvestre Limoncito fue creado el 26 de abril de 1994 con el fin de proteger las especies de aves migratorias en las tierras bajas, bosques pantanosos y bosques de palmeras\u00a0<img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"1800\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/limoncito-parque-nacional-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg?fit=494%2C369&amp;ssl=1\" data-orig-size=\"494,369\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Refugio Nacional de Vida Silvestre Limoncito en Limon, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg?fit=494%2C369&amp;ssl=1\" class=\"alignright wp-image-1800\" title=\"Refugio Nacional de Vida Silvestre Limoncito en Limon, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg?resize=346%2C258&#038;ssl=1\" alt=\"\" width=\"346\" height=\"258\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg?w=494&amp;ssl=1 494w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"(max-width: 346px) 100vw, 346px\" \/>de la regi\u00f3n central costera del Caribe. El refugio se encuentra situado en la desembocadura del r\u00edo Limoncito, justo al sur del puerto de Lim\u00f3n en Costa Rica.<\/p>\n<p>El Refugio de Vida Silvestre Limoncito tiene un gran potencial recreativo, esta cubierto principalmente de palma yolillo (Raphia taedigera). Adem\u00e1s, el refugio cuenta con una hermosa playa, a pesar de sus grandes olas, rodeada de palmas de coco (Cocos nucifera). El mejor acceso a la zona de la playa Limoncito es caminando hacia el sur de Lim\u00f3n, al lo largo de la playa de Lim\u00f3n.<\/p>\n<p>El Refugio Nacional de Vida Silvestre Limoncito no cuenta con servicios p\u00fablicos. Otros parques nacionales cercanos son el Parque Nacional Tortuguero, el Parque Nacional Cahuita y el Refugio de Vida Silvestre Gandoca-Manzanillo.<\/p>\n<p><strong>C\u00f3mo llegar al Refugio de Vida Silvestre Limoncito?<\/strong><\/p>\n<p>Desde el Aeropuerto Internacional Juan Santamar\u00eda conduzca por unos 8 km en direcci\u00f3n hacia San Jos\u00e9. A su mano derecha va estar el Hospital M\u00e9xico. Justo despu\u00e9s del Hospital M\u00e9xico, debe tomar la salida hacia La Uruca (en la rotonda, la tercera salida). Gire a la derecha en el sem\u00e1foro y siga en direcci\u00f3n a San Jos\u00e9 (mant\u00e9ngase en el carril del medio tanto como sea posible) hasta llegar a la gasolinera Shell en la Y, y tome la izquierda. Gire en la salida de Gu\u00e1piles-Lim\u00f3n y siga la carretera (n\u00ba32) hacia Lim\u00f3n, pasando por el puente del Zurqu\u00ed y las monta\u00f1as del Braulio Carrillo. Es probable que usted se encontrar\u00e1 con niebla y lluvia. Por favor, conduzca con las luces encendidas. Despu\u00e9s de las monta\u00f1as, la carretera a Lim\u00f3n es pr\u00e1cticamente recta sin colinas.<\/p>\n<p>Al llegar a Puerto Lim\u00f3n, justo antes de entrar a la ciudad ver\u00e1 una se\u00f1al (en la estaci\u00f3n de Texaco), gire a la derecha hacia Cahuita y Puerto Viejo y contin\u00fae la carretera bordeando la costa hasta llegar al Refugio de Vida Silvestre Limoncito. Esta ruta requiere un total de cinco horas de San Jos\u00e9.<\/p>\n<p>Tenga en cuenta que si no ha salido de San Jos\u00e9 a las 2 pm usted conducir\u00e1 una parte del camino durante la noche. No recomendamos esto para los viajeros que conduzcan por primera en Costa Rica, ya que existen carreteras que no est\u00e1n marcadas, y la lluvia puede no ser conveniente, adem\u00e1s de que en el camino se puede encontrar con baches y gente caminando o en bicicleta, los cuales pueden ser no vistos.<\/p>\n<h2>En autob\u00fas:<\/h2>\n<p>Usted puede tomar un autob\u00fas con la ruta San Jos\u00e9 \u2013 Parque Nacional Cahuita \u2013 Puerto Viejo, el cual tarda unas 3.5 horas (Transportes Caribe\u00f1os, <a href=\"tel:+50622578129\">+506 2257-8129<\/a>.). Se recomienda comprar el tiquete al menos un d\u00eda antes para asegurarse el espacio.<\/p>\n<h2>En avi\u00f3n:<\/h2>\n<p>Tambi\u00e9n se puede tomar un vuelo entre el aeropuerto Juan Santamar\u00eda y el aeropuerto de Lim\u00f3n, ya sea con SANSA, TravelAir o <a href=\"https:\/\/www.costaricainfolink.com\/aerobell.html\" target=\"_blank\">Aerobell Airlines<\/a> todos los d\u00edas. Desde ah\u00ed puede tomar un taxi o conducir hasta el Refugio de Vida Silvestre Limoncito, lo cual puede tardar aproximadamente 15 minutos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click the following link to read this page in English: Limoncito National Wildlife Refuge Costa Rica Ubicaci\u00f3n: al sur de la ciudad de Lim\u00f3n, distrito: Matama, cant\u00f3n: Lim\u00f3n, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70104. Coordenadas para GPS de Lim\u00f3n: 9.989639,-83.03325 (9\u00b059&#8217;22.70&#8243;N, 83\u00b001&#8217;59.70&#8243;W) Tama\u00f1o: 1.056 hect\u00e1reas (2.790 acres) Tel\u00e9fono del \u00c1rea de &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Refugio de Vida Silvestre Limoncito, Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/#more-1796\" aria-label=\"Leer m\u00e1s sobre Refugio de Vida Silvestre Limoncito, Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[127,22,32],"tags":[],"class_list":["post-1796","post","type-post","status-publish","format-standard","hentry","category-127","category-limon","category-parques-nacionales","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Refugio de Vida Silvestre Limoncito, Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Refugio de Vida Silvestre Limoncito, Costa Rica - Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Click the following link to read this page in English: Limoncito National Wildlife Refuge Costa Rica Ubicaci\u00f3n: al sur de la ciudad de Lim\u00f3n, distrito: Matama, cant\u00f3n: Lim\u00f3n, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70104. Coordenadas para GPS de Lim\u00f3n: 9.989639,-83.03325 (9\u00b059&#8217;22.70&#8243;N, 83\u00b001&#8217;59.70&#8243;W) Tama\u00f1o: 1.056 hect\u00e1reas (2.790 acres) Tel\u00e9fono del \u00c1rea de ... Leer M\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2009-08-08T01:22:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-28T16:58:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Refugio de Vida Silvestre Limoncito, Costa Rica\",\"datePublished\":\"2009-08-08T01:22:41+00:00\",\"dateModified\":\"2018-02-28T16:58:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/\"},\"wordCount\":667,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/limoncito-parque-nacional-costa-rica.jpg\",\"articleSection\":[\"70104\",\"Lim\u00f3n\",\"Parques Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/\",\"name\":\"Refugio de Vida Silvestre Limoncito, Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/limoncito-parque-nacional-costa-rica.jpg\",\"datePublished\":\"2009-08-08T01:22:41+00:00\",\"dateModified\":\"2018-02-28T16:58:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/limoncito-parque-nacional-costa-rica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/limoncito-parque-nacional-costa-rica.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/refugio-de-vida-silvestre-limoncito-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Refugio de Vida Silvestre Limoncito, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Refugio de Vida Silvestre Limoncito, Costa Rica - Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Refugio de Vida Silvestre Limoncito, Costa Rica - Costa Rica","og_description":"Click the following link to read this page in English: Limoncito National Wildlife Refuge Costa Rica Ubicaci\u00f3n: al sur de la ciudad de Lim\u00f3n, distrito: Matama, cant\u00f3n: Lim\u00f3n, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70104. Coordenadas para GPS de Lim\u00f3n: 9.989639,-83.03325 (9\u00b059&#8217;22.70&#8243;N, 83\u00b001&#8217;59.70&#8243;W) Tama\u00f1o: 1.056 hect\u00e1reas (2.790 acres) Tel\u00e9fono del \u00c1rea de ... Leer M\u00e1s","og_url":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2009-08-08T01:22:41+00:00","article_modified_time":"2018-02-28T16:58:49+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Refugio de Vida Silvestre Limoncito, Costa Rica","datePublished":"2009-08-08T01:22:41+00:00","dateModified":"2018-02-28T16:58:49+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/"},"wordCount":667,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg","articleSection":["70104","Lim\u00f3n","Parques Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/","name":"Refugio de Vida Silvestre Limoncito, Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg","datePublished":"2009-08-08T01:22:41+00:00","dateModified":"2018-02-28T16:58:49+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/limoncito-parque-nacional-costa-rica.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-limoncito-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Refugio de Vida Silvestre Limoncito, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-sY","jetpack-related-posts":[{"id":1812,"url":"https:\/\/costaricainfolink.com\/es\/reserva-forestal-pacuare-matina-costa-rica\/","url_meta":{"origin":1796,"position":0},"title":"Reserva Forestal Pacuare Matina Costa Rica","author":"Costa Rica Info Link","date":"6 agosto 2009","format":false,"excerpt":"Ubicaci\u00f3n: entre los canales de Tortuguero y el mar Caribe, a unos 25 km de Puerto Lim\u00f3n, distrito: Matina, cant\u00f3n: Matina, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70501. Coordenadas GPS para Matina: 10.071414,-83.288406 (10\u00b004'17.09\"N, 83\u00b017'18.26\"W) Tama\u00f1o: 476 hect\u00e1reas (1176 acres) Tel\u00e9fono de la Reserva Forestal Pacuare Matina:\u2026","rel":"","context":"En \u00ab70501\u00bb","block_context":{"text":"70501","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/70501\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2010\/07\/pacuare-matina-parque-nacional-costa-rica-tortuga2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1052,"url":"https:\/\/costaricainfolink.com\/es\/refugio-nacional-de-vida-silvestre-gandoca-manzanillo-en-costa-rica\/","url_meta":{"origin":1796,"position":1},"title":"Refugio Nacional de Vida Silvestre Gandoca-Manzanillo en Costa Rica","author":"Costa Rica Info Link","date":"10 agosto 2009","format":false,"excerpt":"Click the following link to read this page in English: Gandoca-Manzanillo National Wildlife Refuge Costa Rica El Refugio Nacional de Vida Silvestre Gandoca-Manzanillo fue establecido en 1985 y se encuentra ubicado en el litoral caribe\u00f1o de Costa Rica, en el cant\u00f3n de Talamanca en Lim\u00f3n. Esta reciente incorporaci\u00f3n al sistema\u2026","rel":"","context":"En \u00ab70402\u00bb","block_context":{"text":"70402","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/70402\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/08\/manzanillo-parques-nacionales-costa-rica-manglar.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9319,"url":"https:\/\/costaricainfolink.com\/es\/playa-punta-uva-costa-rica\/","url_meta":{"origin":1796,"position":2},"title":"Playa Punta Uva Costa Rica","author":"Costa Rica Info Link","date":"28 septiembre 2013","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Chiquita y Playa Grande en Lim\u00f3n, Costa Rica. Coordenadas para GPS de playa Punta Uva: 9.636132, -82.699740 (9\u00b038'10.07\"N, 82\u00b041'59.06\"W) Distrito: Cahuita, cant\u00f3n: Talamanca, provincia: Lim\u00f3n. C\u00f3digo postal de la zona: 70403. Las playas de Punta Uva han sido consideradas entre las m\u00e1s bellas del mundo, y es\u2026","rel":"","context":"En \u00ab70403\u00bb","block_context":{"text":"70403","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/70403\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-punta-uva-limon-costa-rica-panoramica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-punta-uva-limon-costa-rica-panoramica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-punta-uva-limon-costa-rica-panoramica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-punta-uva-limon-costa-rica-panoramica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-punta-uva-limon-costa-rica-panoramica.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-punta-uva-limon-costa-rica-panoramica.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16898,"url":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-dr-archie-carr-costa-rica\/","url_meta":{"origin":1796,"position":3},"title":"Refugio Nacional de Vida Silvestre Dr. Archie Carr Costa Rica","author":"Costa Rica Info Link","date":"6 agosto 2009","format":false,"excerpt":"Click the following link to read this page in English: Dr. Archie Carr Wildlife Refuge Costa Rica El Refugio Nacional de Vida Silvestre Dr. Archie Carr fue creado el 19 de mayo de1994 con el fin de operar en la Estaci\u00f3n Biol\u00f3gica John H. Phipps y el Centro de Visitantes\u2026","rel":"","context":"En \u00ab70206\u00bb","block_context":{"text":"70206","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/70206\/"},"img":{"alt_text":"Tortuga beb\u00e9 en el Refugio Nacional de Vida Silvestre Dr. Archie Carr en Lim\u00f3n, Costa Rica.","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2016\/03\/dr-archie-carr-parque-nacional-costa-rica-tortuguita.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":466,"url":"https:\/\/costaricainfolink.com\/es\/museo-regional-de-la-provincia-de-limon-costa-rica\/","url_meta":{"origin":1796,"position":4},"title":"Museo Regional de la Provincia de Lim\u00f3n, Costa Rica","author":"Costa Rica Info Link","date":"1 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: The Regional Museum of the Province of Lim\u00f3n Costa Rica El Museo Regional de la Provincia de Lim\u00f3n es un museo de tem\u00e1tica etnohist\u00f3rica por lo que exhibe la riqueza cultural de los grupos \u00e9tnicos como el afro-limonense, el ind\u00edgena,\u2026","rel":"","context":"En \u00ab70101\u00bb","block_context":{"text":"70101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/70101\/"},"img":{"alt_text":"Lim\u00f3n, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/limon-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9260,"url":"https:\/\/costaricainfolink.com\/es\/playa-chiquita-costa-rica\/","url_meta":{"origin":1796,"position":5},"title":"Playa Chiquita Costa Rica","author":"Costa Rica Info Link","date":"29 septiembre 2013","format":false,"excerpt":"Click the following link to read this page in English: Chiquita Beach Costa Rica Ubicaci\u00f3n: entre Playa Cocles y Playa Punta Uva en Lim\u00f3n, Costa Rica. Coordenadas para GPS de playa Chiquita: 9.637873, -82.709077 (9\u00b038'16.34\"N, 82\u00b042'32.67\"W) Distrito: Cahuita, cant\u00f3n: Talamanca, provincia: Lim\u00f3n. C\u00f3digo postal de la zona: 70403. Playa Chiquita\u2026","rel":"","context":"En \u00ab70403\u00bb","block_context":{"text":"70403","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/70403\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-chiquita-limon-costa-rica-panoramica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-chiquita-limon-costa-rica-panoramica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-chiquita-limon-costa-rica-panoramica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-chiquita-limon-costa-rica-panoramica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-chiquita-limon-costa-rica-panoramica.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/09\/playa-chiquita-limon-costa-rica-panoramica.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/1796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=1796"}],"version-history":[{"count":23,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/1796\/revisions"}],"predecessor-version":[{"id":17793,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/1796\/revisions\/17793"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=1796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=1796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=1796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}