{"id":19523,"date":"2022-06-08T10:06:40","date_gmt":"2022-06-08T15:06:40","guid":{"rendered":"https:\/\/costaricainfolink.com\/es\/?p=19523"},"modified":"2022-06-08T10:08:44","modified_gmt":"2022-06-08T15:08:44","slug":"las-mascaradas-simbolo-nacional-de-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/","title":{"rendered":"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica"},"content":{"rendered":"<p><a href=\"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/mascaradas-costa-rica012\/#main\" rel=\"attachment wp-att-19533\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"19533\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/mascaradas-costa-rica012\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg?fit=1100%2C500&amp;ssl=1\" data-orig-size=\"1100,500\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica\" data-image-description=\"&lt;p&gt;Las Mascaradas, S\u00edmbolo Nacional de Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg?fit=1100%2C500&amp;ssl=1\" class=\"aligncenter  wp-image-19533\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg?resize=550%2C250&#038;ssl=1\" alt=\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica\" width=\"550\" height=\"250\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg?w=1100&amp;ssl=1 1100w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg?resize=768%2C349&amp;ssl=1 768w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n<p>El 21 de abril del 2022, los diputados aprobaron en segundo debate el expediente N\u00b022704 y de esta forma Las Mascaradas se unen a la lista de S\u00edmbolos Nacionales de Costa Rica.<\/p>\n<p>El arte y las costumbres populares transmiten la esencia y la identidad del ser costarricense, y es su gran valor cultural el que debemos procurar mantener a lo largo del tiempo. Una de las costumbres hist\u00f3ricas de Costa Rica, corresponden a las mascaradas, que desde la Colonia hab\u00edan llevado alegr\u00eda a los pueblos costarricenses.<\/p>\n<p>Las mascaradas tradicionales costarricenses no solo son un \u00edcono de la alegr\u00eda del \u00abtico\u00bb, tambi\u00e9n est\u00e1n cargadas de historia, y su creaci\u00f3n conlleva horas de trabajo, convirti\u00e9ndolas en verdaderas obras de arte. Es por esto que este proyecto de ley se cre\u00f3 con la finalidad de seguir conservando las tradiciones ind\u00edgenas, ese patrimonio cultural que se hereda de esta tradici\u00f3n popular, y por ello, Costa Rica debe incentivar que las mascaradas sigan siendo parte de la cultura de nuestro pa\u00eds, y tambi\u00e9n pretenden de rendir homenaje a los maestros artesanos que confeccionan las mascaradas.<\/p>\n<p>El Ministerio de Educaci\u00f3n P\u00fablica (MEP), debe incluir en su programa la sensibilizaci\u00f3n y divulgaci\u00f3n. El Ministerio de Cultura y Juventud deber\u00e1 informar los valore culturales sobre las mascaradas, y el Instituto Costarricense de Turismo (ICT), deber\u00e1 promoverlas como un elemento que incentive el turismo y el comercio de sus actividades.<\/p>\n<p><strong>HISTORIA<\/strong><\/p>\n<p>Las mascaradas se adoptan en el Valle Central, aproximadamente a mediados del siglo XX, como una fiesta para celebrar la libertad y unir al pueblo. Como arte popular hist\u00f3ricamente se contrapuso al arte elitista, buscando que todos los vecinos se reunieran, independientemente de su clase social. Participando desde m\u00fasicos, mascareros, payasos, homenajeados y los espectadores.<\/p>\n<p>La celebraci\u00f3n est\u00e1 impregnada de tem\u00e1ticas como la libertad, el juego y la comunidad, sus personajes representaban esto mismo: el polic\u00eda, leyendas como el cadejo, la llorona, el \u00abpisuicas\u00bb (diablo), personas propias del pueblo, la pareja de gigantes, y hasta personas de la pol\u00edtica nacional, entre otros.<\/p>\n<p>Ahora bien, para buscar el inicio de esta tradici\u00f3n en nuestro territorio es posible que se deba regresar hasta la \u00e9poca precolombina antes de la llegada de los espa\u00f1oles al territorio de Costa Rica en el siglo XVI, donde los pueblos<a href=\"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/mascaradas-costa-rica01\/#main\" rel=\"attachment wp-att-19535\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"19535\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/mascaradas-costa-rica01\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica01.jpg?fit=760%2C570&amp;ssl=1\" data-orig-size=\"760,570\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica\" data-image-description=\"&lt;p&gt;Las Mascaradas, S\u00edmbolo Nacional de Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica01.jpg?fit=760%2C570&amp;ssl=1\" class=\"alignright  wp-image-19535\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica01.jpg?resize=423%2C317&#038;ssl=1\" alt=\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica\" width=\"423\" height=\"317\" \/><\/a> abor\u00edgenes contaban con algunas tradiciones que inclu\u00edan la elaboraci\u00f3n y utilizaci\u00f3n de m\u00e1scaras. La m\u00e1s destacada de estas tradiciones, que ha llegado hasta la fecha, es el juego de los diablitos de la comunidad ind\u00edgena de Boruca. Esta fiesta celebrada por el pueblo boruca posiblemente desde una \u00e9poca previa a la Conquista, involucra la elaboraci\u00f3n de m\u00e1scaras a base de madera de balsa, con las cuales los participantes del juego de los diablitos se disfrazan para la celebraci\u00f3n, que se lleva a cabo entre el 31 de diciembre y el 2 de enero de cada a\u00f1o. No es casualidad entonces, que en las excavaciones arqueol\u00f3gicas realizadas en la zona sur de Costa Rica, donde se asentaron los reinos borucas, sea frecuente el hallazgo de piezas de oro que representan personajes enmascarados, as\u00ed como danzantes y m\u00fasicos.<\/p>\n<p>Las m\u00e1scaras prehisp\u00e1nicas se hac\u00edan de diversos materiales como arcilla, piedra volc\u00e1nica, madera y jade, se coloreaban con pigmentos naturales, y sus tem\u00e1ticas eran propias de la cosmovisi\u00f3n ind\u00edgena. Los personajes enmascarados ejecutaban danzas rituales, lo que les otorgaba un lugar privilegiado y les confer\u00eda poder en la sociedad ind\u00edgena, pues se interpretaba que se transformaba o era pose\u00eddo por la deidad que representaba la m\u00e1scara.<\/p>\n<p>Posteriormente, en la \u00e9poca colonial se considera a los parlampanes como los antecesores inmediatos a la mascarada tradicional de hoy d\u00eda. Los parlampanes eran grupos de vecinos de condici\u00f3n generalmente humilde, los cuales se disfrazaban con trajes rid\u00edculos que utilizaban m\u00e1scaras representando animales. Durante la \u00e9poca colonial, en la ciudad de Cartago, antes del inicio de las corridas de toros durante las festividades populares o religiosas, los parlampanes<br \/>\nsal\u00edan a bailar y corretear al p\u00fablico asistente.<\/p>\n<p>En la Colonia, las m\u00e1scaras eran fabricadas de papel mach\u00e9. En ellas, se presentaba un sincretismo religioso con influencias espa\u00f1olas, ind\u00edgenas y africanas. Los asistentes se vest\u00edan con mantas (de donde proviene el t\u00e9rmino \u201cmantudo\u201d), a las que hac\u00edan agujeros para los ojos, la nariz y la boca, sobre la cual se colocaban las m\u00e1scaras. La mascarada popular de tradici\u00f3n colonial tuvo un resurgimiento en el pa\u00eds, en La Puebla de los Pardos de Cartago, en la misma \u00e9poca en la que se construy\u00f3 el Teatro Nacional de Costa Rica y en la que se fund\u00f3 la Escuela Nacional de Bellas Artes, a finales del siglo XIX. El contraste de esta manifestaci\u00f3n cultural festiva, carnavalesca y sat\u00edrica callejera, con la opulencia del nuevo teatro josefino, s\u00edmbolo de modernidad, progreso y europeizaci\u00f3n, es una de las numerosas muestras de la rica diversidad y complejidad de la historia de la cultura y del arte costarricense.<\/p>\n<p>Es evidente, que las mascaradas tienen un valor importante para el turismo que llegan a observar las festividades, en donde se realizan grandes encargos para vender las m\u00e1scaras tradicionales en el mercado internacional para pa\u00edses como Francia, Espa\u00f1a, Canad\u00e1 y Estados Unidos o en la venta de galer\u00edas de arte o tiendas de souvenirs en San Jos\u00e9 o en las zonas tur\u00edsticas como Papagayo, Tamarindo, Jaco, la Fortuna, etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 21 de abril del 2022, los diputados aprobaron en segundo debate el expediente N\u00b022704 y de esta forma Las Mascaradas se unen a la lista de S\u00edmbolos Nacionales de Costa Rica. El arte y las costumbres populares transmiten la esencia y la identidad del ser costarricense, y es su gran valor cultural el que &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/#more-19523\" aria-label=\"Leer m\u00e1s sobre Las Mascaradas, S\u00edmbolo Nacional de Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12],"tags":[],"class_list":["post-19523","post","type-post","status-publish","format-standard","hentry","category-simbolos-nacionales","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las Mascaradas, S\u00edmbolo Nacional de Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica - Costa Rica\" \/>\n<meta property=\"og:description\" content=\"El 21 de abril del 2022, los diputados aprobaron en segundo debate el expediente N\u00b022704 y de esta forma Las Mascaradas se unen a la lista de S\u00edmbolos Nacionales de Costa Rica. El arte y las costumbres populares transmiten la esencia y la identidad del ser costarricense, y es su gran valor cultural el que ... Leer M\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-08T15:06:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-08T15:08:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica\",\"datePublished\":\"2022-06-08T15:06:40+00:00\",\"dateModified\":\"2022-06-08T15:08:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/\"},\"wordCount\":952,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mascaradas-costa-rica012.jpg\",\"articleSection\":[\"S\u00edmbolos Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/\",\"name\":\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mascaradas-costa-rica012.jpg\",\"datePublished\":\"2022-06-08T15:06:40+00:00\",\"dateModified\":\"2022-06-08T15:08:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mascaradas-costa-rica012.jpg?fit=1100%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mascaradas-costa-rica012.jpg?fit=1100%2C500&ssl=1\",\"width\":1100,\"height\":500,\"caption\":\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/las-mascaradas-simbolo-nacional-de-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica - Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica - Costa Rica","og_description":"El 21 de abril del 2022, los diputados aprobaron en segundo debate el expediente N\u00b022704 y de esta forma Las Mascaradas se unen a la lista de S\u00edmbolos Nacionales de Costa Rica. El arte y las costumbres populares transmiten la esencia y la identidad del ser costarricense, y es su gran valor cultural el que ... Leer M\u00e1s","og_url":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2022-06-08T15:06:40+00:00","article_modified_time":"2022-06-08T15:08:44+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica","datePublished":"2022-06-08T15:06:40+00:00","dateModified":"2022-06-08T15:08:44+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/"},"wordCount":952,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg","articleSection":["S\u00edmbolos Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/","name":"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg","datePublished":"2022-06-08T15:06:40+00:00","dateModified":"2022-06-08T15:08:44+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg?fit=1100%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2022\/06\/mascaradas-costa-rica012.jpg?fit=1100%2C500&ssl=1","width":1100,"height":500,"caption":"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/las-mascaradas-simbolo-nacional-de-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las Mascaradas, S\u00edmbolo Nacional de Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-54T","jetpack-related-posts":[{"id":7004,"url":"https:\/\/costaricainfolink.com\/es\/simbolos-nacionales-de-costa-rica\/","url_meta":{"origin":19523,"position":0},"title":"S\u00edmbolos Nacionales de Costa Rica","author":"Costa Rica Info Link","date":"7 junio 2009","format":false,"excerpt":"S\u00edmbolos Nacionales de Costa Rica o s\u00edmbolos patrios, son aquellos que representan el esp\u00edritu esforzado del pueblo costarricense, para poder ser reconocidos no s\u00f3lo en Costa Rica, sino por otros pa\u00edses. Generalmente estos s\u00edmbolos se formulan a partir de representaciones visuales o verbales que pretenden difundir los valores de la\u2026","rel":"","context":"En \u00abCultura Costarricense\u00bb","block_context":{"text":"Cultura Costarricense","link":"https:\/\/costaricainfolink.com\/es\/category\/cultura-costarricense\/"},"img":{"alt_text":"Mariposa Morpho, S\u00edmbolo Nacional de Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":20147,"url":"https:\/\/costaricainfolink.com\/es\/imagenes-de-simbolos-nacionales-de-costa-rica\/","url_meta":{"origin":19523,"position":1},"title":"Im\u00e1genes de S\u00edmbolos Nacionales de Costa Rica","author":"Costa Rica Info Link","date":"25 septiembre 2023","format":false,"excerpt":"Click en las im\u00e1genes para verlas m\u00e1s grandes.","rel":"","context":"En \u00abS\u00edmbolos Nacionales\u00bb","block_context":{"text":"S\u00edmbolos Nacionales","link":"https:\/\/costaricainfolink.com\/es\/category\/simbolos-nacionales\/"},"img":{"alt_text":"Antorcha de la Independencia S\u00edmbolo Nacional de la Libertad","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2023\/09\/Antorcha-de-la-Independencia-Simbolo-Nacional-de-la-Libertad.webp?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2023\/09\/Antorcha-de-la-Independencia-Simbolo-Nacional-de-la-Libertad.webp?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2023\/09\/Antorcha-de-la-Independencia-Simbolo-Nacional-de-la-Libertad.webp?resize=525%2C300 1.5x"},"classes":[]},{"id":20673,"url":"https:\/\/costaricainfolink.com\/es\/ict-invita-a-turistear-y-disfrutar-de-los-carnavales-de-limon-en-su-75-aniversario\/","url_meta":{"origin":19523,"position":2},"title":"ICT invita a turistear y disfrutar de los Carnavales de Lim\u00f3n en su 75 aniversario","author":"Costa Rica Info Link","date":"7 octubre 2024","format":false,"excerpt":"Costa Rica. La cuenta regresiva para la celebraci\u00f3n del 75 aniversario de los Carnavales de Lim\u00f3n se activ\u00f3 oficialmente esta semana, gracias al anuncio de la programaci\u00f3n oficial de una agenda de actividades que promete estar rebosante de alegr\u00eda, ritmo y sabor. Asimismo, la noche del viernes 04 de octubre,\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/costaricainfolink.com\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/10\/ICT-invita-a-turistear-y-disfrutar-de-los-Carnavales-de-Limon-en-su-75-aniversario-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/10\/ICT-invita-a-turistear-y-disfrutar-de-los-Carnavales-de-Limon-en-su-75-aniversario-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/10\/ICT-invita-a-turistear-y-disfrutar-de-los-Carnavales-de-Limon-en-su-75-aniversario-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/10\/ICT-invita-a-turistear-y-disfrutar-de-los-Carnavales-de-Limon-en-su-75-aniversario-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/10\/ICT-invita-a-turistear-y-disfrutar-de-los-Carnavales-de-Limon-en-su-75-aniversario-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":147,"url":"https:\/\/costaricainfolink.com\/es\/guaria-morada-flor-nacional-de-costa-rica\/","url_meta":{"origin":19523,"position":3},"title":"Guaria Morada Flor Nacional de Costa Rica","author":"Costa Rica Info Link","date":"6 junio 2009","format":false,"excerpt":"Cu\u00e1l es la Flor Nacional de Costa Rica? La Guaria Morada es La Flor Nacional de Costa Rica y fue decretada el 15 de junio de 1939 bajo el gobierno de don Le\u00f3n Cort\u00e9s Castro por la Secretar\u00eda del Estado en el Despacho de Fomento y Agricultura, por acuerdo No.\u2026","rel":"","context":"En \u00abCultura Costarricense\u00bb","block_context":{"text":"Cultura Costarricense","link":"https:\/\/costaricainfolink.com\/es\/category\/cultura-costarricense\/"},"img":{"alt_text":"Flor nacional de Costa Rica Guaria morada Cattleya skinneri","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/guaria-morada-catleya-skinnerii-flor-nacional-costa-rica-1.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/guaria-morada-catleya-skinnerii-flor-nacional-costa-rica-1.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/guaria-morada-catleya-skinnerii-flor-nacional-costa-rica-1.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/guaria-morada-catleya-skinnerii-flor-nacional-costa-rica-1.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/guaria-morada-catleya-skinnerii-flor-nacional-costa-rica-1.webp?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/guaria-morada-catleya-skinnerii-flor-nacional-costa-rica-1.webp?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":7011,"url":"https:\/\/costaricainfolink.com\/es\/marimba-simbolo-nacional-de-la-cultura-y-tradicion\/","url_meta":{"origin":19523,"position":4},"title":"Marimba, S\u00edmbolo Nacional de la Cultura y Tradici\u00f3n","author":"Costa Rica Info Link","date":"5 junio 2009","format":false,"excerpt":"Este hist\u00f3rico y popular instrumento musical es un emblema que representa y dignifica el arte y la cultura del pueblo costarricense, un pueblo pac\u00edfico, amante de la paz y la democracia, la cual prevalece desde la Anexi\u00f3n de Guanacaste a Costa Rica. Seg\u00fan cuenta la historia, la Marimba, que ha\u2026","rel":"","context":"En \u00abCultura de Costa Rica\u00bb","block_context":{"text":"Cultura de Costa Rica","link":"https:\/\/costaricainfolink.com\/es\/category\/cultura-de-costa-rica\/"},"img":{"alt_text":"Marimba, S\u00edmbolo Nacional de la Cultura y Tradici\u00f3n","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/07\/marimba-simbolo-nacional-costa-rica005.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":19019,"url":"https:\/\/costaricainfolink.com\/es\/perezoso-simbolo-nacional-de-costa-rica\/","url_meta":{"origin":19523,"position":5},"title":"Perezoso, S\u00edmbolo Nacional de Costa Rica","author":"Costa Rica Info Link","date":"24 agosto 2021","format":false,"excerpt":"El perezoso es el nuevo S\u00edmbolo Nacional de Costa Rica. El 14 de Julio del 2021, el proyecto de ley que declara al perezoso como s\u00edmbolo nacional fue aprobado por unanimidad y en definitiva, el expediente 22.167 en segundo debate por la Comisi\u00f3n Plena Tercera de la Asamblea Legislativa. La\u2026","rel":"","context":"En \u00abS\u00edmbolos Nacionales\u00bb","block_context":{"text":"S\u00edmbolos Nacionales","link":"https:\/\/costaricainfolink.com\/es\/category\/simbolos-nacionales\/"},"img":{"alt_text":"Oso Perezoso Simbolo Nacional Fauna Silvestre de Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2021\/08\/oso-perezoso-costa-rica.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/19523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=19523"}],"version-history":[{"count":3,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/19523\/revisions"}],"predecessor-version":[{"id":19537,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/19523\/revisions\/19537"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=19523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=19523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=19523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}