{"id":20422,"date":"2024-05-17T11:18:15","date_gmt":"2024-05-17T16:18:15","guid":{"rendered":"https:\/\/costaricainfolink.com\/es\/?p=20422"},"modified":"2025-08-15T10:08:07","modified_gmt":"2025-08-15T15:08:07","slug":"himno-a-la-bandera-de-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/","title":{"rendered":"Himno a la Bandera de Costa Rica"},"content":{"rendered":"\n<pre class=\"wp-block-verse has-medium-font-size\">Himno a la Bandera de Costa Rica<br><strong>Letra<\/strong>: Porfirio Brenes Castro<br><strong>M\u00fasica<\/strong>: J. J. Vargas Calvo<br><br>Salud, noble bandera<br>de blanco, azul y rojo;<br>jam\u00e1s ning\u00fan sonrojo<br>fue mancha a tu esplendor.<br><br>La banda bucanera<br>cay\u00f3 a tu sombra herida<br>y heroica y bendecida<br>salvaste el patrio honor.<br><br>Tan blancas como armi\u00f1o<br>tus franjas representan,<br>la paz que siempre ostentan<br>los hijos del pa\u00eds.<br><br>Vivimos con cari\u00f1o<br>bajo este azul del cielo,<br>labrando con anhelo<br>dichoso porvenir.<br><br>Carm\u00edn en las mejillas<br>del pueblo laborioso,<br>revela el don precioso<br>de entera libertad.<br><br>Ganaste en los combates<br>de Santa Rosa y Rivas,<br>las glorias siempre vivas<br>de honor y lealtad.<br><br>Como ala protectora<br>en toda Costa Rica,<br>tu emblema dignifica<br>el santo patrio amor.<br><br>La tumba de los Moras<br>y Ca\u00f1as t\u00fa proteges<br>y en nuestro pecho tejes<br>escudo al coraz\u00f3n.<\/pre>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1200\" height=\"720\" data-attachment-id=\"20425\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/bandera-de-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png?fit=1200%2C720&amp;ssl=1\" data-orig-size=\"1200,720\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bandera-de-Costa-Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png?fit=1200%2C720&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png?resize=1200%2C720&#038;ssl=1\" alt=\"Bandera de Costa Rica\" class=\"wp-image-20425\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png?resize=768%2C461&amp;ssl=1 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Himno a la Bandera de Costa RicaLetra: Porfirio Brenes CastroM\u00fasica: J. J. Vargas CalvoSalud, noble banderade blanco, azul y rojo;jam\u00e1s ning\u00fan sonrojofue mancha a tu esplendor.La banda bucaneracay\u00f3 a tu sombra heriday heroica y bendecidasalvaste el patrio honor.Tan blancas como armi\u00f1otus franjas representan,la paz que siempre ostentanlos hijos del pa\u00eds.Vivimos con cari\u00f1obajo este azul del &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Himno a la Bandera de Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/#more-20422\" aria-label=\"Leer m\u00e1s sobre Himno a la Bandera de Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-20422","post","type-post","status-publish","format-standard","hentry","category-general","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Himno a la Bandera de Costa Rica<\/title>\n<meta name=\"description\" content=\"Himno a la Bandera de Costa Rica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Himno a la Bandera de Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Himno a la Bandera de Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-17T16:18:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T15:08:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Himno a la Bandera de Costa Rica\",\"datePublished\":\"2024-05-17T16:18:15+00:00\",\"dateModified\":\"2025-08-15T15:08:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/\"},\"wordCount\":7,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Bandera-de-Costa-Rica.png\",\"articleSection\":[\"General\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/\",\"name\":\"Himno a la Bandera de Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Bandera-de-Costa-Rica.png\",\"datePublished\":\"2024-05-17T16:18:15+00:00\",\"dateModified\":\"2025-08-15T15:08:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"description\":\"Himno a la Bandera de Costa Rica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Bandera-de-Costa-Rica.png?fit=1200%2C720&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Bandera-de-Costa-Rica.png?fit=1200%2C720&ssl=1\",\"width\":1200,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/himno-a-la-bandera-de-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Himno a la Bandera de Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Himno a la Bandera de Costa Rica","description":"Himno a la Bandera de Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Himno a la Bandera de Costa Rica","og_description":"Himno a la Bandera de Costa Rica","og_url":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2024-05-17T16:18:15+00:00","article_modified_time":"2025-08-15T15:08:07+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Himno a la Bandera de Costa Rica","datePublished":"2024-05-17T16:18:15+00:00","dateModified":"2025-08-15T15:08:07+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/"},"wordCount":7,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png","articleSection":["General"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/","name":"Himno a la Bandera de Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png","datePublished":"2024-05-17T16:18:15+00:00","dateModified":"2025-08-15T15:08:07+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"description":"Himno a la Bandera de Costa Rica","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png?fit=1200%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2024\/05\/Bandera-de-Costa-Rica.png?fit=1200%2C720&ssl=1","width":1200,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/himno-a-la-bandera-de-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Himno a la Bandera de Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-5jo","jetpack-related-posts":[{"id":159,"url":"https:\/\/costaricainfolink.com\/es\/himno-nacional-de-costa-rica\/","url_meta":{"origin":20422,"position":0},"title":"Himno Nacional de Costa Rica","author":"Costa Rica Info Link","date":"6 junio 2009","format":false,"excerpt":"Click aqu\u00ed para ver m\u00e1s grande M\u00fasica completa mp3 descargable: Descargar M\u00fasica del Himno Nacional de Costa Rica mp3 La m\u00fasica del Himno Nacional de Costa Rica data desde junio de 1852. Su m\u00fasica fue compuesta por Manuel Mar\u00eda Guti\u00e9rrez Flores, director de la banda militar de San Jos\u00e9, quien\u2026","rel":"","context":"En \u00abS\u00edmbolos Nacionales\u00bb","block_context":{"text":"S\u00edmbolos Nacionales","link":"https:\/\/costaricainfolink.com\/es\/category\/simbolos-nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/himno-nacional-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/himno-nacional-costa-rica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/himno-nacional-costa-rica.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":7004,"url":"https:\/\/costaricainfolink.com\/es\/simbolos-nacionales-de-costa-rica\/","url_meta":{"origin":20422,"position":1},"title":"S\u00edmbolos Nacionales de Costa Rica","author":"Costa Rica Info Link","date":"7 junio 2009","format":false,"excerpt":"S\u00edmbolos Nacionales de Costa Rica o s\u00edmbolos patrios, son aquellos que representan el esp\u00edritu esforzado del pueblo costarricense, para poder ser reconocidos no s\u00f3lo en Costa Rica, sino por otros pa\u00edses. Generalmente estos s\u00edmbolos se formulan a partir de representaciones visuales o verbales que pretenden difundir los valores de la\u2026","rel":"","context":"En \u00abCultura Costarricense\u00bb","block_context":{"text":"Cultura Costarricense","link":"https:\/\/costaricainfolink.com\/es\/category\/cultura-costarricense\/"},"img":{"alt_text":"Mariposa Morpho, S\u00edmbolo Nacional de Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Mariposa-Morpho-Simbolo-Nacional-de-Costa-Rica.webp?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":156,"url":"https:\/\/costaricainfolink.com\/es\/la-bandera-de-costa-rica\/","url_meta":{"origin":20422,"position":2},"title":"La Bandera Nacional de Costa Rica","author":"Costa Rica Info Link","date":"6 junio 2009","format":false,"excerpt":"La bandera de Costa Rica fue creada el 29 de septiembre de 1848 junto con el Escudo Nacional. La historia establece que la concepci\u00f3n y dise\u00f1o de la actual bandera, vigente desde ese a\u00f1o, correspondi\u00f3 a Do\u00f1a Pac\u00edfica Fern\u00e1ndez Oreamuno, esposa del entonces Jefe de Estado, don Jos\u00e9 Mar\u00eda Castro\u2026","rel":"","context":"En \u00abS\u00edmbolos Nacionales\u00bb","block_context":{"text":"S\u00edmbolos Nacionales","link":"https:\/\/costaricainfolink.com\/es\/category\/simbolos-nacionales\/"},"img":{"alt_text":"La Bandera, S\u00edmbolo Nacional de Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/bandera-simbolo-nacional-costa-rica2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7023,"url":"https:\/\/costaricainfolink.com\/es\/antorcha-de-la-independencia-simbolo-nacional-de-la-libertad\/","url_meta":{"origin":20422,"position":3},"title":"Antorcha de la Independencia, S\u00edmbolo Nacional de la Libertad","author":"Costa Rica Info Link","date":"5 junio 2009","format":false,"excerpt":"La Antorcha de la Independencia fue declarada S\u00edmbolo Patrio el 14 de setiembre de 2005 bajo la administraci\u00f3n del Dr. Abel Pacheco De La Espriella, como representaci\u00f3n del ideal de Libertad e Independencia que une a Costa Rica con sus pa\u00edses hermanos de Centroam\u00e9rica, seg\u00fan el decreto MEP N\u00ba32647-C, firmando,\u2026","rel":"","context":"En \u00abS\u00edmbolos Nacionales\u00bb","block_context":{"text":"S\u00edmbolos Nacionales","link":"https:\/\/costaricainfolink.com\/es\/category\/simbolos-nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/antorcha-simbolo-nacional-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":19714,"url":"https:\/\/costaricainfolink.com\/es\/costa-rica-tiene-playas\/","url_meta":{"origin":20422,"position":4},"title":"Costa Rica tiene playas?","author":"Costa Rica Info Link","date":"15 febrero 2023","format":false,"excerpt":"Costa Rica cuenta con un total de 1228 kil\u00f3metros de litoral y alrededor de 600 playas. Playas de Guanacaste Avellanas Azul Bah\u00eda Junquillal Bah\u00eda Pez Vela Barco Quebrado Bejuco Blanca en La Cruz Blanca en Liberia Bonita Brasilito Buena Buena Vista Cabuyal Caletas en Nandayure Camaronal Carrillo Cocos Conchal Copal\u2026","rel":"","context":"En \u00abPlayas de Costa Rica\u00bb","block_context":{"text":"Playas de Costa Rica","link":"https:\/\/costaricainfolink.com\/es\/category\/playas-de-costa-rica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":120,"url":"https:\/\/costaricainfolink.com\/es\/traje-tipico-de-costa-rica\/","url_meta":{"origin":20422,"position":5},"title":"Traje T\u00edpico de Costa Rica &#8211; S\u00edmbolo Nacional","author":"Costa Rica Info Link","date":"6 junio 2009","format":false,"excerpt":"El traje t\u00edpico de Costa Rica representan uno de los elementos m\u00e1s importantes del patrimonio hist\u00f3rico y cultural costarricense. En varias regiones usan trajes t\u00edpicos guardando siempre los rasgos de las antiguas tribus ind\u00edgenas que poblaron nuestro pa\u00eds. Uno de los trajes t\u00edpicos m\u00e1s usados en nuestro pa\u00eds consiste en\u2026","rel":"","context":"En \u00abS\u00edmbolos Nacionales\u00bb","block_context":{"text":"S\u00edmbolos Nacionales","link":"https:\/\/costaricainfolink.com\/es\/category\/simbolos-nacionales\/"},"img":{"alt_text":"Traje tipico de Costa Rica hombre y mujer","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/traje-tipico-de-costa-rica-hombre-y-mujer.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/20422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=20422"}],"version-history":[{"count":8,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/20422\/revisions"}],"predecessor-version":[{"id":21807,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/20422\/revisions\/21807"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=20422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=20422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=20422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}