{"id":205,"date":"2009-06-11T21:56:14","date_gmt":"2009-06-12T02:56:14","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=205"},"modified":"2025-04-25T18:50:32","modified_gmt":"2025-04-25T23:50:32","slug":"auditorio-nacional-de-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/","title":{"rendered":"Auditorio Nacional de Costa Rica"},"content":{"rendered":"\n<h6 class=\"wp-block-heading\">Click the following link to read this page in English: <a href=\"https:\/\/www.costaricainfolink.com\/en\/costa-rica-national-auditorium\/\">Costa Rica National Auditorium<\/a><\/h6>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Direcci\u00f3n:<\/strong> Museo de los Ni\u00f1os, distrito: Merced, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10102.<br><strong>Coordenadas para GPS:<\/strong> 9.940364,-84.080258 (9\u00b056&#8217;25.31&#8243;N, 84\u00b0 4&#8217;48.93&#8243;W)<br><strong>Tel\u00e9fono:<\/strong><a href=\"tel:+5062222-7647\">+506 2222-7647<\/a><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-del-auditorio-nacional-de-costa-rica\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Auditorio Nacional en San Jos\u00e9, Costa Rica.<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0w9wvr\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Auditorio Nacional de Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/maps.app.goo.gl\/ZP3pGvPar7xjhZRk8\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Auditorio Nacional de Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/auditorio-nacional-de-costa-rica-2\/#main\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1200\" height=\"800\" data-attachment-id=\"21246\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/auditorio-nacional-de-costa-rica-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Auditorio-Nacional-de-Costa-Rica.jpg?fit=2048%2C1365&amp;ssl=1\" data-orig-size=\"2048,1365\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Auditorio Nacional de Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Auditorio-Nacional-de-Costa-Rica.jpg?fit=1200%2C800&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Auditorio-Nacional-de-Costa-Rica.jpg?resize=1200%2C800&#038;ssl=1\" alt=\"Auditorio Nacional de Costa Rica\" class=\"wp-image-21246\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Auditorio-Nacional-de-Costa-Rica.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Auditorio-Nacional-de-Costa-Rica.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Auditorio-Nacional-de-Costa-Rica.jpg?resize=1536%2C1024&amp;ssl=1 1536w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Capacidad Auditorio Nacional Museo de Los Ni\u00f1os<\/strong>: 664 butacas, es posible ampliar a 703 personas durante conciertos.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El Auditorio Nacional se ubica dentro del Museo de los Ni\u00f1os (Antigua Penitenciar\u00eda Central) en San Jos\u00e9 centro, Costa Rica y es uno de los mejores aforos para espect\u00e1culos de la capital.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"240\" height=\"180\" data-attachment-id=\"206\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/auditorio-nacional-museo-ninos-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/auditorio-nacional-museo-ninos-san-jose-costa-rica.jpg?fit=240%2C180&amp;ssl=1\" data-orig-size=\"240,180\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Auditorio Nacional, Museo de los Ni\u00f1os de San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/auditorio-nacional-museo-ninos-san-jose-costa-rica.jpg?fit=240%2C180&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/auditorio-nacional-museo-ninos-san-jose-costa-rica.jpg?resize=240%2C180&#038;ssl=1\" alt=\"Auditorio Nacional, Museo de los Ni\u00f1os de San Jos\u00e9, Costa Rica\" class=\"wp-image-206\" title=\"Auditorio Nacional, Museo de los Ni\u00f1os de San Jos\u00e9, Costa Rica\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El teatro del Auditorio Nacional, es uno de los escenarios m\u00e1s vers\u00e1tiles para las artes esc\u00e9nicas y todo tipo de eventos especiales. La Galer\u00eda Nacional es el espacio m\u00e1s amplio del pa\u00eds para las artes pl\u00e1sticas y visuales, siempre lleno de propuestas vanguardistas. El Complejo Juvenil desarrolla constantemente ideas para los j\u00f3venes y albergar\u00e1 el Museo Hist\u00f3rico Penitenciario para reconstruir la historia de la Penitenciar\u00eda Central de una forma moderna y din\u00e1mica.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Desde su creaci\u00f3n, el Auditorio Nacional ha ofrecido un escenario apto para todas las artes esc\u00e9nicas debido a que posee un moderno sistema de luces y una concha ac\u00fastica con la capacidad de enviar un sonido casi natural a las 526 butacas en menos de un segundo.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Por su dise\u00f1o, ubicaci\u00f3n, multimedia satelital, fosa para orquesta, y posibilidad de traducci\u00f3n simult\u00e1nea a cuatro idiomas, esta joya arquitect\u00f3nica representa la mejor opci\u00f3n de auditorio del pa\u00eds.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">En el auditorio se presentan conciertos de m\u00fasica cl\u00e1sica, conciertos nacionales e internacionales, cert\u00e1menes de belleza, presentaciones audiovisuales, conferencias, seminarios, congresos cient\u00edficos y culturales, as\u00ed como obras de teatro que complementan la educaci\u00f3n formal costarricense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click the following link to read this page in English: Costa Rica National Auditorium Direcci\u00f3n: Museo de los Ni\u00f1os, distrito: Merced, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10102.Coordenadas para GPS: 9.940364,-84.080258 (9\u00b056&#8217;25.31&#8243;N, 84\u00b0 4&#8217;48.93&#8243;W)Tel\u00e9fono:+506 2222-7647 Mapa con direcci\u00f3n: Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Auditorio Nacional de Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/#more-205\" aria-label=\"Leer m\u00e1s sobre Auditorio Nacional de Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[40,25,10],"tags":[],"class_list":["post-205","post","type-post","status-publish","format-standard","hentry","category-40","category-san-jose","category-teatros","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auditorio Nacional de Costa Rica<\/title>\n<meta name=\"description\" content=\"Auditorio Nacional de Costa Rica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auditorio Nacional de Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Auditorio Nacional de Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-12T02:56:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T23:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Auditorio-Nacional-de-Costa-Rica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Auditorio Nacional de Costa Rica\",\"datePublished\":\"2009-06-12T02:56:14+00:00\",\"dateModified\":\"2025-04-25T23:50:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/\"},\"wordCount\":339,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\",\"articleSection\":[\"10102\",\"San Jos\u00e9\",\"Teatros\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/\",\"name\":\"Auditorio Nacional de Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\",\"datePublished\":\"2009-06-12T02:56:14+00:00\",\"dateModified\":\"2025-04-25T23:50:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"description\":\"Auditorio Nacional de Costa Rica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/auditorio-nacional-de-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auditorio Nacional de Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auditorio Nacional de Costa Rica","description":"Auditorio Nacional de Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Auditorio Nacional de Costa Rica","og_description":"Auditorio Nacional de Costa Rica","og_url":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2009-06-12T02:56:14+00:00","article_modified_time":"2025-04-25T23:50:32+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/Auditorio-Nacional-de-Costa-Rica.jpg","type":"image\/jpeg"}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Auditorio Nacional de Costa Rica","datePublished":"2009-06-12T02:56:14+00:00","dateModified":"2025-04-25T23:50:32+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/"},"wordCount":339,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","articleSection":["10102","San Jos\u00e9","Teatros"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/","name":"Auditorio Nacional de Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","datePublished":"2009-06-12T02:56:14+00:00","dateModified":"2025-04-25T23:50:32+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"description":"Auditorio Nacional de Costa Rica","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/#primaryimage","url":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","contentUrl":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/auditorio-nacional-de-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Auditorio Nacional de Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-3j","jetpack-related-posts":[{"id":741,"url":"https:\/\/costaricainfolink.com\/es\/museo-de-arte-y-diseno-contemporaneo-de-costa-rica\/","url_meta":{"origin":205,"position":0},"title":"Museo de Arte y Dise\u00f1o Contempor\u00e1neo de Costa Rica","author":"Costa Rica Info Link","date":"9 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: The Contemporary Art and Design Museum Costa Rica El Museo de Arte y Dise\u00f1o Contempor\u00e1neo se encuentra ubicado en las instalaciones de la antigua F\u00e1brica Nacional de Licores, fundada en 1856. Este es uno de los sitios de mayor valor\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-arte-diseno-contemporaneo-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":255,"url":"https:\/\/costaricainfolink.com\/es\/teatro-j-vargas-calvo-de-costa-rica\/","url_meta":{"origin":205,"position":1},"title":"Teatro J. Vargas Calvo, Costa Rica","author":"Costa Rica Info Link","date":"16 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: Vargas Calvo Theater Costa Rica Teatro Jos\u00e9 Joaqu\u00edn Vargas Calvo es una peque\u00f1a sala de teatro capitalina. Se encuentra bajo la direcci\u00f3n de Jody Steiger, directora del Teatro Nacional, ente responsable de la producci\u00f3n del mismo. Direcci\u00f3n: en calle 5,\u2026","rel":"","context":"En \u00ab10104\u00bb","block_context":{"text":"10104","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10104\/"},"img":{"alt_text":"Teatro Jos\u00e9 Joaqu\u00edn Vargas Calvo de Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-jose-joaquin-vargas-calvo-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":306,"url":"https:\/\/costaricainfolink.com\/es\/teatro-sala-de-la-calle-15-de-costa-rica\/","url_meta":{"origin":205,"position":2},"title":"Teatro Sala de la Calle 15, Costa Rica","author":"Costa Rica Info Link","date":"18 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: Sala de la Calle 15 Theater Costa Rica En una peque\u00f1a sala de teatro ubicada sobre avenida 2, al costado sur de la Plaza de la Democracia en San Jos\u00e9, se encuentra el llamado Teatro Sala de la Calle 15.\u2026","rel":"","context":"En \u00ab10104\u00bb","block_context":{"text":"10104","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10104\/"},"img":{"alt_text":"Marcia Sabor\u00edo en el Teatro Sala de la Calle 15 en San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-sal-calle-15-san-jose-costa-rica.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":298,"url":"https:\/\/costaricainfolink.com\/es\/teatro-1887-de-costa-rica\/","url_meta":{"origin":205,"position":3},"title":"Teatro 1887 de Costa Rica","author":"Costa Rica Info Link","date":"18 junio 2009","format":false,"excerpt":"Direcci\u00f3n: Calle 11, entre Avenidas 3 y 7, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101. Coordenadas para GPS: 9.935894,-84.073283 (9\u00b056'9.22\"N 84\u00b04'23.82\"W) Tel\u00e9fono:+506 2257-5524 \u00a0\u00a0 Mapa con direcci\u00f3n: Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9,\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Teatro 1887 en San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-1887-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":260,"url":"https:\/\/costaricainfolink.com\/es\/teatro-la-aduana-de-costa-rica\/","url_meta":{"origin":205,"position":4},"title":"Teatro La Aduana de Costa Rica","author":"Costa Rica Info Link","date":"17 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: La Aduana Theater Costa Rica El Teatro La Aduana frecuentemente presenta y organiza bailes y representaciones teatrales, ya que adem\u00e1s es la casa de la Compa\u00f1\u00eda Nacional de Teatro. En la actualidad se encuentran, temporalmente, dentro del edificio patrimonial de\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Teatro La Aduana, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-aduana-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":233,"url":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/","url_meta":{"origin":205,"position":5},"title":"Teatro del \u00c1ngel, Costa Rica","author":"Costa Rica Info Link","date":"13 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: Del Angel Theater Costa Rica El Teatro del \u00c1ngel, es el teatro de la comedia en Costa Rica. Vis\u00edtenos le estamos esperando, y que comience la funci\u00f3n! Direcci\u00f3n: en Avenida Central, entre calles 11 y 15, cant\u00f3n: San Jos\u00e9, provincia:\u2026","rel":"","context":"En \u00abSan Jos\u00e9\u00bb","block_context":{"text":"San Jos\u00e9","link":"https:\/\/costaricainfolink.com\/es\/category\/por-provincia\/san-jose\/"},"img":{"alt_text":"Teatro del Angel, San Jose, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":26,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/205\/revisions"}],"predecessor-version":[{"id":21254,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/205\/revisions\/21254"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}