{"id":233,"date":"2009-06-13T18:33:43","date_gmt":"2009-06-13T23:33:43","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=233"},"modified":"2015-04-03T17:51:57","modified_gmt":"2015-04-03T22:51:57","slug":"el-teatro-del-angel-de-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/","title":{"rendered":"Teatro del \u00c1ngel, Costa Rica"},"content":{"rendered":"<h6>Click the following link to read this page in English: <a href=\"https:\/\/www.costaricainfolink.com\/en\/del-angel-theater-costa-rica\/\">Del Angel Theater Costa Rica<\/a><\/h6>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"234\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/teatro-angel-san-jose-costa-rica-logo2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2.jpg?fit=377%2C338&amp;ssl=1\" data-orig-size=\"377,338\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Teatro del Angel, San Jose, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2.jpg?fit=377%2C338&amp;ssl=1\" class=\"aligncenter size-thumbnail wp-image-234\" title=\"Teatro del Angel, San Jose, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg?resize=150%2C150&#038;ssl=1\" alt=\"Teatro del Angel, San Jose, Costa Rica\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2.jpg?zoom=2&amp;resize=150%2C150&amp;ssl=1 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/p>\n<p>El Teatro del \u00c1ngel, es el teatro de la comedia en Costa Rica. Vis\u00edtenos le estamos esperando, y que comience la funci\u00f3n!<\/p>\n<p><strong>Direcci\u00f3n: <\/strong>en Avenida Central, entre calles 11 y 15, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica.<br \/>\n<strong>Coordenadas para GPS: <\/strong>9.933417,-84.072153 (9\u00b056&#8217;0.30&#8243;N 84\u00b004&#8217;19.75&#8243;W)<br \/>\n<strong>Horario: <\/strong>De Jueves a Domingo de 8 p.m. en adelante<br \/>\n<strong>Horario Boleter\u00eda: <\/strong>abierta desde las 4 p.m.<br \/>\n<strong>Tel\u00e9fono:<\/strong>+506 2222-8258<\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-del-teatro-del-angel\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Teatro del \u00c1ngel en San Jos\u00e9, Costa Rica.<\/a><\/p>\n<h3><a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.google.com\/maps\/place\/9%C2%B056'00.3%22N+84%C2%B004'19.8%22W\/@9.933417,-84.072153,17z\/data=!3m1!4b1!4m2!3m1!1s0x0:0x0?hl=es\">Abrir en Mapas de Google<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Click the following link to read this page in English: Del Angel Theater Costa Rica El Teatro del \u00c1ngel, es el teatro de la comedia en Costa Rica. Vis\u00edtenos le estamos esperando, y que comience la funci\u00f3n! Direcci\u00f3n: en Avenida Central, entre calles 11 y 15, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. Coordenadas &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Teatro del \u00c1ngel, Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/#more-233\" aria-label=\"Leer m\u00e1s sobre Teatro del \u00c1ngel, Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[25,10],"tags":[],"class_list":["post-233","post","type-post","status-publish","format-standard","hentry","category-san-jose","category-teatros","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teatro del \u00c1ngel, Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teatro del \u00c1ngel, Costa Rica - Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Click the following link to read this page in English: Del Angel Theater Costa Rica El Teatro del \u00c1ngel, es el teatro de la comedia en Costa Rica. Vis\u00edtenos le estamos esperando, y que comience la funci\u00f3n! Direcci\u00f3n: en Avenida Central, entre calles 11 y 15, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. Coordenadas ... Leer M\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-13T23:33:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-03T22:51:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Teatro del \u00c1ngel, Costa Rica\",\"datePublished\":\"2009-06-13T23:33:43+00:00\",\"dateModified\":\"2015-04-03T22:51:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/\"},\"wordCount\":123,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg\",\"articleSection\":[\"San Jos\u00e9\",\"Teatros\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/\",\"name\":\"Teatro del \u00c1ngel, Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg\",\"datePublished\":\"2009-06-13T23:33:43+00:00\",\"dateModified\":\"2015-04-03T22:51:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/el-teatro-del-angel-de-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teatro del \u00c1ngel, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teatro del \u00c1ngel, Costa Rica - Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Teatro del \u00c1ngel, Costa Rica - Costa Rica","og_description":"Click the following link to read this page in English: Del Angel Theater Costa Rica El Teatro del \u00c1ngel, es el teatro de la comedia en Costa Rica. Vis\u00edtenos le estamos esperando, y que comience la funci\u00f3n! Direcci\u00f3n: en Avenida Central, entre calles 11 y 15, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. Coordenadas ... Leer M\u00e1s","og_url":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2009-06-13T23:33:43+00:00","article_modified_time":"2015-04-03T22:51:57+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Teatro del \u00c1ngel, Costa Rica","datePublished":"2009-06-13T23:33:43+00:00","dateModified":"2015-04-03T22:51:57+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/"},"wordCount":123,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg","articleSection":["San Jos\u00e9","Teatros"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/","name":"Teatro del \u00c1ngel, Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg","datePublished":"2009-06-13T23:33:43+00:00","dateModified":"2015-04-03T22:51:57+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-angel-san-jose-costa-rica-logo2-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/el-teatro-del-angel-de-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Teatro del \u00c1ngel, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-3L","jetpack-related-posts":[{"id":293,"url":"https:\/\/costaricainfolink.com\/es\/teatro-lucho-barahona-de-costa-rica\/","url_meta":{"origin":233,"position":0},"title":"Teatro Lucho Barahona en Costa Rica","author":"Costa Rica Info Link","date":"18 junio 2009","format":false,"excerpt":"Direcci\u00f3n: En calle 11, entre avenidas 6 y 8, distrito: Catedral, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10104. Coordenadas para GPS: 9.930556,-84.07405 (9\u00b055'50.00\"N 84\u00b04'26.58\"W) Horario: de Viernes a Domingo. Boleter\u00eda abierta desde las 3 p.m. Tel\u00e9fono:+506 2223-5972 \u00a0\u00a0 Mapa con direcci\u00f3n: Haga click\u2026","rel":"","context":"En \u00ab10104\u00bb","block_context":{"text":"10104","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10104\/"},"img":{"alt_text":"Teatro Lucho Barahona en San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-lucho-barahona-san-jose-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":269,"url":"https:\/\/costaricainfolink.com\/es\/teatro-la-comedia-de-costa-rica\/","url_meta":{"origin":233,"position":1},"title":"Teatro La Comedia en Costa Rica","author":"Costa Rica Info Link","date":"17 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: La Comedia Theater Costa Rica Este peque\u00f1o teatro fue fundado por un grupo de artistas independientes. La idea detr\u00e1s de la creaci\u00f3n de este teatro era proporcionar un foro para presentar\u00a0obras originales de Costa Rica. Hoy en d\u00eda este teatro\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Teatro La Comedia, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-comedia-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":302,"url":"https:\/\/costaricainfolink.com\/es\/teatro-moliere-de-costa-rica\/","url_meta":{"origin":233,"position":2},"title":"Teatro Moli\u00e8re en Costa Rica","author":"Costa Rica Info Link","date":"18 junio 2009","format":false,"excerpt":"Direcci\u00f3n: En calle 13, entres avenidas 2 y 4, distrito: Catedral, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10104. Coordenadas para GPS: 9.931492,-84.072756 (9\u00b055'53.37\"N, 84\u00b004'21.92\"W) Horario: de Jueves a Domingo a partir de las 8 p.m., para reservaciones a partir de las 9 a.m.\u2026","rel":"","context":"En \u00ab10104\u00bb","block_context":{"text":"10104","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10104\/"},"img":{"alt_text":"Teatro Moli\u00e8re en San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-moliere-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":274,"url":"https:\/\/costaricainfolink.com\/es\/teatro-la-esquina-de-costa-rica\/","url_meta":{"origin":233,"position":3},"title":"Teatro La Esquina, Costa Rica","author":"Costa Rica Info Link","date":"17 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: La Esquina Theater Costa Rica El Teatro la esquina le invita a pasar un rato agradable, caracterizados por divertir en sus 10 a\u00f1os de vida y m\u00e1s\u00a0de 100 obras de pura risa. Le esperamos 100 metros al oeste del cine\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Obra: Taxiando por un Sue\u00f1o, del Teatro La Esquina en San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-esquina-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":306,"url":"https:\/\/costaricainfolink.com\/es\/teatro-sala-de-la-calle-15-de-costa-rica\/","url_meta":{"origin":233,"position":4},"title":"Teatro Sala de la Calle 15, Costa Rica","author":"Costa Rica Info Link","date":"18 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: Sala de la Calle 15 Theater Costa Rica En una peque\u00f1a sala de teatro ubicada sobre avenida 2, al costado sur de la Plaza de la Democracia en San Jos\u00e9, se encuentra el llamado Teatro Sala de la Calle 15.\u2026","rel":"","context":"En \u00ab10104\u00bb","block_context":{"text":"10104","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10104\/"},"img":{"alt_text":"Marcia Sabor\u00edo en el Teatro Sala de la Calle 15 en San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-sal-calle-15-san-jose-costa-rica.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":226,"url":"https:\/\/costaricainfolink.com\/es\/teatro-chaplin-de-costa-rica\/","url_meta":{"origin":233,"position":5},"title":"Teatro Chaplin, Costa Rica","author":"Costa Rica Info Link","date":"12 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: Chaplin Theater Costa Rica En Enero de 1991, exist\u00eda la necesidad de un grupo de teatro en el Cant\u00f3n de P\u00e9rez Zeled\u00f3n, comunidad que se encuentra 136 Km. al sur de San Jos\u00e9, Costa Rica. Es as\u00ed como surge la\u2026","rel":"","context":"En \u00ab10104\u00bb","block_context":{"text":"10104","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10104\/"},"img":{"alt_text":"Teatro Chaplin, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-chaplin-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=233"}],"version-history":[{"count":19,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/233\/revisions"}],"predecessor-version":[{"id":13105,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/233\/revisions\/13105"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}