{"id":4948,"date":"2011-05-06T19:09:02","date_gmt":"2011-05-07T00:09:02","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=4948"},"modified":"2022-05-06T06:49:54","modified_gmt":"2022-05-06T11:49:54","slug":"parque-nacional-juan-castro-blanco-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/","title":{"rendered":"Parque Nacional Juan Castro Blanco Costa Rica"},"content":{"rendered":"<p><a href=\"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/juan-castro-blanco-parque-nacional-costa-rica-entrada\/#main\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"4996\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/juan-castro-blanco-parque-nacional-costa-rica-entrada\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg?fit=1037%2C778&amp;ssl=1\" data-orig-size=\"1037,778\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.7&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot S2 IS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1198834336&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.0166666666667&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Entrada al Parque Nacional Juan Castro Blanco en Alajuela, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg?fit=1024%2C768&amp;ssl=1\" class=\"alignright wp-image-4996\" title=\"Entrada al Parque Nacional Juan Castro Blanco en Alajuela, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg?resize=415%2C307&#038;ssl=1\" alt=\"\" width=\"415\" height=\"307\"><\/a><strong>Ubicaci\u00f3n:<\/strong> 10 km al este del caser\u00edo de Sucre en Ciudad Quesada, distrito: Quesada, cant\u00f3n: San Carlos, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 21001.<br \/>\n<a href=\"https:\/\/waze.com\/ul\/hd1u42zn3q\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Parque Nacional Juan Castro Blanco Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/8kEbsP5jQHuDRDDB8\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Parque Nacional Juan Castro Blanco Costa Rica\" width=\"50\" height=\"50\"><\/a><br \/>\n<strong>Coordenadas para GPS de Ciudad Quesada:<\/strong> 10.321064,-84.428653 (10\u00b019&#8217;15.83&#8243;N, 84\u00b025&#8217;43.15&#8243;)<br \/>\n<strong>Tama\u00f1o:<\/strong> 14,453 hect\u00e1reas (35,700 acres)<br \/>\n<strong>Altitud:<\/strong> de los 700m a unos 2,267m (2,300 a 7,440 pies) sobre el nivel del mar<br \/>\n<strong>Horario:<\/strong> de 8 a.m. a 4 p.m.<br \/>\n<strong>Tel\u00e9fono del Parque Nacional Juan Castro Blanco:<\/strong> <a href=\"tel:+50624605462\">+506 2460-5462<\/a><br \/>\n<strong>Tel\u00e9fono del \u00c1rea de Conservaci\u00f3n Arenal Huetar Norte (ACA-HN):<\/strong> <a href=\"tel:+50624600055\">+506 2460-0055<\/a><br \/>\n<strong>Informaci\u00f3n Tur\u00edstica INFOTUR:<\/strong> 1192<\/p>\n<p><a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-al-parque-nacional-juan-castro-blanco\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica al Parque Nacional Juan Castro Blanco, Alajuela, Costa Rica.<\/a><\/p>\n<p>El Parque Nacional Juan Castro Blanco fue creado el 26 de Junio de 1975, con el fin de proteger una gran porci\u00f3n de bosques primarios y secundarios, incluyendo bosque nuboso y selva tropical, entre los 700m y los 2,226m, dentro de cinco zonas de vida con importantes especies de flora y fauna. Adem\u00e1s, el parque tambi\u00e9n protegen una naciente de agua fundamental en las laderas del volc\u00e1n Platanar de gran importancia para la zona norte, tanto para el consumo humano e industrial, como para la generaci\u00f3n de energ\u00eda hidroel\u00e9ctrica.<\/p>\n<p>El Parque Nacional Juan Castro Blanco forma parte del \u00c1rea de Conservaci\u00f3n Arenal Huetar Norte (ACA-HN) y se encuentra ubicado en la zona noroeste del Valle Central en la provincia de Alajuela, al este de Ciudad Quesada, rodeado por los distritos de Aguas Zarcas, Venecia, Zapote, Laguna, Tapezco, Palmira, Sarch\u00ed Norte, Toro Amarillo y R\u00edo Cuarto, al sureste del Volc\u00e1n Po\u00e1s y al este del Parque Nacional Braulio Carrillo.<\/p>\n<p>El Parque Nacional Juan Castro Blanco se inicia desde 1975, cuando es declarado como Reserva Forestal Juan Castro Blanco, con una \u00e1rea aproximada a 13.700 ha, que comprende los Cerros Platanar, Volc\u00e1n Viejo, El Siete, Avi\u00f3n y Pel\u00f3n; cubiertos en su mayor\u00eda por bosque natural. En 1989 con la colaboraci\u00f3n del Gobierno, la Municipalidad de San Carlos y la Sociedad Civil, el \u00e1rea es declarada Zona Protectora con una extensi\u00f3n de 14.250 ha. Finalmente el 22 de abril de 1992, bajo la Ley n\u00famero 7297, es declarado Parque Nacional Juan Castro Blanco.<\/p>\n<p>Lo anterior fue logrado gracias a la presi\u00f3n de las fuerzas vivas de la zona, ya que una empresa transnacional quer\u00eda explotar algunos yacimientos de azufre y otros minerales a cielo abierto, lo cual causar\u00eda una grave contaminaci\u00f3n a las fuentes de agua, que en su mayor\u00eda son utilizadas para consumo humano y la agroindustria.<\/p>\n<p>El Parque Nacional Juan Castro Blanco es uno de los parques nacionales menos explorados en Costa Rica, localizado en el centro de algunos de los destinos tur\u00edsticos m\u00e1s populares. Sin embargo, es bien conocido por brindar una excelente oportunidad para la incre\u00edble observaci\u00f3n de aves dentro del bosque primario y la selva tropical, lo cual representa el 50% del parque.<\/p>\n<p>La temperatura del Parque Nacional Juan Castro Blanco se encuentra normalmente entre los 15\u00baC y 27\u00baC (60\u00baF y 80\u00baF), con una precipitaci\u00f3n promedio anual de 3500mm (140 pulgadas) de lluvia al a\u00f1o. Es por esto que en esta \u00e1rea ha sido posible identificar tres zonas principales, conteniendo las mismas una abundante vida natural con bosques pre-montanos, h\u00famedo y muy h\u00famedo, as\u00ed como el bosque monta\u00f1oso de baja altura. (bosque muy h\u00famedo tropical-transici\u00f3n a premontano, bosque muy h\u00famedo premontano, transici\u00f3n a pluvial, bosque pluvial premontano, bosque pluvial montano bajo, bosque muy h\u00famedo montano bajo). Estos bosques se presentan en cinco zonas de vida seg\u00fan la clasificaci\u00f3n de Holdridge: bosque pluvial premontano transici\u00f3n a perh\u00famedo, bosque pluvial montano bajo transici\u00f3n a muy h\u00famedo, bosque muy h\u00famedo premontano transici\u00f3n a pluvial, bosque pluvial montano bajo y bosque pluvial premontano.<\/p>\n<p>La vegetaci\u00f3n de la zona es muy variada y diversa en donde predomina una cobertura de bosque primario entremezclado con claros en regeneraci\u00f3n natural, ocasionados por los constantes deslizamientos de las \u00e1reas m\u00e1s escarpadas. Estos bosques contienen \u00e1rboles hasta de 30 metros de altura y m\u00e1s; entre las especies m\u00e1s sobresalientes est\u00e1n el Ja\u00fal (Alnus acuminata), el Aguacatillo (Persea vesticula), el Balsa (Ochroma pyramidale), el Laurel (Cordia alliodora), el Roble Encino (Quercus seemannii), el Cedro Amargo (Cedrela odorata), el Cipresillo o Pinillo <a href=\"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/juan-castro-blanco-parque-nacional-costa-rica-rio\/#main\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"5000\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/juan-castro-blanco-parque-nacional-costa-rica-rio\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-rio.jpg?fit=450%2C600&amp;ssl=1\" data-orig-size=\"450,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Parque Nacional Juan Castro Blanco en Alajuela, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-rio.jpg?fit=450%2C600&amp;ssl=1\" class=\"alignleft wp-image-5000\" title=\"Parque Nacional Juan Castro Blanco en Alajuela, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-rio.jpg?resize=315%2C420&#038;ssl=1\" alt=\"\" width=\"315\" height=\"420\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-rio.jpg?w=450&amp;ssl=1 450w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-rio.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"(max-width: 315px) 100vw, 315px\" \/><\/a>(Podocarpus guatemalensis) y el Yayo (Xylopia sericophylla) as\u00ed como variedades de palmas y helechos. En las \u00e1reas de menor pendiente no se producen deslizamientos, lo que permite encontrar bosques muy maduros con edades de m\u00e1s de cien a\u00f1os, mientras que en las partes altas se encuentra una vegetaci\u00f3n achaparrada cubierta con gran cantidad de orqu\u00eddeas, bromelias, musgos, arbustos , y muchos tipos diferentes de plantas trepadoras ep\u00edfitas o, que se unen a la vegetaci\u00f3n ya establecida.<\/p>\n<p>Al igual que muchos parques nacionales en el pa\u00eds, el Parque Juan Castro Blanco es un excelente lugar para ver una colecci\u00f3n diversa de vida silvestre, pero en un entorno muy aislado. Sin embargo, explorar el extenso territorio del Parque Nacional Juan Castro Blanco, es posible gracias a su amplio pero abrupto sistema de senderos que le permite a los visitantes la oportunidad de apreciar y descubrir la amplia gama de flora y fauna de Costa Rica desde muy de cerca. El parque cuenta con unas 57 especies de mam\u00edferos, siendo los m\u00e1s comunes los monos congo (Alouatta palliata) y cariblancos (Cebus capucinus), perezosos de dos dedos (Choloepus hoffmanni ), y de tres dedos (Bradypus variegatus), sa\u00ednos (Tayassu tajacu), coyotes (Canis latrans), armadillos (Dasypus novemcinctus), tepezcuintles (Cuniculus paca), dantas (Tapirus bairdii), venados de cola blanca (Odocoileus virginianus), mapaches (Procyon cancrivorus), cabros de monte (Mazama americana), al menos 22 esepcies de murci\u00e9lagos y varios felinos, entre ellos el Le\u00f3n Bre\u00f1ero o Jaguarundi (Puma yagouaroundi), pumas (Puma concolor)y manigordos (Leopardus pardalis). M\u00e1s de 44 especies de anfibios (15% del total nacional) y reptiles tambi\u00e9n son encontradas dentro del parque como por ejemplo ranas, lagartijas, basiliscos, lagartos y serpientes. Adem\u00e1s, el parque tambi\u00e9n cuenta con m\u00e1s de 230 especies de aves, incluyendo al Ave Nacional de Costa Rica el Yig\u00fcirro (Turdus grayi), la Pava Negra (Chamaepetes unicolor), el Halc\u00f3n cuelliblanco (Falco rufigularis), el Pavo Real (Pavo cristatus), el Pav\u00f3n (Crax rubra), la Chachalaca (Ortalis vetula), el Gorri\u00f3n Arlequ\u00edn (Chondestes grammacus), el Jilguero o Solitario Carinegro (Myadestes melanops), el Pecho amarillo (Megarynchus pitangua) e incluso el Quetzal Resplandeciente (Pharomachrus mocinno), as\u00ed como una gran variedad de colibr\u00edes, cucos, halcones y gavilanes, convirti\u00e9ndolo en un para\u00edso para los observadores de aves. Es importante destacar que de todas las especies de vida silvestre, alrededor de unas 64 est\u00e1n calificadas en peligro de extinci\u00f3n en Costa Rica.<\/p>\n<p>Dentro del Parque Nacional Juan Castro Blanco se presentan importantes rasgos geomorfol\u00f3gicos como calderas (Fila Chocosuela), focos volc\u00e1nicos activos e inactivos, adem\u00e1s de conos volc\u00e1nicos cuaternarios, conos aluviales y formas de sedimentaci\u00f3n aluvial de topograf\u00eda muy escarpada. Los suelos son profundos con un buen contenido de materia org\u00e1nica derivados de cenizas volc\u00e1nicas, pero muy susceptible a la erosi\u00f3n. Varios volcanes rodean el parque, haciendo de este destino una aventura para cualquiera. Los tres volcanes que existen dentro del parque que son los activos Volc\u00e1n Platanar (2183m o 7.162 pies), y el Volc\u00e1n Porvenir (2267 m o7.438 pies), as\u00ed como el Volc\u00e1n El Viejo(2122m o 6.962 pies) actualmente inactivo junto con el Cerro Pel\u00f3n. En el extremo norte del Volc\u00e1n Platanar se encuentra el grupo de nueve conos de Aguas Zarcas, que son volcanes miniatura hechos de lava o ceniza. Aunque no ha habido erupciones registradas en la historia reciente, estas bellezas geol\u00f3gicas calientan las aguas termales y los ba\u00f1os de azufre encontrados por todo el parque que se emergen desde el flanco norte y desembocan en los r\u00edos m\u00e1s importantes de la regi\u00f3n, incluyendo los r\u00edos Toro, Platanar, La Vieja, Tres Amigos y Aguas Zarcas.<\/p>\n<p>De hecho, la hidrolog\u00eda de la zona es lo que le brinda relevancia especial al Parque Nacional Juan Castro Blanco. Es el d\u00e9cimo recurso m\u00e1s importante de agua dulce del planeta. Se identifican varias cuencas hidrogr\u00e1ficas, que cuentan con numerosas quebradas y r\u00edos de aguas fr\u00edas y cristalinas con abundantes lagunas y cataratas. Las corrientes de estos r\u00edos proporcionan el 15% de la energ\u00eda el\u00e9ctrica del pa\u00eds, as\u00ed<img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"4998\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/juan-castro-blanco-parque-nacional-costa-rica-lago2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-lago2.jpg?fit=500%2C375&amp;ssl=1\" data-orig-size=\"500,375\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Laguna del Parque Nacional Juan Castro Blanco en Alajuela, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-lago2.jpg?fit=500%2C375&amp;ssl=1\" class=\"alignright wp-image-4998\" title=\"Laguna del Parque Nacional Juan Castro Blanco en Alajuela, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-lago2.jpg?resize=400%2C300&#038;ssl=1\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-lago2.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-lago2.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/> como el agua potable a 105 pueblos de los alrededores y sirven como una fuente viable de alimento, ya que tambi\u00e9n est\u00e1n llenos de truchas.<\/p>\n<p>El Parque Nacional Juan Castro Blanco es tambi\u00e9n un excelente destino para los amantes de la historia, ya que descubrimientos arqueol\u00f3gicos han indicado que el sitio fue utilizado como punto de encuentro de las civilizaciones antiguas de Costa Rica, reuniendo las culturas norte y sur americanas.<\/p>\n<p>La estaci\u00f3n del MINAE (Ministerio Nacional de Ambiente y Energia de Costa Rica), se encuentra junto a la estaci\u00f3n de polic\u00eda de El Sucre, a seis millas de distancia de la entrada del parque de San Jos\u00e9 de la Monta\u00f1a. La estaci\u00f3n de Bajos del Toro Amarillo no tiene un tel\u00e9fono, radio, o cualquier otro m\u00e9todo de comunicaci\u00f3n.<\/p>\n<p>Exceptuando el sistema de senderos, el Parque Nacional Juan Castro Blanco no presta ning\u00fan otro servicio, por lo que se recomienda la supervisi\u00f3n de un gu\u00eda para realizar las caminatas. S\u00f3lo dos de las ocho entradas al parque son sancionadas por el gobierno: una se encuentra en San Jos\u00e9 de la Monta\u00f1a y el otro en Bajo del Toro Amarillo. Otros parques nacionales cercanos incluyen al Parque Nacional Volc\u00e1n Arenal, la Reserva Forestal de Zona de Emergencia del Volc\u00e1n Arenal y al Refugio Nacional de Vida Silvestre Bosque Alegre.<\/p>\n<h2><strong>C\u00f3mo llegar al Parque Nacional Juan Castro Blanco?<\/strong><\/h2>\n<p>Desde San Jos\u00e9, tome la carretera Interamericana hasta Naranjo y siga el camino atravesando los pueblos de Zarcero hasta Ciudad Quesada. La entrada al parque est\u00e1 situada al este de Ciudad Quesada. El acceso principal al Parque, es por el sector del caser\u00edo San Jos\u00e9 de la Monta\u00f1a, 10 km al este del caser\u00edo de Sucre. Durante la temporada de lluvias, es sumamente recomendado utilizar un veh\u00edculo 4X4. El tiempo de conducci\u00f3n desde San Jos\u00e9 es de aproximadamente unas 4 horas.<\/p>\n<p>Desde Liberia (el Aeropuerto Internacional Daniel Oduber) siga la carretera en direcci\u00f3n a la ciudad de Liberia. En la intersecci\u00f3n de Liberia siga la autopista Interamericana en direcci\u00f3n a y luego conduzca a trav\u00e9s de las colinas de la ciudad de Tilar\u00e1n y siga el Lago Arenal hasta la Fortuna de San Carlos y contin\u00fae por unos 25km mas hasta llegar a Ciudad Quesada. La entrada al parque est\u00e1 situada al este de Ciudad Quesada. El acceso principal al Parque, es por el sector del caser\u00edo San Jos\u00e9 de la Monta\u00f1a, 10 km al este del caser\u00edo de Sucre. Durante la temporada de lluvias, es sumamente recomendado utilizar un veh\u00edculo 4X4. El tiempo de conducci\u00f3n desde Liberia es de aproximadamente unas 3 horas.<\/p>\n<h2><strong>En autob\u00fas<\/strong><\/h2>\n<p>Usted puede tomar un autob\u00fas de la ruta San Jos\u00e9 \u2013 Ciudad Quesada, el cual tarda unas 3 horas (Auto Transportes San Jos\u00e9-San Carlos, <a href=\"tel:+50622568914\">+506 2256-8914<\/a>) y de ah\u00ed puede tomar un taxi hasta la entrada del parque.<\/p>\n<h2><strong>En avi\u00f3n<\/strong><\/h2>\n<p>Tambi\u00e9n se puede tomar un vuelo entre el aeropuerto Juan Santamar\u00eda y el aeropuerto de Arenal, ya sea con las aerol\u00edneas de Sansa o <a href=\"https:\/\/www.costaricainfolink.com\/aerobell.html\" target=\"_blank\" rel=\"noopener\">Aerobell Airlines<\/a> todos los d\u00edas. Desde ah\u00ed usted puede rentar un autom\u00f3vil y conducir hasta el refugio, lo cual puede tardar unos 40 minutos, o bien tomar un autob\u00fas de la ruta La Fortuna \u2013 San Jos\u00e9, haciendo la parada en Ciudad Quesada, y de ah\u00ed puede tomar un taxi hasta la entrada del parque.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ubicaci\u00f3n: 10 km al este del caser\u00edo de Sucre en Ciudad Quesada, distrito: Quesada, cant\u00f3n: San Carlos, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 21001. &nbsp;&nbsp; Coordenadas para GPS de Ciudad Quesada: 10.321064,-84.428653 (10\u00b019&#8217;15.83&#8243;N, 84\u00b025&#8217;43.15&#8243;) Tama\u00f1o: 14,453 hect\u00e1reas (35,700 acres) Altitud: de los 700m a unos 2,267m (2,300 a 7,440 pies) sobre el &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Parque Nacional Juan Castro Blanco Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/#more-4948\" aria-label=\"Leer m\u00e1s sobre Parque Nacional Juan Castro Blanco Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[119,20,32],"tags":[],"class_list":["post-4948","post","type-post","status-publish","format-standard","hentry","category-119","category-alajuela","category-parques-nacionales","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parque Nacional Juan Castro Blanco Costa Rica - Costa Rica<\/title>\n<meta name=\"description\" content=\"Parque Nacional Juan Castro Blanco Costa Rica: tel\u00e9fono, horario, direcci\u00f3n, bus y tel\u00e9fonos, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parque Nacional Juan Castro Blanco Costa Rica - Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Parque Nacional Juan Castro Blanco Costa Rica: tel\u00e9fono, horario, direcci\u00f3n, bus y tel\u00e9fonos, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-07T00:09:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-06T11:49:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Parque Nacional Juan Castro Blanco Costa Rica\",\"datePublished\":\"2011-05-07T00:09:02+00:00\",\"dateModified\":\"2022-05-06T11:49:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/\"},\"wordCount\":2034,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg\",\"articleSection\":[\"21001\",\"Alajuela\",\"Parques Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/\",\"name\":\"Parque Nacional Juan Castro Blanco Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg\",\"datePublished\":\"2011-05-07T00:09:02+00:00\",\"dateModified\":\"2022-05-06T11:49:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"description\":\"Parque Nacional Juan Castro Blanco Costa Rica: tel\u00e9fono, horario, direcci\u00f3n, bus y tel\u00e9fonos, ubicaci\u00f3n WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/parque-nacional-juan-castro-blanco-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parque Nacional Juan Castro Blanco Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parque Nacional Juan Castro Blanco Costa Rica - Costa Rica","description":"Parque Nacional Juan Castro Blanco Costa Rica: tel\u00e9fono, horario, direcci\u00f3n, bus y tel\u00e9fonos, ubicaci\u00f3n WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Parque Nacional Juan Castro Blanco Costa Rica - Costa Rica","og_description":"Parque Nacional Juan Castro Blanco Costa Rica: tel\u00e9fono, horario, direcci\u00f3n, bus y tel\u00e9fonos, ubicaci\u00f3n WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2011-05-07T00:09:02+00:00","article_modified_time":"2022-05-06T11:49:54+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Parque Nacional Juan Castro Blanco Costa Rica","datePublished":"2011-05-07T00:09:02+00:00","dateModified":"2022-05-06T11:49:54+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/"},"wordCount":2034,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg","articleSection":["21001","Alajuela","Parques Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/","name":"Parque Nacional Juan Castro Blanco Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg","datePublished":"2011-05-07T00:09:02+00:00","dateModified":"2022-05-06T11:49:54+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"description":"Parque Nacional Juan Castro Blanco Costa Rica: tel\u00e9fono, horario, direcci\u00f3n, bus y tel\u00e9fonos, ubicaci\u00f3n WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/10\/juan-castro-blanco-parque-nacional-costa-rica-entrada.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/parque-nacional-juan-castro-blanco-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Parque Nacional Juan Castro Blanco Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-1hO","jetpack-related-posts":[{"id":3418,"url":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-maquenque-costa-rica\/","url_meta":{"origin":4948,"position":0},"title":"Refugio de Vida Silvestre Maquenque Costa Rica","author":"Costa Rica Info Link","date":"5 mayo 2011","format":false,"excerpt":"Ubicaci\u00f3n: justo al norte de Boca Tapada, cerca de la Frontera con Nicaragua, abarca los distritos Pocosol y Pital del cant\u00f3n de San Carlos, provincia: Alajuela y La Virgen y Cure\u00f1a del cant\u00f3n Sarapiqu\u00ed, provincia: Heredia, Costa Rica. \u00a0\u00a0 Coordenadas para GPS de Pital: 10.453049, -84.273272 (10\u00b027'10.97\"N, 84\u00b016'23.78\"W) Tama\u00f1o: 60\u2026","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/es\/category\/por-provincia\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/maquenque-parque-nacional-costa-rica3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4852,"url":"https:\/\/costaricainfolink.com\/es\/parque-nacional-volcan-tenorio-costa-rica\/","url_meta":{"origin":4948,"position":1},"title":"Parque Nacional Volc\u00e1n Tenorio Costa Rica","author":"Costa Rica Info Link","date":"6 mayo 2011","format":false,"excerpt":"Ubicaci\u00f3n: la entrada al parque se encuentra 16 km al noroeste de Bijagua, distrito: Bijagua, cant\u00f3n: Upala, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 21304. Adem\u00e1s otras zonas del parque se encuentran dentro de los distritos San Rafael, Cote y Katira del cant\u00f3n de Guatuso, provincia: Alajuela, Costa\u2026","rel":"","context":"En \u00ab21304\u00bb","block_context":{"text":"21304","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/21304\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/Parque-Nacional-Volcan-Tenorio-Rio-Celeste-Costa-Rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/Parque-Nacional-Volcan-Tenorio-Rio-Celeste-Costa-Rica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/Parque-Nacional-Volcan-Tenorio-Rio-Celeste-Costa-Rica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/Parque-Nacional-Volcan-Tenorio-Rio-Celeste-Costa-Rica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/Parque-Nacional-Volcan-Tenorio-Rio-Celeste-Costa-Rica.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/Parque-Nacional-Volcan-Tenorio-Rio-Celeste-Costa-Rica.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":4876,"url":"https:\/\/costaricainfolink.com\/es\/reserva-forestal-de-zona-de-emergencia-del-volcan-arenal-costa-rica\/","url_meta":{"origin":4948,"position":2},"title":"Reserva Forestal de Zona de Emergencia del Volc\u00e1n Arenal, Costa Rica","author":"Costa Rica Info Link","date":"6 mayo 2011","format":false,"excerpt":"Click the following link to read this page in English: Arenal Volcano Emergency Forest Reserve, Costa Rica La Reserva Forestal de Zona de Emergencia del Volc\u00e1n Arenal fue creada el 14 de octubre de 1972, con el fin de proteger y conservar las \u00e1reas forestales en la zona de emergencia\u2026","rel":"","context":"En \u00ab21007\u00bb","block_context":{"text":"21007","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/21007\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4824,"url":"https:\/\/costaricainfolink.com\/es\/refugio-de-vida-silvestre-laguna-las-camelias\/","url_meta":{"origin":4948,"position":3},"title":"Refugio de Vida Silvestre Laguna Las Camelias Costa Rica","author":"Costa Rica Info Link","date":"6 mayo 2011","format":false,"excerpt":"Ubicaci\u00f3n: 220 km (137 miles) norte de San Jos\u00e9, distrito: San Jos\u00e9, cant\u00f3n: Upala, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 21303. Coordenadas para GPS de Upala: 10.896381, -85.025328 (10\u00b053\u201946.97\u2033N, 85\u00b001\u201931.18\u2033W) Tama\u00f1o: 64 ha (160 acres) Altitud: de los 30 m a unos 100 m (100 pies to\u2026","rel":"","context":"En \u00ab21303\u00bb","block_context":{"text":"21303","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/21303\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/09\/las-camelias-parque-nacional-costa-rica3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4810,"url":"https:\/\/costaricainfolink.com\/es\/reserva-forestal-cerro-el-jardin-costa-rica\/","url_meta":{"origin":4948,"position":4},"title":"Reserva Forestal Cerro El Jard\u00edn, Costa Rica","author":"Costa Rica Info Link","date":"6 mayo 2011","format":false,"excerpt":"Click the following link to read this page in English: Cerro El Jardin Forest Reserve, Costa Rica La Reserva Forestal Cerro El Jard\u00edn fue creada el 16 de Marzo de 1994 con el fin de proteger las zonas de bosque bajo y un remanente de bosque muy h\u00famedo que existe\u2026","rel":"","context":"En \u00ab21011\u00bb","block_context":{"text":"21011","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/21011\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2011\/09\/el-jardin-parque-nacional-costa-rica21.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4910,"url":"https:\/\/costaricainfolink.com\/es\/parque-nacional-volcan-arenal-costa-rica\/","url_meta":{"origin":4948,"position":5},"title":"Parque Nacional Volc\u00e1n Arenal Costa Rica","author":"Costa Rica Info Link","date":"6 mayo 2011","format":false,"excerpt":"Ubicaci\u00f3n: 15km al suroeste de La Fortuna de San Carlos, distrito: Fortuna, cant\u00f3n: San Carlos, provincia: Alajuela, Costa Rica. C\u00f3digo Postal de la zona: 21007. Coordenadas para GPS: 10.461577, -84.739702 (N 10 27.695, W 84 44.382) \u00a0\u00a0 Tama\u00f1o: 12,124 hect\u00e1reas (29,945 acres) Altitud: de los 300m a unos 1633m (985\u2026","rel":"","context":"En \u00ab21007\u00bb","block_context":{"text":"21007","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/21007\/"},"img":{"alt_text":"Parque Nacional Volc\u00e1n Arenal Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/Parque-Nacional-Volcan-Arenal-Costa-Rica-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/Parque-Nacional-Volcan-Arenal-Costa-Rica-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2011\/05\/Parque-Nacional-Volcan-Arenal-Costa-Rica-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/4948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=4948"}],"version-history":[{"count":22,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/4948\/revisions"}],"predecessor-version":[{"id":19470,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/4948\/revisions\/19470"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=4948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=4948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=4948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}