{"id":5959,"date":"2012-04-23T12:46:36","date_gmt":"2012-04-23T17:46:36","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=5959"},"modified":"2023-02-14T10:20:25","modified_gmt":"2023-02-14T15:20:25","slug":"playa-penca-punta-cacique-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/","title":{"rendered":"Playa Penca Punta Cacique Costa Rica"},"content":{"rendered":"<p><a href=\"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/playa-penca-punta-cacique-costa-rica-2-2\/#main\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"18248\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/playa-penca-punta-cacique-costa-rica-2-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?fit=1920%2C422&amp;ssl=1\" data-orig-size=\"1920,422\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DSC-TX10&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1329556177&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.43&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.001&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Playa Penca Punta Cacique Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?fit=1200%2C264&amp;ssl=1\" class=\"aligncenter wp-image-18248 size-full\" title=\"Playa Penca Punta Cacique en Guanacaste, Costa Rica\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?resize=1200%2C264&#038;ssl=1\" alt=\"Playa Penca Punta Cacique Costa Rica\" width=\"1200\" height=\"264\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?resize=768%2C169&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?resize=560%2C123&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?resize=260%2C57&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?resize=160%2C35&amp;ssl=1 160w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p><strong>Ubicaci\u00f3n:<\/strong> entre Playas del Coco y Playa Hermosa en Guanacaste, Costa Rica.<br \/>\n<strong>Coordenadas para GPS de la entrada a playa Penca Punta Cacique:<\/strong> 10.560686,-85.681171 (10\u00b033&#8217;38.45&#8243;N, 85\u00b040&#8217;52.22&#8243;W)<br \/>\n<strong>Coordenadas para GPS de playa Penca Punta Cacique:<\/strong> 10.573041,-85.697393 (10\u00b034&#8217;22.95&#8243;N, 85\u00b041&#8217;50.61&#8243;W)<br \/>\n<strong>Distrito:<\/strong> Sardinal, <strong>cant\u00f3n:<\/strong> Carrillo, <strong>provincia:<\/strong> Guanacaste<br \/>\n<strong>C\u00f3digo postal de la zona:<\/strong> 50503.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1gh1uv0h\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Playa Penca Punta Cacique en Sardinal Carrillo Guanacaste Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/goo.gl\/maps\/1yi1C7MLGsz\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Playa Penca Punta Cacique en Sardinal Carrillo Guanacaste Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p>Playa Penca en Punta Cacique es una hermosa y paradis\u00edaca playa coralina de arena blanca y tranquilas aguas turquesas cristalinas, de menos de 1km de largo, ubicada en la provincia de Guanacaste. Playa Penca en Punta Cacique es ideal para practicar el snorkeling, buceo, o bien disfrutar de sus tranquilas aguas.<\/p>\n<p>Al ser Playa Penca en Punta Cacique una playa no muy conocida, es poco visitada y la convierte en el lugar ideal para pasar unas relajantes vacaciones de ensue\u00f1o, alejado del ruido y del estr\u00e9s, disfrutando del sol, el mar y su ex\u00f3tico paisaje de bosque seco tropical que la rodea.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/0AaY10qysH4?rel=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>C\u00f3mo llegar a Playa Penca Punta Cacique en Guanacaste?<\/strong><\/p>\n<p><em>Desde San Jos\u00e9<\/em><\/p>\n<p>Conduzca al norte hacia Puntarenas y luego siga la autopista Interamericana hasta llegar a Liberia. Gire a la izquierda y contin\u00fae por unos 8 km (5 millas), pase el Do It Center y tome la siguiente salida a la derecha hacia Sardinal. Una vez en Sardinal, contin\u00fae por la carretera en direcci\u00f3n a Playa Hermosa por unos 7 km (4 millas), aqu\u00ed debe ingresar en un carretera a su izquierda, que ademas de ser la entrada p\u00fablica a la Playa, es la entrada a una propiedad privada, entonces debe reportarse con el encargado para poder continuar por unos 700 m (2,300 pies) m\u00e1s hasta la playa. Esta ruta requiere un total de 4 a 5 horas desde San Jos\u00e9.<\/p>\n<p><em>Desde el Aeropuerto Internacional Daniel Oduber Quir\u00f3s (LIR)<\/em><\/p>\n<p>Conduzca hacia el Sur en direcci\u00f3n a Santa Cruz por unos 8 km (5 millas), pase el Do It Center y tome la siguiente salida a la derecha hacia Sardinal. Una vez en Sardinal, contin\u00fae por la carretera en direcci\u00f3n a Playas Hermosa por unos 7 km (4 millas) aqu\u00ed debe ingresar en un carretera a su izquierda, que ademas de ser la entrada p\u00fablica a la Playa, es la entrada a una propiedad privada, entonces debe reportarse con el encargado para poder continuar por unos 700 m (2,300 pies) m\u00e1s hasta la playa.<\/p>\n<h2>En autob\u00fas:<\/h2>\n<p>Usted puede puede tomar un autob\u00fas de la ruta San Jos\u00e9 &#8211; Playas del Coco, el cual tarda de 4 a 5 horas (Pulmitan Liberia, <a href=\"tel:+50622221650\">+506 2222-1650<\/a> \/ <a href=\"tel:+50626660458\">+506 2666-0458<\/a>). Desde ah\u00ed puede tomar un taxi o conducir hasta Playa Penca Punta Cacique, lo cual puede tardar aproximadamente 5 minutos. Se recomienda comprar el tiquete un d\u00eda antes para asegurar su espacio.<\/p>\n<h2>En avi\u00f3n:<\/h2>\n<p>Tambi\u00e9n se puede tomar un vuelo entre el aeropuerto Juan Santamar\u00eda y el aeropuerto Daniel Oduber en Liberia, ya sea con Sansa o <a href=\"https:\/\/www.costaricainfolink.com\/aerobell.html\" target=\"_blank\" rel=\"noopener noreferrer\">Aerobell Airlines<\/a> todos los d\u00edas. Desde ah\u00ed puede tomar un taxi o conducir hasta Playa Penca Punta Cacique, lo cual puede tardar aproximadamente 20 minutos.<\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-a-playa-penca-punta-cacique\/\">Haga click aqu\u00ed para ver la direcci\u00f3n a Playa Penca Punta Cacique en Guanacaste, Costa Rica en Google Maps<\/a><\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1200\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/&quot;,&quot;likes_blog_id&quot;:77104606}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1200px; height: 554px;\" data-original-width=\"1200\" data-original-height=\"554\" > <div class=\"gallery-group images-1\" style=\"width: 832px; height: 554px;\" data-original-width=\"832\" data-original-height=\"554\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/playa-penca-punta-cacique-costa-rica-4\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"828\"> <meta itemprop=\"height\" content=\"550\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"18251\" data-orig-file=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;SLT-A55V&quot;,&quot;caption&quot;:&quot;SONY DSC&quot;,&quot;created_timestamp&quot;:&quot;1329559883&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;SONY DSC&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Playa Penca Punta Cacique Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?fit=768%2C510&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?fit=1200%2C798&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?w=828&#038;h=550&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"828\" height=\"550\" loading=\"lazy\" data-original-width=\"828\" data-original-height=\"550\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Penca Punta Cacique Costa Rica\" alt=\"Playa Penca Punta Cacique Costa Rica\" style=\"width: 828px; height: 550px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 368px; height: 554px;\" data-original-width=\"368\" data-original-height=\"554\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/playa-penca-punta-cacique-costa-rica-3-2\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"364\"> <meta itemprop=\"height\" content=\"273\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"18252\" data-orig-file=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-3.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DSC-TX10&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1329555527&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;8.33&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.00125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Playa Penca Punta Cacique Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-3.jpg?fit=768%2C576&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-3.jpg?fit=1200%2C900&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-3.jpg?w=364&#038;h=273&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-3.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-3.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-3.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-3.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-3.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"364\" height=\"273\" loading=\"lazy\" data-original-width=\"364\" data-original-height=\"273\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Penca Punta Cacique Costa Rica\" alt=\"Playa Penca Punta Cacique Costa Rica\" style=\"width: 364px; height: 273px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/playa-penca-punta-cacique-costa-rica-5\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"364\"> <meta itemprop=\"height\" content=\"273\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"18253\" data-orig-file=\"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-5.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DSC-TX10&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1329555537&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.88&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.001&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Playa Penca Punta Cacique Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-5.jpg?fit=768%2C576&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-5.jpg?fit=1200%2C900&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-5.jpg?w=364&#038;h=273&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-5.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-5.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-5.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-5.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-5.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"364\" height=\"273\" loading=\"lazy\" data-original-width=\"364\" data-original-height=\"273\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Penca Punta Cacique Costa Rica\" alt=\"Playa Penca Punta Cacique Costa Rica\" style=\"width: 364px; height: 273px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<h2><a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-penca-punta-cacique-costa-rica\/\" target=\"_blank\" rel=\"noopener\">Galer\u00eda de Fotos de Playa Penca Punta Cacique Costa Rica<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Ubicaci\u00f3n: entre Playas del Coco y Playa Hermosa en Guanacaste, Costa Rica. Coordenadas para GPS de la entrada a playa Penca Punta Cacique: 10.560686,-85.681171 (10\u00b033&#8217;38.45&#8243;N, 85\u00b040&#8217;52.22&#8243;W) Coordenadas para GPS de playa Penca Punta Cacique: 10.573041,-85.697393 (10\u00b034&#8217;22.95&#8243;N, 85\u00b041&#8217;50.61&#8243;W) Distrito: Sardinal, cant\u00f3n: Carrillo, provincia: Guanacaste C\u00f3digo postal de la zona: 50503. Playa Penca en Punta Cacique es &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Playa Penca Punta Cacique Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/#more-5959\" aria-label=\"Leer m\u00e1s sobre Playa Penca Punta Cacique Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[107,24,33],"tags":[135,136,138],"class_list":["post-5959","post","type-post","status-publish","format-standard","hentry","category-107","category-guanacaste","category-playas-de-costa-rica","tag-playas-bonitas-en-guanacaste","tag-playas-de-guanacaste","tag-playas-en-guanacaste-costa-rica","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informaci\u00f3n Tur\u00edstica de Playa Penca Punta Cacique Costa Rica<\/title>\n<meta name=\"description\" content=\"Playa Penca Punta Cacique Costa Rica: mapa con direcci\u00f3n, fotos, video, bus y tel\u00e9fonos, c\u00f3mo llegar, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informaci\u00f3n Tur\u00edstica de Playa Penca Punta Cacique Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Playa Penca Punta Cacique Costa Rica: mapa con direcci\u00f3n, fotos, video, bus y tel\u00e9fonos, c\u00f3mo llegar, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-23T17:46:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-14T15:20:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?w=828&#038;h=550&#038;ssl=1\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Playa Penca Punta Cacique Costa Rica\",\"datePublished\":\"2012-04-23T17:46:36+00:00\",\"dateModified\":\"2023-02-14T15:20:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/\"},\"wordCount\":547,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/playa-penca-punta-cacique-costa-rica-2.jpg\",\"keywords\":[\"Playas Bonitas en Guanacaste\",\"Playas de Guanacaste\",\"Playas en Guanacaste Costa Rica\"],\"articleSection\":[\"50503\",\"Guanacaste\",\"Playas de Costa Rica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/\",\"name\":\"Informaci\u00f3n Tur\u00edstica de Playa Penca Punta Cacique Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/playa-penca-punta-cacique-costa-rica-2.jpg\",\"datePublished\":\"2012-04-23T17:46:36+00:00\",\"dateModified\":\"2023-02-14T15:20:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"description\":\"Playa Penca Punta Cacique Costa Rica: mapa con direcci\u00f3n, fotos, video, bus y tel\u00e9fonos, c\u00f3mo llegar, ubicaci\u00f3n WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/playa-penca-punta-cacique-costa-rica-2.jpg?fit=1920%2C422&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/playa-penca-punta-cacique-costa-rica-2.jpg?fit=1920%2C422&ssl=1\",\"width\":1920,\"height\":422,\"caption\":\"Playa Penca Punta Cacique Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-penca-punta-cacique-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Playa Penca Punta Cacique Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informaci\u00f3n Tur\u00edstica de Playa Penca Punta Cacique Costa Rica","description":"Playa Penca Punta Cacique Costa Rica: mapa con direcci\u00f3n, fotos, video, bus y tel\u00e9fonos, c\u00f3mo llegar, ubicaci\u00f3n WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Informaci\u00f3n Tur\u00edstica de Playa Penca Punta Cacique Costa Rica","og_description":"Playa Penca Punta Cacique Costa Rica: mapa con direcci\u00f3n, fotos, video, bus y tel\u00e9fonos, c\u00f3mo llegar, ubicaci\u00f3n WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2012-04-23T17:46:36+00:00","article_modified_time":"2023-02-14T15:20:25+00:00","og_image":[{"url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2019\/03\/playa-penca-punta-cacique-costa-rica-2.jpg?w=828&#038;h=550&#038;ssl=1","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Playa Penca Punta Cacique Costa Rica","datePublished":"2012-04-23T17:46:36+00:00","dateModified":"2023-02-14T15:20:25+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/"},"wordCount":547,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg","keywords":["Playas Bonitas en Guanacaste","Playas de Guanacaste","Playas en Guanacaste Costa Rica"],"articleSection":["50503","Guanacaste","Playas de Costa Rica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/","name":"Informaci\u00f3n Tur\u00edstica de Playa Penca Punta Cacique Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg","datePublished":"2012-04-23T17:46:36+00:00","dateModified":"2023-02-14T15:20:25+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"description":"Playa Penca Punta Cacique Costa Rica: mapa con direcci\u00f3n, fotos, video, bus y tel\u00e9fonos, c\u00f3mo llegar, ubicaci\u00f3n WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?fit=1920%2C422&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-penca-punta-cacique-costa-rica-2.jpg?fit=1920%2C422&ssl=1","width":1920,"height":422,"caption":"Playa Penca Punta Cacique Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/playa-penca-punta-cacique-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Playa Penca Punta Cacique Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-1y7","jetpack-related-posts":[{"id":5984,"url":"https:\/\/costaricainfolink.com\/es\/playa-hermosa-en-guanacaste-costa-rica\/","url_meta":{"origin":5959,"position":0},"title":"Playa Hermosa en Guanacaste, Costa Rica","author":"Costa Rica Info Link","date":"1 mayo 2012","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Penca Punta Cacique y Playa Bonita en Guanacaste, Costa Rica. Coordenadas para GPS de playa Hermosa: 10.576574,-85.676565 (10\u00b034'35.67\"N, 85\u00b040'35.63\"W) Distrito: Sardinal, cant\u00f3n: Carrillo, provincia: Guanacaste C\u00f3digo postal de la zona: 50503. Playa Hermosa es una extensa y bella playa de unos 2km de largo, con arena blanca\u2026","rel":"","context":"En \u00ab50503\u00bb","block_context":{"text":"50503","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/50503\/"},"img":{"alt_text":"Playa Hermosa, Guanacaste, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-hermosa-guanacaste-costa-rica-15.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-hermosa-guanacaste-costa-rica-15.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-hermosa-guanacaste-costa-rica-15.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-hermosa-guanacaste-costa-rica-15.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-hermosa-guanacaste-costa-rica-15.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/05\/playa-hermosa-guanacaste-costa-rica-15.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":5892,"url":"https:\/\/costaricainfolink.com\/es\/playas-del-coco-costa-rica\/","url_meta":{"origin":5959,"position":1},"title":"Playas del Coco Costa Rica","author":"Costa Rica Info Link","date":"16 abril 2012","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Ocotal y Playa Penca Punta Cacique en Guanacaste, Costa Rica. Coordenadas para GPS de playas del Coco: 10.551831,-85.697673 (10\u00b033'06.59\"N, 85\u00b041'51.62\"W) Distrito: Sardinal, cant\u00f3n: Carrillo, provincia: Guanacaste C\u00f3digo postal de la zona: 50503. Hoteles \u00b7 Restaurantes Playas del Coco Costa Rica es una hermosa playa de arena gris\u2026","rel":"","context":"En \u00ab50503\u00bb","block_context":{"text":"50503","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/50503\/"},"img":{"alt_text":"Playas del Coco Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-del-coco-costa-rica-4.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-del-coco-costa-rica-4.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-del-coco-costa-rica-4.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-del-coco-costa-rica-4.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-del-coco-costa-rica-4.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-del-coco-costa-rica-4.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":5643,"url":"https:\/\/costaricainfolink.com\/es\/playa-la-penca-costa-rica\/","url_meta":{"origin":5959,"position":2},"title":"Playa La Penca Costa Rica","author":"Costa Rica Info Link","date":"14 marzo 2012","format":false,"excerpt":"Playa Penca Donde Queda? Ubicaci\u00f3n: entre Playa Potrero y Playa Prieta en Guanacaste, Costa Rica. Coordenadas para GPS: 10.460002,-85.775671 (10\u00b027'36.01\"N, 85\u00b046'32.42\"W) Distrito: Tempate, cant\u00f3n: Santa Cruz, provincia: Guanacaste C\u00f3digo postal de la zona: 50304 Playa La Penca Costa Rica es una tranquila y hermosa semi bah\u00eda de arena blanca con\u2026","rel":"","context":"En \u00ab50304\u00bb","block_context":{"text":"50304","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/50304\/"},"img":{"alt_text":"Playa La Penca Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-3-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-3-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-3-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-3-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-3-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-3-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":5788,"url":"https:\/\/costaricainfolink.com\/es\/playa-zapotal-costa-rica\/","url_meta":{"origin":5959,"position":3},"title":"Playa Zapotal Costa Rica","author":"Costa Rica Info Link","date":"29 marzo 2012","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Dantita y Playa Matapalo en Guanacaste, Costa Rica. Coordenadas para GPS: 10.501626,-85.797615 (10\u00b030'05.85\"N, 85\u00b047'51.41\"W) Distrito: Sardinal, cant\u00f3n: Carrillo, provincia: Guanacaste C\u00f3digo postal de la zona: 50503. Playa Zapotal es una remota y hermosa playa de arena gris clara y tranquilas aguas, ubicada en la provincia de Guanacaste.\u2026","rel":"","context":"En \u00ab50503\u00bb","block_context":{"text":"50503","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/50503\/"},"img":{"alt_text":"Playa Zapotal Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-zapotal-guanacaste-costa-rica-panoramicas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-zapotal-guanacaste-costa-rica-panoramicas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-zapotal-guanacaste-costa-rica-panoramicas.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-zapotal-guanacaste-costa-rica-panoramicas.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/03\/playa-zapotal-guanacaste-costa-rica-panoramicas.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5835,"url":"https:\/\/costaricainfolink.com\/es\/bahia-pez-vela-costa-rica\/","url_meta":{"origin":5959,"position":4},"title":"Bah\u00eda Pez Vela Costa Rica","author":"Costa Rica Info Link","date":"9 abril 2012","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Matapalo y Playa Ocotal en Guanacaste, Costa Rica. Coordenadas para GPS a la entrada de Bah\u00eda Pez Vela: 10.544141,-85.719492 (10\u00b032'38.91\"N, 85\u00b043'10.17\"W) Coordenadas para GPS de Bah\u00eda Pez Vela: 10.543439,-85.728594 (10\u00b032'36.38\"N, 85\u00b043'42.94\"W) Distrito: Sardinal, cant\u00f3n: Carrillo, provincia: Guanacaste C\u00f3digo postal de la zona: 50503. Bah\u00eda Pez Vela es\u2026","rel":"","context":"En \u00ab50503\u00bb","block_context":{"text":"50503","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/50503\/"},"img":{"alt_text":"Playa Bah\u00eda Pez Vela Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-bahia-pez-vela-costa-rica-9-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-bahia-pez-vela-costa-rica-9-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-bahia-pez-vela-costa-rica-9-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-bahia-pez-vela-costa-rica-9-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-bahia-pez-vela-costa-rica-9-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-bahia-pez-vela-costa-rica-9-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":5812,"url":"https:\/\/costaricainfolink.com\/es\/playa-matapalo-guanacaste-costa-rica\/","url_meta":{"origin":5959,"position":5},"title":"Playa Matapalo en Guanacaste, Costa Rica","author":"Costa Rica Info Link","date":"4 abril 2012","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Zapotal y Playa Pez Vela en Guanacaste, Costa Rica. Coordenadas para GPS: 10.529164,-85.751638 (10\u00b031'44.99\"N, 85\u00b045'05.90\"W) Distrito: Sardinal, cant\u00f3n: Carrillo, provincia: Guanacaste C\u00f3digo postal de la zona: 50503. Playa Matapalo Guanacaste Costa Rica es una hermosa y extensa playa de arenas claras y aguas turquesas, muy rica en\u2026","rel":"","context":"En \u00ab50503\u00bb","block_context":{"text":"50503","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/50503\/"},"img":{"alt_text":"Playa Matapalo Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-matapalo-costa-rica-35.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-matapalo-costa-rica-35.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-matapalo-costa-rica-35.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-matapalo-costa-rica-35.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-matapalo-costa-rica-35.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/04\/playa-matapalo-costa-rica-35.jpg?resize=1400%2C800 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/5959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=5959"}],"version-history":[{"count":61,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/5959\/revisions"}],"predecessor-version":[{"id":19700,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/5959\/revisions\/19700"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=5959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=5959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=5959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}