{"id":7723,"date":"2013-01-03T07:13:30","date_gmt":"2013-01-03T12:13:30","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=7723"},"modified":"2018-03-26T09:13:59","modified_gmt":"2018-03-26T14:13:59","slug":"playa-tarcoles-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/","title":{"rendered":"Playa T\u00e1rcoles Costa Rica &#8211; Ubicaci\u00f3n, Fotos, Video"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"7736\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/playa-tarcoles-puntarenas-costa-rica-panoramica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg?fit=1667%2C300&amp;ssl=1\" data-orig-size=\"1667,300\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Playa T\u00e1rcoles en Garabito, Puntarenas, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg?fit=1024%2C184&amp;ssl=1\" class=\"aligncenter size-full wp-image-7736\" alt=\"Playa T\u00e1rcoles en Garabito, Puntarenas, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg?resize=1200%2C216&#038;ssl=1\" width=\"1200\" height=\"216\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg?w=1667&amp;ssl=1 1667w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg?resize=300%2C53&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg?resize=1024%2C184&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg?resize=150%2C26&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg?resize=400%2C71&amp;ssl=1 400w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p><strong>Ubicaci\u00f3n:<\/strong> entre Playa Azul y Playa La Pita en Puntarenas, Costa Rica.<br \/>\n<strong>Coordenadas para GPS de la entrada a playa T\u00e1rcoles:<\/strong> 9.760068,-84.626570 (9\u00b045&#8217;36.24&#8243;N, 84\u00b037&#8217;35.65&#8243;W)<br \/>\n<strong>Coordenadas para GPS de playa T\u00e1rcoles:<\/strong> 9.759754,-84.627771 (9\u00b045&#8217;35.11&#8243;N, 84\u00b037&#8217;39.97&#8243;W)<br \/>\n<strong>Distrito:<\/strong> T\u00e1rcoles <strong>cant\u00f3n:<\/strong> Garabito, <strong>provincia:<\/strong> Puntarenas.<br \/>\n<strong>C\u00f3digo postal de la zona:<\/strong> 61102.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1ezd0zdg\" target=\"_blank\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE Playa T\u00e1rcoles Costa Rica, Garabito, Puntarenas\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/9%C2%B045'35.1%22N+84%C2%B037'40.0%22W\/@9.7597593,-84.6299597,17z\/data=!3m1!4b1!4m5!3m4!1s0x0:0x0!8m2!3d9.759754!4d-84.627771\" target=\"_blank\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google Playa T\u00e1rcoles Costa Rica, Garabito, Puntarenas\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<p>Playa T\u00e1rcoles, ubicada en el cant\u00f3n de Garabito, Puntarenas, es una bella y tranquila playa de arenas gris\u00e1ceas y aguas azuladas.<\/p>\n<p>Se encuentra rodeada de una exuberante belleza natural que incluye bosques, manglares y lagunas que sirven de zona de anidaci\u00f3n para muchas aves, entre ellas la espectacular Guacamaya Roja o Lapa Roja (Ara macao) y la sin igual Esp\u00e1tula Rosada (Platalea ajaja), entre muchas otras.<\/p>\n<p>De hecho, playa T\u00e1rcoles ofrece una gran variedad de tipos de recreaci\u00f3n tales como viajes en botes por el r\u00edo, tour de cocodrilos, caminatas a la Catarata Manantial de Agua Viva, una de las cataratas m\u00e1s altas del pa\u00eds, o bien, relajarse en alguna de las piscinas naturales de la zona. Adem\u00e1s, es una playa de pescadores artesanales, por lo que es ideal para pescar. Sin embargo, debido a su cercan\u00eda con la desembocadura del R\u00edo T\u00e1rcoles, ba\u00f1arse en la zona es peligroso, ya que los cocodrilos pasan del r\u00edo al mar.<\/p>\n<p><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/_ZeKe-zvsbM?rel=0\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p><strong>C\u00f3mo llegar a Playa T\u00e1rcoles en Garabito, Puntarenas?<\/strong><\/p>\n<h2>Desde San Jos\u00e9<\/h2>\n<p>Conduzca al norte en direcci\u00f3n a Puntarenas por la carretera #27. Tome la salida de Poz\u00f3n (hacia Jac\u00f3), contin\u00fae por esta carretera unos 16 km (10 millas) y gire a la derecha hacia el pueblo de T\u00e1rcoles. Contin\u00fae por 1 km (0.6 millas), gire de nuevo a la derecha, contin\u00fae por unos 100 m (350 pi\u00e9s) y gire a la izquierda hasta llegar a playa T\u00e1rcoles. Esta ruta requiere un total de 1 hora desde San Jos\u00e9.<\/p>\n<h2>Desde el Aeropuerto Internacional Daniel Oduber Quir\u00f3s (LIR)<\/h2>\n<p>Conduzca hacia el Noreste en direcci\u00f3n a Liberia. Una vez en Liberia, debe continuar por la misma autopista en direcci\u00f3n hacia Puntarenas por unos 120 km (75 millas). Una vez en la entrada hacia Puntarenas, contin\u00fae por la ruta #27 hacia San Jos\u00e9 por unos 25 km (15 millas) hasta llegar a la entrada de Poz\u00f3n y T\u00e1rcoles, tome esta salida, contin\u00fae por unos 16 km (10 millas) y gire a la derecha hacia el pueblo de T\u00e1rcoles. Contin\u00fae por 1 km (0.6 millas), gire de nuevo a la derecha, contin\u00fae por unos 100 m (350 pi\u00e9s) y gire a la izquierda hasta llegar a playa T\u00e1rcoles. Esta ruta requiere un total de 2.5 horas.<\/p>\n<h2>En autob\u00fas:<\/h2>\n<p>No existen servicios de buses directos hasta Playa T\u00e1rcoles, sin embargo usted puede tomar un autob\u00fas de la ruta San Jos\u00e9 &#8211; T\u00e1rcoles (Transportes Morales, <a href=\"tel:+5062223-5567\">+506 2223-5567<\/a>), haciendo la parada en T\u00e1rcoles, el cual tarda unas 2 horas, y de ah\u00ed tomar un taxi o bien caminar hasta la playa. Se recomienda comprar el tiquete un d\u00eda antes para asegurar su espacio.<\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-a-playa-tarcoles\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica a Playa T\u00e1rcoles en Garabito, Puntarenas, Costa Rica<\/a><\/p>\n<p><a href=\"https:\/\/www.costaricainfolink.com\/fotos\/playa-tarcoles-costa-rica\/\" target=\"_blank\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"7733\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/playa-tarcoles-puntarenas-costa-rica001\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica001.jpg?fit=649%2C484&amp;ssl=1\" data-orig-size=\"649,484\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Playa T\u00e1rcoles en Garabito, Puntarenas, click en la foto para ver album m\u00e1s grande\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica001.jpg?fit=649%2C484&amp;ssl=1\" class=\"alignnone  wp-image-7733\" title=\"Playa T\u00e1rcoles en Garabito, Puntarenas, click en la foto para ver album m\u00e1s grande\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica001.jpg?resize=341%2C227&#038;ssl=1\" width=\"341\" height=\"227\" \/><\/a> <a href=\"https:\/\/www.costaricainfolink.com\/fotos\/playa-tarcoles-costa-rica\/\" target=\"_blank\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"7734\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/playa-tarcoles-puntarenas-costa-rica002\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica002.jpg?fit=645%2C484&amp;ssl=1\" data-orig-size=\"645,484\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Playa T\u00e1rcoles en Garabito, Puntarenas, click en la foto para ver album m\u00e1s grande\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica002.jpg?fit=645%2C484&amp;ssl=1\" class=\"alignnone  wp-image-7734\" title=\"Playa T\u00e1rcoles en Garabito, Puntarenas, click en la foto para ver album m\u00e1s grande\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica002.jpg?resize=341%2C227&#038;ssl=1\" width=\"341\" height=\"227\" \/><\/a> <a href=\"https:\/\/www.costaricainfolink.com\/fotos\/playa-tarcoles-costa-rica\/\" target=\"_blank\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"7735\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/playa-tarcoles-puntarenas-costa-rica003\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica003.jpg?fit=650%2C484&amp;ssl=1\" data-orig-size=\"650,484\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Playa T\u00e1rcoles en Garabito, Puntarenas, click en la foto para ver album m\u00e1s grande\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica003.jpg?fit=650%2C484&amp;ssl=1\" class=\"alignnone  wp-image-7735\" title=\"Playa T\u00e1rcoles en Garabito, Puntarenas, click en la foto para ver album m\u00e1s grande\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica003.jpg?resize=341%2C227&#038;ssl=1\" width=\"341\" height=\"227\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ubicaci\u00f3n: entre Playa Azul y Playa La Pita en Puntarenas, Costa Rica. Coordenadas para GPS de la entrada a playa T\u00e1rcoles: 9.760068,-84.626570 (9\u00b045&#8217;36.24&#8243;N, 84\u00b037&#8217;35.65&#8243;W) Coordenadas para GPS de playa T\u00e1rcoles: 9.759754,-84.627771 (9\u00b045&#8217;35.11&#8243;N, 84\u00b037&#8217;39.97&#8243;W) Distrito: T\u00e1rcoles cant\u00f3n: Garabito, provincia: Puntarenas. C\u00f3digo postal de la zona: 61102. Playa T\u00e1rcoles, ubicada en el cant\u00f3n de Garabito, Puntarenas, es &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Playa T\u00e1rcoles Costa Rica &#8211; Ubicaci\u00f3n, Fotos, Video\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/#more-7723\" aria-label=\"Leer m\u00e1s sobre Playa T\u00e1rcoles Costa Rica &#8211; Ubicaci\u00f3n, Fotos, Video\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[61,33,23],"tags":[],"class_list":["post-7723","post","type-post","status-publish","format-standard","hentry","category-61","category-playas-de-costa-rica","category-puntarenas","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Playa T\u00e1rcoles Costa Rica - Ubicaci\u00f3n, Fotos, Video<\/title>\n<meta name=\"description\" content=\"Playa Tarcoles Costa Rica en Garabito, Puntarenas: informacion, coordenadas para GPS, fotos, mapa con direccion, video, como llegar en autobus, ubicacion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playa T\u00e1rcoles Costa Rica - Ubicaci\u00f3n, Fotos, Video\" \/>\n<meta property=\"og:description\" content=\"Playa Tarcoles Costa Rica en Garabito, Puntarenas: informacion, coordenadas para GPS, fotos, mapa con direccion, video, como llegar en autobus, ubicacion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-03T12:13:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-26T14:13:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Playa T\u00e1rcoles Costa Rica &#8211; Ubicaci\u00f3n, Fotos, Video\",\"datePublished\":\"2013-01-03T12:13:30+00:00\",\"dateModified\":\"2018-03-26T14:13:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/\"},\"wordCount\":547,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg\",\"articleSection\":[\"61102\",\"Playas de Costa Rica\",\"Puntarenas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/\",\"name\":\"Playa T\u00e1rcoles Costa Rica - Ubicaci\u00f3n, Fotos, Video\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg\",\"datePublished\":\"2013-01-03T12:13:30+00:00\",\"dateModified\":\"2018-03-26T14:13:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"description\":\"Playa Tarcoles Costa Rica en Garabito, Puntarenas: informacion, coordenadas para GPS, fotos, mapa con direccion, video, como llegar en autobus, ubicacion.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-tarcoles-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Playa T\u00e1rcoles Costa Rica &#8211; Ubicaci\u00f3n, Fotos, Video\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playa T\u00e1rcoles Costa Rica - Ubicaci\u00f3n, Fotos, Video","description":"Playa Tarcoles Costa Rica en Garabito, Puntarenas: informacion, coordenadas para GPS, fotos, mapa con direccion, video, como llegar en autobus, ubicacion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Playa T\u00e1rcoles Costa Rica - Ubicaci\u00f3n, Fotos, Video","og_description":"Playa Tarcoles Costa Rica en Garabito, Puntarenas: informacion, coordenadas para GPS, fotos, mapa con direccion, video, como llegar en autobus, ubicacion.","og_url":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2013-01-03T12:13:30+00:00","article_modified_time":"2018-03-26T14:13:59+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Playa T\u00e1rcoles Costa Rica &#8211; Ubicaci\u00f3n, Fotos, Video","datePublished":"2013-01-03T12:13:30+00:00","dateModified":"2018-03-26T14:13:59+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/"},"wordCount":547,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg","articleSection":["61102","Playas de Costa Rica","Puntarenas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/","name":"Playa T\u00e1rcoles Costa Rica - Ubicaci\u00f3n, Fotos, Video","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg","datePublished":"2013-01-03T12:13:30+00:00","dateModified":"2018-03-26T14:13:59+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"description":"Playa Tarcoles Costa Rica en Garabito, Puntarenas: informacion, coordenadas para GPS, fotos, mapa con direccion, video, como llegar en autobus, ubicacion.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/playa-tarcoles-puntarenas-costa-rica-panoramica.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/playa-tarcoles-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Playa T\u00e1rcoles Costa Rica &#8211; Ubicaci\u00f3n, Fotos, Video"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-20z","jetpack-related-posts":[{"id":7738,"url":"https:\/\/costaricainfolink.com\/es\/playa-la-pita-costa-rica\/","url_meta":{"origin":7723,"position":0},"title":"Playa La Pita Costa Rica &#8211; Informaci\u00f3n, ubicaci\u00f3n, fotos, video","author":"Costa Rica Info Link","date":"3 enero 2013","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa T\u00e1rcoles y Playa Agujas en Puntarenas, Costa Rica. Coordenadas para GPS de la entrada a playa La Pita: 9.740358,-84.631376 (9\u00b044'25.28\"N, 84\u00b037'52.95\"W) Distrito: T\u00e1rcoles cant\u00f3n: Garabito, provincia: Puntarenas. C\u00f3digo postal de la zona: 61102. La Pita es una peque\u00f1a playa de de arenas gris\u00e1ceas y aguas azuladas dedicada\u2026","rel":"","context":"En \u00ab61102\u00bb","block_context":{"text":"61102","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/61102\/"},"img":{"alt_text":"Playa La Pita Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-39.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-39.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-39.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-39.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-39.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-39.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":7780,"url":"https:\/\/costaricainfolink.com\/es\/playa-agujas-costa-rica\/","url_meta":{"origin":7723,"position":1},"title":"Playa Agujas Costa Rica &#8211; Mapa, Fotos, Video","author":"Costa Rica Info Link","date":"27 febrero 2013","format":false,"excerpt":"Playa Agujas donde queda? Ubicaci\u00f3n: entre Playa La Pita y Playa Limoncito en Puntarenas, Costa Rica. Coordenadas para GPS de la entrada a playa Agujas: 9.716883,-84.632535 (9\u00b043'00.77\"N, 84\u00b037'57.12\"W) Coordenadas para GPS de playa Agujas: 9.722593,-84.652448 (9\u00b043'21.33\"N, 84\u00b039'08.81\"W) Distrito: T\u00e1rcoles cant\u00f3n: Garabito, provincia: Puntarenas. C\u00f3digo postal de la zona: 61102. Playa\u2026","rel":"","context":"En \u00ab61102\u00bb","block_context":{"text":"61102","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/61102\/"},"img":{"alt_text":"Playa Agujas Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-agujas-costa-rica-3.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-agujas-costa-rica-3.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-agujas-costa-rica-3.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-agujas-costa-rica-3.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-agujas-costa-rica-3.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-agujas-costa-rica-3.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":7667,"url":"https:\/\/costaricainfolink.com\/es\/playa-guacalillo-costa-rica\/","url_meta":{"origin":7723,"position":2},"title":"Playa Guacalillo Costa Rica","author":"Costa Rica Info Link","date":"21 diciembre 2012","format":false,"excerpt":"Playa Guacalillo donde queda? Ubicaci\u00f3n: entre Playa Bajamar y Playa Azul en Puntarenas, Costa Rica.Coordenadas para GPS: 9.832894,-84.673599 (9\u00b049'58.41\"N, 84\u00b040'24.95\"W)Coordenadas para GPS de la entrada a playa Guacalillo: 9.851475,-84.655227 (9\u00b051'05.31\"N, 84\u00b039'18.81\"W)Distrito: T\u00e1rcoles cant\u00f3n: Garabito, provincia: Puntarenas.C\u00f3digo postal de la zona: 61102. Playa Guacalillo es una extensa playa de unos 4km\u2026","rel":"","context":"En \u00ab61102\u00bb","block_context":{"text":"61102","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/61102\/"},"img":{"alt_text":"Playa Guacalillo Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":7995,"url":"https:\/\/costaricainfolink.com\/es\/playa-palma-costa-rica\/","url_meta":{"origin":7723,"position":3},"title":"Playa Palma Costa Rica","author":"Costa Rica Info Link","date":"17 marzo 2013","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Bejuco y Playa Palo Seco en Puntarenas, Costa Rica.Coordenadas para GPS de la entrada a playa Palma: 9.523078,-84.371615 (9\u00b031'23.08\"N, 84\u00b022'17.81\"W)Coordenadas para GPS de playa Palma: 9.504677,-84.381631 (9\u00b030'16.83\"N, 84\u00b022'53.87\"W)Distrito: Parrita, cant\u00f3n: Parrita, provincia: Puntarenas.C\u00f3digo postal de la zona: 60901. \u00a0\u00a0 Playa Palma, tambi\u00e9n conocida como Playa Bandera, es\u2026","rel":"","context":"En \u00ab60901\u00bb","block_context":{"text":"60901","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60901\/"},"img":{"alt_text":"Playa Palma Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-57.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-57.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-57.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-57.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-57.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-57.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":8078,"url":"https:\/\/costaricainfolink.com\/es\/playa-gemelas-costa-rica\/","url_meta":{"origin":7723,"position":4},"title":"Playa Gemelas Costa Rica","author":"Costa Rica Info Link","date":"22 marzo 2013","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Manuel Antonio y Playa Puerto Escondido en Puntarenas, Costa Rica. Coordenadas para GPS de la entrada a playa Gemelas: 9.391385,-84.149654 (9\u00b023'28.98\"N, 84\u00b008'58.75\"W) Coordenadas para GPS de playa Gemelas: 9.379899,-84.139823 (9\u00b022'47.63\"N, 84\u00b008'23.36\"W) Distrito: Quepos, cant\u00f3n: Aguirre, provincia: Puntarenas. C\u00f3digo postal de la zona: 60601. Playa Gemelas es una\u2026","rel":"","context":"En \u00ab60601\u00bb","block_context":{"text":"60601","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60601\/"},"img":{"alt_text":"Playa Gemelas en Aguirre, Puntarenas, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/playa-gemelas-puntarenas-costa-rica-panoramica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/playa-gemelas-puntarenas-costa-rica-panoramica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/playa-gemelas-puntarenas-costa-rica-panoramica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/playa-gemelas-puntarenas-costa-rica-panoramica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/playa-gemelas-puntarenas-costa-rica-panoramica.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7931,"url":"https:\/\/costaricainfolink.com\/es\/playa-hermosa-en-puntarenas-costa-rica\/","url_meta":{"origin":7723,"position":5},"title":"Playa Hermosa en Puntarenas, Costa Rica","author":"Costa Rica Info Link","date":"8 marzo 2013","format":false,"excerpt":"Donde queda Playa Hermosa? Ubicaci\u00f3n: entre Playa Jac\u00f3 y Playa Esterillos en Puntarenas, Costa Rica.Coordenadas para GPS de playa Hermosa: 9.576397,-84.606346 (9\u00b034'35.02\"N, 84\u00b036'22.84\"W)Coordenadas para GPS de la entrada a playa Hermosa: 9.577148,-84.605638 (9\u00b034'37.73\"N, 84\u00b036'20.29\"W)Distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas.C\u00f3digo postal de la zona: 61101. \u00a0\u00a0 Playa Hermosa es una amplia\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"Playa Hermosa Costa Rica en Jac\u00f3 Garabito Puntarenas","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Hermosa-Costa-Rica-en-Jaco-Garabito-Puntarenas-7.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Hermosa-Costa-Rica-en-Jaco-Garabito-Puntarenas-7.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Hermosa-Costa-Rica-en-Jaco-Garabito-Puntarenas-7.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Hermosa-Costa-Rica-en-Jaco-Garabito-Puntarenas-7.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Hermosa-Costa-Rica-en-Jaco-Garabito-Puntarenas-7.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2013\/03\/Playa-Hermosa-Costa-Rica-en-Jaco-Garabito-Puntarenas-7.jpg?resize=1400%2C800 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/7723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=7723"}],"version-history":[{"count":21,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/7723\/revisions"}],"predecessor-version":[{"id":17817,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/7723\/revisions\/17817"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=7723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=7723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=7723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}