{"id":7866,"date":"2012-12-04T10:52:58","date_gmt":"2012-12-04T15:52:58","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=7866"},"modified":"2026-04-27T06:58:31","modified_gmt":"2026-04-27T11:58:31","slug":"playa-caldera-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/","title":{"rendered":"Playa Caldera Costa Rica"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ubicaci\u00f3n<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Entre Playa Tivives y <a href=\"https:\/\/costaricainfolink.com\/es\/playa-dona-ana-costa-rica\/\"><strong>Playa Do\u00f1a Ana<\/strong><\/a> en Puntarenas, Costa Rica.<br><strong>Coordenadas para GPS de playa Caldera:<\/strong> 9.923993,-84.714117 (9\u00b055&#8217;26.37&#8243;N, 84\u00b042&#8217;50.82&#8243;W)<br><strong>Distrito:<\/strong> Espir\u00edtu Santo, <strong>cant\u00f3n:<\/strong> Esparza, <strong>provincia:<\/strong> Puntarenas.<br><strong>C\u00f3digo postal de la zona:<\/strong> 60201.<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-8f761849 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full wp-container-content-e1bb55cb\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2012\/12\/waze2026.webp?ssl=1\" target=\"_blank\" rel=\" noreferrer noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2012\/12\/waze2026.webp?w=1200&#038;ssl=1\" alt=\"Ubicaci\u00f3n en WAZE de Playa Caldera Costa Rica\" class=\"wp-image-19898\" style=\"object-fit:cover\" title=\"Ubicaci\u00f3n en WAZE de Playa Caldera Costa Rica\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized wp-container-content-e1bb55cb\"><a href=\"https:\/\/maps.app.goo.gl\/bH4BHJhYS6FpQCuq9\" target=\"_blank\" rel=\" noreferrer noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/en\/wp-content\/uploads\/2026\/04\/googlemaps20262.webp?w=1200&#038;ssl=1\" alt=\"Ubicaci\u00f3n en Mapas de Google de Playa Caldera Costa Rica\" class=\"wp-image-19887\" style=\"object-fit:cover;width:50px;height:50px\" title=\"Ubicaci\u00f3n en Mapas de Google de Playa Caldera Costa Rica\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1200\" height=\"900\" data-attachment-id=\"22130\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-36\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-36.jpg?fit=2000%2C1500&amp;ssl=1\" data-orig-size=\"2000,1500\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-36.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22130\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-36.jpg?resize=1200%2C900&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22130\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-36.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-36.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-36.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-36.jpg?w=2000&amp;ssl=1 2000w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1200\" height=\"900\" data-attachment-id=\"22129\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-2.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-2.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22129\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-2.jpg?resize=1200%2C900&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22129\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-2.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-2.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-2.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-2.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-2.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1200\" height=\"887\" data-attachment-id=\"22131\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-14-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-1.jpg?fit=2500%2C1848&amp;ssl=1\" data-orig-size=\"2500,1848\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-1.jpg?fit=1200%2C887&amp;ssl=1\" data-id=\"22131\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-1.jpg?resize=1200%2C887&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22131\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-1.jpg?resize=1200%2C887&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-1.jpg?resize=768%2C568&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-1.jpg?resize=1536%2C1135&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-1.jpg?resize=2048%2C1514&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-1.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Restaurantes<\/h2>\n\n\n\n<ul class=\"wp-block-list has-medium-font-size\">\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-leda\/\" target=\"_blank\" rel=\"noreferrer noopener\">Leda Restaurante y Marisquer\u00eda<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/costa-del-sol-puntarenas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Costa del Sol Restaurante y Hotel<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/maps.app.goo.gl\/U7M6R8Wv4CjyP6Nh6\" target=\"_blank\" rel=\"noreferrer noopener\">La Casa del Sabor Restaurante<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/maps.app.goo.gl\/98ijXQ7fm5F97qfD7\" target=\"_blank\" rel=\"noreferrer noopener\">Marisquer\u00eda Mar Azul<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/maps.app.goo.gl\/DcLxMmgBqtes8VU49\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e1baris <\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"thingstodo\">Cosas que hacer<\/h2>\n\n\n\n<ul class=\"wp-block-list has-medium-font-size\">\n<li><a href=\"https:\/\/maps.app.goo.gl\/85pSWLJdEfimNsFUA\" target=\"_blank\" rel=\"noreferrer noopener\">Natives Paddleboard Tour<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/maps.app.goo.gl\/Mzs2LErZANJMuNCf6\" target=\"_blank\" rel=\"noreferrer noopener\">Fishing Tours and Kayak Rental \u2014 Javi&#8217;s Little Shop<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/maps.app.goo.gl\/LXFVXo3Vvckrfbfk6\" target=\"_blank\" rel=\"noreferrer noopener\">Mel\u00e9ndez Tours &amp; Travel<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/costaricainfolink.com\/es\/museo-historico-marino-de-la-ciudad-de-puntarenas-costa-rica\/\" target=\"_blank\" rel=\"noreferrer noopener\">Parque Marino del Pac\u00edfico<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/maps.app.goo.gl\/deaTLBjvDwQjzDJ27\" target=\"_blank\" rel=\"noreferrer noopener\">Costa Tours<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/ParapenteCaldera\/\" target=\"_blank\" rel=\"noreferrer noopener\">Parapente<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Playa de Caldera, mejor conocida como Puerto Caldera, es una extensa playa de 3,5 km con arenas gris\u00e1ceas, aguas azuladas de fuerte oleaje e impresionantes acantilados escarpados, ubicada 28km al Sur de Puntarenas, o bien 26 km al oeste de Orotina.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Caldera es una zona con gran atractivo recreativo, en cuyos alrededores existe un bosque tropical seco con transici\u00f3n a h\u00famedo. De hecho, esta belleza natural de la regi\u00f3n es una de las atracciones principales de playa Caldera. Su selva tropical, que comienza justo dentro de la l\u00ednea costera y contin\u00faa arriba hacia las monta\u00f1as, cuenta con hermosos r\u00edos, cascadas, parques y reservas naturales, como lo es La Zona Protectora Tivives, una importante \u00e1rea forestal que protege uno de los \u00faltimos remanentes costeros del bosque seco tropical en la Regi\u00f3n Pac\u00edfico Central, la cual se encuentra a 5 km al sur del puerto.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Playa Caldera es ideal para disfrutar del sol, el mar y la playa, tomando precauciones a la hora del ba\u00f1o tanto en el mar como en el estero en marea baja debido a las fuertes corrientes. Adem\u00e1s, el estuario se puede recorrer en lancha para observar la flora y fauna del manglar. Por otro lado, en las inmediaciones de playa Caldera se encuentra el Cerro Coyolar desde el cual se puede observar la belleza del paisaje. De hecho, esta zona tambi\u00e9n es utilizada con frecuencia para vuelos en parapente desde el acantilado que domina la bah\u00eda de Caldera, perfecto para el turismo de aventura en busca de alg\u00fan tipo de acci\u00f3n.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Playa de Caldera, es adem\u00e1s el hogar del puerto naviero m\u00e1s grande e importante para usos comerciales de la costa Pac\u00edfica de Costa Rica, as\u00ed como tambi\u00e9n acoge buques de cruceros. Caldera comenz\u00f3 a funcionar como puerto en 1577, momento cuando el comercio exterior mar\u00edtimo fue trasladado all\u00ed desde la ciudad de Puntarenas en 1834. El puerto de Caldera que es utilizado actualmente fue creado de forma artificial en 1978, iniciando operaciones hasta 1981, luego de que fuera descontinuado para usos comerciales el principal de Puntarenas, ya peque\u00f1o y obsoleto para embarcaciones de gran calado. Actualmente es administrado por la Sociedad Portuaria de Caldera, empresa colombiana, con quien Costa Rica tiene un contrato por tiempo indefinido para la administraci\u00f3n del puerto. Puerto Caldera juega un papel vital en el comercio de Costa Rica con el mundo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n  <div class=\"wp-block-embed__wrapper\">\n    <iframe \n      title=\"Caldera Beach Costa Rica \u2014 Video\"\n      width=\"960\" \n      height=\"540\"\n      src=\"https:\/\/www.youtube-nocookie.com\/embed\/ZhZ6bOIkTqE?version=3&#038;rel=0\"\n      allowfullscreen=\"true\"\n      style=\"border:0;\"\n      loading=\"lazy\"\n      sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation\">\n    <\/iframe>\n  <\/div>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3mo llegar a Playa Caldera en Puntarenas?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Desde San Jos\u00e9<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conduzca al norte en direcci\u00f3n a Puntarenas por la carretera #27, pasando por los tres peajes, hasta llegar a playa Caldera. Esta ruta requiere un total de 1 hora desde San Jos\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Desde el Aeropuerto Internacional Daniel Oduber Quir\u00f3s (LIR)<\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Conduzca hacia el Noreste en direcci\u00f3n a Liberia. Una vez en Liberia, debe continuar por la misma autopista en direcci\u00f3n hacia San Jos\u00e9 por unos 120 km (75 millas) hasta toparse con la desviaci\u00f3n hacia Puntarenas. T\u00f3mela y contin\u00fae por esta carretera en direcci\u00f3n a San Jos\u00e9 por unos 13 km (8 millas), hasta llegar a playa Caldera. Esta ruta requiere un total de 2.5 horas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">En autob\u00fas:<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Usted puede tomar un autob\u00fas de la ruta San Jos\u00e9 &#8211; Puntarenas (Empresarios Unidos, <a href=\"tel:+50622220064\">+506 2222-0064<\/a>), el cual tarda unas 2 horas, haciendo la parada en playa Caldera. Se recomienda comprar el tiquete un d\u00eda antes para asegurar su espacio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-a-playa-caldera\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica a Playa Caldera en Puntarenas, Puntarenas, Costa Rica<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Galer\u00eda<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22154\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-1-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-1-1.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-1-1.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22154\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-1-1.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22154\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-1-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-1-1.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-1-1.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-1-1.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-1-1.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22158\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-3\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-3.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-3.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22158\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-3.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22158\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-3.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-3.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-3.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-3.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-3.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22166\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-4\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-4.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-4.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22166\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-4.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22166\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-4.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-4.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-4.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-4.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-4.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22159\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-5\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-5.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-5.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22159\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-5.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22159\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-5.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-5.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-5.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-5.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-5.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"566\" data-attachment-id=\"22156\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-6\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-6.jpg?fit=2500%2C1844&amp;ssl=1\" data-orig-size=\"2500,1844\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-6.jpg?fit=1200%2C885&amp;ssl=1\" data-id=\"22156\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-6.jpg?resize=768%2C566&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22156\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-6.jpg?resize=768%2C566&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-6.jpg?resize=1200%2C885&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-6.jpg?resize=1536%2C1133&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-6.jpg?resize=2048%2C1511&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-6.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"571\" data-attachment-id=\"22157\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-7\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-7.jpg?fit=2500%2C1860&amp;ssl=1\" data-orig-size=\"2500,1860\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-7.jpg?fit=1200%2C893&amp;ssl=1\" data-id=\"22157\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-7.jpg?resize=768%2C571&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22157\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-7.jpg?resize=768%2C571&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-7.jpg?resize=1200%2C893&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-7.jpg?resize=1536%2C1143&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-7.jpg?resize=2048%2C1524&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-7.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22161\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-9\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-9.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-9.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22161\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-9.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22161\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-9.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-9.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-9.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-9.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-9.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22169\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-10\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-10.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-10.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22169\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-10.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22169\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-10.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-10.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-10.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-10.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-10.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"573\" data-attachment-id=\"22163\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-11\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-11.jpg?fit=2500%2C1866&amp;ssl=1\" data-orig-size=\"2500,1866\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-11.jpg?fit=1200%2C896&amp;ssl=1\" data-id=\"22163\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-11.jpg?resize=768%2C573&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22163\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-11.jpg?resize=768%2C573&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-11.jpg?resize=1200%2C896&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-11.jpg?resize=1536%2C1146&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-11.jpg?resize=2048%2C1529&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-11.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22155\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-12\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-12.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-12.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22155\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-12.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22155\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-12.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-12.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-12.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-12.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-12.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22162\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-13-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-13-1.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-13-1.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22162\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-13-1.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22162\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-13-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-13-1.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-13-1.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-13-1.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-13-1.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"568\" data-attachment-id=\"22165\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-14-3\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-2.jpg?fit=2500%2C1848&amp;ssl=1\" data-orig-size=\"2500,1848\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-2.jpg?fit=1200%2C887&amp;ssl=1\" data-id=\"22165\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-2.jpg?resize=768%2C568&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22165\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-2.jpg?resize=768%2C568&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-2.jpg?resize=1200%2C887&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-2.jpg?resize=1536%2C1135&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-2.jpg?resize=2048%2C1514&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-14-2.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22164\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-15\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-15.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-15.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22164\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-15.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22164\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-15.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-15.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-15.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-15.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-15.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22160\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-16\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-16.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-16.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22160\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-16.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22160\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-16.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-16.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-16.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-16.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-16.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22167\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-17\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-17.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-17.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22167\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-17.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22167\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-17.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-17.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-17.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-17.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-17.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22168\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-18\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-18.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-18.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22168\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-18.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22168\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-18.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-18.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-18.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-18.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-18.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22170\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-19\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-19.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-19.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22170\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-19.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22170\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-19.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-19.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-19.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-19.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-19.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22171\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-20-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-20-1.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-20-1.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22171\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-20-1.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22171\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-20-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-20-1.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-20-1.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-20-1.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-20-1.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22172\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-21\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-21.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-21.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22172\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-21.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22172\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-21.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-21.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-21.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-21.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-21.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22174\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-22\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-22.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-22.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22174\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-22.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22174\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-22.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-22.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-22.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-22.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-22.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"567\" data-attachment-id=\"22175\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-23\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-23.jpg?fit=2500%2C1847&amp;ssl=1\" data-orig-size=\"2500,1847\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-23.jpg?fit=1200%2C887&amp;ssl=1\" data-id=\"22175\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-23.jpg?resize=768%2C567&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22175\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-23.jpg?resize=768%2C567&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-23.jpg?resize=1200%2C887&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-23.jpg?resize=1536%2C1135&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-23.jpg?resize=2048%2C1513&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-23.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"574\" data-attachment-id=\"22173\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-24\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-24.jpg?fit=2500%2C1867&amp;ssl=1\" data-orig-size=\"2500,1867\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-24.jpg?fit=1200%2C896&amp;ssl=1\" data-id=\"22173\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-24.jpg?resize=768%2C574&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22173\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-24.jpg?resize=768%2C574&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-24.jpg?resize=1200%2C896&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-24.jpg?resize=1536%2C1147&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-24.jpg?resize=2048%2C1529&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-24.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22177\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-25\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-25.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-25.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22177\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-25.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22177\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-25.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-25.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-25.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-25.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-25.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22176\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-26\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-26.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-26.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22176\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-26.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22176\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-26.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-26.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-26.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-26.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-26.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22179\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-27\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-27.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-27.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22179\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-27.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22179\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-27.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-27.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-27.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-27.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-27.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22181\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-28\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-28.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-28.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22181\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-28.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22181\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-28.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-28.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-28.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-28.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-28.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22178\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-29\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-29.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-29.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22178\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-29.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22178\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-29.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-29.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-29.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-29.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-29.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22180\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-30\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-30.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-30.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22180\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-30.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22180\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-30.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-30.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-30.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-30.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-30.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22182\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-31\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-31.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-31.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22182\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-31.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22182\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-31.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-31.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-31.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-31.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-31.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22183\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-32\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-32.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-32.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22183\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-32.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22183\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-32.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-32.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-32.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-32.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-32.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22184\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-33\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-33.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-33.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22184\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-33.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22184\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-33.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-33.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-33.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-33.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-33.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"576\" data-attachment-id=\"22186\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-34\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-34.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-34.jpg?fit=1200%2C900&amp;ssl=1\" data-id=\"22186\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-34.jpg?resize=768%2C576&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22186\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-34.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-34.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-34.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-34.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-34.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"567\" data-attachment-id=\"22185\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/playa-caldera-costa-rica-35\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-35.jpg?fit=2500%2C1847&amp;ssl=1\" data-orig-size=\"2500,1847\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playa Caldera Costa Rica\" data-image-description=\"&lt;p&gt;Playa Caldera Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-35.jpg?fit=1200%2C887&amp;ssl=1\" data-id=\"22185\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-35.jpg?resize=768%2C567&#038;ssl=1\" alt=\"Playa Caldera Costa Rica\" class=\"wp-image-22185\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-35.jpg?resize=768%2C567&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-35.jpg?resize=1200%2C887&amp;ssl=1 1200w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-35.jpg?resize=1536%2C1135&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-35.jpg?resize=2048%2C1513&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Caldera-Costa-Rica-35.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ubicaci\u00f3n Entre Playa Tivives y Playa Do\u00f1a Ana en Puntarenas, Costa Rica.Coordenadas para GPS de playa Caldera: 9.923993,-84.714117 (9\u00b055&#8217;26.37&#8243;N, 84\u00b042&#8217;50.82&#8243;W)Distrito: Espir\u00edtu Santo, cant\u00f3n: Esparza, provincia: Puntarenas.C\u00f3digo postal de la zona: 60201. Restaurantes Cosas que hacer Playa de Caldera, mejor conocida como Puerto Caldera, es una extensa playa de 3,5 km con arenas gris\u00e1ceas, aguas azuladas &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Playa Caldera Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/#more-7866\" aria-label=\"Leer m\u00e1s sobre Playa Caldera Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[115,33,23],"tags":[],"class_list":["post-7866","post","type-post","status-publish","format-standard","hentry","category-115","category-playas-de-costa-rica","category-puntarenas","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Playa Caldera Costa Rica - Fotos, Video, Bus y Tel\u00e9fonos<\/title>\n<meta name=\"description\" content=\"Playa Caldera en Espiritu Santo, Esparza, Puntarenas, Costa Rica. Fotos, video, bus y telefonos, ubicacion WAZE y mapas de Google, direcci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playa Caldera Costa Rica - Fotos, Video, Bus y Tel\u00e9fonos\" \/>\n<meta property=\"og:description\" content=\"Playa Caldera en Espiritu Santo, Esparza, Puntarenas, Costa Rica. Fotos, video, bus y telefonos, ubicacion WAZE y mapas de Google, direcci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-04T15:52:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T11:58:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2012\/12\/waze2026.webp\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Playa Caldera Costa Rica\",\"datePublished\":\"2012-12-04T15:52:58+00:00\",\"dateModified\":\"2026-04-27T11:58:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/\"},\"wordCount\":693,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/waze2026.webp\",\"articleSection\":[\"60201\",\"Playas de Costa Rica\",\"Puntarenas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/\",\"name\":\"Playa Caldera Costa Rica - Fotos, Video, Bus y Tel\u00e9fonos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/waze2026.webp\",\"datePublished\":\"2012-12-04T15:52:58+00:00\",\"dateModified\":\"2026-04-27T11:58:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"description\":\"Playa Caldera en Espiritu Santo, Esparza, Puntarenas, Costa Rica. Fotos, video, bus y telefonos, ubicacion WAZE y mapas de Google, direcci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/waze2026.webp\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/en\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/waze2026.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/playa-caldera-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Playa Caldera Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playa Caldera Costa Rica - Fotos, Video, Bus y Tel\u00e9fonos","description":"Playa Caldera en Espiritu Santo, Esparza, Puntarenas, Costa Rica. Fotos, video, bus y telefonos, ubicacion WAZE y mapas de Google, direcci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Playa Caldera Costa Rica - Fotos, Video, Bus y Tel\u00e9fonos","og_description":"Playa Caldera en Espiritu Santo, Esparza, Puntarenas, Costa Rica. Fotos, video, bus y telefonos, ubicacion WAZE y mapas de Google, direcci\u00f3n.","og_url":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2012-12-04T15:52:58+00:00","article_modified_time":"2026-04-27T11:58:31+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2012\/12\/waze2026.webp","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Playa Caldera Costa Rica","datePublished":"2012-12-04T15:52:58+00:00","dateModified":"2026-04-27T11:58:31+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/"},"wordCount":693,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2012\/12\/waze2026.webp","articleSection":["60201","Playas de Costa Rica","Puntarenas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/","name":"Playa Caldera Costa Rica - Fotos, Video, Bus y Tel\u00e9fonos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2012\/12\/waze2026.webp","datePublished":"2012-12-04T15:52:58+00:00","dateModified":"2026-04-27T11:58:31+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"description":"Playa Caldera en Espiritu Santo, Esparza, Puntarenas, Costa Rica. Fotos, video, bus y telefonos, ubicacion WAZE y mapas de Google, direcci\u00f3n.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/#primaryimage","url":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2012\/12\/waze2026.webp","contentUrl":"https:\/\/costaricainfolink.com\/en\/wp-content\/uploads\/2012\/12\/waze2026.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/playa-caldera-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Playa Caldera Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-22S","jetpack-related-posts":[{"id":7842,"url":"https:\/\/costaricainfolink.com\/es\/playa-dona-ana-costa-rica\/","url_meta":{"origin":7866,"position":0},"title":"Playa Do\u00f1a Ana Costa Rica","author":"Costa Rica Info Link","date":"3 diciembre 2012","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Chacarita y Playa Caldera en Puntarenas, Costa Rica. Coordenadas para GPS de playa Do\u00f1a Ana: 9.957674,-84.735141 (9\u00b057'27.62\"N, 84\u00b044'06.50\"W) Distrito: Espir\u00edtu Santo, cant\u00f3n: Esparza, provincia: Puntarenas. C\u00f3digo postal de la zona: 60201. Playa Do\u00f1a Ana Costa Rica tambi\u00e9n conocida como playas de Do\u00f1a Ana, es una hermosa playa\u2026","rel":"","context":"En \u00ab60201\u00bb","block_context":{"text":"60201","link":"https:\/\/costaricainfolink.com\/es\/category\/60201\/"},"img":{"alt_text":"Playa Do\u00f1a Ana Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-dona-ana-puntarenas-costa-rica-panoramica1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-dona-ana-puntarenas-costa-rica-panoramica1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-dona-ana-puntarenas-costa-rica-panoramica1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-dona-ana-puntarenas-costa-rica-panoramica1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/02\/playa-dona-ana-puntarenas-costa-rica-panoramica1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7815,"url":"https:\/\/costaricainfolink.com\/es\/playa-chacarita-costa-rica\/","url_meta":{"origin":7866,"position":1},"title":"Playa Chacarita Costa Rica","author":"Costa Rica Info Link","date":"2 diciembre 2012","format":false,"excerpt":"Click the following link to read this page in English: Chacarita Beach Costa Rica Ubicaci\u00f3n: entre Playa Do\u00f1a Ana y Playa Puntarenas en Puntarenas, Costa Rica. Coordenadas para GPS de playa Chacarita: 9.974277,-84.753278 (9\u00b058'27.39\"N, 84\u00b045'11.80\"W) Distrito: Chacarita, cant\u00f3n: Puntarenas, provincia: Puntarenas. C\u00f3digo postal de la zona: 60112. Playa Chacarita es\u2026","rel":"","context":"En \u00ab60112\u00bb","block_context":{"text":"60112","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60112\/"},"img":{"alt_text":"Playa Chacarita en Puntarenas, Puntarenas, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-chacarita-puntarenas-costa-rica-panoramica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-chacarita-puntarenas-costa-rica-panoramica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-chacarita-puntarenas-costa-rica-panoramica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-chacarita-puntarenas-costa-rica-panoramica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-chacarita-puntarenas-costa-rica-panoramica.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2013\/01\/playa-chacarita-puntarenas-costa-rica-panoramica.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":19714,"url":"https:\/\/costaricainfolink.com\/es\/costa-rica-tiene-playas\/","url_meta":{"origin":7866,"position":2},"title":"Costa Rica tiene playas?","author":"Costa Rica Info Link","date":"15 febrero 2023","format":false,"excerpt":"Costa Rica cuenta con un total de 1228 kil\u00f3metros de litoral y alrededor de 600 playas. Playas de Guanacaste Avellanas Azul Bah\u00eda Junquillal Bah\u00eda Pez Vela Barco Quebrado Bejuco Blanca en La Cruz Blanca en Liberia Bonita Brasilito Buena Buena Vista Cabuyal Caletas en Nandayure Camaronal Carrillo Cocos Conchal Copal\u2026","rel":"","context":"En \u00abPlayas de Costa Rica\u00bb","block_context":{"text":"Playas de Costa Rica","link":"https:\/\/costaricainfolink.com\/es\/category\/playas-de-costa-rica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7760,"url":"https:\/\/costaricainfolink.com\/es\/playa-puntarenas-costa-rica\/","url_meta":{"origin":7866,"position":3},"title":"Playa Puntarenas Costa Rica","author":"Costa Rica Info Link","date":"1 diciembre 2012","format":false,"excerpt":"Ubicaci\u00f3n: junto a Playa Chacarita en Puntarenas, Costa Rica.Coordenadas para GPS de la entrada a playa Puntarenas: 9.974662,-84.844455 (9\u00b058'28.78\"N, 84\u00b050'40.03\"W)Distrito: Puntarenas, cant\u00f3n: Puntarenas, provincia: Puntarenas.C\u00f3digo postal de la zona: 60101. \u00a0\u00a0 https:\/\/youtu.be\/e5IUNEJTzlw?si=1cySjHtefDAH21QC Bus \u00b7 Restaurantes \u00b7 Hoteles \u00b7 Fotos \u00b7 Cosas que hacer Puntarenas es una extensa playa tipo rectil\u00ednea\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"Playa Puntarenas Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Puntarenas-Costa-Rica-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Puntarenas-Costa-Rica-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Puntarenas-Costa-Rica-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Puntarenas-Costa-Rica-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Puntarenas-Costa-Rica-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Puntarenas-Costa-Rica-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":7706,"url":"https:\/\/costaricainfolink.com\/es\/playa-azul-en-garabito-costa-rica\/","url_meta":{"origin":7866,"position":4},"title":"Playa Azul Costa Rica","author":"Costa Rica Info Link","date":"24 diciembre 2012","format":false,"excerpt":"Ubicaci\u00f3n: entre Playa Guacalillo y Playa T\u00e1rcoles en Puntarenas, Costa Rica.Distrito: T\u00e1rcoles cant\u00f3n: Garabito, provincia: Puntarenas.C\u00f3digo postal de la zona: 61102. \u00a0\u00a0 Playa Azul, ubicada en la desembocadura del r\u00edo T\u00e1rcoles, en Puntarenas, es una playa con arenas de color gris oscuro y aguas azuladas. Bus\u00a0\u00b7\u00a0Restaurantes\u00a0\u00b7\u00a0Hospedaje\u00a0\u00b7\u00a0Camping\u00a0\u00b7\u00a0Fotos\u00a0\u00b7\u00a0Cosas que hacer\u00a0\u00b7\u00a0Supermercados\u00a0\u00b7\u00a0Farmacias\u00a0\u00b7\u00a0Veterinaria Debido a\u2026","rel":"","context":"En \u00ab61102\u00bb","block_context":{"text":"61102","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/61102\/"},"img":{"alt_text":"Playa Azul Costa Rica en T\u00e1rcoles, Garabito, Puntarenas","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Azul-Costa-Rica-en-Tarcoles-Garabito-Puntarenas-13-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Azul-Costa-Rica-en-Tarcoles-Garabito-Puntarenas-13-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Azul-Costa-Rica-en-Tarcoles-Garabito-Puntarenas-13-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Azul-Costa-Rica-en-Tarcoles-Garabito-Puntarenas-13-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Azul-Costa-Rica-en-Tarcoles-Garabito-Puntarenas-13-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Azul-Costa-Rica-en-Tarcoles-Garabito-Puntarenas-13-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":7667,"url":"https:\/\/costaricainfolink.com\/es\/playa-guacalillo-costa-rica\/","url_meta":{"origin":7866,"position":5},"title":"Playa Guacalillo Costa Rica","author":"Costa Rica Info Link","date":"21 diciembre 2012","format":false,"excerpt":"Playa Guacalillo donde queda? Ubicaci\u00f3n: entre Playa Bajamar y Playa Azul en Puntarenas, Costa Rica.Coordenadas para GPS: 9.832894,-84.673599 (9\u00b049'58.41\"N, 84\u00b040'24.95\"W)Coordenadas para GPS de la entrada a playa Guacalillo: 9.851475,-84.655227 (9\u00b051'05.31\"N, 84\u00b039'18.81\"W)Distrito: T\u00e1rcoles cant\u00f3n: Garabito, provincia: Puntarenas.C\u00f3digo postal de la zona: 61102. Playa Guacalillo es una extensa playa de unos 4km\u2026","rel":"","context":"En \u00ab61102\u00bb","block_context":{"text":"61102","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/61102\/"},"img":{"alt_text":"Playa Guacalillo Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2012\/12\/Playa-Guacalillo-Costa-Rica-1.jpg?resize=1400%2C800 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/7866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=7866"}],"version-history":[{"count":57,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/7866\/revisions"}],"predecessor-version":[{"id":22195,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/7866\/revisions\/22195"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=7866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=7866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=7866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}