{"id":813,"date":"2009-07-11T08:58:03","date_gmt":"2009-07-11T13:58:03","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=813"},"modified":"2016-02-23T14:01:08","modified_gmt":"2016-02-23T19:01:08","slug":"museo-historico-tecnologico-del-grupo-ice-en-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/","title":{"rendered":"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica"},"content":{"rendered":"<h6>Click the following link to read this page in English: <a href=\"https:\/\/www.costaricainfolink.com\/en\/the-ice-group-technological-history-museum-costa-rica\/\">The ICE Group Technological History Museum Costa Rica<\/a><\/h6>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"821\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/museo-historico-tecnologico-grupo-ice-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg?fit=280%2C142&amp;ssl=1\" data-orig-size=\"280,142\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg?fit=280%2C142&amp;ssl=1\" class=\"aligncenter wp-image-821\" title=\"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg?resize=227%2C115&#038;ssl=1\" alt=\"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\" width=\"227\" height=\"115\" \/><\/p>\n<p>El Museo Hist\u00f3rico y Tecnol\u00f3gico del Grupo ICE nace el 1 de marzo de 1993, con la misi\u00f3n de rescatar y exhibir la <img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"822\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/museo-historico-tecnologico-grupo-ice-costa-rica-fachada\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica-fachada.jpg?fit=174%2C141&amp;ssl=1\" data-orig-size=\"174,141\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Fachada del Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica-fachada.jpg?fit=174%2C141&amp;ssl=1\" class=\"wp-image-822 alignright\" title=\"Fachada del Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica-fachada.jpg?resize=157%2C127&#038;ssl=1\" alt=\"Fachada del Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\" width=\"157\" height=\"127\" \/>riqueza hist\u00f3rica del Grupo ICE, es decir de la Compa\u00f1\u00eda Nacional de Fuerza y Luz (CNFL), el Instituto Costarricense de Electricidad (ICE) y Radiogr\u00e1fica Costarricense S.A. (RACSA). Desde entonces, los objetivos van orientados a investigar, educar y comunicar a la poblaci\u00f3n todo lo referente al desarrollo tecnol\u00f3gico de los servicios de electricidad y telecomunicaciones en Costa Rica.<\/p>\n<p>Con cada uno de los servicios, se busca satisfacer de manera eficaz las necesidades de informaci\u00f3n de todas aquellas personas que se interesan por el conocimiento de la historia y obras del Grupo ICE. Actualmente, el Museo forma parte de la Direcci\u00f3n de Mercadeo y Comunicaci\u00f3n Institucional, y cuenta con una exhibici\u00f3n de arte, documentos, fotos e historia de la electricidad y de las telecomunicaciones en Costa Rica.<\/p>\n<p><strong>Direcci\u00f3n:<\/strong> 400 metros Norte del ICE sobre calle Luisa, La Sabana, distrito: Mata Redonda, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10108.<br \/>\n<strong>Coordenadas para GPS:<\/strong> 9.942367,-84.101858 (9\u00b056&#8217;32.52&#8243;N, 84\u00b006&#8217;06.69&#8243;W)<br \/>\n<strong>Horario:<\/strong> de Lunes a Viernes de\u00a0 8 a.m. a 4 p.m.<br \/>\n<strong>Tel\u00e9fono:<\/strong> <a href=\"callto:+5062220-7656\">+506 2220-7656<\/a>, <a href=\"callto:+5062220-6387\">+506 2220-6387<\/a>, <a href=\"callto:+5062220-6497\">+506 2220-6497<\/a>, <a href=\"callto:+5062290-2890\">+506 2290-2890<\/a>.<\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-del-museo-historico-tecnologico-del-grupo-ice\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque Central, San Jos\u00e9, Costa Rica al Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en San Jos\u00e9, Costa Rica.<\/a><\/p>\n<h3><a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.google.com\/maps\/place\/9%C2%B056'29.6%22N+84%C2%B006'07.3%22W\/@9.9413072,-84.1020263,19z\/data=!4m2!3m1!1s0x0:0x0?hl=es\">Abrir en Mapas de Google<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Click the following link to read this page in English: The ICE Group Technological History Museum Costa Rica El Museo Hist\u00f3rico y Tecnol\u00f3gico del Grupo ICE nace el 1 de marzo de 1993, con la misi\u00f3n de rescatar y exhibir la riqueza hist\u00f3rica del Grupo ICE, es decir de la Compa\u00f1\u00eda Nacional de Fuerza y &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/#more-813\" aria-label=\"Leer m\u00e1s sobre Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[74,15,25],"tags":[],"class_list":["post-813","post","type-post","status-publish","format-standard","hentry","category-74","category-museos","category-san-jose","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica - Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica - Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Click the following link to read this page in English: The ICE Group Technological History Museum Costa Rica El Museo Hist\u00f3rico y Tecnol\u00f3gico del Grupo ICE nace el 1 de marzo de 1993, con la misi\u00f3n de rescatar y exhibir la riqueza hist\u00f3rica del Grupo ICE, es decir de la Compa\u00f1\u00eda Nacional de Fuerza y ... Leer M\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-11T13:58:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-23T19:01:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\",\"datePublished\":\"2009-07-11T13:58:03+00:00\",\"dateModified\":\"2016-02-23T19:01:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/\"},\"wordCount\":279,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg\",\"articleSection\":[\"10108\",\"Museos\",\"San Jos\u00e9\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/\",\"name\":\"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica - Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg\",\"datePublished\":\"2009-07-11T13:58:03+00:00\",\"dateModified\":\"2016-02-23T19:01:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica - Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica - Costa Rica","og_description":"Click the following link to read this page in English: The ICE Group Technological History Museum Costa Rica El Museo Hist\u00f3rico y Tecnol\u00f3gico del Grupo ICE nace el 1 de marzo de 1993, con la misi\u00f3n de rescatar y exhibir la riqueza hist\u00f3rica del Grupo ICE, es decir de la Compa\u00f1\u00eda Nacional de Fuerza y ... Leer M\u00e1s","og_url":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2009-07-11T13:58:03+00:00","article_modified_time":"2016-02-23T19:01:08+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica","datePublished":"2009-07-11T13:58:03+00:00","dateModified":"2016-02-23T19:01:08+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/"},"wordCount":279,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg","articleSection":["10108","Museos","San Jos\u00e9"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/","name":"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica - Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg","datePublished":"2009-07-11T13:58:03+00:00","dateModified":"2016-02-23T19:01:08+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-tecnologico-grupo-ice-costa-rica.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-tecnologico-del-grupo-ice-en-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Museo Hist\u00f3rico Tecnol\u00f3gico del Grupo ICE en Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-d7","jetpack-related-posts":[{"id":902,"url":"https:\/\/costaricainfolink.com\/es\/el-arte-y-los-museos-en-costa-rica\/","url_meta":{"origin":813,"position":0},"title":"El Arte y los Museos en Costa Rica","author":"Costa Rica Info Link","date":"12 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: Art and Museums in Costa Rica Museos en Costa Rica: Museos en San Jos\u00e9: Museo Nacional de Costa Rica, Calle 17, Avenida Central y 2, San Jos\u00e9. Tel\u00e9fono: +506 2211-5700 Museo del Jade, Calle 9 y 11, Avenida 7 y\u2026","rel":"","context":"En \u00abMuseos\u00bb","block_context":{"text":"Museos","link":"https:\/\/costaricainfolink.com\/es\/category\/museos\/"},"img":{"alt_text":"Museos de Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-jade-ins-costa-rica-pieza.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":491,"url":"https:\/\/costaricainfolink.com\/es\/museo-historico-marino-de-la-ciudad-de-puntarenas-costa-rica\/","url_meta":{"origin":813,"position":1},"title":"Museo Hist\u00f3rico Marino de la Ciudad de Puntarenas, Costa Rica","author":"Costa Rica Info Link","date":"3 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: Marine Historic Museum of Puntarenas City Costa Rica El Museo Hist\u00f3rico Marino de la Ciudad de Puntarenas no solo es un acuario con la vida marina existente hasta el Parque Nacional Isla del Coco, con especies de agua salada y\u2026","rel":"","context":"En \u00ab60101\u00bb","block_context":{"text":"60101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/60101\/"},"img":{"alt_text":"Museo Hist\u00f3rico Marino de la Ciudad de Puntarenas, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-marino-puntarenas-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":677,"url":"https:\/\/costaricainfolink.com\/es\/museo-historico-religioso-de-nuestra-senora-de-ujarras-costa-rica\/","url_meta":{"origin":813,"position":2},"title":"Museo Hist\u00f3rico Religioso de Nuestra Se\u00f1ora de Ujarr\u00e1s, Costa Rica","author":"Costa Rica Info Link","date":"7 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: Our Ujarr\u00e1s Lady Historical Religious Museum Costa Rica La idea de su creaci\u00f3n surge en la d\u00e9cada de los ochentas con el entonces p\u00e1rroco Jorge Picado, el cual invita a varios miembros de la comunidad para que se organicen y\u2026","rel":"","context":"En \u00ab30201\u00bb","block_context":{"text":"30201","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/30201\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/ujarras-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":696,"url":"https:\/\/costaricainfolink.com\/es\/museo-historico-etnografico-elias-leiva-quiros-del-colegio-san-luis-gonzaga-en-costa-rica\/","url_meta":{"origin":813,"position":3},"title":"Museo Hist\u00f3rico Etnogr\u00e1fico El\u00edas Leiva Quir\u00f3s del Colegio San Luis Gonzaga en Costa Rica","author":"Costa Rica Info Link","date":"8 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: The El\u00edas Leiva Quir\u00f3s of the San Luis Gonzaga High School Historical Ethnographic Museum Costa Rica El Museo Hist\u00f3rico Etnogr\u00e1fico El\u00edas Leiva Quir\u00f3s del Colegio San Luis Gonzaga tiene como objetivos conservar y exhibir la colecci\u00f3n arqueol\u00f3gica e hist\u00f3rica iniciada\u2026","rel":"","context":"En \u00ab30102\u00bb","block_context":{"text":"30102","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/30102\/"},"img":{"alt_text":"Fachada del Museo Hist\u00f3rico Etnogr\u00e1fico El\u00edas Leiva Quir\u00f3s del Colegio San Luis Gonzaga en Cartago, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-historico-etnografico-elias-leiva-quiros-cartago-costa-rica-fachada.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":828,"url":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/","url_meta":{"origin":813,"position":4},"title":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica","author":"Costa Rica Info Link","date":"11 julio 2009","format":false,"excerpt":"Direcci\u00f3n: en avenida 11, entre calles 25 y 27, Avenida 11, 100 metros este y 100 metros norte de la Iglesia Santa Teresita, Barrio Escalante, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101. Coordenadas para GPS: 9.936856,-84.065711 (9\u00b056'12.68\"N, 84\u00b003'56.56\"W) \u00a0\u00a0 Horario: de\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":593,"url":"https:\/\/costaricainfolink.com\/es\/museo-de-san-ramon-centro-cultural-historico-de-jose-figueres-ferrer-costa-rica\/","url_meta":{"origin":813,"position":5},"title":"Museo de San Ram\u00f3n (Centro Cultural e Hist\u00f3rico Jos\u00e9 Figueres Ferrer), Costa Rica","author":"Costa Rica Info Link","date":"6 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: The San Ram\u00f3n Museum (Jos\u00e9 Figueres Ferrer Historic Cultural Center) Costa Rica El Museo de San Ram\u00f3n o Centro Cultural e Hist\u00f3rico de Jos\u00e9 Figueres Ferrer es una instituci\u00f3n adscrita al Ministerio de Cultura y Juventud,\u00a0que tiene como prop\u00f3sito fomentar\u2026","rel":"","context":"En \u00ab20201\u00bb","block_context":{"text":"20201","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/20201\/"},"img":{"alt_text":"Museo de San Ram\u00f3n (Centro Cultural Hist\u00f3rico de Jos\u00e9 Figueres Ferrer), Alajuela, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-centro-cultural-historico-jose-figueres-ferrer-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=813"}],"version-history":[{"count":24,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/813\/revisions"}],"predecessor-version":[{"id":16884,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/813\/revisions\/16884"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}