{"id":828,"date":"2009-07-11T10:48:28","date_gmt":"2009-07-11T15:48:28","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=828"},"modified":"2022-03-15T18:45:01","modified_gmt":"2022-03-15T23:45:01","slug":"museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/","title":{"rendered":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"831\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg?fit=720%2C487&amp;ssl=1\" data-orig-size=\"720,487\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg?fit=720%2C487&amp;ssl=1\" class=\"wp-image-831 alignright\" title=\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg?resize=346%2C234&#038;ssl=1\" alt=\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\" width=\"346\" height=\"234\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg?resize=300%2C202&amp;ssl=1 300w\" sizes=\"(max-width: 346px) 100vw, 346px\" \/><strong>Direcci\u00f3n:<\/strong> en avenida 11, entre calles 25 y 27, Avenida 11, 100 metros este y 100 metros norte de la Iglesia Santa Teresita, Barrio Escalante, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101.<br \/>\n<strong>Coordenadas para GPS:<\/strong> 9.936856,-84.065711 (9\u00b056&#8217;12.68&#8243;N, 84\u00b003&#8217;56.56&#8243;W)<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0x1127\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/FXdBDAWDHLUJWZDV6\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p><strong>Horario:<\/strong> de Lunes a S\u00e1bado 9 a.m. a 5 p.m.<br \/>\n<strong>Sitio Web:<\/strong> <a href=\"http:\/\/www.mcj.go.cr\/\" target=\"_blank\" rel=\"nofollow noopener\">www.mcjdcr.go.cr<\/a><br \/>\n<strong>Tel\u00e9fono: <\/strong><a href=\"tel:+50622211239\">+506 2221-1239<\/a> \/ <a href=\"tel:+50622551218\">+506 2255-1218<\/a><\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-del-museo-historico-del-dr-rafael-angel-calderon-guardia\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque Central, San Jos\u00e9, Costa Rica al Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia en San Jos\u00e9, Costa Rica<\/a><\/p>\n<p>El Museo Hist\u00f3rico Dr. Rafael \u00c1ngel Calder\u00f3n Guardia abri\u00f3 sus puertas en marzo de 1994 aunque el decreto de creaci\u00f3n data de 1991 y debe su nombre al expresidente de la Rep\u00fablica (per\u00edodo 1940-1944), Benem\u00e9rito de la Patria y gran reformador social de Costa Rica, el cual en B\u00e9lgica conoci\u00f3 y se inspir\u00f3 en la doctrina social de la Iglesia Cat\u00f3lica, que fue su gu\u00eda para asumir una posici\u00f3n pol\u00edtica e ideol\u00f3gica a favor de los grupos m\u00e1s despose\u00eddos de la sociedad. Incursion\u00f3 en la vida pol\u00edtica en 1930 con un gran respaldo de los grupos populares.<\/p>\n<p>Su gobierno impuls\u00f3 la gran reforma social de Costa Rica que incluy\u00f3 la creaci\u00f3n de la Universidad de Costa Rica (1940) y de la Caja Costarricense de Seguro Social (1941), la inclusi\u00f3n del Cap\u00edtulo de las Garant\u00edas Sociales en la Constituci\u00f3n Pol\u00edtica (1943) y la promulgaci\u00f3n del primer C\u00f3digo de Trabajo (1943). Su visionaria obra gubernamental ayud\u00f3 a sentar las bases de justicia y paz social, valores que son orgullo de la Costa Rica actual.<\/p>\n<p>El inmueble alberga la Galer\u00eda Manuel de la Cruz Gonz\u00e1lez como parte del Museo y en ella se llevan a cabo exposiciones de arte de diversos pintores, escultores y artesanos. La casa que lo alberga es una antigua construcci\u00f3n de bahareque franc\u00e9s de 800 metros cuadrados, construida en 1912 utilizando una interpretaci\u00f3n arquitect\u00f3nica neocl\u00e1sica. Es la antigua mansi\u00f3n familiar Calder\u00f3n, un edificio hist\u00f3rico, presenta la vida del Presidente Rafael \u00c1ngel Calder\u00f3n Guardia ubicada en Barrio Escalante, 100 metros Este y 150 metros Norte de la Iglesia de Santa Teresita en San Jos\u00e9.<\/p>\n<p>En 1979 fue declarada patrimonio nacional y recientemente fue reconocida por el Centro de Investigaci\u00f3n y Conservaci\u00f3n del Patrimonio Cultural&nbsp;del MCJD como uno de los edificios mejor conservados, adem\u00e1s, funcion\u00f3 por varios a\u00f1os como sede del Liceo Anastacio Alfaro, el ITCO y la Orquesta Sinf\u00f3nica Juvenil. El Museo Hist\u00f3rico Dr. Rafael \u00c1ngel Calder\u00f3n cuenta con documentaci\u00f3n de la guerra de 1948, biblioteca estudiantil, exposiciones, pel\u00edculas, teatro, danza en el auditorio, un amplio estacionamiento con seguridad para 30 veh\u00edculos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n: en avenida 11, entre calles 25 y 27, Avenida 11, 100 metros este y 100 metros norte de la Iglesia Santa Teresita, Barrio Escalante, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101. Coordenadas para GPS: 9.936856,-84.065711 (9\u00b056&#8217;12.68&#8243;N, 84\u00b003&#8217;56.56&#8243;W) &nbsp;&nbsp; Horario: de Lunes a S\u00e1bado 9 a.m. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/#more-828\" aria-label=\"Leer m\u00e1s sobre Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37,15,25],"tags":[],"class_list":["post-828","post","type-post","status-publish","format-standard","hentry","category-37","category-museos","category-san-jose","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica<\/title>\n<meta name=\"description\" content=\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica en avenida 11 San Jos\u00e9. Tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica en avenida 11 San Jos\u00e9. Tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-11T15:48:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-15T23:45:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\",\"datePublished\":\"2009-07-11T15:48:28+00:00\",\"dateModified\":\"2022-03-15T23:45:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/\"},\"wordCount\":489,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg\",\"articleSection\":[\"10101\",\"Museos\",\"San Jos\u00e9\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/\",\"name\":\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg\",\"datePublished\":\"2009-07-11T15:48:28+00:00\",\"dateModified\":\"2022-03-15T23:45:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"description\":\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica en avenida 11 San Jos\u00e9. Tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/es\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica","description":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica en avenida 11 San Jos\u00e9. Tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica","og_description":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica en avenida 11 San Jos\u00e9. Tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2009-07-11T15:48:28+00:00","article_modified_time":"2022-03-15T23:45:01+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica","datePublished":"2009-07-11T15:48:28+00:00","dateModified":"2022-03-15T23:45:01+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/"},"wordCount":489,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg","articleSection":["10101","Museos","San Jos\u00e9"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/","name":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg","datePublished":"2009-07-11T15:48:28+00:00","dateModified":"2022-03-15T23:45:01+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"description":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica en avenida 11 San Jos\u00e9. Tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-dm","jetpack-related-posts":[{"id":274,"url":"https:\/\/costaricainfolink.com\/es\/teatro-la-esquina-de-costa-rica\/","url_meta":{"origin":828,"position":0},"title":"Teatro La Esquina, Costa Rica","author":"Costa Rica Info Link","date":"17 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: La Esquina Theater Costa Rica El Teatro la esquina le invita a pasar un rato agradable, caracterizados por divertir en sus 10 a\u00f1os de vida y m\u00e1s\u00a0de 100 obras de pura risa. Le esperamos 100 metros al oeste del cine\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Obra: Taxiando por un Sue\u00f1o, del Teatro La Esquina en San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-esquina-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":798,"url":"https:\/\/costaricainfolink.com\/es\/museo-sala-magon-de-costa-rica\/","url_meta":{"origin":828,"position":1},"title":"Museo Sala Mag\u00f3n de Costa Rica","author":"Costa Rica Info Link","date":"10 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: Sala Mag\u00f3n Museum Costa Rica Direcci\u00f3n: En calles 11 y 15, entre Avenidas 3 y 7, en el CENAC, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101. Coordenadas para GPS: 9.935878,-84.073328 (9\u00b056'9.16\"N,\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Fachada del CENAC en San Jose, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/cenac-antigua-fanal-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":741,"url":"https:\/\/costaricainfolink.com\/es\/museo-de-arte-y-diseno-contemporaneo-de-costa-rica\/","url_meta":{"origin":828,"position":2},"title":"Museo de Arte y Dise\u00f1o Contempor\u00e1neo de Costa Rica","author":"Costa Rica Info Link","date":"9 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: The Contemporary Art and Design Museum Costa Rica El Museo de Arte y Dise\u00f1o Contempor\u00e1neo se encuentra ubicado en las instalaciones de la antigua F\u00e1brica Nacional de Licores, fundada en 1856. Este es uno de los sitios de mayor valor\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-arte-diseno-contemporaneo-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":723,"url":"https:\/\/costaricainfolink.com\/es\/museo-de-formas-espacios-y-sonidos-de-costa-rica\/","url_meta":{"origin":828,"position":3},"title":"Museo de Formas, Espacios y Sonidos, Costa Rica","author":"Costa Rica Info Link","date":"8 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: Shapes, Spaces and Sounds Museum Costa Rica El Museo de Formas, Espacios y Sonidos (MUFES) abri\u00f3 sus puertas al p\u00fablico en el mes de abril del a\u00f1o 2002, es un programa del Museo de Arte Costarricense;\u00a0\u00e9ste \u00faltimo creado por la\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Museo de Formas, Espacios y Sonidos de Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-formas-espacios-sonidos-san-jose-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":298,"url":"https:\/\/costaricainfolink.com\/es\/teatro-1887-de-costa-rica\/","url_meta":{"origin":828,"position":4},"title":"Teatro 1887 de Costa Rica","author":"Costa Rica Info Link","date":"18 junio 2009","format":false,"excerpt":"Direcci\u00f3n: Calle 11, entre Avenidas 3 y 7, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101. Coordenadas para GPS: 9.935894,-84.073283 (9\u00b056'9.22\"N 84\u00b04'23.82\"W) Tel\u00e9fono:+506 2257-5524 \u00a0\u00a0 Mapa con direcci\u00f3n: Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9,\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Teatro 1887 en San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-1887-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":269,"url":"https:\/\/costaricainfolink.com\/es\/teatro-la-comedia-de-costa-rica\/","url_meta":{"origin":828,"position":5},"title":"Teatro La Comedia en Costa Rica","author":"Costa Rica Info Link","date":"17 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: La Comedia Theater Costa Rica Este peque\u00f1o teatro fue fundado por un grupo de artistas independientes. La idea detr\u00e1s de la creaci\u00f3n de este teatro era proporcionar un foro para presentar\u00a0obras originales de Costa Rica. Hoy en d\u00eda este teatro\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Teatro La Comedia, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-comedia-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=828"}],"version-history":[{"count":23,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/828\/revisions"}],"predecessor-version":[{"id":19335,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/828\/revisions\/19335"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}