{"id":836,"date":"2009-07-11T12:44:43","date_gmt":"2009-07-11T17:44:43","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/es\/?p=836"},"modified":"2022-03-08T10:29:32","modified_gmt":"2022-03-08T15:29:32","slug":"museo-del-jade-de-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/","title":{"rendered":"Museo del Jade de Costa Rica"},"content":{"rendered":"<p><strong>Direcci\u00f3n:<\/strong> en avenida 7, entre calles 9 y 11, en el edificio del INS, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101.<br \/>\n<strong>Coordenadas para GPS:<\/strong> 9.936456,-84.073833 (9\u00b056&#8217;11.24&#8243;N, 84\u00b04&#8217;25.80&#8243;W)<br \/>\n<strong>Horario:<\/strong> de Lunes a Viernes de 8:30 a.m. a 3:30 p.m. y S\u00e1bados de 9 a.m. a 1 p.m.<br \/>\n<strong>Tel\u00e9fono:<\/strong><a href=\"tel:+50622876034\">+506 2287-6034<\/a><\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/es\/mapa-con-la-direccion-del-museo-del-jade\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque Central, San Jos\u00e9, Costa Rica al Museo del Jade en San Jos\u00e9, Costa Rica.<\/a><\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0wbk43\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Museo del Jade de Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/maps.app.goo.gl\/uaPoN2chyTzZsc2G8\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Museo del Jade de Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<p>El 30 de octubre de 1924, el Congreso Constitucional de la Rep\u00fablica de Costa Rica aprob\u00f3 la Ley N\u00ba12,\u00a0la cual cre\u00f3 el monopolio de los seguros a favor del Estado, d\u00e1ndole el nombre de Banco Nacional de Seguros, y 24 a\u00f1os despu\u00e9s, cambi\u00f3 su nombre por Instituto Nacional de Seguros (INS). Esta instituci\u00f3n tiene como objetivo primordial brindar <img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"839\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/museo-jade-ins-costa-rica-fachada\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-jade-ins-costa-rica-fachada.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Entrada del Museo del Jade del INS, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-jade-ins-costa-rica-fachada.jpg?fit=1024%2C768&amp;ssl=1\" class=\"alignleft wp-image-839\" title=\"Entrada del Museo del Jade del INS, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-jade-ins-costa-rica-fachada.jpg?resize=282%2C214&#038;ssl=1\" alt=\"Entrada del Museo del Jade del INS, Costa Rica\" width=\"282\" height=\"214\" \/>protecci\u00f3n y servicio al pueblo costarricense.<\/p>\n<p>En los a\u00f1os setenta el Instituto Nacional de Seguros, ante una situaci\u00f3n de incansable huaquerismo y comercializaci\u00f3n de objetos arqueol\u00f3gicos, tanto dentro como fuera del territorio nacional, adquiri\u00f3 artefactos provenientes de coleccionistas por compra y en pocos casos, por donaci\u00f3n. Para entonces, el INS hab\u00eda conformado su colecci\u00f3n de objetos de la \u00e9poca precolombina con alrededor de 7000 piezas de diversos materiales como jade, cer\u00e1mica, piedra, oro, concha, madera, resina, hueso y otros. Para su adquisici\u00f3n y por razones hist\u00f3ricas, prevaleci\u00f3 lo est\u00e9tico en contraposici\u00f3n con lo cotidiano. El 31 de octubre de 1977, el INS inaugur\u00f3 el Museo bajo el nombre de \u201cColecci\u00f3n Arqueol\u00f3gica del Instituto Nacional de Seguros\u201d; posteriormente, en 1980 con el acuerdo XI de la Sesi\u00f3n 6556 de la Junta Directiva vigente, cambi\u00f3 el nombre por el actual de Museo del Jade.<\/p>\n<p>Ante la imposibilidad de reestructurar un contexto perdido por causa de los m\u00e9todos de excavaci\u00f3n no cient\u00edficos, el Museo del Jade se ha dado a la tarea de impulsar proyectos de investigaci\u00f3n, con el fin de conocer, en lo posible, el contexto mediante la asociaci\u00f3n de objetos excavados cient\u00edficamente. Estas investigaciones han incursionado en campos tales como: el antropol\u00f3gico, el arqueol\u00f3gico, el geol\u00f3gico, el art\u00edstico y el etnomusical.<\/p>\n<p>El Museo del Jade, a trav\u00e9s de m\u00e1s de veinte a\u00f1os de funcionamiento ha permitido que miles de visitantes nacionales y extranjeros visiten sus salas de exhibici\u00f3n, teniendo la oportunidad de admirar una de las colecciones institucionales m\u00e1s ricas de Am\u00e9rica. La variedad de su acervo, constituido por cuatro colecciones; <img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"840\" data-permalink=\"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/museo-jade-ins-costa-rica-piezas\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-jade-ins-costa-rica-piezas.jpg?fit=364%2C276&amp;ssl=1\" data-orig-size=\"364,276\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Piezas del Museo del Jade del INS, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-jade-ins-costa-rica-piezas.jpg?fit=364%2C276&amp;ssl=1\" class=\"alignright wp-image-840\" title=\"Piezas del Museo del Jade del INS, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-jade-ins-costa-rica-piezas.jpg?resize=186%2C142&#038;ssl=1\" alt=\"Piezas del Museo del Jade del INS, Costa Rica\" width=\"186\" height=\"142\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-jade-ins-costa-rica-piezas.jpg?w=364&amp;ssl=1 364w, https:\/\/i0.wp.com\/costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-jade-ins-costa-rica-piezas.jpg?resize=300%2C227&amp;ssl=1 300w\" sizes=\"(max-width: 186px) 100vw, 186px\" \/>arqueolog\u00eda, arte, etnograf\u00eda y numism\u00e1tica; refleja uno de los objetivos del INS, de generar una contribuci\u00f3n social, a trav\u00e9s del registro, documentaci\u00f3n y exhibici\u00f3n de exposiciones.<\/p>\n<p>Durante m\u00e1s de un cuarto de siglo, el patrimonio cultural que custodia el museo, ha servido de embajador costarricense, al formar parte de exposiciones internacionales mostradas en diferentes ciudades de Am\u00e9rica, Europa y Asia. La alta calidad de la colecci\u00f3n de arte se ve reflejada por ejemplo, en la significativa cantidad de obras de los m\u00e1s renombrados artistas costarricenses, representantes de diversos per\u00edodos de la producci\u00f3n pl\u00e1stica nacional, las cuales en muchos momentos han sido cedidas en calidad de pr\u00e9stamo para exhibici\u00f3n e investigaci\u00f3n.<\/p>\n<p>De igual manera el Museo del Jade a lo largo de estos a\u00f1os, ha facilitado sus salas de exposiciones, tanto para la divulgaci\u00f3n del producto de artistas pl\u00e1sticos nacionales e internacionales como la muestra de exhibiciones relacionadas con temas muy diversos como historia, ciencias, tecnolog\u00eda y otros temas relacionados con el quehacer humano. Constituye hoy en d\u00eda el \u00fanico museo de jade precolombino existente y la m\u00e1s grande colecci\u00f3n de \u00e9ste en exhibici\u00f3n, ya que este museo arqueol\u00f3gico muestra no s\u00f3lo objetos de jade sino valiosas piezas labradas en piedra y piezas de cer\u00e1mica de gran calidad art\u00edstica. El museo se encuentra ubicado en la planta baja del edificio de las oficinas centrales del Instituto Nacional de Seguros de Costa Rica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n: en avenida 7, entre calles 9 y 11, en el edificio del INS, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101. Coordenadas para GPS: 9.936456,-84.073833 (9\u00b056&#8217;11.24&#8243;N, 84\u00b04&#8217;25.80&#8243;W) Horario: de Lunes a Viernes de 8:30 a.m. a 3:30 p.m. y S\u00e1bados de 9 a.m. a 1 p.m. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Museo del Jade de Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/#more-836\" aria-label=\"Leer m\u00e1s sobre Museo del Jade de Costa Rica\">Leer M\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37,15,25],"tags":[],"class_list":["post-836","post","type-post","status-publish","format-standard","hentry","category-37","category-museos","category-san-jose","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Museo del Jade de Costa Rica - Tel\u00e9fono, Horario, Ubicaci\u00f3n WAZE<\/title>\n<meta name=\"description\" content=\"Museo del Jade de Costa Rica en avenida 7 San Jos\u00e9: tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museo del Jade de Costa Rica - Tel\u00e9fono, Horario, Ubicaci\u00f3n WAZE\" \/>\n<meta property=\"og:description\" content=\"Museo del Jade de Costa Rica en avenida 7 San Jos\u00e9: tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-11T17:44:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-08T15:29:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"headline\":\"Museo del Jade de Costa Rica\",\"datePublished\":\"2009-07-11T17:44:43+00:00\",\"dateModified\":\"2022-03-08T15:29:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/\"},\"wordCount\":701,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\",\"articleSection\":[\"10101\",\"Museos\",\"San Jos\u00e9\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/\",\"name\":\"Museo del Jade de Costa Rica - Tel\u00e9fono, Horario, Ubicaci\u00f3n WAZE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\",\"datePublished\":\"2009-07-11T17:44:43+00:00\",\"dateModified\":\"2022-03-08T15:29:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\"},\"description\":\"Museo del Jade de Costa Rica en avenida 7 San Jos\u00e9: tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/museo-del-jade-de-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museo del Jade de Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/\",\"name\":\"Costa Rica\",\"description\":\"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/#\\\/schema\\\/person\\\/c6bdf66e6057a0997502bab84cba5c3c\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museo del Jade de Costa Rica - Tel\u00e9fono, Horario, Ubicaci\u00f3n WAZE","description":"Museo del Jade de Costa Rica en avenida 7 San Jos\u00e9: tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Museo del Jade de Costa Rica - Tel\u00e9fono, Horario, Ubicaci\u00f3n WAZE","og_description":"Museo del Jade de Costa Rica en avenida 7 San Jos\u00e9: tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/","og_site_name":"Costa Rica","article_published_time":"2009-07-11T17:44:43+00:00","article_modified_time":"2022-03-08T15:29:32+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"headline":"Museo del Jade de Costa Rica","datePublished":"2009-07-11T17:44:43+00:00","dateModified":"2022-03-08T15:29:32+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/"},"wordCount":701,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","articleSection":["10101","Museos","San Jos\u00e9"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/","url":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/","name":"Museo del Jade de Costa Rica - Tel\u00e9fono, Horario, Ubicaci\u00f3n WAZE","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","datePublished":"2009-07-11T17:44:43+00:00","dateModified":"2022-03-08T15:29:32+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c"},"description":"Museo del Jade de Costa Rica en avenida 7 San Jos\u00e9: tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/#primaryimage","url":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","contentUrl":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/es\/museo-del-jade-de-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/es\/"},{"@type":"ListItem","position":2,"name":"Museo del Jade de Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/es\/#website","url":"https:\/\/costaricainfolink.com\/es\/","name":"Costa Rica","description":"Playas, Parques Nacionales, Museos, Hoteles, Restaurantes, Teatros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/es\/#\/schema\/person\/c6bdf66e6057a0997502bab84cba5c3c","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","url":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","contentUrl":"https:\/\/costaricainfolink.com\/es\/wp-content\/litespeed\/avatar\/c43d6f8612aa8b6e587cc3f739565538.jpg?ver=1783687405","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5dwqG-du","jetpack-related-posts":[{"id":798,"url":"https:\/\/costaricainfolink.com\/es\/museo-sala-magon-de-costa-rica\/","url_meta":{"origin":836,"position":0},"title":"Museo Sala Mag\u00f3n de Costa Rica","author":"Costa Rica Info Link","date":"10 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: Sala Mag\u00f3n Museum Costa Rica Direcci\u00f3n: En calles 11 y 15, entre Avenidas 3 y 7, en el CENAC, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101. Coordenadas para GPS: 9.935878,-84.073328 (9\u00b056'9.16\"N,\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Fachada del CENAC en San Jose, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/cenac-antigua-fanal-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":723,"url":"https:\/\/costaricainfolink.com\/es\/museo-de-formas-espacios-y-sonidos-de-costa-rica\/","url_meta":{"origin":836,"position":1},"title":"Museo de Formas, Espacios y Sonidos, Costa Rica","author":"Costa Rica Info Link","date":"8 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: Shapes, Spaces and Sounds Museum Costa Rica El Museo de Formas, Espacios y Sonidos (MUFES) abri\u00f3 sus puertas al p\u00fablico en el mes de abril del a\u00f1o 2002, es un programa del Museo de Arte Costarricense;\u00a0\u00e9ste \u00faltimo creado por la\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Museo de Formas, Espacios y Sonidos de Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-formas-espacios-sonidos-san-jose-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":741,"url":"https:\/\/costaricainfolink.com\/es\/museo-de-arte-y-diseno-contemporaneo-de-costa-rica\/","url_meta":{"origin":836,"position":2},"title":"Museo de Arte y Dise\u00f1o Contempor\u00e1neo de Costa Rica","author":"Costa Rica Info Link","date":"9 julio 2009","format":false,"excerpt":"Click the following link to read this page in English: The Contemporary Art and Design Museum Costa Rica El Museo de Arte y Dise\u00f1o Contempor\u00e1neo se encuentra ubicado en las instalaciones de la antigua F\u00e1brica Nacional de Licores, fundada en 1856. Este es uno de los sitios de mayor valor\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-arte-diseno-contemporaneo-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":828,"url":"https:\/\/costaricainfolink.com\/es\/museo-historico-del-dr-rafael-angel-calderon-guardia-de-costa-rica\/","url_meta":{"origin":836,"position":3},"title":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica","author":"Costa Rica Info Link","date":"11 julio 2009","format":false,"excerpt":"Direcci\u00f3n: en avenida 11, entre calles 25 y 27, Avenida 11, 100 metros este y 100 metros norte de la Iglesia Santa Teresita, Barrio Escalante, distrito: Carmen, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101. Coordenadas para GPS: 9.936856,-84.065711 (9\u00b056'12.68\"N, 84\u00b003'56.56\"W) \u00a0\u00a0 Horario: de\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Museo Hist\u00f3rico del Dr. Rafael \u00c1ngel Calder\u00f3n Guardia de Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/07\/museo-doctor-rafael-angel-calderon-guardia-san-jose-costa-rica1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":269,"url":"https:\/\/costaricainfolink.com\/es\/teatro-la-comedia-de-costa-rica\/","url_meta":{"origin":836,"position":4},"title":"Teatro La Comedia en Costa Rica","author":"Costa Rica Info Link","date":"17 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: La Comedia Theater Costa Rica Este peque\u00f1o teatro fue fundado por un grupo de artistas independientes. La idea detr\u00e1s de la creaci\u00f3n de este teatro era proporcionar un foro para presentar\u00a0obras originales de Costa Rica. Hoy en d\u00eda este teatro\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Teatro La Comedia, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-comedia-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":274,"url":"https:\/\/costaricainfolink.com\/es\/teatro-la-esquina-de-costa-rica\/","url_meta":{"origin":836,"position":5},"title":"Teatro La Esquina, Costa Rica","author":"Costa Rica Info Link","date":"17 junio 2009","format":false,"excerpt":"Click the following link to read this page in English: La Esquina Theater Costa Rica El Teatro la esquina le invita a pasar un rato agradable, caracterizados por divertir en sus 10 a\u00f1os de vida y m\u00e1s\u00a0de 100 obras de pura risa. Le esperamos 100 metros al oeste del cine\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/es\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Obra: Taxiando por un Sue\u00f1o, del Teatro La Esquina en San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/es\/wp-content\/uploads\/2009\/06\/teatro-esquina-san-jose-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/comments?post=836"}],"version-history":[{"count":24,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/836\/revisions"}],"predecessor-version":[{"id":19297,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/posts\/836\/revisions\/19297"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/media?parent=836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/categories?post=836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/es\/wp-json\/wp\/v2\/tags?post=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}