{"id":54,"count":1,"description":"","link":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/pecaries-o-sainos\/","name":"Pecar\u00edes o Sa\u00ednos","slug":"pecaries-o-sainos","taxonomy":"category","parent":8,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pecar\u00edes o Sa\u00ednos Archivos - Fotos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/pecaries-o-sainos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pecar\u00edes o Sa\u00ednos Archivos - Fotos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/pecaries-o-sainos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/category\\\/animales\\\/pecaries-o-sainos\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/category\\\/animales\\\/pecaries-o-sainos\\\/\",\"name\":\"Pecar\u00edes o Sa\u00ednos Archivos - Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/category\\\/animales\\\/pecaries-o-sainos\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/category\\\/animales\\\/pecaries-o-sainos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animales\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/category\\\/animales\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pecar\u00edes o Sa\u00ednos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pecar\u00edes o Sa\u00ednos Archivos - Fotos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/pecaries-o-sainos\/","og_locale":"es_ES","og_type":"article","og_title":"Pecar\u00edes o Sa\u00ednos Archivos - Fotos","og_url":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/pecaries-o-sainos\/","og_site_name":"Fotos","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/pecaries-o-sainos\/","url":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/pecaries-o-sainos\/","name":"Pecar\u00edes o Sa\u00ednos Archivos - Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/pecaries-o-sainos\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/pecaries-o-sainos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Animales","item":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/"},{"@type":"ListItem","position":3,"name":"Pecar\u00edes o Sa\u00ednos"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/categories\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/categories\/8"}],"wp:post_type":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts?categories=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}