{"id":3749,"date":"2013-03-16T20:08:01","date_gmt":"2013-03-17T01:08:01","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg"},"modified":"2013-03-16T20:08:01","modified_gmt":"2013-03-17T01:08:01","slug":"playa-espadilla-norte-puntarenas-costa-rica015","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/fotos\/playa-espadilla-norte-costa-rica\/playa-espadilla-norte-puntarenas-costa-rica015\/#main","title":{"rendered":"Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-3749","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica - Fotos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica - Fotos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"645\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/playa-espadilla-norte-puntarenas-costa-rica015.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/playa-espadilla-norte-puntarenas-costa-rica015.jpg\",\"name\":\"Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica - Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2013-03-17T01:08:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/playa-espadilla-norte-puntarenas-costa-rica015.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/playa-espadilla-norte-puntarenas-costa-rica015.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/playa-espadilla-norte-puntarenas-costa-rica015.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de Playa Espadilla Norte Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-espadilla-norte-costa-rica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica - Fotos","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica - Fotos","og_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg","og_site_name":"Fotos","og_image":[{"width":645,"height":484,"url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg","url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg","name":"Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica - Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2013-03-17T01:08:01+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Fotos de Playa Espadilla Norte Costa Rica","item":"https:\/\/costaricainfolink.com\/fotos\/playa-espadilla-norte-costa-rica\/"},{"@type":"ListItem","position":3,"name":"Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1lmaw-Yt","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?w=645&amp;ssl=1 645w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"3749\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/playa-espadilla-norte-costa-rica\/playa-espadilla-norte-puntarenas-costa-rica015\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?fit=645%2C484&amp;ssl=1\" data-orig-size=\"645,484\" data-comments-opened=\"1\" data-image-title=\"Playa Espadilla Norte en Aguirre, Puntarenas, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?fit=645%2C484&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":645,"height":484,"file":"2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg","sizes":{"thumbnail":{"file":"playa-espadilla-norte-puntarenas-costa-rica015-200x150.jpg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?fit=185%2C139&ssl=1"},"medium":{"file":"playa-espadilla-norte-puntarenas-costa-rica015-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?fit=300%2C225&ssl=1"},"post-thumbnail":{"file":"playa-espadilla-norte-puntarenas-costa-rica015-150x112.jpg","width":150,"height":112,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015-150x112.jpg"},"single-post-thumbnail":{"file":"playa-espadilla-norte-puntarenas-costa-rica015-400x300.jpg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015-400x300.jpg"},"full":{"file":"playa-espadilla-norte-puntarenas-costa-rica015.jpg?fit=645%2C484&ssl=1","width":645,"height":484,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg?fit=645%2C484&ssl=1"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":3734,"source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/playa-espadilla-norte-puntarenas-costa-rica015.jpg","filename":"playa-espadilla-norte-puntarenas-costa-rica015.jpg","filesize":230240,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media\/3749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=3749"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3734,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/3734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}