{"id":4220,"date":"2015-06-30T07:02:50","date_gmt":"2015-06-30T12:02:50","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg"},"modified":"2015-06-30T07:12:30","modified_gmt":"2015-06-30T12:12:30","slug":"playa-avellanas-costa-rica-18","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/fotos\/playa-avellanas-costa-rica\/playa-avellanas-costa-rica-18\/#main","title":{"rendered":""},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-4220","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Fotos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Fotos\" \/>\n<meta property=\"og:description\" content=\"Playa Avellanas en Tamarindo, Santa Cruz, Guanacaste, Costa Rica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-30T12:12:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18-1024x225.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-avellanas-costa-rica-18.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-avellanas-costa-rica-18.jpg\",\"name\":\"- Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2015-06-30T12:02:50+00:00\",\"dateModified\":\"2015-06-30T12:12:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-avellanas-costa-rica-18.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-avellanas-costa-rica-18.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-avellanas-costa-rica-18.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de Playa Avellanas Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-avellanas-costa-rica\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Fotos","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"- Fotos","og_description":"Playa Avellanas en Tamarindo, Santa Cruz, Guanacaste, Costa Rica.","og_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg","og_site_name":"Fotos","article_modified_time":"2015-06-30T12:12:30+00:00","og_image":[{"width":1024,"height":225,"url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18-1024x225.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg","url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg","name":"- Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2015-06-30T12:02:50+00:00","dateModified":"2015-06-30T12:12:30+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Fotos de Playa Avellanas Costa Rica","item":"https:\/\/costaricainfolink.com\/fotos\/playa-avellanas-costa-rica\/"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1lmaw-164","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"66\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?fit=300%2C66&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Playa Avellanas Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?w=4912&amp;ssl=1 4912w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?resize=185%2C41&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?resize=300%2C66&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?resize=1024%2C225&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?resize=150%2C33&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?resize=400%2C88&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?w=3600&amp;ssl=1 3600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"4220\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/playa-avellanas-costa-rica\/playa-avellanas-costa-rica-18\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?fit=4912%2C1080&amp;ssl=1\" data-orig-size=\"4912,1080\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Playa Avellanas en Tamarindo, Santa Cruz, Guanacaste, Costa Rica.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?fit=1024%2C225&amp;ssl=1\" \/><\/a><\/p>\n<p>Playa Avellanas en Tamarindo, Santa Cruz, Guanacaste, Costa Rica.<\/p>\n"},"caption":{"rendered":"<p>Playa Avellanas en Tamarindo, Santa Cruz, Guanacaste, Costa Rica.<\/p>\n"},"alt_text":"Playa Avellanas Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4912,"height":1080,"file":"2011\/06\/playa-avellanas-costa-rica-18.jpg","sizes":{"thumbnail":{"file":"playa-avellanas-costa-rica-18-185x41.jpg","width":185,"height":41,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?fit=185%2C41&ssl=1"},"medium":{"file":"playa-avellanas-costa-rica-18-300x66.jpg","width":300,"height":66,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?fit=300%2C66&ssl=1"},"large":{"file":"playa-avellanas-costa-rica-18-1024x225.jpg","width":1024,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?fit=1024%2C225&ssl=1"},"post-thumbnail":{"file":"playa-avellanas-costa-rica-18-150x33.jpg","width":150,"height":33,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18-150x33.jpg"},"single-post-thumbnail":{"file":"playa-avellanas-costa-rica-18-400x88.jpg","width":400,"height":88,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18-400x88.jpg"},"full":{"file":"playa-avellanas-costa-rica-18.jpg?fit=4912%2C1080&ssl=1","width":4912,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg?fit=4912%2C1080&ssl=1"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":1270,"source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-avellanas-costa-rica-18.jpg","filename":"playa-avellanas-costa-rica-18.jpg","filesize":2339175,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media\/4220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=4220"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1270,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/1270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}