{"id":4564,"date":"2015-07-22T13:03:51","date_gmt":"2015-07-22T18:03:51","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg"},"modified":"2015-07-22T13:34:44","modified_gmt":"2015-07-22T18:34:44","slug":"playa-brasilito-costa-rica-12","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/fotos\/playa-brasilito-costa-rica\/playa-brasilito-costa-rica-12\/#main","title":{"rendered":""},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-4564","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Fotos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Fotos\" \/>\n<meta property=\"og:description\" content=\"Playa Brasilito en Cabo Velas, Santa Cruz, Guanacaste, Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-22T18:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12-978x650.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"978\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/playa-brasilito-costa-rica-12.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/playa-brasilito-costa-rica-12.jpg\",\"name\":\"- Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2015-07-22T18:03:51+00:00\",\"dateModified\":\"2015-07-22T18:34:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/playa-brasilito-costa-rica-12.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/playa-brasilito-costa-rica-12.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/playa-brasilito-costa-rica-12.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de Playa Brasilito Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-brasilito-costa-rica\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Fotos","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"- Fotos","og_description":"Playa Brasilito en Cabo Velas, Santa Cruz, Guanacaste, Costa Rica","og_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg","og_site_name":"Fotos","article_modified_time":"2015-07-22T18:34:44+00:00","og_image":[{"width":978,"height":650,"url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12-978x650.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg","url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg","name":"- Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2015-07-22T18:03:51+00:00","dateModified":"2015-07-22T18:34:44+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Fotos de Playa Brasilito Costa Rica","item":"https:\/\/costaricainfolink.com\/fotos\/playa-brasilito-costa-rica\/"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1lmaw-1bC","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?fit=300%2C199&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Playa Brasilito Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?w=4912&amp;ssl=1 4912w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?resize=400%2C266&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?w=3600&amp;ssl=1 3600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"4564\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/playa-brasilito-costa-rica\/playa-brasilito-costa-rica-12\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?fit=4912%2C3264&amp;ssl=1\" data-orig-size=\"4912,3264\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Playa Brasilito en Cabo Velas, Santa Cruz, Guanacaste, Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?fit=978%2C650&amp;ssl=1\" \/><\/a><\/p>\n<p>Playa Brasilito en Cabo Velas, Santa Cruz, Guanacaste, Costa Rica<\/p>\n"},"caption":{"rendered":"<p>Playa Brasilito en Cabo Velas, Santa Cruz, Guanacaste, Costa Rica<\/p>\n"},"alt_text":"Playa Brasilito Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4912,"height":3264,"file":"2012\/02\/playa-brasilito-costa-rica-12.jpg","sizes":{"thumbnail":{"file":"playa-brasilito-costa-rica-12-185x123.jpg","width":185,"height":123,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?fit=185%2C123&ssl=1"},"medium":{"file":"playa-brasilito-costa-rica-12-300x199.jpg","width":300,"height":199,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?fit=300%2C199&ssl=1"},"large":{"file":"playa-brasilito-costa-rica-12-978x650.jpg","width":978,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?fit=978%2C650&ssl=1"},"post-thumbnail":{"file":"playa-brasilito-costa-rica-12-150x100.jpg","width":150,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12-150x100.jpg"},"single-post-thumbnail":{"file":"playa-brasilito-costa-rica-12-400x266.jpg","width":400,"height":266,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12-400x266.jpg"},"full":{"file":"playa-brasilito-costa-rica-12.jpg?fit=4912%2C3264&ssl=1","width":4912,"height":3264,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg?fit=4912%2C3264&ssl=1"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":2215,"source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica-12.jpg","filename":"playa-brasilito-costa-rica-12.jpg","filesize":4510819,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media\/4564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=4564"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2215,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/2215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}