{"id":5015,"date":"2015-08-31T12:29:52","date_gmt":"2015-08-31T17:29:52","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg"},"modified":"2015-08-31T12:34:25","modified_gmt":"2015-08-31T17:34:25","slug":"playa-garza-costa-rica-2-2","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/fotos\/playa-garza-costa-rica\/playa-garza-costa-rica-2-2\/#main","title":{"rendered":""},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-5015","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Fotos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Fotos\" \/>\n<meta property=\"og:description\" content=\"Playa Garza en Nosara, Nicoya, Guanacaste, Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:modified_time\" content=\"2015-08-31T17:34:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2592\" \/>\n\t<meta property=\"og:image:height\" content=\"1944\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-garza-costa-rica-2.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-garza-costa-rica-2.jpg\",\"name\":\"- Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2015-08-31T17:29:52+00:00\",\"dateModified\":\"2015-08-31T17:34:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-garza-costa-rica-2.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-garza-costa-rica-2.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/playa-garza-costa-rica-2.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de Playa Garza Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-garza-costa-rica\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Fotos","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"- Fotos","og_description":"Playa Garza en Nosara, Nicoya, Guanacaste, Costa Rica","og_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg","og_site_name":"Fotos","article_modified_time":"2015-08-31T17:34:25+00:00","og_image":[{"width":2592,"height":1944,"url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg","url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg","name":"- Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2015-08-31T17:29:52+00:00","dateModified":"2015-08-31T17:34:25+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Fotos de Playa Garza Costa Rica","item":"https:\/\/costaricainfolink.com\/fotos\/playa-garza-costa-rica\/"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1lmaw-1iT","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Playa Garza Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?w=2592&amp;ssl=1 2592w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"5015\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/playa-garza-costa-rica\/playa-garza-costa-rica-2-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?fit=2592%2C1944&amp;ssl=1\" data-orig-size=\"2592,1944\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Playa Garza en Nosara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?fit=867%2C650&amp;ssl=1\" \/><\/a><\/p>\n<p>Playa Garza en Nosara, Nicoya, Guanacaste, Costa Rica<\/p>\n"},"caption":{"rendered":"<p>Playa Garza en Nosara, Nicoya, Guanacaste, Costa Rica<\/p>\n"},"alt_text":"Playa Garza Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2592,"height":1944,"file":"2011\/06\/playa-garza-costa-rica-2.jpg","sizes":{"thumbnail":{"file":"playa-garza-costa-rica-2-185x139.jpg","width":185,"height":139,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?fit=185%2C139&ssl=1"},"medium":{"file":"playa-garza-costa-rica-2-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?fit=300%2C225&ssl=1"},"large":{"file":"playa-garza-costa-rica-2-867x650.jpg","width":867,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?fit=867%2C650&ssl=1"},"post-thumbnail":{"file":"playa-garza-costa-rica-2-150x113.jpg","width":150,"height":113,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2-150x113.jpg"},"single-post-thumbnail":{"file":"playa-garza-costa-rica-2-400x300.jpg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2-400x300.jpg"},"full":{"file":"playa-garza-costa-rica-2.jpg?fit=2592%2C1944&ssl=1","width":2592,"height":1944,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg?fit=2592%2C1944&ssl=1"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":1196,"source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-garza-costa-rica-2.jpg","filename":"playa-garza-costa-rica-2.jpg","filesize":1911565,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media\/5015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=5015"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1196,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/1196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}