{"id":5210,"date":"2017-05-30T01:52:39","date_gmt":"2017-05-30T06:52:39","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg"},"modified":"2017-05-30T01:59:09","modified_gmt":"2017-05-30T06:59:09","slug":"playa-iguanita-costa-rica-40","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/fotos\/playa-iguanita-costa-rica\/playa-iguanita-costa-rica-40\/#main","title":{"rendered":"Playa Iguanita Costa Rica"},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-5210","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Playa Iguanita Costa Rica - Fotos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playa Iguanita Costa Rica - Fotos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-30T06:59:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-iguanita-costa-rica-40.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-iguanita-costa-rica-40.jpg\",\"name\":\"Playa Iguanita Costa Rica - Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2017-05-30T06:52:39+00:00\",\"dateModified\":\"2017-05-30T06:59:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-iguanita-costa-rica-40.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-iguanita-costa-rica-40.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/playa-iguanita-costa-rica-40.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de Playa Iguanita Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-iguanita-costa-rica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Playa Iguanita Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playa Iguanita Costa Rica - Fotos","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Playa Iguanita Costa Rica - Fotos","og_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg","og_site_name":"Fotos","article_modified_time":"2017-05-30T06:59:09+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg","url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg","name":"Playa Iguanita Costa Rica - Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2017-05-30T06:52:39+00:00","dateModified":"2017-05-30T06:59:09+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Fotos de Playa Iguanita Costa Rica","item":"https:\/\/costaricainfolink.com\/fotos\/playa-iguanita-costa-rica\/"},{"@type":"ListItem","position":3,"name":"Playa Iguanita Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1lmaw-1m2","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Playa Iguanita Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?resize=160%2C120&amp;ssl=1 160w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"5210\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/playa-iguanita-costa-rica\/playa-iguanita-costa-rica-40\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?fit=1920%2C1440&amp;ssl=1\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Iguanita Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?fit=867%2C650&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Playa Iguanita Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1440,"file":"2012\/05\/playa-iguanita-costa-rica-40.jpg","sizes":{"thumbnail":{"file":"playa-iguanita-costa-rica-40-185x139.jpg","width":185,"height":139,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?fit=185%2C139&ssl=1"},"medium":{"file":"playa-iguanita-costa-rica-40-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?fit=300%2C225&ssl=1"},"medium_large":{"file":"playa-iguanita-costa-rica-40-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?fit=768%2C576&ssl=1"},"large":{"file":"playa-iguanita-costa-rica-40-867x650.jpg","width":867,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?fit=867%2C650&ssl=1"},"1_column":{"file":"playa-iguanita-costa-rica-40-560x420.jpg","width":560,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40-560x420.jpg"},"2_column":{"file":"playa-iguanita-costa-rica-40-260x195.jpg","width":260,"height":195,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40-260x195.jpg"},"3_column":{"file":"playa-iguanita-costa-rica-40-160x120.jpg","width":160,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40-160x120.jpg"},"full":{"file":"playa-iguanita-costa-rica-40.jpg?fit=1920%2C1440&ssl=1","width":1920,"height":1440,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg?fit=1920%2C1440&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2548,"source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-iguanita-costa-rica-40.jpg","filename":"playa-iguanita-costa-rica-40.jpg","filesize":1399199,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media\/5210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=5210"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2548,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/2548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}