{"id":5336,"date":"2017-06-11T08:41:12","date_gmt":"2017-06-11T13:41:12","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg"},"modified":"2017-06-11T08:44:44","modified_gmt":"2017-06-11T13:44:44","slug":"playa-la-penca-costa-rica-24","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/fotos\/playa-la-penca-costa-rica\/playa-la-penca-costa-rica-24\/#main","title":{"rendered":"Playa La Penca Costa Rica"},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-5336","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Playa La Penca Costa Rica - Fotos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playa La Penca Costa Rica - Fotos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-11T13:44:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1276\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/playa-la-penca-costa-rica-24.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/playa-la-penca-costa-rica-24.jpg\",\"name\":\"Playa La Penca Costa Rica - Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2017-06-11T13:41:12+00:00\",\"dateModified\":\"2017-06-11T13:44:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/playa-la-penca-costa-rica-24.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/playa-la-penca-costa-rica-24.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/playa-la-penca-costa-rica-24.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de Playa La Penca Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-la-penca-costa-rica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Playa La Penca Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playa La Penca Costa Rica - Fotos","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Playa La Penca Costa Rica - Fotos","og_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg","og_site_name":"Fotos","article_modified_time":"2017-06-11T13:44:44+00:00","og_image":[{"width":1920,"height":1276,"url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg","url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg","name":"Playa La Penca Costa Rica - Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2017-06-11T13:41:12+00:00","dateModified":"2017-06-11T13:44:44+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Fotos de Playa La Penca Costa Rica","item":"https:\/\/costaricainfolink.com\/fotos\/playa-la-penca-costa-rica\/"},{"@type":"ListItem","position":3,"name":"Playa La Penca Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1lmaw-1o4","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?fit=300%2C199&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Playa La Penca Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?resize=160%2C106&amp;ssl=1 160w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"5336\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/playa-la-penca-costa-rica\/playa-la-penca-costa-rica-24\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?fit=1920%2C1276&amp;ssl=1\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa La Penca Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?fit=978%2C650&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Playa La Penca Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1276,"file":"2012\/03\/playa-la-penca-costa-rica-24.jpg","sizes":{"thumbnail":{"file":"playa-la-penca-costa-rica-24-185x123.jpg","width":185,"height":123,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?fit=185%2C123&ssl=1"},"medium":{"file":"playa-la-penca-costa-rica-24-300x199.jpg","width":300,"height":199,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?fit=300%2C199&ssl=1"},"medium_large":{"file":"playa-la-penca-costa-rica-24-768x510.jpg","width":768,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?fit=768%2C510&ssl=1"},"large":{"file":"playa-la-penca-costa-rica-24-978x650.jpg","width":978,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?fit=978%2C650&ssl=1"},"1_column":{"file":"playa-la-penca-costa-rica-24-560x372.jpg","width":560,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24-560x372.jpg"},"2_column":{"file":"playa-la-penca-costa-rica-24-260x173.jpg","width":260,"height":173,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24-260x173.jpg"},"3_column":{"file":"playa-la-penca-costa-rica-24-160x106.jpg","width":160,"height":106,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24-160x106.jpg"},"full":{"file":"playa-la-penca-costa-rica-24.jpg?fit=1920%2C1276&ssl=1","width":1920,"height":1276,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg?fit=1920%2C1276&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2263,"source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-la-penca-costa-rica-24.jpg","filename":"playa-la-penca-costa-rica-24.jpg","filesize":220816,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media\/5336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=5336"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2263,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/2263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}