{"id":7016,"date":"2024-11-28T18:46:32","date_gmt":"2024-11-28T23:46:32","guid":{"rendered":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg"},"modified":"2024-11-28T18:47:37","modified_gmt":"2024-11-28T23:47:37","slug":"playa-manuel-antonio-costa-rica-25","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/fotos\/playa-manuel-antonio-costa-rica-2\/playa-manuel-antonio-costa-rica-25\/#main","title":{"rendered":"Playa Manuel Antonio Costa Rica"},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-7016","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Playa Manuel Antonio Costa Rica - Fotos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playa Manuel Antonio Costa Rica - Fotos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-28T23:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Playa-Manuel-Antonio-Costa-Rica-25.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Playa-Manuel-Antonio-Costa-Rica-25.jpg\",\"name\":\"Playa Manuel Antonio Costa Rica - Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2024-11-28T23:46:32+00:00\",\"dateModified\":\"2024-11-28T23:47:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Playa-Manuel-Antonio-Costa-Rica-25.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Playa-Manuel-Antonio-Costa-Rica-25.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Playa-Manuel-Antonio-Costa-Rica-25.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de Playa Manuel Antonio Costa Rica\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-manuel-antonio-costa-rica-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Playa Manuel Antonio Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playa Manuel Antonio Costa Rica - Fotos","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Playa Manuel Antonio Costa Rica - Fotos","og_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg","og_site_name":"Fotos","article_modified_time":"2024-11-28T23:47:37+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg","url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg","name":"Playa Manuel Antonio Costa Rica - Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2024-11-28T23:46:32+00:00","dateModified":"2024-11-28T23:47:37+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Fotos de Playa Manuel Antonio Costa Rica","item":"https:\/\/costaricainfolink.com\/fotos\/playa-manuel-antonio-costa-rica-2\/"},{"@type":"ListItem","position":3,"name":"Playa Manuel Antonio Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1lmaw-1Pa","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Playa Manuel Antonio Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?w=2500&amp;ssl=1 2500w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"7016\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/playa-manuel-antonio-costa-rica-2\/playa-manuel-antonio-costa-rica-25\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"1\" data-image-title=\"Playa Manuel Antonio Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=867%2C650&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Playa Manuel Antonio Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2500,"height":1875,"file":"2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg","filesize":531283,"sizes":{"medium":{"file":"Playa-Manuel-Antonio-Costa-Rica-25-300x225.jpg","width":300,"height":225,"filesize":12833,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=300%2C225&ssl=1"},"large":{"file":"Playa-Manuel-Antonio-Costa-Rica-25-867x650.jpg","width":867,"height":650,"filesize":94491,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=867%2C650&ssl=1"},"thumbnail":{"file":"Playa-Manuel-Antonio-Costa-Rica-25-185x139.jpg","width":185,"height":139,"filesize":5743,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=185%2C139&ssl=1"},"medium_large":{"file":"Playa-Manuel-Antonio-Costa-Rica-25-768x576.jpg","width":768,"height":576,"filesize":73761,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=768%2C576&ssl=1"},"1536x1536":{"file":"Playa-Manuel-Antonio-Costa-Rica-25-1536x1152.jpg","width":1536,"height":1152,"filesize":293278,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=1536%2C1152&ssl=1"},"2048x2048":{"file":"Playa-Manuel-Antonio-Costa-Rica-25-2048x1536.jpg","width":2048,"height":1536,"filesize":498979,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=2048%2C1536&ssl=1"},"full":{"file":"Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=2500%2C1875&ssl=1","width":2500,"height":1875,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg?fit=2500%2C1875&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3777,"source_url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Manuel-Antonio-Costa-Rica-25.jpg","filename":"Playa-Manuel-Antonio-Costa-Rica-25.jpg","filesize":531283,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media\/7016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=7016"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3777,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/3777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}