{"id":1191,"date":"2011-06-19T21:15:11","date_gmt":"2011-06-20T02:15:11","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/?p=1191"},"modified":"2023-03-28T17:28:04","modified_gmt":"2023-03-28T22:28:04","slug":"playa-barco-quebrado-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/","title":{"rendered":"Fotos de Playa Barco Quebrado Costa Rica"},"content":{"rendered":"<h5><a title=\"Barco Quebrado Beach, Costa Rica\" href=\"https:\/\/www.costaricainfolink.com\/photos\/barco-quebrado-beach-costa-rica\/\">Click here to view this page in English<\/a><\/h5>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1200\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/&quot;,&quot;likes_blog_id&quot;:19866444}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1200px; height: 601px;\" data-original-width=\"1200\" data-original-height=\"601\" > <div class=\"gallery-group images-1\" style=\"width: 800px; height: 601px;\" data-original-width=\"800\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-2\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"796\"> <meta itemprop=\"height\" content=\"597\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4341\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg\" data-orig-size=\"2592,1944\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?w=796&#038;h=597&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?w=2592&amp;ssl=1 2592w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica.jpg?w=2400&amp;ssl=1 2400w\" width=\"796\" height=\"597\" loading=\"lazy\" data-original-width=\"796\" data-original-height=\"597\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Playa Barco Quebrado Costa Rica\" style=\"width: 796px; height: 597px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 400px; height: 601px;\" data-original-width=\"400\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-2-2\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4342\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg\" data-orig-size=\"2592,1944\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?w=2592&amp;ssl=1 2592w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-2.jpg?w=2400&amp;ssl=1 2400w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Playa Barco Quebrado Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-3\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4343\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg\" data-orig-size=\"2592,1944\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?w=396&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?w=2592&amp;ssl=1 2592w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-3.jpg?w=2400&amp;ssl=1 2400w\" width=\"396\" height=\"296\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Playa Barco Quebrado Costa Rica\" style=\"width: 396px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 301px;\" data-original-width=\"1200\" data-original-height=\"301\" > <div class=\"gallery-group images-1\" style=\"width: 400px; height: 301px;\" data-original-width=\"400\" data-original-height=\"301\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-4\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4344\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-4.jpg?w=3600&amp;ssl=1 3600w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Playa Barco Quebrado Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 400px; height: 301px;\" data-original-width=\"400\" data-original-height=\"301\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-5\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4345\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-5.jpg?w=3600&amp;ssl=1 3600w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Playa Barco Quebrado Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 400px; height: 301px;\" data-original-width=\"400\" data-original-height=\"301\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-7\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4346\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-7.jpg?w=3600&amp;ssl=1 3600w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Playa Barco Quebrado Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 601px;\" data-original-width=\"1200\" data-original-height=\"601\" > <div class=\"gallery-group images-2\" style=\"width: 400px; height: 601px;\" data-original-width=\"400\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-ave\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4347\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Ave en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-ave.jpg?w=3600&amp;ssl=1 3600w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Ave en Playa Barco Quebrado Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4348\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Mono en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?w=396&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-.jpg?w=3600&amp;ssl=1 3600w\" width=\"396\" height=\"296\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Mono en Playa Barco Quebrado Costa Rica\" style=\"width: 396px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 800px; height: 601px;\" data-original-width=\"800\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-2\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"796\"> <meta itemprop=\"height\" content=\"597\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4349\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg\" data-orig-size=\"2592,1944\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Mono en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?w=796&#038;h=597&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?w=2592&amp;ssl=1 2592w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-2.jpg?w=2400&amp;ssl=1 2400w\" width=\"796\" height=\"597\" loading=\"lazy\" data-original-width=\"796\" data-original-height=\"597\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Mono en Playa Barco Quebrado Costa Rica\" style=\"width: 796px; height: 597px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 451px;\" data-original-width=\"1200\" data-original-height=\"451\" > <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-3\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4350\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Monos en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-3.jpg?w=3600&amp;ssl=1 3600w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Monos en Playa Barco Quebrado Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-4\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4351\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Monos en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-4.jpg?w=3600&amp;ssl=1 3600w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Mono en Playa Barco Quebrado Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 601px;\" data-original-width=\"1200\" data-original-height=\"601\" > <div class=\"gallery-group images-1\" style=\"width: 800px; height: 601px;\" data-original-width=\"800\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-5\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"796\"> <meta itemprop=\"height\" content=\"597\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4352\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Monos en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?w=796&#038;h=597&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-5.jpg?w=3600&amp;ssl=1 3600w\" width=\"796\" height=\"597\" loading=\"lazy\" data-original-width=\"796\" data-original-height=\"597\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Mono en Playa Barco Quebrado Costa Rica\" style=\"width: 796px; height: 597px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 400px; height: 601px;\" data-original-width=\"400\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-6\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4353\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Monos en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-6.jpg?w=3600&amp;ssl=1 3600w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Monos en Playa Barco Quebrado Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-7\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4354\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Monos en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?w=396&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-7.jpg?w=3600&amp;ssl=1 3600w\" width=\"396\" height=\"296\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Monos en Playa Barco Quebrado Costa Rica\" style=\"width: 396px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 451px;\" data-original-width=\"1200\" data-original-height=\"451\" > <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-8\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4355\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Mono en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-8.jpg?w=3600&amp;ssl=1 3600w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Monos en Playa Barco Quebrado Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-9\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4356\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Mono en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-9.jpg?w=3600&amp;ssl=1 3600w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Monos en Playa Barco Quebrado Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 226px;\" data-original-width=\"1200\" data-original-height=\"226\" > <div class=\"gallery-group images-1\" style=\"width: 300px; height: 226px;\" data-original-width=\"300\" data-original-height=\"226\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-10\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"296\"> <meta itemprop=\"height\" content=\"222\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4357\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Monos en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?w=296&#038;h=222&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-10.jpg?w=3600&amp;ssl=1 3600w\" width=\"296\" height=\"222\" loading=\"lazy\" data-original-width=\"296\" data-original-height=\"222\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Monos en Playa Barco Quebrado Costa Rica\" style=\"width: 296px; height: 222px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 300px; height: 226px;\" data-original-width=\"300\" data-original-height=\"226\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-11\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"296\"> <meta itemprop=\"height\" content=\"222\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4358\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Mono en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?w=296&#038;h=222&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-11.jpg?w=3600&amp;ssl=1 3600w\" width=\"296\" height=\"222\" loading=\"lazy\" data-original-width=\"296\" data-original-height=\"222\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Mono en Playa Barco Quebrado Costa Rica\" style=\"width: 296px; height: 222px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 300px; height: 226px;\" data-original-width=\"300\" data-original-height=\"226\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-12\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"296\"> <meta itemprop=\"height\" content=\"222\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4359\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Mono en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?w=296&#038;h=222&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-12.jpg?w=3600&amp;ssl=1 3600w\" width=\"296\" height=\"222\" loading=\"lazy\" data-original-width=\"296\" data-original-height=\"222\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Mono en Playa Barco Quebrado Costa Rica\" style=\"width: 296px; height: 222px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 300px; height: 226px;\" data-original-width=\"300\" data-original-height=\"226\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/playa-barco-quebrado-costa-rica-mono-13\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"296\"> <meta itemprop=\"height\" content=\"222\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4360\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg\" data-orig-size=\"4320,3240\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Monos en Playa Barco Quebrado en Samara, Nicoya, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?w=296&#038;h=222&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?w=4320&amp;ssl=1 4320w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?w=2400&amp;ssl=1 2400w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-mono-13.jpg?w=3600&amp;ssl=1 3600w\" width=\"296\" height=\"222\" loading=\"lazy\" data-original-width=\"296\" data-original-height=\"222\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Monos en Playa Barco Quebrado Costa Rica\" style=\"width: 296px; height: 222px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<h3><a href=\"https:\/\/www.costaricainfolink.com\/es\/playa-barco-quebrado-costa-rica\/\">Click aqu\u00ed para ver video, mapa con direcci\u00f3n, coordenadas para GPS, ubicaci\u00f3n, informaci\u00f3n de Playa Barco Quebrado Costa Rica<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Click here to view this page in English Click aqu\u00ed para ver video, mapa con direcci\u00f3n, coordenadas para GPS, ubicaci\u00f3n, informaci\u00f3n de Playa Barco Quebrado Costa Rica<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[70,25],"tags":[],"class_list":["post-1191","post","type-post","status-publish","format-standard","hentry","category-guanacaste","category-playas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fotos de Playa Barco Quebrado Costa Rica - Nicoya, Guanacaste<\/title>\n<meta name=\"description\" content=\"Fotos de Playa Barco Quebrado Costa Rica. Distrito: Samara, canton: Nicoya, provincia: Guanacaste.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotos de Playa Barco Quebrado Costa Rica - Nicoya, Guanacaste\" \/>\n<meta property=\"og:description\" content=\"Fotos de Playa Barco Quebrado Costa Rica. Distrito: Samara, canton: Nicoya, provincia: Guanacaste.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-20T02:15:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-28T22:28:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-185x139.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\"},\"headline\":\"Fotos de Playa Barco Quebrado Costa Rica\",\"datePublished\":\"2011-06-20T02:15:11+00:00\",\"dateModified\":\"2023-03-28T22:28:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/\"},\"wordCount\":41,\"commentCount\":0,\"articleSection\":[\"Guanacaste\",\"Playas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/\",\"name\":\"Fotos de Playa Barco Quebrado Costa Rica - Nicoya, Guanacaste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2011-06-20T02:15:11+00:00\",\"dateModified\":\"2023-03-28T22:28:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\"},\"description\":\"Fotos de Playa Barco Quebrado Costa Rica. Distrito: Samara, canton: Nicoya, provincia: Guanacaste.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-barco-quebrado-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de Playa Barco Quebrado Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"caption\":\"Costa Rica Info Link\"},\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/author\\\/nata\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fotos de Playa Barco Quebrado Costa Rica - Nicoya, Guanacaste","description":"Fotos de Playa Barco Quebrado Costa Rica. Distrito: Samara, canton: Nicoya, provincia: Guanacaste.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Fotos de Playa Barco Quebrado Costa Rica - Nicoya, Guanacaste","og_description":"Fotos de Playa Barco Quebrado Costa Rica. Distrito: Samara, canton: Nicoya, provincia: Guanacaste.","og_url":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/","og_site_name":"Fotos","article_published_time":"2011-06-20T02:15:11+00:00","article_modified_time":"2023-03-28T22:28:04+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-barco-quebrado-costa-rica-185x139.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db"},"headline":"Fotos de Playa Barco Quebrado Costa Rica","datePublished":"2011-06-20T02:15:11+00:00","dateModified":"2023-03-28T22:28:04+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/"},"wordCount":41,"commentCount":0,"articleSection":["Guanacaste","Playas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/","url":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/","name":"Fotos de Playa Barco Quebrado Costa Rica - Nicoya, Guanacaste","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2011-06-20T02:15:11+00:00","dateModified":"2023-03-28T22:28:04+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db"},"description":"Fotos de Playa Barco Quebrado Costa Rica. Distrito: Samara, canton: Nicoya, provincia: Guanacaste.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/playa-barco-quebrado-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Fotos de Playa Barco Quebrado Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","caption":"Costa Rica Info Link"},"url":"https:\/\/costaricainfolink.com\/fotos\/author\/nata\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1lmaw-jd","jetpack-related-posts":[{"id":3830,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-linda-costa-rica\/","url_meta":{"origin":1191,"position":0},"title":"Fotos de Playa Linda Costa Rica","author":"Costa Rica Info Link","date":"24 mayo 2013","format":false,"excerpt":"Click here to view this page in English Click en la foto para verla m\u00e1s grande. Para m\u00e1s informaci\u00f3n acerca de Playa Linda en Aguirre, Puntarenas, haga click aqu\u00ed","rel":"","context":"En \u00abPlayas\u00bb","block_context":{"text":"Playas","link":"https:\/\/costaricainfolink.com\/fotos\/category\/playas\/"},"img":{"alt_text":"Playa Linda Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/05\/Playa-Linda-Costa-Rica-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/05\/Playa-Linda-Costa-Rica-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/05\/Playa-Linda-Costa-Rica-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/05\/Playa-Linda-Costa-Rica-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/05\/Playa-Linda-Costa-Rica-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/05\/Playa-Linda-Costa-Rica-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":2215,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-brasilito-costa-rica\/","url_meta":{"origin":1191,"position":1},"title":"Fotos de Playa Brasilito Costa Rica","author":"Costa Rica Info Link","date":"29 febrero 2012","format":false,"excerpt":"Click here to read this page in English Click en las fotos para verlas m\u00e1s grandes Click aqu\u00ed para ver video, mapa con direcci\u00f3n, coordenadas para GPS, ubicaci\u00f3n, informaci\u00f3n de Playa Brasilito, Costa Rica","rel":"","context":"En \u00abGuanacaste\u00bb","block_context":{"text":"Guanacaste","link":"https:\/\/costaricainfolink.com\/fotos\/category\/guanacaste\/"},"img":{"alt_text":"Playa Brasilito Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":2502,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-buena-costa-rica\/","url_meta":{"origin":1191,"position":2},"title":"Fotos de Playa Buena Costa Rica","author":"Costa Rica Info Link","date":"8 mayo 2012","format":false,"excerpt":"Click here to read this page in English Click en las fotos para verlas m\u00e1s grandes Click aqu\u00ed para ver video, mapa con direcci\u00f3n, coordenadas para GPS, ubicaci\u00f3n WAZE y mapas de Google, informaci\u00f3n de Playa Buena Costa Rica","rel":"","context":"En \u00abGuanacaste\u00bb","block_context":{"text":"Guanacaste","link":"https:\/\/costaricainfolink.com\/fotos\/category\/guanacaste\/"},"img":{"alt_text":"Playa Buena Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-buena-costa-rica.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-buena-costa-rica.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-buena-costa-rica.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-buena-costa-rica.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-buena-costa-rica.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-buena-costa-rica.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":2483,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-bonita-en-guanacaste-costa-rica\/","url_meta":{"origin":1191,"position":3},"title":"Fotos de Playa Bonita en Guanacaste, Costa Rica","author":"Costa Rica Info Link","date":"5 mayo 2012","format":false,"excerpt":"Click here to read this page in English Click en las fotos para verlas m\u00e1s grandes Click aqu\u00ed para ver video, mapa con direcci\u00f3n, coordenadas para GPS, ubicaci\u00f3n, informaci\u00f3n de Playa Bonita Costa Rica","rel":"","context":"En \u00abGuanacaste\u00bb","block_context":{"text":"Guanacaste","link":"https:\/\/costaricainfolink.com\/fotos\/category\/guanacaste\/"},"img":{"alt_text":"Playa Bonita Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-bonita-costa-rica.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-bonita-costa-rica.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-bonita-costa-rica.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-bonita-costa-rica.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-bonita-costa-rica.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/05\/playa-bonita-costa-rica.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":3752,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-palma-costa-rica\/","url_meta":{"origin":1191,"position":4},"title":"Fotos de Playa Palma Costa Rica","author":"Costa Rica Info Link","date":"17 marzo 2013","format":false,"excerpt":"Click here to view this page in English Click en la foto para verla m\u00e1s grande. Para m\u00e1s informaci\u00f3n acerca de Playa Palma (Playa Bandera) en Puntarenas, haga click aqu\u00ed","rel":"","context":"En \u00abFotograf\u00eda de Viajes\u00bb","block_context":{"text":"Fotograf\u00eda de Viajes","link":"https:\/\/costaricainfolink.com\/fotos\/category\/fotografia-de-viajes\/"},"img":{"alt_text":"Playa Palma Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/03\/Playa-Palma-Costa-Rica-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":2185,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/","url_meta":{"origin":1191,"position":5},"title":"Fotos de Playa Junquillal Costa Rica","author":"Costa Rica Info Link","date":"23 febrero 2012","format":false,"excerpt":"Click en las fotos para verlas m\u00e1s grandes Para m\u00e1s informaci\u00f3n acerca de Playa Junquillal, haga click aqu\u00ed","rel":"","context":"En \u00abGuanacaste\u00bb","block_context":{"text":"Guanacaste","link":"https:\/\/costaricainfolink.com\/fotos\/category\/guanacaste\/"},"img":{"alt_text":"Playa Junquillal Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=1400%2C800 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/1191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=1191"}],"version-history":[{"count":10,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/1191\/revisions"}],"predecessor-version":[{"id":6479,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/1191\/revisions\/6479"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media?parent=1191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/categories?post=1191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/tags?post=1191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}