{"id":2185,"date":"2012-02-23T12:33:28","date_gmt":"2012-02-23T17:33:28","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/?p=2185"},"modified":"2017-06-06T19:15:11","modified_gmt":"2017-06-07T00:15:11","slug":"playa-junquillal-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/","title":{"rendered":"Fotos de Playa Junquillal Costa Rica"},"content":{"rendered":"<h2>Click en las fotos para verlas m\u00e1s grandes<\/h2>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1200\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/&quot;,&quot;likes_blog_id&quot;:19866444}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1200px; height: 601px;\" data-original-width=\"1200\" data-original-height=\"601\" > <div class=\"gallery-group images-1\" style=\"width: 800px; height: 601px;\" data-original-width=\"800\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-1\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"796\"> <meta itemprop=\"height\" content=\"597\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5260\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?w=796&#038;h=597&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"796\" height=\"597\" loading=\"lazy\" data-original-width=\"796\" data-original-height=\"597\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 796px; height: 597px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 400px; height: 601px;\" data-original-width=\"400\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-2\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5261\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-2.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-3\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5262\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?w=396&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-3.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"396\" height=\"296\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 301px;\" data-original-width=\"1200\" data-original-height=\"301\" > <div class=\"gallery-group images-1\" style=\"width: 400px; height: 301px;\" data-original-width=\"400\" data-original-height=\"301\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-4\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5263\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-4.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 400px; height: 301px;\" data-original-width=\"400\" data-original-height=\"301\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-5\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5264\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-5.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 400px; height: 301px;\" data-original-width=\"400\" data-original-height=\"301\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-6\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5265\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-6.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 601px;\" data-original-width=\"1200\" data-original-height=\"601\" > <div class=\"gallery-group images-2\" style=\"width: 400px; height: 601px;\" data-original-width=\"400\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-7\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5266\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-7.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-8\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5267\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?w=396&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-8.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"396\" height=\"296\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 800px; height: 601px;\" data-original-width=\"800\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-9\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"796\"> <meta itemprop=\"height\" content=\"597\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5268\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?w=796&#038;h=597&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-9.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"796\" height=\"597\" loading=\"lazy\" data-original-width=\"796\" data-original-height=\"597\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 796px; height: 597px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 451px;\" data-original-width=\"1200\" data-original-height=\"451\" > <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-10\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5269\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-10.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-11\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5270\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-11.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 601px;\" data-original-width=\"1200\" data-original-height=\"601\" > <div class=\"gallery-group images-1\" style=\"width: 800px; height: 601px;\" data-original-width=\"800\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-12\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"796\"> <meta itemprop=\"height\" content=\"597\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5271\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?w=796&#038;h=597&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-12.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"796\" height=\"597\" loading=\"lazy\" data-original-width=\"796\" data-original-height=\"597\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 796px; height: 597px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 400px; height: 601px;\" data-original-width=\"400\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-16\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5272\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-16.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-17\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5273\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?w=396&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-17.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"396\" height=\"296\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 278px;\" data-original-width=\"1200\" data-original-height=\"278\" > <div class=\"gallery-group images-1\" style=\"width: 369px; height: 278px;\" data-original-width=\"369\" data-original-height=\"278\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-18\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"365\"> <meta itemprop=\"height\" content=\"274\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5274\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?fit=867%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?w=365&#038;h=274&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?resize=185%2C139&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?resize=867%2C650&amp;ssl=1 867w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-18.jpg?resize=160%2C120&amp;ssl=1 160w\" width=\"365\" height=\"274\" loading=\"lazy\" data-original-width=\"365\" data-original-height=\"274\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 365px; height: 274px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 416px; height: 278px;\" data-original-width=\"416\" data-original-height=\"278\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-20\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"412\"> <meta itemprop=\"height\" content=\"274\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5275\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?w=412&#038;h=274&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-20.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"412\" height=\"274\" loading=\"lazy\" data-original-width=\"412\" data-original-height=\"274\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 412px; height: 274px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 415px; height: 278px;\" data-original-width=\"415\" data-original-height=\"278\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-21\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"411\"> <meta itemprop=\"height\" content=\"274\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5276\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?w=411&#038;h=274&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-21.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"411\" height=\"274\" loading=\"lazy\" data-original-width=\"411\" data-original-height=\"274\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 411px; height: 274px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 533px;\" data-original-width=\"1200\" data-original-height=\"533\" > <div class=\"gallery-group images-2\" style=\"width: 399px; height: 533px;\" data-original-width=\"399\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-22\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"395\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5277\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?w=395&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-22.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"395\" height=\"263\" loading=\"lazy\" data-original-width=\"395\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 395px; height: 263px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-23\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"395\"> <meta itemprop=\"height\" content=\"262\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5278\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?w=395&#038;h=262&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-23.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"395\" height=\"262\" loading=\"lazy\" data-original-width=\"395\" data-original-height=\"262\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 395px; height: 262px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 801px; height: 533px;\" data-original-width=\"801\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-24\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"797\"> <meta itemprop=\"height\" content=\"529\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5279\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?w=797&#038;h=529&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-24.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"797\" height=\"529\" loading=\"lazy\" data-original-width=\"797\" data-original-height=\"529\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 797px; height: 529px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 400px;\" data-original-width=\"1200\" data-original-height=\"400\" > <div class=\"gallery-group images-1\" style=\"width: 600px; height: 400px;\" data-original-width=\"600\" data-original-height=\"400\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-25\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"396\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5280\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?w=596&#038;h=396&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-25.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"596\" height=\"396\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"396\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 596px; height: 396px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 600px; height: 400px;\" data-original-width=\"600\" data-original-height=\"400\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-26\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"396\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5281\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?w=596&#038;h=396&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-26.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"596\" height=\"396\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"396\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 596px; height: 396px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 533px;\" data-original-width=\"1200\" data-original-height=\"533\" > <div class=\"gallery-group images-1\" style=\"width: 801px; height: 533px;\" data-original-width=\"801\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-27\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"797\"> <meta itemprop=\"height\" content=\"529\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5282\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?w=797&#038;h=529&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-27.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"797\" height=\"529\" loading=\"lazy\" data-original-width=\"797\" data-original-height=\"529\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 797px; height: 529px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 399px; height: 533px;\" data-original-width=\"399\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-28\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"395\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5283\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?w=395&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-28.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"395\" height=\"263\" loading=\"lazy\" data-original-width=\"395\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 395px; height: 263px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-29\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"395\"> <meta itemprop=\"height\" content=\"262\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5284\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?w=395&#038;h=262&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-29.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"395\" height=\"262\" loading=\"lazy\" data-original-width=\"395\" data-original-height=\"262\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 395px; height: 262px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 267px;\" data-original-width=\"1200\" data-original-height=\"267\" > <div class=\"gallery-group images-1\" style=\"width: 400px; height: 267px;\" data-original-width=\"400\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-30\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5285\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?w=396&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-30.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"396\" height=\"263\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 263px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 400px; height: 267px;\" data-original-width=\"400\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-31\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5286\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?w=396&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-31.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"396\" height=\"263\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 263px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 400px; height: 267px;\" data-original-width=\"400\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-32\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5287\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?w=396&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-32.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"396\" height=\"263\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 396px; height: 263px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 201px;\" data-original-width=\"1200\" data-original-height=\"201\" > <div class=\"gallery-group images-1\" style=\"width: 300px; height: 201px;\" data-original-width=\"300\" data-original-height=\"201\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-33\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"296\"> <meta itemprop=\"height\" content=\"197\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5288\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg\" data-orig-size=\"1920,1276\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?fit=978%2C650&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?w=296&#038;h=197&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?resize=185%2C123&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?resize=978%2C650&amp;ssl=1 978w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?resize=560%2C372&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?resize=260%2C173&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-33.jpg?resize=160%2C106&amp;ssl=1 160w\" width=\"296\" height=\"197\" loading=\"lazy\" data-original-width=\"296\" data-original-height=\"197\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 296px; height: 197px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 900px; height: 201px;\" data-original-width=\"900\" data-original-height=\"201\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/playa-junquillal-costa-rica-panoramica-2\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"896\"> <meta itemprop=\"height\" content=\"197\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5289\" data-orig-file=\"https:\/\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg\" data-orig-size=\"1920,422\" data-comments-opened=\"1\" data-image-title=\"Playa Junquillal Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?fit=300%2C66&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?fit=1024%2C225&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?w=896&#038;h=197&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?resize=185%2C41&amp;ssl=1 185w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?resize=300%2C66&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?resize=768%2C169&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?resize=1024%2C225&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?resize=560%2C123&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?resize=260%2C57&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-panoramica-2.jpg?resize=160%2C35&amp;ssl=1 160w\" width=\"896\" height=\"197\" loading=\"lazy\" data-original-width=\"896\" data-original-height=\"197\" itemprop=\"http:\/\/schema.org\/image\" title=\"Playa Junquillal Costa Rica\" alt=\"Playa Junquillal Costa Rica\" style=\"width: 896px; height: 197px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<p><a href=\"https:\/\/www.costaricainfolink.com\/es\/playa-junquillal-costa-rica\/\">Para m\u00e1s informaci\u00f3n acerca de Playa Junquillal, haga click aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click en las fotos para verlas m\u00e1s grandes Para m\u00e1s informaci\u00f3n acerca de Playa Junquillal, haga click aqu\u00ed<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[70,25],"tags":[],"class_list":["post-2185","post","type-post","status-publish","format-standard","hentry","category-guanacaste","category-playas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fotos de Playa Junquillal Costa Rica - Veintisiete de Abril, Santa Cruz<\/title>\n<meta name=\"description\" content=\"Fotos de Playa Junquillal Costa Rica. Distrito: Veintisiete de Abril, cant\u00f3n: Santa Cruz, provincia: Guanacaste.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotos de Playa Junquillal Costa Rica - Veintisiete de Abril, Santa Cruz\" \/>\n<meta property=\"og:description\" content=\"Fotos de Playa Junquillal Costa Rica. Distrito: Veintisiete de Abril, cant\u00f3n: Santa Cruz, provincia: Guanacaste.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-23T17:33:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-07T00:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?w=690&#038;h=517&#038;ssl=1\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\"},\"headline\":\"Fotos de Playa Junquillal Costa Rica\",\"datePublished\":\"2012-02-23T17:33:28+00:00\",\"dateModified\":\"2017-06-07T00:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/\"},\"wordCount\":31,\"commentCount\":0,\"articleSection\":[\"Guanacaste\",\"Playas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/\",\"name\":\"Fotos de Playa Junquillal Costa Rica - Veintisiete de Abril, Santa Cruz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2012-02-23T17:33:28+00:00\",\"dateModified\":\"2017-06-07T00:15:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\"},\"description\":\"Fotos de Playa Junquillal Costa Rica. Distrito: Veintisiete de Abril, cant\u00f3n: Santa Cruz, provincia: Guanacaste.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/playa-junquillal-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de Playa Junquillal Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"caption\":\"Costa Rica Info Link\"},\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/author\\\/nata\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fotos de Playa Junquillal Costa Rica - Veintisiete de Abril, Santa Cruz","description":"Fotos de Playa Junquillal Costa Rica. Distrito: Veintisiete de Abril, cant\u00f3n: Santa Cruz, provincia: Guanacaste.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Fotos de Playa Junquillal Costa Rica - Veintisiete de Abril, Santa Cruz","og_description":"Fotos de Playa Junquillal Costa Rica. Distrito: Veintisiete de Abril, cant\u00f3n: Santa Cruz, provincia: Guanacaste.","og_url":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/","og_site_name":"Fotos","article_published_time":"2012-02-23T17:33:28+00:00","article_modified_time":"2017-06-07T00:15:11+00:00","og_image":[{"url":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-junquillal-costa-rica-1.jpg?w=690&#038;h=517&#038;ssl=1","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db"},"headline":"Fotos de Playa Junquillal Costa Rica","datePublished":"2012-02-23T17:33:28+00:00","dateModified":"2017-06-07T00:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/"},"wordCount":31,"commentCount":0,"articleSection":["Guanacaste","Playas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/","url":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/","name":"Fotos de Playa Junquillal Costa Rica - Veintisiete de Abril, Santa Cruz","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2012-02-23T17:33:28+00:00","dateModified":"2017-06-07T00:15:11+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db"},"description":"Fotos de Playa Junquillal Costa Rica. Distrito: Veintisiete de Abril, cant\u00f3n: Santa Cruz, provincia: Guanacaste.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/playa-junquillal-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Fotos de Playa Junquillal Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","caption":"Costa Rica Info Link"},"url":"https:\/\/costaricainfolink.com\/fotos\/author\/nata\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1lmaw-zf","jetpack-related-posts":[{"id":1248,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-frijolar-costa-rica\/","url_meta":{"origin":2185,"position":0},"title":"Fotos de Playa Frijolar Costa Rica","author":"Costa Rica Info Link","date":"23 junio 2011","format":false,"excerpt":"Click en las fotos para verlas m\u00e1s grandes Para m\u00e1s informaci\u00f3n acerca de Playa Frijolar Costa Rica, haga click aqu\u00ed","rel":"","context":"En \u00abGuanacaste\u00bb","block_context":{"text":"Guanacaste","link":"https:\/\/costaricainfolink.com\/fotos\/category\/guanacaste\/"},"img":{"alt_text":"Playa Frijolar Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-frijolar-costa-rica.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-frijolar-costa-rica.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-frijolar-costa-rica.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-frijolar-costa-rica.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-frijolar-costa-rica.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-frijolar-costa-rica.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":2215,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-brasilito-costa-rica\/","url_meta":{"origin":2185,"position":1},"title":"Fotos de Playa Brasilito Costa Rica","author":"Costa Rica Info Link","date":"29 febrero 2012","format":false,"excerpt":"Click here to read this page in English Click en las fotos para verlas m\u00e1s grandes Click aqu\u00ed para ver video, mapa con direcci\u00f3n, coordenadas para GPS, ubicaci\u00f3n, informaci\u00f3n de Playa Brasilito, Costa Rica","rel":"","context":"En \u00abGuanacaste\u00bb","block_context":{"text":"Guanacaste","link":"https:\/\/costaricainfolink.com\/fotos\/category\/guanacaste\/"},"img":{"alt_text":"Playa Brasilito Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/02\/playa-brasilito-costa-rica.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":3471,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-la-pita-costa-rica\/","url_meta":{"origin":2185,"position":2},"title":"Fotos de Playa La Pita Costa Rica","author":"Costa Rica Info Link","date":"3 enero 2013","format":false,"excerpt":"Click here to view this page in English Click en las fotos para verla m\u00e1s grande. Para m\u00e1s informaci\u00f3n acerca de Playa La Pita en Puntarenas, haga click aqu\u00ed","rel":"","context":"En \u00abPlayas\u00bb","block_context":{"text":"Playas","link":"https:\/\/costaricainfolink.com\/fotos\/category\/playas\/"},"img":{"alt_text":"Playa La Pita Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-33.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-33.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-33.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-33.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-33.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2013\/01\/playa-la-pita-costa-rica-33.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":1148,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-islita-costa-rica\/","url_meta":{"origin":2185,"position":3},"title":"Fotos de Playa Islita Costa Rica","author":"Costa Rica Info Link","date":"15 junio 2011","format":false,"excerpt":"Click en las fotos para verlas m\u00e1s grandes Para m\u00e1s informaci\u00f3n acerca de Playa Islita, haga click aqu\u00ed","rel":"","context":"En \u00abGuanacaste\u00bb","block_context":{"text":"Guanacaste","link":"https:\/\/costaricainfolink.com\/fotos\/category\/guanacaste\/"},"img":{"alt_text":"Playa Islita Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-islita-costa-rica-13.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-islita-costa-rica-13.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-islita-costa-rica-13.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-islita-costa-rica-13.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-islita-costa-rica-13.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-islita-costa-rica-13.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":1210,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-pelada-costa-rica\/","url_meta":{"origin":2185,"position":4},"title":"Fotos de Playa Pelada Costa Rica","author":"Costa Rica Info Link","date":"20 junio 2011","format":false,"excerpt":"Click en la foto para verlas m\u00e1s grandes Click aqu\u00ed para video, direcci\u00f3n, mapas de Google, WAZE, como llegar, bus y tel\u00e9fonos. Para m\u00e1s informaci\u00f3n acerca de Playa Pelada, haga click aqu\u00ed","rel":"","context":"En \u00abGuanacaste\u00bb","block_context":{"text":"Guanacaste","link":"https:\/\/costaricainfolink.com\/fotos\/category\/guanacaste\/"},"img":{"alt_text":"Playa Pelada Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-pelada-costa-rica-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-pelada-costa-rica-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-pelada-costa-rica-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-pelada-costa-rica-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-pelada-costa-rica-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/06\/playa-pelada-costa-rica-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":2320,"url":"https:\/\/costaricainfolink.com\/fotos\/playa-dantita-costa-rica\/","url_meta":{"origin":2185,"position":5},"title":"Fotos de Playa Dantita Costa Rica","author":"Costa Rica Info Link","date":"22 marzo 2012","format":false,"excerpt":"Click en las fotos para verlas m\u00e1s grandes Click aqu\u00ed para ver video, mapa con direcci\u00f3n, coordenadas para GPS, ubicaci\u00f3n, informaci\u00f3n de Playa Dantita Costa Rica","rel":"","context":"En \u00abGuanacaste\u00bb","block_context":{"text":"Guanacaste","link":"https:\/\/costaricainfolink.com\/fotos\/category\/guanacaste\/"},"img":{"alt_text":"Playa Dantita Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-dantita-costa-rica.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-dantita-costa-rica.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-dantita-costa-rica.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-dantita-costa-rica.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-dantita-costa-rica.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/playa-dantita-costa-rica.jpg?resize=1400%2C800 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/2185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=2185"}],"version-history":[{"count":8,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/2185\/revisions"}],"predecessor-version":[{"id":5290,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/2185\/revisions\/5290"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media?parent=2185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/categories?post=2185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/tags?post=2185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}