{"id":28,"date":"2009-04-21T22:25:38","date_gmt":"2009-04-22T03:25:38","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/?p=28"},"modified":"2012-03-21T09:20:09","modified_gmt":"2012-03-21T14:20:09","slug":"volcan-arenal-san-carlos-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/","title":{"rendered":"Volc\u00e1n Arenal, San Carlos, Costa Rica"},"content":{"rendered":"<h5><a title=\"Arenal Volcano in San Carlos, Alajuela, Costa Rica\" href=\"https:\/\/www.costaricainfolink.com\/photos\/arenal-volcano-in-san-carlos-costa-rica\/\">Click here to view this page in English<\/a><\/h5>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1442\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/volcan-arenal-en-san-carlos-alajuela-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg?fit=504%2C307&amp;ssl=1\" data-orig-size=\"504,307\" data-comments-opened=\"1\" data-image-title=\"Volc\u00e1n Arenal en San Carlos, Alajuela, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg?fit=504%2C307&amp;ssl=1\" class=\"alignnone size-full wp-image-1442\" title=\"Volc\u00e1n Arenal en San Carlos, Alajuela, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg?resize=504%2C307&#038;ssl=1\" alt=\"\" width=\"504\" height=\"307\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg?w=504&amp;ssl=1 504w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg?resize=150%2C91&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg?resize=300%2C182&amp;ssl=1 300w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/p>\n<p><a href=\"https:\/\/www.costaricainfolink.com\/es\/parque-nacional-volcan-arenal-costa-rica\/\">Para m\u00e1s informaci\u00f3n acerca del Parque Nacional Volc\u00e1n Arenal, haga click aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click here to view this page in English Para m\u00e1s informaci\u00f3n acerca del Parque Nacional Volc\u00e1n Arenal, haga click aqu\u00ed<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,4,15],"tags":[],"class_list":["post-28","post","type-post","status-publish","format-standard","hentry","category-alajuela","category-san-carlos","category-volcanes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Volc\u00e1n Arenal, San Carlos, Costa Rica - Fotos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volc\u00e1n Arenal, San Carlos, Costa Rica - Fotos\" \/>\n<meta property=\"og:description\" content=\"Click here to view this page in English Para m\u00e1s informaci\u00f3n acerca del Parque Nacional Volc\u00e1n Arenal, haga click aqu\u00ed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-22T03:25:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-03-21T14:20:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Steven Madrigal Alfaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steven Madrigal Alfaro\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/\"},\"author\":{\"name\":\"Steven Madrigal Alfaro\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/9e1865e473f53d280e0e64022a9ad9f9\"},\"headline\":\"Volc\u00e1n Arenal, San Carlos, Costa Rica\",\"datePublished\":\"2009-04-22T03:25:38+00:00\",\"dateModified\":\"2012-03-21T14:20:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/\"},\"wordCount\":30,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg\",\"articleSection\":[\"Alajuela\",\"San Carlos\",\"Volcanes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/\",\"name\":\"Volc\u00e1n Arenal, San Carlos, Costa Rica - Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg\",\"datePublished\":\"2009-04-22T03:25:38+00:00\",\"dateModified\":\"2012-03-21T14:20:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/9e1865e473f53d280e0e64022a9ad9f9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/volcan-arenal-san-carlos-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volc\u00e1n Arenal, San Carlos, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/9e1865e473f53d280e0e64022a9ad9f9\",\"name\":\"Steven Madrigal Alfaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Steven Madrigal Alfaro\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"],\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/author\\\/costaricainfolink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Volc\u00e1n Arenal, San Carlos, Costa Rica - Fotos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Volc\u00e1n Arenal, San Carlos, Costa Rica - Fotos","og_description":"Click here to view this page in English Para m\u00e1s informaci\u00f3n acerca del Parque Nacional Volc\u00e1n Arenal, haga click aqu\u00ed","og_url":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/","og_site_name":"Fotos","article_published_time":"2009-04-22T03:25:38+00:00","article_modified_time":"2012-03-21T14:20:09+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg","type":"","width":"","height":""}],"author":"Steven Madrigal Alfaro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Steven Madrigal Alfaro"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/"},"author":{"name":"Steven Madrigal Alfaro","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/9e1865e473f53d280e0e64022a9ad9f9"},"headline":"Volc\u00e1n Arenal, San Carlos, Costa Rica","datePublished":"2009-04-22T03:25:38+00:00","dateModified":"2012-03-21T14:20:09+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/"},"wordCount":30,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg","articleSection":["Alajuela","San Carlos","Volcanes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/","url":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/","name":"Volc\u00e1n Arenal, San Carlos, Costa Rica - Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg","datePublished":"2009-04-22T03:25:38+00:00","dateModified":"2012-03-21T14:20:09+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/9e1865e473f53d280e0e64022a9ad9f9"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/volcan-arenal-en-san-carlos-alajuela-costa-rica.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/volcan-arenal-san-carlos-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Volc\u00e1n Arenal, San Carlos, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/9e1865e473f53d280e0e64022a9ad9f9","name":"Steven Madrigal Alfaro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Steven Madrigal Alfaro"},"sameAs":["http:\/\/www.costaricainfolink.com"],"url":"https:\/\/costaricainfolink.com\/fotos\/author\/costaricainfolink\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1lmaw-s","jetpack-related-posts":[{"id":108,"url":"https:\/\/costaricainfolink.com\/fotos\/tenideros-de-rio-celeste-costa-rica\/","url_meta":{"origin":28,"position":0},"title":"Te\u00f1ideros de R\u00edo Celeste, Costa Rica","author":"Steven Madrigal Alfaro","date":"4 mayo 2009","format":false,"excerpt":"Click here to view this page in English Para m\u00e1s informaci\u00f3n acerca del Parque Nacional Volc\u00e1n Tenorio haga click aqu\u00ed","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/05\/te%C3%B1ideros-rio-celeste-alajuela-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":120,"url":"https:\/\/costaricainfolink.com\/fotos\/catarata-de-rio-celeste-costa-rica\/","url_meta":{"origin":28,"position":1},"title":"Catarata de R\u00edo Celeste, Costa Rica","author":"Costa Rica Info Link","date":"9 mayo 2009","format":false,"excerpt":"Click here to view this page in English Para m\u00e1s informaci\u00f3n acerca del Parque Nacional Volc\u00e1n Tenorio haga click aqu\u00ed","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/05\/rio-celeste-catarata-varablanca-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":56,"url":"https:\/\/costaricainfolink.com\/fotos\/crater-del-volcan-poas-alajuela-costa-rica\/","url_meta":{"origin":28,"position":2},"title":"Cr\u00e1ter del Volc\u00e1n Po\u00e1s, Alajuela, Costa Rica","author":"Steven Madrigal Alfaro","date":"23 abril 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/crater-del-volcan-poas-alajuela-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":60,"url":"https:\/\/costaricainfolink.com\/fotos\/laguna-del-volcan-poas-alajuela-costa-rica\/","url_meta":{"origin":28,"position":3},"title":"Laguna del Volc\u00e1n Po\u00e1s, Alajuela, Costa Rica","author":"Steven Madrigal Alfaro","date":"23 abril 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/laguna-del-volcan-poas-alajuela-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":484,"url":"https:\/\/costaricainfolink.com\/fotos\/pernettya-coriacea-flor-del-volcan-poas-en-costa-rica\/","url_meta":{"origin":28,"position":4},"title":"Pernettya Coriacea, Flor del Volc\u00e1n Po\u00e1s en Costa Rica","author":"Costa Rica Info Link","date":"1 agosto 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abFlores\u00bb","block_context":{"text":"Flores","link":"https:\/\/costaricainfolink.com\/fotos\/category\/flores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/pernettya-coriacea-poas-volcano-flower-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":511,"url":"https:\/\/costaricainfolink.com\/fotos\/espinillo-ulex-europaeus-flor-del-volcan-poas-costa-rica\/","url_meta":{"origin":28,"position":5},"title":"Espinillo (Ulex Europaeus) Flor del Volc\u00e1n Po\u00e1s, Costa Rica","author":"Costa Rica Info Link","date":"10 agosto 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/tojo-espinillo-ulex-europaeus-flor-volcan-poas-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":7,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/28\/revisions"}],"predecessor-version":[{"id":720,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/28\/revisions\/720"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media?parent=28"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/categories?post=28"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/tags?post=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}