{"id":30,"date":"2009-04-22T15:25:19","date_gmt":"2009-04-22T20:25:19","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/?p=30"},"modified":"2011-12-30T19:57:03","modified_gmt":"2011-12-31T00:57:03","slug":"flor-de-san-ramon-alajuela-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/","title":{"rendered":"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica"},"content":{"rendered":"<h5><a title=\"Tillandsia, Bromeliad Flower in San Ram\u00f3n, Costa Rica\" href=\"https:\/\/www.costaricainfolink.com\/photos\/tillandsia-bromeliad-flower-in-san-ramon-costa-rica\/\">Click here to view this page in English<\/a><\/h5>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1445\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/flor-tillandsia-pinuela-bromelia-san-ramon-alajuela-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/flor-tillandsia-pi%C3%B1uela-bromelia-san-ramon-alajuela-costa-rica.jpg?fit=378%2C504&amp;ssl=1\" data-orig-size=\"378,504\" data-comments-opened=\"1\" data-image-title=\"Bromelia Tillandsia, Flor de San Ram\u00f3n, Alajuela, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/flor-tillandsia-pi%C3%B1uela-bromelia-san-ramon-alajuela-costa-rica.jpg?fit=378%2C504&amp;ssl=1\" class=\"alignnone size-full wp-image-1445\" title=\"Bromelia Tillandsia, Flor de San Ram\u00f3n, Alajuela, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/flor-tillandsia-pi%C3%B1uela-bromelia-san-ramon-alajuela-costa-rica.jpg?resize=378%2C504&#038;ssl=1\" alt=\"\" width=\"378\" height=\"504\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/flor-tillandsia-pi%C3%B1uela-bromelia-san-ramon-alajuela-costa-rica.jpg?w=378&amp;ssl=1 378w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/flor-tillandsia-pi%C3%B1uela-bromelia-san-ramon-alajuela-costa-rica.jpg?resize=112%2C150&amp;ssl=1 112w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/flor-tillandsia-pi%C3%B1uela-bromelia-san-ramon-alajuela-costa-rica.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 378px) 100vw, 378px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click here to view this page in English<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,16,5,13],"tags":[],"class_list":["post-30","post","type-post","status-publish","format-standard","hentry","category-alajuela","category-bromelias","category-flores","category-san-ramon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica - Fotos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica - Fotos\" \/>\n<meta property=\"og:description\" content=\"Click here to view this page in English\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-22T20:25:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-12-31T00:57:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/flor-tillandsia-pi\u00f1uela-bromelia-san-ramon-alajuela-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Steven Madrigal Alfaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steven Madrigal Alfaro\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/flor-de-san-ramon-alajuela-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/flor-de-san-ramon-alajuela-costa-rica\\\/\"},\"author\":{\"name\":\"Steven Madrigal Alfaro\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/9e1865e473f53d280e0e64022a9ad9f9\"},\"headline\":\"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica\",\"datePublished\":\"2009-04-22T20:25:19+00:00\",\"dateModified\":\"2011-12-31T00:57:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/flor-de-san-ramon-alajuela-costa-rica\\\/\"},\"wordCount\":17,\"commentCount\":0,\"articleSection\":[\"Alajuela\",\"Bromelias\",\"Flores\",\"San Ram\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/flor-de-san-ramon-alajuela-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/flor-de-san-ramon-alajuela-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/flor-de-san-ramon-alajuela-costa-rica\\\/\",\"name\":\"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica - Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"datePublished\":\"2009-04-22T20:25:19+00:00\",\"dateModified\":\"2011-12-31T00:57:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/9e1865e473f53d280e0e64022a9ad9f9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/flor-de-san-ramon-alajuela-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/flor-de-san-ramon-alajuela-costa-rica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/flor-de-san-ramon-alajuela-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/9e1865e473f53d280e0e64022a9ad9f9\",\"name\":\"Steven Madrigal Alfaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Steven Madrigal Alfaro\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"],\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/author\\\/costaricainfolink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica - Fotos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica - Fotos","og_description":"Click here to view this page in English","og_url":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/","og_site_name":"Fotos","article_published_time":"2009-04-22T20:25:19+00:00","article_modified_time":"2011-12-31T00:57:03+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/flor-tillandsia-pi\u00f1uela-bromelia-san-ramon-alajuela-costa-rica.jpg","type":"","width":"","height":""}],"author":"Steven Madrigal Alfaro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Steven Madrigal Alfaro"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/"},"author":{"name":"Steven Madrigal Alfaro","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/9e1865e473f53d280e0e64022a9ad9f9"},"headline":"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica","datePublished":"2009-04-22T20:25:19+00:00","dateModified":"2011-12-31T00:57:03+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/"},"wordCount":17,"commentCount":0,"articleSection":["Alajuela","Bromelias","Flores","San Ram\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/","url":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/","name":"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica - Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"datePublished":"2009-04-22T20:25:19+00:00","dateModified":"2011-12-31T00:57:03+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/9e1865e473f53d280e0e64022a9ad9f9"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/flor-de-san-ramon-alajuela-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Bromelia Tillandsia, Flor de San Ram\u00f3n, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/9e1865e473f53d280e0e64022a9ad9f9","name":"Steven Madrigal Alfaro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Steven Madrigal Alfaro"},"sameAs":["http:\/\/www.costaricainfolink.com"],"url":"https:\/\/costaricainfolink.com\/fotos\/author\/costaricainfolink\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1lmaw-u","jetpack-related-posts":[{"id":38,"url":"https:\/\/costaricainfolink.com\/fotos\/guzmania-sprucei-bromelia-flor-de-san-ramon-costa-rica\/","url_meta":{"origin":30,"position":0},"title":"Bromelia (Guzmania Sprucei) Flor de San Ram\u00f3n, Costa Rica","author":"Steven Madrigal Alfaro","date":"23 abril 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/guzmania-sprucei-flor-san-ramon-alajuela-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":41,"url":"https:\/\/costaricainfolink.com\/fotos\/guzmania-lingulata-bromelia-flor-de-san-ramon-costa-rica\/","url_meta":{"origin":30,"position":1},"title":"Bromelia (Guzmania Lingulata) Flor de San Ram\u00f3n, Costa Rica","author":"Steven Madrigal Alfaro","date":"23 abril 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/guzmania-lingulata-bromelia-flor-san-ramon-alajuela-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":45,"url":"https:\/\/costaricainfolink.com\/fotos\/flor-de-bromelia-roja-y-amarilla-de-san-ramon-costa-rica\/","url_meta":{"origin":30,"position":2},"title":"Flor de Bromelia Roja y Amarilla de San Ram\u00f3n, Costa Rica","author":"Steven Madrigal Alfaro","date":"23 abril 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/flor-bromelia-san-ramon-alajuela-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":104,"url":"https:\/\/costaricainfolink.com\/fotos\/hortensia-blanca-flor-de-costa-rica\/","url_meta":{"origin":30,"position":3},"title":"Hortensia Blanca, Flor de Costa Rica","author":"Steven Madrigal Alfaro","date":"4 mayo 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/05\/flor-hortensia-blanca-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":570,"url":"https:\/\/costaricainfolink.com\/fotos\/labios-de-puta-psychotria-poeppigiana-flor-de-costa-rica\/","url_meta":{"origin":30,"position":4},"title":"Labios de Puta (Psychotria Poeppigiana) Flor de Costa Rica","author":"Costa Rica Info Link","date":"22 agosto 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/labios-puta-psychotria-poeppigiana-flor-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":430,"url":"https:\/\/costaricainfolink.com\/fotos\/bromelia-en-arbol-flor-de-costa-rica\/","url_meta":{"origin":30,"position":5},"title":"Bromelia en \u00c1rbol, Flor de Costa Rica","author":"Costa Rica Info Link","date":"17 julio 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abBromelias\u00bb","block_context":{"text":"Bromelias","link":"https:\/\/costaricainfolink.com\/fotos\/category\/flores\/bromelias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/07\/bromelia-arbol-flor-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":9,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/30\/revisions"}],"predecessor-version":[{"id":34,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/30\/revisions\/34"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media?parent=30"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/categories?post=30"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/tags?post=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}