{"id":355,"date":"2009-06-27T13:42:10","date_gmt":"2009-06-27T18:42:10","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/?p=355"},"modified":"2011-12-26T15:43:00","modified_gmt":"2011-12-26T20:43:00","slug":"salvia-leucantha-flor-de-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/","title":{"rendered":"Salvia Leucantha, Flor de Costa Rica"},"content":{"rendered":"<h5><a title=\"Salvia Leucantha, Flower of Costa Rica\" href=\"https:\/\/www.costaricainfolink.com\/photos\/salvia-leucantha-flower-of-costa-rica\/\">Click here to view this page in English<\/a><\/h5>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1592\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/salvia-leucantha-flor-varablanca-heredia-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg?fit=504%2C378&amp;ssl=1\" data-orig-size=\"504,378\" data-comments-opened=\"1\" data-image-title=\"Salvia Leucantha, Flor en Varablanca de Heredia, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg?fit=504%2C378&amp;ssl=1\" class=\"alignnone size-full wp-image-1592\" title=\"Salvia Leucantha, Flor en Varablanca de Heredia, Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg?resize=504%2C378&#038;ssl=1\" alt=\"\" width=\"504\" height=\"378\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg?w=504&amp;ssl=1 504w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click here to view this page in English<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,22,57,23],"tags":[],"class_list":["post-355","post","type-post","status-publish","format-standard","hentry","category-flores","category-heredia","category-salvia","category-varablanca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salvia Leucantha, Flor de Costa Rica - Fotos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salvia Leucantha, Flor de Costa Rica - Fotos\" \/>\n<meta property=\"og:description\" content=\"Click here to view this page in English\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-27T18:42:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-12-26T20:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\"},\"headline\":\"Salvia Leucantha, Flor de Costa Rica\",\"datePublished\":\"2009-06-27T18:42:10+00:00\",\"dateModified\":\"2011-12-26T20:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/\"},\"wordCount\":14,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg\",\"articleSection\":[\"Flores\",\"Heredia\",\"Salvia\",\"Varablanca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/\",\"name\":\"Salvia Leucantha, Flor de Costa Rica - Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg\",\"datePublished\":\"2009-06-27T18:42:10+00:00\",\"dateModified\":\"2011-12-26T20:43:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/06\\\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/salvia-leucantha-flor-de-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salvia Leucantha, Flor de Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"caption\":\"Costa Rica Info Link\"},\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/author\\\/nata\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salvia Leucantha, Flor de Costa Rica - Fotos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Salvia Leucantha, Flor de Costa Rica - Fotos","og_description":"Click here to view this page in English","og_url":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/","og_site_name":"Fotos","article_published_time":"2009-06-27T18:42:10+00:00","article_modified_time":"2011-12-26T20:43:00+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db"},"headline":"Salvia Leucantha, Flor de Costa Rica","datePublished":"2009-06-27T18:42:10+00:00","dateModified":"2011-12-26T20:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/"},"wordCount":14,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg","articleSection":["Flores","Heredia","Salvia","Varablanca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/","url":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/","name":"Salvia Leucantha, Flor de Costa Rica - Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg","datePublished":"2009-06-27T18:42:10+00:00","dateModified":"2011-12-26T20:43:00+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/06\/salvia-leucantha-flor-varablanca-heredia-costa-rica.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/salvia-leucantha-flor-de-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Salvia Leucantha, Flor de Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","caption":"Costa Rica Info Link"},"url":"https:\/\/costaricainfolink.com\/fotos\/author\/nata\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1lmaw-5J","jetpack-related-posts":[{"id":684,"url":"https:\/\/costaricainfolink.com\/fotos\/china-rosada-flor-de-costa-rica\/","url_meta":{"origin":355,"position":0},"title":"China Rosada (Impatiens Walleriana), Flor de Costa Rica","author":"Costa Rica Info Link","date":"15 octubre 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abChinas\u00bb","block_context":{"text":"Chinas","link":"https:\/\/costaricainfolink.com\/fotos\/category\/flores\/chinas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/10\/china-rosa-impatiens-walleriana-flor-heredia-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":502,"url":"https:\/\/costaricainfolink.com\/fotos\/orquidea-doritaenopsis-principe-leopardo-flor-de-costa-rica\/","url_meta":{"origin":355,"position":1},"title":"Orqu\u00eddea Doritaenopsis Pr\u00edncipe Leopardo, Flor de Costa Rica","author":"Costa Rica Info Link","date":"7 agosto 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abFlores\u00bb","block_context":{"text":"Flores","link":"https:\/\/costaricainfolink.com\/fotos\/category\/flores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/orquidea-doritaenopsis-principe-leopardo-flor-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":560,"url":"https:\/\/costaricainfolink.com\/fotos\/orquidea-doritaenopsis-o-principe-leopardo-flor-de-costa-rica\/","url_meta":{"origin":355,"position":2},"title":"Orqu\u00eddea Doritaenopsis o Pr\u00edncipe Leopardo, Flor de Costa Rica","author":"Costa Rica Info Link","date":"19 agosto 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abFlores\u00bb","block_context":{"text":"Flores","link":"https:\/\/costaricainfolink.com\/fotos\/category\/flores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/orquidea-doritaenopsis-principe-leopardo-flor-costa-rica2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":123,"url":"https:\/\/costaricainfolink.com\/fotos\/rosa-roja-y-amarilla-flor-de-costa-rica\/","url_meta":{"origin":355,"position":3},"title":"Rosa Roja y Amarilla, Flor de Costa Rica","author":"Costa Rica Info Link","date":"9 mayo 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abFlores\u00bb","block_context":{"text":"Flores","link":"https:\/\/costaricainfolink.com\/fotos\/category\/flores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/05\/flor-rosa-roja-amarilla-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":79,"url":"https:\/\/costaricainfolink.com\/fotos\/catarata-la-paz-en-varablanca-costa-rica\/","url_meta":{"origin":355,"position":4},"title":"Catarata La Paz en Varablanca, Costa Rica","author":"Steven Madrigal Alfaro","date":"29 abril 2009","format":false,"excerpt":"Click here to view this page in English Para m\u00e1s informaci\u00f3n acerca del Refugio de Vida Silvestre y Parque Natural La Paz Waterfall Gardens, haga click aqu\u00ed","rel":"","context":"En \u00abCataratas\u00bb","block_context":{"text":"Cataratas","link":"https:\/\/costaricainfolink.com\/fotos\/category\/cataratas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/04\/catarata-de-la-paz-waterfall-gardens-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":979,"url":"https:\/\/costaricainfolink.com\/fotos\/colibri-manguito-pechiverde-anthracothorax-prevostii-costa-rica\/","url_meta":{"origin":355,"position":5},"title":"Colibr\u00ed Manguito Pechiverde (Anthracothorax prevostii), Costa Rica","author":"Costa Rica Info Link","date":"8 febrero 2011","format":false,"excerpt":"Click here to view this page in English Fotograf\u00eda tomada en La Paz Waterfall Gardens, Varablanca, Heredia, Costa Rica.","rel":"","context":"En \u00abAnimales\u00bb","block_context":{"text":"Animales","link":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2011\/02\/colibr%C3%AD-manguito-pechiverde-anthracothorax-prevostii-ave-costa-rica3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=355"}],"version-history":[{"count":6,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/355\/revisions"}],"predecessor-version":[{"id":1630,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/355\/revisions\/1630"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media?parent=355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/categories?post=355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/tags?post=355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}