{"id":496,"date":"2009-08-05T09:03:43","date_gmt":"2009-08-05T14:03:43","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/fotos\/?p=496"},"modified":"2012-01-03T12:24:05","modified_gmt":"2012-01-03T17:24:05","slug":"saino-o-pecari-de-collar-tayassu-tajacu-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/","title":{"rendered":"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica"},"content":{"rendered":"<h5><a title=\"Collared Peccary or Javelina (Tayassu Tajacu) Costa Rica\" href=\"https:\/\/www.costaricainfolink.com\/photos\/collared-peccary-or-javelina-tayassu-tajacu-costa-rica\/\">Click here to view this page in English<\/a><\/h5>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1761\" data-permalink=\"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/saino-pecari-tayassu-tajacu-fauna-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg?fit=504%2C378&amp;ssl=1\" data-orig-size=\"504,378\" data-comments-opened=\"1\" data-image-title=\"Pecar\u00ed de Collar, Sa\u00edno, Sajino, Cuche de Monte, Chancho Rosillo, Ch\u00e1charo o B\u00e1quiro (Tayassu Tajacu) de Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg?fit=504%2C378&amp;ssl=1\" class=\"alignnone size-full wp-image-1761\" title=\"Pecar\u00ed de Collar, Sa\u00edno, Sajino, Cuche de Monte, Chancho Rosillo, Ch\u00e1charo o B\u00e1quiro (Tayassu Tajacu) de Costa Rica\" src=\"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg?resize=504%2C378&#038;ssl=1\" alt=\"\" width=\"504\" height=\"378\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg?w=504&amp;ssl=1 504w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click here to view this page in English<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,37,54],"tags":[],"class_list":["post-496","post","type-post","status-publish","format-standard","hentry","category-animales","category-limon","category-pecaries-o-sainos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica - Fotos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica - Fotos\" \/>\n<meta property=\"og:description\" content=\"Click here to view this page in English\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fotos\" \/>\n<meta property=\"article:published_time\" content=\"2009-08-05T14:03:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-01-03T17:24:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\"},\"headline\":\"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica\",\"datePublished\":\"2009-08-05T14:03:43+00:00\",\"dateModified\":\"2012-01-03T17:24:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/\"},\"wordCount\":18,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/08\\\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg\",\"articleSection\":[\"Animales\",\"Lim\u00f3n\",\"Pecar\u00edes o Sa\u00ednos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/\",\"name\":\"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica - Fotos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/08\\\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg\",\"datePublished\":\"2009-08-05T14:03:43+00:00\",\"dateModified\":\"2012-01-03T17:24:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/08\\\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/fotos\\\/wp-content\\\/uploads\\\/2009\\\/08\\\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/\",\"name\":\"Fotos\",\"description\":\"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/#\\\/schema\\\/person\\\/416b4ccbe7c8750d241746b4e59fb2db\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g\",\"caption\":\"Costa Rica Info Link\"},\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/fotos\\\/author\\\/nata\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica - Fotos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica - Fotos","og_description":"Click here to view this page in English","og_url":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/","og_site_name":"Fotos","article_published_time":"2009-08-05T14:03:43+00:00","article_modified_time":"2012-01-03T17:24:05+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db"},"headline":"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica","datePublished":"2009-08-05T14:03:43+00:00","dateModified":"2012-01-03T17:24:05+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/"},"wordCount":18,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg","articleSection":["Animales","Lim\u00f3n","Pecar\u00edes o Sa\u00ednos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/","url":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/","name":"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica - Fotos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg","datePublished":"2009-08-05T14:03:43+00:00","dateModified":"2012-01-03T17:24:05+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/08\/saino-pecari-tayassu-tajacu-fauna-costa-rica.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/fotos\/saino-o-pecari-de-collar-tayassu-tajacu-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/fotos\/"},{"@type":"ListItem","position":2,"name":"Sa\u00edno o Pecar\u00ed de Collar (Tayassu Tajacu) Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/fotos\/#website","url":"https:\/\/costaricainfolink.com\/fotos\/","name":"Fotos","description":"Fotos de Costa Rica, Turismo, Playas, Paisajes, Aves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/fotos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/fotos\/#\/schema\/person\/416b4ccbe7c8750d241746b4e59fb2db","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5748d182304857d546112592901468f363f161e7037fcd61df89b84aaa0f8e07?s=96&d=mm&r=g","caption":"Costa Rica Info Link"},"url":"https:\/\/costaricainfolink.com\/fotos\/author\/nata\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1lmaw-80","jetpack-related-posts":[{"id":477,"url":"https:\/\/costaricainfolink.com\/fotos\/achiote-onoto-o-urucu-bixa-orellana-de-costa-rica\/","url_meta":{"origin":496,"position":0},"title":"Achiote, Onoto o Uruc\u00fa (Bixa Orellana) de Costa Rica","author":"Costa Rica Info Link","date":"30 julio 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abFrutas\u00bb","block_context":{"text":"Frutas","link":"https:\/\/costaricainfolink.com\/fotos\/category\/frutas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/07\/achiote-urucu-onoto-bixa-orellana-costa-rica1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":408,"url":"https:\/\/costaricainfolink.com\/fotos\/yiguirro-o-turdus-grayi-clay-colored-robin-ave-de-costa-rica\/","url_meta":{"origin":496,"position":1},"title":"Yig\u00fcirro o Turdus Grayi (Clay-Colored Robin) Ave de Costa Rica","author":"Costa Rica Info Link","date":"12 julio 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAnimales\u00bb","block_context":{"text":"Animales","link":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/07\/yig%C3%BCirro-turdus-grayi-clay-colored-robin-ave-costa-rica-Copy.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":634,"url":"https:\/\/costaricainfolink.com\/fotos\/siriri-vientre-negro-o-piches-dendrocygna-autummali-aves-de-costa-rica\/","url_meta":{"origin":496,"position":2},"title":"Sirir\u00ed Vientre Negro o Piches (Dendrocygna Autummali) Aves de Costa Rica.","author":"Costa Rica Info Link","date":"24 septiembre 2009","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/fotos\/category\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2009\/09\/piches-dendrocygna-autummalis-ave-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2285,"url":"https:\/\/costaricainfolink.com\/fotos\/martin-pescador-de-collar-megaceryle-torquata-ave-de-costa-rica\/","url_meta":{"origin":496,"position":3},"title":"Mart\u00edn Pescador de Collar (Megaceryle torquata) Ave de Costa Rica","author":"Costa Rica Info Link","date":"12 marzo 2012","format":false,"excerpt":"Click here to read this page in English","rel":"","context":"En \u00abAnimales\u00bb","block_context":{"text":"Animales","link":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2012\/03\/mart%C3%ADn-pescador-megaceryle-torquata-ave-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":783,"url":"https:\/\/costaricainfolink.com\/fotos\/mono-cariblanco-o-capuchino-cebus-capucinus-costa-rica\/","url_meta":{"origin":496,"position":4},"title":"Mono Cariblanco o Capuchino (Cebus Capucinus) Costa Rica","author":"Costa Rica Info Link","date":"24 enero 2010","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAnimales\u00bb","block_context":{"text":"Animales","link":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2010\/01\/mono-cariblanco-capuchino-cebus-capucinus-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":879,"url":"https:\/\/costaricainfolink.com\/fotos\/mono-capuchino-o-cariblanco-cebus-capucinus-costa-rica\/","url_meta":{"origin":496,"position":5},"title":"Mono Capuchino o Cariblanco (Cebus Capucinus) Costa Rica","author":"Costa Rica Info Link","date":"23 junio 2010","format":false,"excerpt":"Click here to view this page in English","rel":"","context":"En \u00abAnimales\u00bb","block_context":{"text":"Animales","link":"https:\/\/costaricainfolink.com\/fotos\/category\/animales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.costaricainfolink.com\/fotos\/wp-content\/uploads\/2010\/06\/mono-cariblanco-capuchino-cebus-capucinus-costa-rica2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/comments?post=496"}],"version-history":[{"count":3,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/496\/revisions"}],"predecessor-version":[{"id":1760,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/posts\/496\/revisions\/1760"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/media?parent=496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/categories?post=496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/fotos\/wp-json\/wp\/v2\/tags?post=496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}