{"id":69,"count":1,"description":"","link":"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/10201\/","name":"10201","slug":"10201","taxonomy":"category","parent":49,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10201 Archivos - Hoteles en Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/10201\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10201 Archivos - Hoteles en Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/10201\/\" \/>\n<meta property=\"og:site_name\" content=\"Hoteles en Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/category\\\/codigo-postal\\\/10201\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/category\\\/codigo-postal\\\/10201\\\/\",\"name\":\"10201 Archivos - Hoteles en Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/category\\\/codigo-postal\\\/10201\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/category\\\/codigo-postal\\\/10201\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3digo postal\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/category\\\/codigo-postal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10201\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/\",\"name\":\"Hoteles en Costa Rica\",\"description\":\"Ubicaci\u00f3n, mapa con direcci\u00f3n, coordenadas para GPS, tel\u00e9fono, sitio web y fotos.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10201 Archivos - Hoteles en Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/10201\/","og_locale":"es_ES","og_type":"article","og_title":"10201 Archivos - Hoteles en Costa Rica","og_url":"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/10201\/","og_site_name":"Hoteles en Costa Rica","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/10201\/","url":"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/10201\/","name":"10201 Archivos - Hoteles en Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/#website"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/10201\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/10201\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/hoteles\/"},{"@type":"ListItem","position":2,"name":"C\u00f3digo postal","item":"https:\/\/costaricainfolink.com\/hoteles\/category\/codigo-postal\/"},{"@type":"ListItem","position":3,"name":"10201"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/hoteles\/#website","url":"https:\/\/costaricainfolink.com\/hoteles\/","name":"Hoteles en Costa Rica","description":"Ubicaci\u00f3n, mapa con direcci\u00f3n, coordenadas para GPS, tel\u00e9fono, sitio web y fotos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/hoteles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/categories\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/categories\/49"}],"wp:post_type":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/posts?categories=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}