{"id":578,"date":"2011-05-30T13:39:46","date_gmt":"2011-05-30T18:39:46","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/hoteles\/?p=578"},"modified":"2018-04-02T16:31:40","modified_gmt":"2018-04-02T21:31:40","slug":"hotel-casa-marbella","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/","title":{"rendered":"Hotel Casa Marbella Costa Rica"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"581\" data-permalink=\"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/hotel-casa-marbella-puntarenas-costa-rica-logo\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg\" data-orig-size=\"500,139\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Hotel Casa Marbella en Santa Teresa, Puntarenas, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg\" class=\"size-full wp-image-581 alignright\" title=\"Hotel Casa Marbella en Santa Teresa, Puntarenas, Costa Rica\" src=\"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg\" alt=\"Hotel Casa Marbella Costa Rica en Santa Teresa\" width=\"350\" height=\"97\" srcset=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg 500w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo-300x83.jpg 300w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo-150x41.jpg 150w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo-400x111.jpg 400w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><strong>Ubicaci\u00f3n:<\/strong>125 m este de Super Ronnie en Santa Teresa, distrito: C\u00f3bano, cant\u00f3n: Puntarenas, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 60111.<br \/>\n<strong>Coordenadas para GPS:<\/strong> 9.629946,-85.152798 (9\u00b037&#8217;47.8056&#8243;N, 85\u00b09&#8217;10.0728&#8243;W)<br \/>\n<strong>Tel\u00e9fono:<\/strong><a href=\"tel:+5062640-0749\">+506 2640 0749<\/a> \/ <a href=\"tel:+50683503596\">+506 8350 35 96<\/a><br \/>\n<strong>Tel\u00e9fono del Ferri Tambor:<\/strong> <a href=\"tel:+5062661-2084\">+506 2661-2084<\/a><\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/www.costaricainfolink.com\/hoteles\/mapa-con-la-direccion-al-hotel-casa-marbella\/\">Haga click aqu\u00ed para ver la direcci\u00f3n al Hotel Casa Marbella Costa Rica en Santa Teresa.<\/a><\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1eqy3640\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.costaricainfolink.com\/ubicacion-waze.jpg\" alt=\"Ubicaci\u00f3n WAZE de Hotel Casa Marbella Cobano, Puntarenas, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.com\/maps\/place\/9%C2%B037'47.8%22N+85%C2%B009'10.1%22W\/@9.629946,-85.152798,17z\/data=!3m1!4b1!4m2!3m1!1s0x0:0x0?hl=es\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.costaricainfolink.com\/ubicacion-mapas-de-google.jpg\" alt=\"Ubicaci\u00f3n Mapas de Google de Playa Colonia en Hotel Casa Marbella en Cobano, Puntarenas, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<p>El Hotel Casa Marbella Costa Rica es un hotel estilo boutique, ubicado en el centro de Santa Teresa, en la ladera de una monta\u00f1a, a 200 m de la playa y con unas vistas incre\u00edbles al Oc\u00e9ano Pac\u00edfico.\u00a0<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"594\" data-permalink=\"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/hotel-casa-marbella-puntarenas-costa-rica\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica.jpg\" data-orig-size=\"460,300\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Hotel Casa Marbella en Santa Teresa, Puntarenas, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica.jpg\" class=\"alignright size-full wp-image-594\" title=\"Hotel Casa Marbella en Santa Teresa, Puntarenas, Costa Rica\" src=\"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica.jpg\" alt=\"Hotel Casa Marbella Costa Rica en Santa Teresa\" width=\"368\" height=\"240\" srcset=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica.jpg 460w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-300x195.jpg 300w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-150x97.jpg 150w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-400x260.jpg 400w\" sizes=\"auto, (max-width: 368px) 100vw, 368px\" \/><\/p>\n<p>El Hotel Casa Marbella ofrece un ambiente confortable en medio del tr\u00f3pico de Costa Rica, invitando a sus hu\u00e9spedes a explorar algunas de las m\u00e1s prestigiosas playas en Costa Rica, con estilo, comodidad y seguridad. Es muy f\u00e1cil quedarse adormecido con la fresca brisa del atardecer y el movimiento r\u00edtmico de las olas del mar, ya que todas las habitaciones cuentan con vista al oc\u00e9ano.<\/p>\n<p>El Hotel Casa Marbella ofrece 3 tipos de alojamientos (hay de uno, dos, o tres dormitorios) con ba\u00f1o privado, nevera, wi-fi, cafetera el\u00e9ctrica, DVD (consultar), aire acondicionado y caja de seguridad, todas conectadas con el \u00e1rea de piscina. Adem\u00e1s, algunas pueden ser con cocina, sala y balc\u00f3n privado con vista al mar.<\/p>\n<p>Admire la belleza de la vista del Hotel Casa Marbella o simplemente rel\u00e1jese en la piscina. Sea como sea, al final del d\u00eda, habr\u00e1 experimentado una de las puestas de sol m\u00e1s espectaculares del Oc\u00e9ano Pac\u00edfico.<\/p>\n<p><strong>Como llegar al Hotel Casa Marbella Costa Rica en Santa Teresa?<\/strong><\/p>\n<p>Desde San Jos\u00e9 dir\u00edjase a Puntarenas y ah\u00ed tome el Ferri Tambor \u00f3 el Ferri a Paquera. (Tambor es el Ferri m\u00e1s grande y el m\u00e1s c\u00f3modo, adem\u00e1s, se recomienda que llegue a Puntarenas una hora antes de que salga el ferri). Vaya por Tambor hacia C\u00f3bano. En C\u00f3bano cruce el pueblo y despu\u00e9s de unos 8 km y poco antes de la playa encontrar\u00e1 un cruce, gire a la derecha hacia Santa Teresa. Contin\u00fae por la carretera hasta llegar al S\u00faper Ronnie, y ah\u00ed gire a la derecha por unos 120m hasta llegar al hotel, al lado izquierdo. Necesitar\u00e1 un total de cinco horas y media desde San Jos\u00e9.<\/p>\n<p>Desde el Aeropuerto Internacional Daniel Oduber Quir\u00f3s (LIR), conduzca hacia el Sur por Nosara, S\u00e1mara y Coyote, cruce el r\u00edo Bongo y contin\u00fae por Manzanillo hasta Santa Teresa. Entre Ar\u00edo y Manzanillo hay un trecho de playa. Aseg\u00farese que la marea est\u00e9 BAJA y use s\u00f3lo un veh\u00edculo 4&#215;4 para \u00e9sta ruta. Es un viaje muy esc\u00e9nico a medida que va bajando por la costa (esta ruta ejemplifica la Costa Rica rural y es sumamente bella). O bien, puede llegar al cruce que lleva a Playa Ar\u00edo y realizar el viaje a trav\u00e9s de la monta\u00f1a, este camino toma m\u00e1s tiempo, pero es una carretera oficial y su uso no depende de las mareas.<br \/>\n<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"598\" data-permalink=\"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/hotel-casa-marbella-puntarenas-costa-rica-2\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica1.jpg\" data-orig-size=\"208,156\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Hotel Casa Marbella en Santa Teresa, Puntarenas, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica1.jpg\" class=\"alignnone size-full wp-image-598\" title=\"Hotel Casa Marbella en Santa Teresa, Puntarenas, Costa Rica\" src=\"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica1.jpg\" alt=\"Hotel Casa Marbella Costa Rica en Santa Teresa\" width=\"208\" height=\"156\" srcset=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica1.jpg 208w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica1-150x112.jpg 150w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"606\" data-permalink=\"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/hotel-casa-marbella-puntarenas-costa-rica-habitaciones\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-habitaciones.jpg\" data-orig-size=\"208,156\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Habitaciones del Hotel Casa Marbella en Puntarenas, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-habitaciones.jpg\" class=\"alignnone size-full wp-image-606\" title=\"Habitaciones del Hotel Casa Marbella en Puntarenas, Costa Rica\" src=\"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-habitaciones.jpg\" alt=\"Hotel Casa Marbella Costa Rica en Santa Teresa\" width=\"208\" height=\"156\" srcset=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-habitaciones.jpg 208w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-habitaciones-150x112.jpg 150w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"603\" data-permalink=\"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/hotel-casa-marbella-puntarenas-costa-rica-piscina\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-piscina.jpg\" data-orig-size=\"208,156\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Area de Piscina y Jacuzzi del Hotel Casa Marbella en Santa Teresa, Puntarenas, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-piscina.jpg\" class=\"alignnone size-full wp-image-603\" title=\"Area de Piscina y Jacuzzi del Hotel Casa Marbella en Santa Teresa, Puntarenas, Costa Rica\" src=\"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-piscina.jpg\" alt=\"Hotel Casa Marbella Costa Rica en Santa Teresa\" width=\"208\" height=\"156\" srcset=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-piscina.jpg 208w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-piscina-150x112.jpg 150w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"607\" data-permalink=\"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/hotel-casa-marbella-puntarenas-costa-rica-mirador\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-mirador.jpg\" data-orig-size=\"208,156\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Miradores del Hotel Casa Marbella en Puntarenas, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-mirador.jpg\" class=\"alignnone size-full wp-image-607\" title=\"Miradores del Hotel Casa Marbella en Puntarenas, Costa Rica\" src=\"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-mirador.jpg\" alt=\"Hotel Casa Marbella Costa Rica en Santa Teresa\" width=\"208\" height=\"156\" srcset=\"https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-mirador.jpg 208w, https:\/\/costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-mirador-150x112.jpg 150w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ubicaci\u00f3n:125 m este de Super Ronnie en Santa Teresa, distrito: C\u00f3bano, cant\u00f3n: Puntarenas, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 60111. Coordenadas para GPS: 9.629946,-85.152798 (9\u00b037&#8217;47.8056&#8243;N, 85\u00b09&#8217;10.0728&#8243;W) Tel\u00e9fono:+506 2640 0749 \/ +506 8350 35 96 Tel\u00e9fono del Ferri Tambor: +506 2661-2084 Mapa con direcci\u00f3n: Haga click aqu\u00ed para ver la direcci\u00f3n al Hotel &#8230; <a title=\"Hotel Casa Marbella Costa Rica\" class=\"read-more\" href=\"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/\" aria-label=\"M\u00e1s en Hotel Casa Marbella Costa Rica\">Read more<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[77,10,30,43],"tags":[],"class_list":["post-578","post","type-post","status-publish","format-standard","hentry","category-77","category-de-playa","category-puntarenas","category-santa-teresa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hotel Casa Marbella Costa Rica en Santa Teresa - Tel\u00e9fono, Direcci\u00f3n<\/title>\n<meta name=\"description\" content=\"Informaci\u00f3n del Hotel Casa Marbella Costa Rica en Santa Teresa: ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel Casa Marbella Costa Rica en Santa Teresa - Tel\u00e9fono, Direcci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Informaci\u00f3n del Hotel Casa Marbella Costa Rica en Santa Teresa: ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/\" \/>\n<meta property=\"og:site_name\" content=\"Hoteles en Costa Rica\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-30T18:39:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-02T21:31:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/#\\\/schema\\\/person\\\/e0b4013e83a54a7f246ea9f568373055\"},\"headline\":\"Hotel Casa Marbella Costa Rica\",\"datePublished\":\"2011-05-30T18:39:46+00:00\",\"dateModified\":\"2018-04-02T21:31:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/\"},\"wordCount\":530,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/hoteles\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg\",\"articleSection\":[\"60111\",\"De playa\",\"Puntarenas\",\"Santa Teresa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/\",\"name\":\"Hotel Casa Marbella Costa Rica en Santa Teresa - Tel\u00e9fono, Direcci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/hoteles\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg\",\"datePublished\":\"2011-05-30T18:39:46+00:00\",\"dateModified\":\"2018-04-02T21:31:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/#\\\/schema\\\/person\\\/e0b4013e83a54a7f246ea9f568373055\"},\"description\":\"Informaci\u00f3n del Hotel Casa Marbella Costa Rica en Santa Teresa: ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/hoteles\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/hoteles\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/hotel-casa-marbella\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel Casa Marbella Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/\",\"name\":\"Hoteles en Costa Rica\",\"description\":\"Ubicaci\u00f3n, mapa con direcci\u00f3n, coordenadas para GPS, tel\u00e9fono, sitio web y fotos.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/#\\\/schema\\\/person\\\/e0b4013e83a54a7f246ea9f568373055\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"],\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/author\\\/costaricainfolink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel Casa Marbella Costa Rica en Santa Teresa - Tel\u00e9fono, Direcci\u00f3n","description":"Informaci\u00f3n del Hotel Casa Marbella Costa Rica en Santa Teresa: ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/","og_locale":"es_ES","og_type":"article","og_title":"Hotel Casa Marbella Costa Rica en Santa Teresa - Tel\u00e9fono, Direcci\u00f3n","og_description":"Informaci\u00f3n del Hotel Casa Marbella Costa Rica en Santa Teresa: ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.","og_url":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/","og_site_name":"Hoteles en Costa Rica","article_published_time":"2011-05-30T18:39:46+00:00","article_modified_time":"2018-04-02T21:31:40+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Costa Rica Info Link","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/hoteles\/#\/schema\/person\/e0b4013e83a54a7f246ea9f568373055"},"headline":"Hotel Casa Marbella Costa Rica","datePublished":"2011-05-30T18:39:46+00:00","dateModified":"2018-04-02T21:31:40+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/"},"wordCount":530,"commentCount":2,"image":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg","articleSection":["60111","De playa","Puntarenas","Santa Teresa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/","url":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/","name":"Hotel Casa Marbella Costa Rica en Santa Teresa - Tel\u00e9fono, Direcci\u00f3n","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg","datePublished":"2011-05-30T18:39:46+00:00","dateModified":"2018-04-02T21:31:40+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/#\/schema\/person\/e0b4013e83a54a7f246ea9f568373055"},"description":"Informaci\u00f3n del Hotel Casa Marbella Costa Rica en Santa Teresa: ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/hoteles\/wp-content\/uploads\/2011\/05\/hotel-casa-marbella-puntarenas-costa-rica-logo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/hoteles\/hotel-casa-marbella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/hoteles\/"},{"@type":"ListItem","position":2,"name":"Hotel Casa Marbella Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/hoteles\/#website","url":"https:\/\/costaricainfolink.com\/hoteles\/","name":"Hoteles en Costa Rica","description":"Ubicaci\u00f3n, mapa con direcci\u00f3n, coordenadas para GPS, tel\u00e9fono, sitio web y fotos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/hoteles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/hoteles\/#\/schema\/person\/e0b4013e83a54a7f246ea9f568373055","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"],"url":"https:\/\/costaricainfolink.com\/hoteles\/author\/costaricainfolink\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5ifSl-9k","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/posts\/578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/comments?post=578"}],"version-history":[{"count":29,"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/posts\/578\/revisions"}],"predecessor-version":[{"id":1651,"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/posts\/578\/revisions\/1651"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/media?parent=578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/categories?post=578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/tags?post=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}