{"id":107,"count":1,"description":"","link":"https:\/\/costaricainfolink.com\/hoteles\/tag\/villas-la-paillote\/","name":"Villas La Paillote","slug":"villas-la-paillote","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villas La Paillote Archivos - Hoteles en Costa Rica<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villas La Paillote Archivos - Hoteles en Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/hoteles\/tag\/villas-la-paillote\/\" \/>\n<meta property=\"og:site_name\" content=\"Hoteles en Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/tag\\\/villas-la-paillote\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/tag\\\/villas-la-paillote\\\/\",\"name\":\"Villas La Paillote Archivos - Hoteles en Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/tag\\\/villas-la-paillote\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/tag\\\/villas-la-paillote\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villas La Paillote\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/\",\"name\":\"Hoteles en Costa Rica\",\"description\":\"Ubicaci\u00f3n, mapa con direcci\u00f3n, coordenadas para GPS, tel\u00e9fono, sitio web y fotos.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/hoteles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villas La Paillote Archivos - Hoteles en Costa Rica","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Villas La Paillote Archivos - Hoteles en Costa Rica","og_url":"https:\/\/costaricainfolink.com\/hoteles\/tag\/villas-la-paillote\/","og_site_name":"Hoteles en Costa Rica","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/costaricainfolink.com\/hoteles\/tag\/villas-la-paillote\/","url":"https:\/\/costaricainfolink.com\/hoteles\/tag\/villas-la-paillote\/","name":"Villas La Paillote Archivos - Hoteles en Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/#website"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/hoteles\/tag\/villas-la-paillote\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/hoteles\/tag\/villas-la-paillote\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/hoteles\/"},{"@type":"ListItem","position":2,"name":"Villas La Paillote"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/hoteles\/#website","url":"https:\/\/costaricainfolink.com\/hoteles\/","name":"Hoteles en Costa Rica","description":"Ubicaci\u00f3n, mapa con direcci\u00f3n, coordenadas para GPS, tel\u00e9fono, sitio web y fotos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/hoteles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/tags\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/costaricainfolink.com\/hoteles\/wp-json\/wp\/v2\/posts?tags=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}