{"id":94,"date":"2010-03-03T14:04:48","date_gmt":"2010-03-03T14:04:48","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/hotels\/?p=94"},"modified":"2017-01-30T22:35:53","modified_gmt":"2017-01-30T22:35:53","slug":"luisiana-hotel","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/hotels\/luisiana-hotel\/","title":{"rendered":"Luisiana Hotel Costa Rica"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"99\" data-permalink=\"https:\/\/costaricainfolink.com\/hotels\/luisiana-hotel\/hotel-luisiana-santa-ana-costa-rica-logo\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2010\/02\/hotel-luisiana-santa-ana-costa-rica-logo.jpg\" data-orig-size=\"169,124\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Luisiana Hotel in Santa Ana, San Jose, Costa Rica.\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2010\/02\/hotel-luisiana-santa-ana-costa-rica-logo.jpg\" class=\"wp-image-99 size-full alignright\" title=\"Luisiana Hotel in Santa Ana, San Jose, Costa Rica.\" src=\"http:\/\/www.costaricainfolink.com\/hotels\/wp-content\/uploads\/2010\/02\/hotel-luisiana-santa-ana-costa-rica-logo.jpg\" alt=\"Luisiana Hotel Costa Rica in Santa Ana\" width=\"169\" height=\"124\" \/><strong>Location:<\/strong> from Santa Ana&#8217;s Red Cross, 100m west and 400m south, in Machete street, district: Uruca, canton: Santa Ana, Costa Rica. Zone postal code: 10904.<br \/>\n<strong>Phone:<\/strong> <a href=\"tel:+5062203-5060\">+506 2203-5060<\/a><br \/>\n<strong>GPS coordinates: <\/strong>9.928914,-84.188894 (9\u00b055&#8217;44.09&#8243;N, 84\u00b011&#8217;20.02&#8243;W)<br \/>\n<strong>Website: <\/strong><a href=\"http:\/\/hotelluisiana.com\/\" target=\"_blank\" rel=\"nofollow\">www.hotelluisiana.com<\/a><br \/>\n<a href=\"http:\/\/www.expedia.com\/Santa-Ana-Hotels-Hotel-Luisiana.h2314601.Hotel-Reviews\" target=\"_blank\" rel=\"nofollow\">Hotel Luisiana | Expedia Hotel Reviews<\/a><br \/>\n<a href=\"http:\/\/www.tripadvisor.com\/Hotel_Review-g1122840-d1178560-Reviews-Hotel_Luisiana-Santa_Ana_San_Jose_Metro_Province_of_San_Jose.html#REVIEWS\" target=\"_blank\" rel=\"nofollow\">Hotel Luisiana &#8211; TripAdvisor Read Hotel Reviews<\/a><\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0kprx5\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg\" alt=\"WAZE location for Luisiana Hotel in Santa Ana, San Jose, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Hotel+Luisiana\/@9.9287123,-84.1909101,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0fea62fde470b:0x60e6e1672b2da07a!8m2!3d9.9287123!4d-84.1887214\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg\" alt=\"Google Maps location for Luisiana Hotel in Santa Ana, San Jose, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<p>Luisiana Hotel Costa Rica is located in a strategic position near the Lindora road, in Santa Ana. The owners bought this old Louisiana-style house, built sixty years ago by an immigrant from Louisiana, reason for the name. Louisiana Hotel is a place where you can enjoy peace, comfort, American and Italian home cooking, as an old-style blends with modern American and European details, since the current owners are from Italy.<\/p>\n<p>The hotel has 12 comfortable rooms equipped with cable tv, air conditioning, Wi-Fi internet, kitchen, refrigerator, with hot water private bathroom or jacuzzi, parking in front of the room, laundry service and 24h security, as well as transportation and restaurant services.<\/p>\n<p><strong>Address map:<\/strong> <a href=\"http:\/\/www.costaricainfolink.com\/hotels\/luisiana-hotel-directions-map\/\">Click here to view address map to Luisiana Hotel in San Jose, Costa Rica.<\/a><\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1200\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/costaricainfolink.com\\\/hotels\\\/luisiana-hotel\\\/&quot;,&quot;likes_blog_id&quot;:78229379}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1200px; height: 601px;\" data-original-width=\"1200\" data-original-height=\"601\" > <div class=\"gallery-group images-1\" style=\"width: 800px; height: 601px;\" data-original-width=\"800\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/hotels\/?attachment_id=1152#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"796\"> <meta itemprop=\"height\" content=\"597\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1152\" data-orig-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-5.jpg\" data-orig-size=\"500,375\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-5-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-5.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-5.jpg?w=796&#038;h=597&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-5.jpg 500w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-5-300x225.jpg 300w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-5-150x112.jpg 150w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-5-400x300.jpg 400w\" width=\"796\" height=\"597\" loading=\"lazy\" data-original-width=\"796\" data-original-height=\"597\" itemprop=\"http:\/\/schema.org\/image\" title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" alt=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" style=\"width: 796px; height: 597px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 400px; height: 601px;\" data-original-width=\"400\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/hotels\/?attachment_id=1154#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1154\" data-orig-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-8.jpg\" data-orig-size=\"500,375\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-8-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-8.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-8.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-8.jpg 500w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-8-300x225.jpg 300w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-8-150x112.jpg 150w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-8-400x300.jpg 400w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" alt=\"Hotel Luisiana Santa Ana, San Jose, Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/hotels\/?attachment_id=1153#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1153\" data-orig-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-6.jpg\" data-orig-size=\"500,375\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-6-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-6.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-6.jpg?w=396&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-6.jpg 500w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-6-300x225.jpg 300w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-6-150x112.jpg 150w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-6-400x300.jpg 400w\" width=\"396\" height=\"296\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" alt=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" style=\"width: 396px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 451px;\" data-original-width=\"1200\" data-original-height=\"451\" > <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/hotels\/?attachment_id=1150#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1150\" data-orig-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica.jpg\" data-orig-size=\"500,375\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica.jpg 500w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-300x225.jpg 300w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-150x112.jpg 150w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-400x300.jpg 400w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" alt=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/hotels\/?attachment_id=1151#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1151\" data-orig-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-3.jpg\" data-orig-size=\"500,375\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" data-image-description=\"\" data-medium-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-3-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-3.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-3.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-3.jpg 500w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-3-300x225.jpg 300w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-3-150x112.jpg 150w, https:\/\/costaricainfolink.com\/hotels\/wp-content\/uploads\/2014\/07\/hotel-luisiana-costa-rica-3-400x300.jpg 400w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" alt=\"Luisiana Hotel Santa Ana, San Jose, Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Location: from Santa Ana&#8217;s Red Cross, 100m west and 400m south, in Machete street, district: Uruca, canton: Santa Ana, Costa Rica. Zone postal code: 10904. Phone: +506 2203-5060 GPS coordinates: 9.928914,-84.188894 (9\u00b055&#8217;44.09&#8243;N, 84\u00b011&#8217;20.02&#8243;W) Website: www.hotelluisiana.com Hotel Luisiana | Expedia Hotel Reviews Hotel Luisiana &#8211; TripAdvisor Read Hotel Reviews Luisiana Hotel Costa Rica is located in &#8230; <a title=\"Luisiana Hotel Costa Rica\" class=\"read-more\" href=\"https:\/\/costaricainfolink.com\/hotels\/luisiana-hotel\/\" aria-label=\"Read more about Luisiana Hotel Costa Rica\">Read more<\/a><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[38,13,14],"tags":[],"class_list":["post-94","post","type-post","status-publish","format-standard","hentry","category-38","category-san-jose","category-santa-ana"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5if2b-1w","_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/posts\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/comments?post=94"}],"version-history":[{"count":34,"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/posts\/94\/revisions"}],"predecessor-version":[{"id":1380,"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/posts\/94\/revisions\/1380"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/media?parent=94"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/categories?post=94"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/hotels\/wp-json\/wp\/v2\/tags?post=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}