{"id":100,"count":2,"description":"","link":"https:\/\/costaricainfolink.com\/photos\/category\/travel\/","name":"Travel","slug":"travel","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Travel Archives - Costa Rica Photos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel Archives - Costa Rica Photos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/photos\/category\/travel\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica Photos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/category\\\/travel\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/category\\\/travel\\\/\",\"name\":\"Travel Archives - Costa Rica Photos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/category\\\/travel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/category\\\/travel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\",\"name\":\"Costa Rica Photos\",\"description\":\"Beautiful photos from beautiful Costa Rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel Archives - Costa Rica Photos","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Travel Archives - Costa Rica Photos","og_url":"https:\/\/costaricainfolink.com\/photos\/category\/travel\/","og_site_name":"Costa Rica Photos","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/costaricainfolink.com\/photos\/category\/travel\/","url":"https:\/\/costaricainfolink.com\/photos\/category\/travel\/","name":"Travel Archives - Costa Rica Photos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/photos\/#website"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/photos\/category\/travel\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/photos\/category\/travel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/photos\/"},{"@type":"ListItem","position":2,"name":"Travel"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/photos\/#website","url":"https:\/\/costaricainfolink.com\/photos\/","name":"Costa Rica Photos","description":"Beautiful photos from beautiful Costa Rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/photos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/categories\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts?categories=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}