{"id":4403,"date":"2015-07-01T12:33:55","date_gmt":"2015-07-01T17:33:55","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg"},"modified":"2015-07-01T12:48:12","modified_gmt":"2015-07-01T17:48:12","slug":"avellanas-beach-costa-rica-16","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/photos\/avellanas-beach-costa-rica\/avellanas-beach-costa-rica-16\/#main","title":{"rendered":""},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-4403","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Costa Rica Photos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Costa Rica Photos\" \/>\n<meta property=\"og:description\" content=\"Avellanas Beach in Tamarindo, Santa Cruz, Guanacaste, Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica Photos\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-01T17:48:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-1024x225.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/avellanas-beach-costa-rica-16.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/avellanas-beach-costa-rica-16.jpg\",\"name\":\"- Costa Rica Photos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\"},\"datePublished\":\"2015-07-01T17:33:55+00:00\",\"dateModified\":\"2015-07-01T17:48:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/avellanas-beach-costa-rica-16.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/avellanas-beach-costa-rica-16.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/avellanas-beach-costa-rica-16.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avellanas Beach Costa Rica Photos\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/avellanas-beach-costa-rica\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\",\"name\":\"Costa Rica Photos\",\"description\":\"Beautiful photos from beautiful Costa Rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Costa Rica Photos","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"- Costa Rica Photos","og_description":"Avellanas Beach in Tamarindo, Santa Cruz, Guanacaste, Costa Rica","og_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg","og_site_name":"Costa Rica Photos","article_modified_time":"2015-07-01T17:48:12+00:00","og_image":[{"width":1024,"height":225,"url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-1024x225.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg","url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg","name":"- Costa Rica Photos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/photos\/#website"},"datePublished":"2015-07-01T17:33:55+00:00","dateModified":"2015-07-01T17:48:12+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/photos\/"},{"@type":"ListItem","position":2,"name":"Avellanas Beach Costa Rica Photos","item":"https:\/\/costaricainfolink.com\/photos\/avellanas-beach-costa-rica\/"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/photos\/#website","url":"https:\/\/costaricainfolink.com\/photos\/","name":"Costa Rica Photos","description":"Beautiful photos from beautiful Costa Rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/photos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1lm9J-191","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"66\" src=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-300x66.jpg\" class=\"attachment-medium size-medium\" alt=\"Avellanas Beach Costa Rica\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-300x66.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-185x41.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-1024x225.jpg 1024w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-150x33.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-400x88.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"4403\" data-permalink=\"https:\/\/costaricainfolink.com\/photos\/avellanas-beach-costa-rica\/avellanas-beach-costa-rica-16\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg\" data-orig-size=\"4912,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Avellanas Beach in Tamarindo, Santa Cruz, Guanacaste, Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-1024x225.jpg\" \/><\/a><\/p>\n<p>Avellanas Beach in Tamarindo, Santa Cruz, Guanacaste, Costa Rica<\/p>\n"},"caption":{"rendered":"<p>Avellanas Beach in Tamarindo, Santa Cruz, Guanacaste, Costa Rica<\/p>\n"},"alt_text":"Avellanas Beach Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4912,"height":1080,"file":"2011\/06\/avellanas-beach-costa-rica-16.jpg","sizes":{"thumbnail":{"file":"avellanas-beach-costa-rica-16-185x41.jpg","width":185,"height":41,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-185x41.jpg"},"medium":{"file":"avellanas-beach-costa-rica-16-300x66.jpg","width":300,"height":66,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-300x66.jpg"},"large":{"file":"avellanas-beach-costa-rica-16-1024x225.jpg","width":1024,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-1024x225.jpg"},"post-thumbnail":{"file":"avellanas-beach-costa-rica-16-150x33.jpg","width":150,"height":33,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-150x33.jpg"},"single-post-thumbnail":{"file":"avellanas-beach-costa-rica-16-400x88.jpg","width":400,"height":88,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16-400x88.jpg"},"full":{"file":"avellanas-beach-costa-rica-16.jpg","width":4912,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":1265,"source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/avellanas-beach-costa-rica-16.jpg","filename":"avellanas-beach-costa-rica-16.jpg","filesize":2279801,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/media\/4403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/comments?post=4403"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1265,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/1265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}