{"id":4601,"date":"2015-07-19T14:48:44","date_gmt":"2015-07-19T19:48:44","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg"},"modified":"2015-07-19T16:05:04","modified_gmt":"2015-07-19T21:05:04","slug":"blanca-beach-liberia-costa-rica-22","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-liberia-costa-rica\/blanca-beach-liberia-costa-rica-22\/#main","title":{"rendered":""},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-4601","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Costa Rica Photos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Costa Rica Photos\" \/>\n<meta property=\"og:description\" content=\"Blanca Beach in Nacascolo, Liberia, Guanacaste, Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica Photos\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-19T21:05:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-978x650.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"978\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/blanca-beach-liberia-costa-rica-22.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/blanca-beach-liberia-costa-rica-22.jpg\",\"name\":\"- Costa Rica Photos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\"},\"datePublished\":\"2015-07-19T19:48:44+00:00\",\"dateModified\":\"2015-07-19T21:05:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/blanca-beach-liberia-costa-rica-22.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/blanca-beach-liberia-costa-rica-22.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/blanca-beach-liberia-costa-rica-22.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blanca Beach in Liberia Costa Rica Photos\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-liberia-costa-rica\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\",\"name\":\"Costa Rica Photos\",\"description\":\"Beautiful photos from beautiful Costa Rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Costa Rica Photos","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"- Costa Rica Photos","og_description":"Blanca Beach in Nacascolo, Liberia, Guanacaste, Costa Rica","og_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg","og_site_name":"Costa Rica Photos","article_modified_time":"2015-07-19T21:05:04+00:00","og_image":[{"width":978,"height":650,"url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-978x650.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg","url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg","name":"- Costa Rica Photos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/photos\/#website"},"datePublished":"2015-07-19T19:48:44+00:00","dateModified":"2015-07-19T21:05:04+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/photos\/"},{"@type":"ListItem","position":2,"name":"Blanca Beach in Liberia Costa Rica Photos","item":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-liberia-costa-rica\/"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/photos\/#website","url":"https:\/\/costaricainfolink.com\/photos\/","name":"Costa Rica Photos","description":"Beautiful photos from beautiful Costa Rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/photos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1lm9J-1cd","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"Blanca Beach Costa Rica\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-300x199.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-185x123.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-978x650.jpg 978w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-150x100.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-400x266.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"4601\" data-permalink=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-liberia-costa-rica\/blanca-beach-liberia-costa-rica-22\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg\" data-orig-size=\"4912,3264\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Nacascolo, Liberia, Guanacaste, Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-978x650.jpg\" \/><\/a><\/p>\n<p>Blanca Beach in Nacascolo, Liberia, Guanacaste, Costa Rica<\/p>\n"},"caption":{"rendered":"<p>Blanca Beach in Nacascolo, Liberia, Guanacaste, Costa Rica<\/p>\n"},"alt_text":"Blanca Beach Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4912,"height":3264,"file":"2012\/05\/blanca-beach-liberia-costa-rica-22.jpg","sizes":{"thumbnail":{"file":"blanca-beach-liberia-costa-rica-22-185x123.jpg","width":185,"height":123,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-185x123.jpg"},"medium":{"file":"blanca-beach-liberia-costa-rica-22-300x199.jpg","width":300,"height":199,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-300x199.jpg"},"large":{"file":"blanca-beach-liberia-costa-rica-22-978x650.jpg","width":978,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-978x650.jpg"},"post-thumbnail":{"file":"blanca-beach-liberia-costa-rica-22-150x100.jpg","width":150,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-150x100.jpg"},"single-post-thumbnail":{"file":"blanca-beach-liberia-costa-rica-22-400x266.jpg","width":400,"height":266,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22-400x266.jpg"},"full":{"file":"blanca-beach-liberia-costa-rica-22.jpg","width":4912,"height":3264,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":2809,"source_url":"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-liberia-costa-rica-22.jpg","filename":"blanca-beach-liberia-costa-rica-22.jpg","filesize":3790815,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/media\/4601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/comments?post=4601"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2809,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/2809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}