{"id":1270,"date":"2011-06-19T20:01:22","date_gmt":"2011-06-20T01:01:22","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/photos\/?p=1270"},"modified":"2012-01-14T12:06:33","modified_gmt":"2012-01-14T17:06:33","slug":"hermit-crabs-paguroidea-in-guanacaste-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/","title":{"rendered":"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica"},"content":{"rendered":"<h5><a title=\"Cangrejos Ermita\u00f1os (Paguroidea) en Guanacaste, Costa Rica\" href=\"https:\/\/www.costaricainfolink.com\/fotos\/cangrejos-ermitanos-paguroidea-en-guanacaste-costa-rica\/\">Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol<\/a><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2267\" data-permalink=\"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/hermit-crabs-azul-beach-guanacaste-costa-rica\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg\" data-orig-size=\"504,378\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Hermit Crabs (Paguroidea) picture in Azul beach, Guanacaste, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg\" class=\"alignnone size-full wp-image-2267\" title=\"Hermit Crabs (Paguroidea) picture in Azul beach, Guanacaste, Costa Rica\" src=\"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg\" alt=\"\" width=\"504\" height=\"378\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg 504w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica-150x112.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica-400x300.jpg 400w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[68,73],"tags":[],"class_list":["post-1270","post","type-post","status-publish","format-standard","hentry","category-crabs","category-guanacaste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica - Costa Rica Photos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica - Costa Rica Photos\" \/>\n<meta property=\"og:description\" content=\"Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica Photos\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-20T01:01:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-01-14T17:06:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#\\\/schema\\\/person\\\/74cfe7eea26ea47a4dad189e44ff48b8\"},\"headline\":\"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica\",\"datePublished\":\"2011-06-20T01:01:22+00:00\",\"dateModified\":\"2012-01-14T17:06:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/\"},\"wordCount\":17,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg\",\"articleSection\":[\"Crabs\",\"Guanacaste\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/\",\"name\":\"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica - Costa Rica Photos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg\",\"datePublished\":\"2011-06-20T01:01:22+00:00\",\"dateModified\":\"2012-01-14T17:06:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#\\\/schema\\\/person\\\/74cfe7eea26ea47a4dad189e44ff48b8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costaricainfolink.com\\\/photos\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\",\"name\":\"Costa Rica Photos\",\"description\":\"Beautiful photos from beautiful Costa Rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#\\\/schema\\\/person\\\/74cfe7eea26ea47a4dad189e44ff48b8\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"],\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/author\\\/costaricainfolink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica - Costa Rica Photos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/","og_locale":"en_US","og_type":"article","og_title":"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica - Costa Rica Photos","og_description":"Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol","og_url":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/","og_site_name":"Costa Rica Photos","article_published_time":"2011-06-20T01:01:22+00:00","article_modified_time":"2012-01-14T17:06:33+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Costa Rica Info Link"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/photos\/#\/schema\/person\/74cfe7eea26ea47a4dad189e44ff48b8"},"headline":"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica","datePublished":"2011-06-20T01:01:22+00:00","dateModified":"2012-01-14T17:06:33+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/"},"wordCount":17,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg","articleSection":["Crabs","Guanacaste"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/","url":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/","name":"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica - Costa Rica Photos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/photos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg","datePublished":"2011-06-20T01:01:22+00:00","dateModified":"2012-01-14T17:06:33+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/photos\/#\/schema\/person\/74cfe7eea26ea47a4dad189e44ff48b8"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/#primaryimage","url":"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg","contentUrl":"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2011\/06\/hermit-crabs-azul-beach-guanacaste-costa-rica.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/photos\/hermit-crabs-paguroidea-in-guanacaste-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/photos\/"},{"@type":"ListItem","position":2,"name":"Hermit Crabs (Paguroidea) in Guanacaste, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/photos\/#website","url":"https:\/\/costaricainfolink.com\/photos\/","name":"Costa Rica Photos","description":"Beautiful photos from beautiful Costa Rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/photos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/photos\/#\/schema\/person\/74cfe7eea26ea47a4dad189e44ff48b8","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"],"url":"https:\/\/costaricainfolink.com\/photos\/author\/costaricainfolink\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1lm9J-ku","_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/1270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/comments?post=1270"}],"version-history":[{"count":3,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/1270\/revisions"}],"predecessor-version":[{"id":2268,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/1270\/revisions\/2268"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/media?parent=1270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/categories?post=1270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/tags?post=1270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}