{"id":2803,"date":"2012-05-30T12:30:27","date_gmt":"2012-05-30T17:30:27","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/photos\/?p=2803"},"modified":"2015-07-16T18:04:47","modified_gmt":"2015-07-16T23:04:47","slug":"blanca-beach-in-la-cruz-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/","title":{"rendered":"Blanca Beach in La Cruz, Costa Rica"},"content":{"rendered":"<p><a title=\"Playa Blanca en la Cruz, Costa Rica\" href=\"https:\/\/www.costaricainfolink.com\/fotos\/playa-blanca-en-la-cruz-costa-rica\/\">Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol<\/a><\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1200\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/&quot;,&quot;likes_blog_id&quot;:19866395}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1200px; height: 601px;\" data-original-width=\"1200\" data-original-height=\"601\" > <div class=\"gallery-group images-1\" style=\"width: 800px; height: 601px;\" data-original-width=\"800\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"796\"> <meta itemprop=\"height\" content=\"597\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4559\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica.jpg?w=796&#038;h=597&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-400x300.jpg 400w\" width=\"796\" height=\"597\" loading=\"lazy\" data-original-width=\"796\" data-original-height=\"597\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 796px; height: 597px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 400px; height: 601px;\" data-original-width=\"400\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-2\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4560\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-2-400x300.jpg 400w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-3\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4561\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3.jpg?w=396&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-3-400x300.jpg 400w\" width=\"396\" height=\"296\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 396px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 301px;\" data-original-width=\"1200\" data-original-height=\"301\" > <div class=\"gallery-group images-1\" style=\"width: 400px; height: 301px;\" data-original-width=\"400\" data-original-height=\"301\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-4\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4562\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-4-400x300.jpg 400w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 400px; height: 301px;\" data-original-width=\"400\" data-original-height=\"301\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-5\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4563\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-5-400x300.jpg 400w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 400px; height: 301px;\" data-original-width=\"400\" data-original-height=\"301\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-6\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4564\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-6-400x300.jpg 400w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 601px;\" data-original-width=\"1200\" data-original-height=\"601\" > <div class=\"gallery-group images-2\" style=\"width: 400px; height: 601px;\" data-original-width=\"400\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-7\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"297\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4565\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7.jpg?w=396&#038;h=297&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-7-400x300.jpg 400w\" width=\"396\" height=\"297\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"297\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 396px; height: 297px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-8\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"296\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4566\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8.jpg?w=396&#038;h=296&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-8-400x300.jpg 400w\" width=\"396\" height=\"296\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"296\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 396px; height: 296px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 800px; height: 601px;\" data-original-width=\"800\" data-original-height=\"601\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-9\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"796\"> <meta itemprop=\"height\" content=\"597\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4567\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9.jpg?w=796&#038;h=597&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-9-400x300.jpg 400w\" width=\"796\" height=\"597\" loading=\"lazy\" data-original-width=\"796\" data-original-height=\"597\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 796px; height: 597px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 451px;\" data-original-width=\"1200\" data-original-height=\"451\" > <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-10\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4568\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-10-400x300.jpg 400w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 600px; height: 451px;\" data-original-width=\"600\" data-original-height=\"451\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-11\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"447\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4569\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11.jpg\" data-orig-size=\"4608,3456\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11-300x225.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11-867x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11.jpg?w=596&#038;h=447&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11.jpg 4608w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11-185x139.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11-300x225.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11-867x650.jpg 867w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11-150x113.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-11-400x300.jpg 400w\" width=\"596\" height=\"447\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"447\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 596px; height: 447px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 533px;\" data-original-width=\"1200\" data-original-height=\"533\" > <div class=\"gallery-group images-1\" style=\"width: 801px; height: 533px;\" data-original-width=\"801\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-12\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"797\"> <meta itemprop=\"height\" content=\"529\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4570\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12.jpg\" data-orig-size=\"4912,3264\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12-300x199.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12-978x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12.jpg?w=797&#038;h=529&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12.jpg 4912w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12-185x123.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12-300x199.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12-978x650.jpg 978w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12-150x100.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-12-400x266.jpg 400w\" width=\"797\" height=\"529\" loading=\"lazy\" data-original-width=\"797\" data-original-height=\"529\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 797px; height: 529px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 399px; height: 533px;\" data-original-width=\"399\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-13\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"395\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4571\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13.jpg\" data-orig-size=\"4912,3264\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13-300x199.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13-978x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13.jpg?w=395&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13.jpg 4912w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13-185x123.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13-300x199.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13-978x650.jpg 978w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13-150x100.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-13-400x266.jpg 400w\" width=\"395\" height=\"263\" loading=\"lazy\" data-original-width=\"395\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 395px; height: 263px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-14\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"395\"> <meta itemprop=\"height\" content=\"262\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4572\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14.jpg\" data-orig-size=\"4912,3264\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14-300x199.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14-978x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14.jpg?w=395&#038;h=262&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14.jpg 4912w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14-185x123.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14-300x199.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14-978x650.jpg 978w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14-150x100.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-14-400x266.jpg 400w\" width=\"395\" height=\"262\" loading=\"lazy\" data-original-width=\"395\" data-original-height=\"262\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 395px; height: 262px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 400px;\" data-original-width=\"1200\" data-original-height=\"400\" > <div class=\"gallery-group images-1\" style=\"width: 600px; height: 400px;\" data-original-width=\"600\" data-original-height=\"400\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-15\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"396\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4573\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15.jpg\" data-orig-size=\"4912,3264\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15-300x199.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15-978x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15.jpg?w=596&#038;h=396&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15.jpg 4912w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15-185x123.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15-300x199.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15-978x650.jpg 978w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15-150x100.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-15-400x266.jpg 400w\" width=\"596\" height=\"396\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"396\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 596px; height: 396px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 600px; height: 400px;\" data-original-width=\"600\" data-original-height=\"400\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-16\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"596\"> <meta itemprop=\"height\" content=\"396\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4574\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16.jpg\" data-orig-size=\"4912,3264\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16-300x199.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16-978x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16.jpg?w=596&#038;h=396&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16.jpg 4912w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16-185x123.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16-300x199.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16-978x650.jpg 978w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16-150x100.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-16-400x266.jpg 400w\" width=\"596\" height=\"396\" loading=\"lazy\" data-original-width=\"596\" data-original-height=\"396\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 596px; height: 396px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 533px;\" data-original-width=\"1200\" data-original-height=\"533\" > <div class=\"gallery-group images-2\" style=\"width: 399px; height: 533px;\" data-original-width=\"399\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-17\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"395\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4575\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17.jpg\" data-orig-size=\"4912,3264\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17-300x199.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17-978x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17.jpg?w=395&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17.jpg 4912w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17-185x123.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17-300x199.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17-978x650.jpg 978w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17-150x100.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-17-400x266.jpg 400w\" width=\"395\" height=\"263\" loading=\"lazy\" data-original-width=\"395\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 395px; height: 263px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-18\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"395\"> <meta itemprop=\"height\" content=\"262\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4576\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18.jpg\" data-orig-size=\"4912,3264\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18-300x199.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18-978x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18.jpg?w=395&#038;h=262&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18.jpg 4912w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18-185x123.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18-300x199.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18-978x650.jpg 978w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18-150x100.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-18-400x266.jpg 400w\" width=\"395\" height=\"262\" loading=\"lazy\" data-original-width=\"395\" data-original-height=\"262\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 395px; height: 262px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 801px; height: 533px;\" data-original-width=\"801\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-19\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"797\"> <meta itemprop=\"height\" content=\"529\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4577\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19.jpg\" data-orig-size=\"4912,3264\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19-300x199.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19-978x650.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19.jpg?w=797&#038;h=529&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19.jpg 4912w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19-185x123.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19-300x199.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19-978x650.jpg 978w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19-150x100.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-19-400x266.jpg 400w\" width=\"797\" height=\"529\" loading=\"lazy\" data-original-width=\"797\" data-original-height=\"529\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 797px; height: 529px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 267px;\" data-original-width=\"1200\" data-original-height=\"267\" > <div class=\"gallery-group images-1\" style=\"width: 1200px; height: 267px;\" data-original-width=\"1200\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/blanca-beach-la-cruz-guanacaste-costa-rica-20\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"1196\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4578\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20.jpg\" data-orig-size=\"4912,1080\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Blanca Beach in Santa Elena, La Cruz, Guanacaste, Costa Rica&lt;\/p&gt; \" data-medium-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20-300x66.jpg\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20-1024x225.jpg\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20.jpg?w=1196&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20.jpg 4912w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20-185x41.jpg 185w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20-300x66.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20-1024x225.jpg 1024w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20-150x33.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica-20-400x88.jpg 400w\" width=\"1196\" height=\"263\" loading=\"lazy\" data-original-width=\"1196\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Blanca Beach Costa Rica\" style=\"width: 1196px; height: 263px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<h3><a href=\"https:\/\/www.costaricainfolink.com\/en\/blanca-beach-in-la-cruz-costa-rica\/\">Click here to view Blanca Beach information, location address map, GPS coordinates, video, how to get there by bus or airplane.<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol Click here to view Blanca Beach information, location address map, GPS coordinates, video, how to get there by bus or airplane.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[29,73],"tags":[],"class_list":["post-2803","post","type-post","status-publish","format-standard","hentry","category-beaches","category-guanacaste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blanca Beach in La Cruz, Costa Rica - Costa Rica Photos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blanca Beach in La Cruz, Costa Rica - Costa Rica Photos\" \/>\n<meta property=\"og:description\" content=\"Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol Click here to view Blanca Beach information, location address map, GPS coordinates, video, how to get there by bus or airplane.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica Photos\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-30T17:30:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-16T23:04:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica.jpg?w=636&#038;h=477&#038;ssl=1\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#\\\/schema\\\/person\\\/74cfe7eea26ea47a4dad189e44ff48b8\"},\"headline\":\"Blanca Beach in La Cruz, Costa Rica\",\"datePublished\":\"2012-05-30T17:30:27+00:00\",\"dateModified\":\"2015-07-16T23:04:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/\"},\"wordCount\":42,\"commentCount\":0,\"articleSection\":[\"Beaches\",\"Guanacaste\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/\",\"name\":\"Blanca Beach in La Cruz, Costa Rica - Costa Rica Photos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\"},\"datePublished\":\"2012-05-30T17:30:27+00:00\",\"dateModified\":\"2015-07-16T23:04:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#\\\/schema\\\/person\\\/74cfe7eea26ea47a4dad189e44ff48b8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/blanca-beach-in-la-cruz-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blanca Beach in La Cruz, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\",\"name\":\"Costa Rica Photos\",\"description\":\"Beautiful photos from beautiful Costa Rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#\\\/schema\\\/person\\\/74cfe7eea26ea47a4dad189e44ff48b8\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"],\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/author\\\/costaricainfolink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blanca Beach in La Cruz, Costa Rica - Costa Rica Photos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/","og_locale":"en_US","og_type":"article","og_title":"Blanca Beach in La Cruz, Costa Rica - Costa Rica Photos","og_description":"Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol Click here to view Blanca Beach information, location address map, GPS coordinates, video, how to get there by bus or airplane.","og_url":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/","og_site_name":"Costa Rica Photos","article_published_time":"2012-05-30T17:30:27+00:00","article_modified_time":"2015-07-16T23:04:47+00:00","og_image":[{"url":"https:\/\/i1.wp.com\/costaricainfolink.com\/photos\/wp-content\/uploads\/2012\/05\/blanca-beach-la-cruz-guanacaste-costa-rica.jpg?w=636&#038;h=477&#038;ssl=1","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Costa Rica Info Link"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/photos\/#\/schema\/person\/74cfe7eea26ea47a4dad189e44ff48b8"},"headline":"Blanca Beach in La Cruz, Costa Rica","datePublished":"2012-05-30T17:30:27+00:00","dateModified":"2015-07-16T23:04:47+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/"},"wordCount":42,"commentCount":0,"articleSection":["Beaches","Guanacaste"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/","url":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/","name":"Blanca Beach in La Cruz, Costa Rica - Costa Rica Photos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/photos\/#website"},"datePublished":"2012-05-30T17:30:27+00:00","dateModified":"2015-07-16T23:04:47+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/photos\/#\/schema\/person\/74cfe7eea26ea47a4dad189e44ff48b8"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/photos\/blanca-beach-in-la-cruz-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/photos\/"},{"@type":"ListItem","position":2,"name":"Blanca Beach in La Cruz, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/photos\/#website","url":"https:\/\/costaricainfolink.com\/photos\/","name":"Costa Rica Photos","description":"Beautiful photos from beautiful Costa Rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/photos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/photos\/#\/schema\/person\/74cfe7eea26ea47a4dad189e44ff48b8","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"],"url":"https:\/\/costaricainfolink.com\/photos\/author\/costaricainfolink\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1lm9J-Jd","_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/comments?post=2803"}],"version-history":[{"count":6,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/2803\/revisions"}],"predecessor-version":[{"id":4579,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/2803\/revisions\/4579"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/media?parent=2803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/categories?post=2803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/tags?post=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}